{"id":1470796,"date":"2026-02-03T03:03:48","date_gmt":"2026-02-03T11:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/"},"modified":"2026-02-03T03:03:48","modified_gmt":"2026-02-03T11:03:48","slug":"analisis-petro-trump-reunion-casa-blanca-colombia-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/","title":{"rendered":"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia"},"content":{"rendered":"<p>En el primer a\u00f1o del segundo mandato de Donald Trump, su relaci\u00f3n con el Gobierno de Colombia parece haber estado siempre al borde de la ruptura: Gustavo Petro ha caminado en el filo del abismo con declaraciones incendiarias mutuas y disputas en redes sociales.<\/p>\n<p>Pero en lo que amenazaba con ser el peor momento de la relaci\u00f3n bilateral tras las cr\u00edticas de Petro por la captura de Nicol\u00e1s Maduro, el presidente de Colombia confirm\u00f3 una reuni\u00f3n con Trump en la Casa Blanca para este 3 de febrero. Es el primer encuentro luego de un per\u00edodo de cruces y Petro tiene como objetivo lograr beneficios concretos para Colombia a partir del di\u00e1logo con Washington, en medio \u2014adem\u00e1s\u2014 de una etapa electoral.<\/p>\n<p>La reuni\u00f3n qued\u00f3 agendada en<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/08\/colombia\/efectos-llamado-petro-trump-colombia-eeuu-venezuela-orix\"> la llamada<\/a> que ambos mandatarios tuvieron el 7 de enero, en un intento de desescalar tensiones por las duras declaraciones del presidente de EE.UU. sobre Colombia y el narcotr\u00e1fico y despu\u00e9s del ataque en Venezuela. Tras acusaciones mutuas (<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/10\/eeuu\/trump-petro-siguiente-maduro-efe\">Trump sugiri\u00f3 que el pr\u00f3ximo en la lista de captura podr\u00eda ser Petro<\/a> y dijo que no le disgustaba la idea de una intervenci\u00f3n militar en Colombia), en la llamada los gobernantes acordaron restablecer comunicaciones de alto nivel y apuntar a la reuni\u00f3n en la Casa Blanca para abordar temas como seguridad, drogas y cooperaci\u00f3n regional.<\/p>\n<p>Para Ana Mar\u00eda Salazar, experta en temas internacionales y de seguridad, Petro \u201cse dio cuenta de que seguir en esta t\u00f3nica de estar amenazando, ri\u00e9ndose, burl\u00e1ndose hasta cierto punto del presidente Donald Trump era un horror\u201d. Salazar opina que, tras las acciones militares de Estados Unidos en el Caribe y la captura de Maduro \u2014y \u201cviendo que no ha habido consecuencias muy negativas para Trump\u201d\u2014, el presidente de Colombia entendi\u00f3 que la posici\u00f3n deb\u00eda ser diferente.<\/p>\n<p>El objetivo, sobre el papel,<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/15\/colombia\/petro-trump-reunion-eeuu-febrero-orix\"> es restablecer el di\u00e1logo y avanzar en temas urgentes para Colombia y Estados Unidos<\/a>. Petro y su equipo han dicho que en la agenda de la reuni\u00f3n estar\u00e1n cuestiones de seguridad y cooperaci\u00f3n, especialmente la lucha contra el narcotr\u00e1fico, el combate a grupos armados ilegales como el ELN y la renegociaci\u00f3n de la colaboraci\u00f3n estrat\u00e9gica entre ambos pa\u00edses.<\/p>\n<p>En cabeza del ministro de Defensa Pedro S\u00e1nchez, el Gobierno de Colombia ha mostrado en las \u00faltimas semanas que su intenci\u00f3n es demostrarle a Washington que el pa\u00eds tiene una lucha activa y eficiente contra el narcotr\u00e1fico.<\/p>\n<p>Adem\u00e1s, el presidente de Colombia quiere que Washington reconsidere sanciones impuestas a su entorno m\u00e1s cercano, incluyendo la posibilidad de que Petro pueda viajar sin limitaciones a EE.UU.: en septiembre pasado EE.UU. le revoc\u00f3 la visa y<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/25\/colombia\/razones-sanciones-petro-orix\"> en octubre lo incluy\u00f3 en la lista de la Oficina de Control de Activos Extranjeros<\/a> (OFAC, por sus siglas en ingl\u00e9s, la llamada Lista Clinton) por su presunto papel en el tr\u00e1fico il\u00edcito global de drogas, junto a su esposa, su hijo y el ministro del Interior de Colombia, Armando Benedetti. Para el encuentro, EE.UU. dio tanto a Petro como a Benedetti un permiso de d\u00edas, una visa especial.<\/p>\n<p>En paralelo, el Gobierno colombiano trabaja en otros frentes diplom\u00e1ticos relacionados. Petro ha propuesto una articulaci\u00f3n energ\u00e9tica regional que incluya a Venezuela y Panam\u00e1 para mejorar la eficiencia y la reducci\u00f3n de costos, adem\u00e1s de buscar un enfoque compartido sobre temas de energ\u00eda limpia y comercio.<\/p>\n<p>Por su parte, \u00bfqu\u00e9 busca Trump? \u201cDesde la \u00f3ptica de Washington, hay intereses estrat\u00e9gicos en Colombia: Estados Unidos buscar\u00eda empujar, presionar, de una forma diferente a lo que pas\u00f3 en Venezuela\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/09\/colombia\/video\/analisis-eeuu-colombia-relaciones-petro-trump-perspectivas-mexico-tv\">dijo Salazar a CNN<\/a>.<\/p>\n<p>\u201cEstados Unidos va a estar viendo c\u00f3mo Colombia podr\u00eda jugar un papel en la transici\u00f3n que pudiera suceder en Venezuela\u201d, concluye la analista.<\/p>\n<p>As\u00ed las cosas, la reuni\u00f3n con Trump resulta ser primordial para Petro, quien pretende concluir su mandato sin tropiezos, asegurar la continuidad de su proyecto pol\u00edtico y dejar un legado a la altura del concepto que tiene de s\u00ed mismo, por lo que necesita calmar las aguas con el mayor aliado comercial y de seguridad de Colombia.<\/p>\n<p>Eso explica que el presidente de Colombia haya cancelado su asistencia al Foro Econ\u00f3mico Mundial de Davos para concentrarse en los preparativos de la reuni\u00f3n con Trump.<\/p>\n<p>Pero la ret\u00f3rica de Petro sigue siendo su enemigo: una semana antes del encuentro, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/27\/colombia\/video\/gustavo-petro-maduro-venezuela-trump\">en un pronunciamiento extenso y lleno de opiniones <\/a>de temas que nada tienen que ver con pol\u00edtica, el presidente dijo que se trataba de una reuni\u00f3n determinante \u201cen su vida personal\u201d y para \u201cla humanidad\u201d, pero volvi\u00f3 a criticar a EE.UU. por la operaci\u00f3n en Venezuela: \u201cBombardear a Caracas, la patria de Bol\u00edvar, eso no es un acto contra Maduro\u2026 que se parece (a Trump) porque creen en el petr\u00f3leo\u201d.<\/p>\n<p>El giro de Petro hacia un di\u00e1logo con Trump choca con la postura m\u00e1s cr\u00edtica y antiestadounidense de figuras como Iv\u00e1n Cepeda, senador y aspirante presidencial del oficialismo. Cepeda considera que el planteamiento del Gobierno de EE.UU., como la acusaci\u00f3n contra Petro por narcotr\u00e1fico, es una \u201cmentira c\u00ednica\u201d que puede ser utilizada para provocar una crisis militar o pol\u00edtica en la regi\u00f3n.<\/p>\n<p>La distensi\u00f3n entre Petro y Trump ha descolocado al uribismo (el movimiento pol\u00edtico asociado al expresidente \u00c1lvaro Uribe) en plena campa\u00f1a electoral. La narrativa usual de la oposici\u00f3n con base en la cercan\u00eda ideol\u00f3gica con EE.UU. pierde fuerza si Petro y Trump muestran cooperaci\u00f3n diplom\u00e1tica, complicando la estrategia de candidatos de derecha que buscaban el respaldo de Washington.<\/p>\n<p>A pesar de tensiones y cr\u00edticas, Petro conserva niveles de aprobaci\u00f3n relevantes para un a\u00f1o electoral. Seg\u00fan varias mediciones de opini\u00f3n p\u00fablica, su imagen positiva ronda el 40 %, aunque con variaciones seg\u00fan la encuesta. Estas cifras muestran que, pese a la polarizaci\u00f3n y a los ataques verbales de Trump, su base de respaldo sigue siendo significativa.<\/p>\n<p>Con eso en mente, Salazar cree que \u201cla ventaja que tiene Petro en este momento es que pol\u00edticamente \u00e9l puede hacer este giro, este acercamiento sin que tenga costos pol\u00edticos internos que podr\u00edan afectarlo a \u00e9l o a su partido o a la persona que vaya a reemplazarlo si es de su l\u00ednea pol\u00edtica\u201d.<\/p>\n<p>El acercamiento a Trump se suma a medidas de Petro que podr\u00edan tener un impacto electoral a favor del candidato oficialista, como <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/12\/30\/colombia\/gobierno-sube-salario-minimo-2026-efe\">el aumento del 23 % del salario m\u00ednimo<\/a> y la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/21\/colombia\/petro-reduce-salario-congresistas-quita-prima-efe\">reducci\u00f3n del salario de los congresistas.<\/a><\/p>\n<p>Aunque las relaciones entre Petro y Trump han sido tensas, la cooperaci\u00f3n antidrogas entre Colombia y Estados Unidos contin\u00faa<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/08\/colombia\/alianza-antidrogas-eeuu-petro-trump-trax\"> siendo un pilar de la relaci\u00f3n bilateral<\/a>, incluso a pesar de la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/15\/colombia\/trump-descertifica-narcotrafico-trax\">descertificaci\u00f3n<\/a> de Colombia en la lucha contra el narcotr\u00e1fico y la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/23\/colombia\/trump-asistencia-colombia-petro-orix\">cancelaci\u00f3n de la ayuda financiera<\/a>. Ambos pa\u00edses han mantenido mecanismos de coordinaci\u00f3n contra el narcotr\u00e1fico, compartiendo inteligencia, tecnolog\u00eda y esfuerzos operativos para interceptar env\u00edos ilegales y debilitar a organizaciones criminales que operan en la regi\u00f3n. Esta colaboraci\u00f3n tiene ra\u00edces profundas en d\u00e9cadas de trabajo conjunto, incluso cuando ha habido alejamiento pol\u00edtico en otros frentes.<\/p>\n<p>Las autoridades de ambos pa\u00edses \u2014incluidos altos funcionarios como el secretario de Estado estadounidense Marco Rubio y representantes del Gobierno colombiano\u2014 han enfatizado que la lucha contra el narcotr\u00e1fico es un inter\u00e9s compartido que trasciende las diferencias pol\u00edticas y que seguir\u00e1 siendo una base de su cooperaci\u00f3n.<\/p>\n<p>Un a\u00f1o despu\u00e9s de tensiones diplom\u00e1ticas que incluyeron acusaciones de Trump hacia Petro y advertencias sobre acciones militares y aranceles, el hecho de que ambos l\u00edderes hayan decidido tener un di\u00e1logo <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/09\/colombia\/trump-petro-amenazas-tension-llamada-orix\">puede verse como un intento de resetear<\/a> una relaci\u00f3n que hab\u00eda estado al borde de la ruptura.<\/p>\n<p>Pero tanto Petro como Trump son impulsivos en sus declaraciones y el resultado es incierto. Aunque no dar\u00e1n conferencia de prensa juntos tras la reuni\u00f3n, las conclusiones de cada uno las sabremos despu\u00e9s. \u00bfSer\u00e1 un encuentro como el que tuvo Trump con Volodymyr Zelensky <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/28\/mundo\/reunion-zelensky-trump-trax\">en febrero de 2025 que termin\u00f3 en una confrontaci\u00f3n<\/a> o, m\u00e1s bien, como el que tuvo con Zohran Mamdani en noviembre <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/11\/24\/eeuu\/reunion-trump-mamdani-detalles-trax\">con sonrisas y una cordialidad inesperada <\/a>entre opuestos ideol\u00f3gicos?<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el primer a\u00f1o del segundo mandato de Donald Trump, su relaci\u00f3n con el Gobierno de Colombia parece haber estado siempre al borde de la ruptura: Gustavo Petro ha caminado en el filo del abismo con declaraciones incendiarias mutuas y disputas en redes sociales. Pero en lo que amenazaba con ser el peor momento de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470796","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia - Noticias\" \/>\n<meta property=\"og:description\" content=\"En el primer a\u00f1o del segundo mandato de Donald Trump, su relaci\u00f3n con el Gobierno de Colombia parece haber estado siempre al borde de la ruptura: Gustavo Petro ha caminado en el filo del abismo con declaraciones incendiarias mutuas y disputas en redes sociales. Pero en lo que amenazaba con ser el peor momento de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T11:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia\",\"datePublished\":\"2026-02-03T11:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/\"},\"wordCount\":1477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/\",\"name\":\"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-03T11:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia - Noticias","og_description":"En el primer a\u00f1o del segundo mandato de Donald Trump, su relaci\u00f3n con el Gobierno de Colombia parece haber estado siempre al borde de la ruptura: Gustavo Petro ha caminado en el filo del abismo con declaraciones incendiarias mutuas y disputas en redes sociales. Pero en lo que amenazaba con ser el peor momento de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/","og_site_name":"Noticias","article_published_time":"2026-02-03T11:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia","datePublished":"2026-02-03T11:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/"},"wordCount":1477,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/","url":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/","name":"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-03T11:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfC\u00f3mo llegan Petro y Trump a la reuni\u00f3n en la Casa Blanca? Del choque al di\u00e1logo: un encuentro clave para Colombia","url":"http:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-03T11:03:48Z","datePublished":"2026-02-03T11:03:48Z","dateModified":"2026-02-03T11:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfC\\u00f3mo llegan Petro y Trump a la reuni\\u00f3n en la Casa Blanca? Del choque al di\\u00e1logo: un encuentro clave para Colombia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/02\\\/03\\\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/02\\\/03\\\/analisis-petro-trump-reunion-casa-blanca-colombia-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-03T11:03:48Z\",\"datePublished\":\"2026-02-03T11:03:48Z\",\"dateModified\":\"2026-02-03T11:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470830,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/trump-petro-reunion-optimista-orix\/","url_meta":{"origin":1470796,"position":0},"title":"Petro y Trump tuvieron una reuni\u00f3n &#171;muy buena&#187; que dej\u00f3 un &#171;aire optimista&#187;, tras un a\u00f1o marcado por el choque constante","author":"","date":"febrero 3, 2026","format":false,"excerpt":"Despu\u00e9s de un a\u00f1o marcado por cruces verbales y amenazas, y en el que la relaci\u00f3n entre Colombia y Estados Unidos estuvo constantemente al borde de la ruptura, los presidentes Gustavo Petro y Donald Trump finalmente se vieron este martes cara a cara en Washington.Puede que los l\u00edderes no hayan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470108,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/15\/petro-trump-reunion-eeuu-febrero-orix\/","url_meta":{"origin":1470796,"position":1},"title":"\u00bfQu\u00e9 buscar\u00e1 Petro en la reuni\u00f3n con Trump en Washington el 3 de febrero?","author":"","date":"enero 15, 2026","format":false,"excerpt":"En un Consejo de ministros, realizado en la noche del mi\u00e9rcoles en la Casa de Nari\u00f1o en Bogot\u00e1, Gustavo Petro dijo que el 3 de febrero se reunir\u00e1 con el presidente de Estados Unidos, Donald Trump, en Washington. Petro resalt\u00f3 que la intenci\u00f3n de este encuentro es que los colombianos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470825,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/petro-victoria-geopolitica-reunion-trump-orix\/","url_meta":{"origin":1470796,"position":2},"title":"Petro logra una victoria geopol\u00edtica tras mantener una reuni\u00f3n &#171;positiva&#187; con Trump en la Casa Blanca","author":"","date":"febrero 3, 2026","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, logr\u00f3 una victoria pol\u00edtica significativa tras mantener una reuni\u00f3n \u201cpositiva\u201d con el presidente de EE.UU., Donald Trump, este martes en la Casa Blanca.Fue apenas en octubre cuando el Gobierno de Estados Unidos acus\u00f3 a Petro de estar involucrado en el narcotr\u00e1fico (Petro ha negado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469886,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/01\/07\/trump-hablo-presidente-colombia-gustavo-petro-trax\/","url_meta":{"origin":1470796,"position":3},"title":"Trump habl\u00f3 con el presidente de Colombia, Gustavo Petro, y lo invit\u00f3 a una reuni\u00f3n en la Casa Blanca en el &#171;futuro cercano&#187;","author":"","date":"enero 7, 2026","format":false,"excerpt":"El presidente Donald Trump confirm\u00f3 este mi\u00e9rcoles en redes sociales que \u201caprecia\u201d la llamada que sostuvo con el presidente de Colombia, Gustavo Petro, e invit\u00f3 al mandatario sudamericano a una reuni\u00f3n en la Casa Blanca en el \u201cfuturo cercano\u201d.\u201cFue un gran honor hablar con el presidente de Colombia, Gustavo Petro,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470755,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/02\/petro-reunion-trump-washington-orix\/","url_meta":{"origin":1470796,"position":4},"title":"Petro lleg\u00f3 a Washington para su reuni\u00f3n con Trump tras un a\u00f1o de fuertes tensiones","author":"","date":"febrero 2, 2026","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, lleg\u00f3 este lunes a Washington para reunirse con el mandatario estadounidense, Donald Trump, quien lo recibir\u00e1 el martes en la Casa Blanca tras un a\u00f1o de varios ataques verbales y tensiones que se aliviaron en las \u00faltimas semanas.\u201cEmpiezo mi jornada de comunicaci\u00f3n intensa con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472144,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/03\/12\/trump-petro-llamada-energia-narcotrafico-trax\/","url_meta":{"origin":1470796,"position":5},"title":"Trump y Petro hablan por tel\u00e9fono sobre energ\u00eda, narcotr\u00e1fico y Venezuela","author":"","date":"marzo 12, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, sostuvo una llamada telef\u00f3nica de casi media hora la tarde de este jueves con el presidente de Colombia, Gustavo Petro, seg\u00fan inform\u00f3 el asesor presidencial colombiano Andr\u00e9s Hern\u00e1ndez Ram\u00edrez.La conversaci\u00f3n se centr\u00f3 en la cooperaci\u00f3n energ\u00e9tica, los esfuerzos para combatir el narcotr\u00e1fico y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1470796"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470796\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1470796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1470796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1470796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}