{"id":1470816,"date":"2026-02-03T12:03:48","date_gmt":"2026-02-03T20:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/"},"modified":"2026-02-03T12:03:48","modified_gmt":"2026-02-03T20:03:48","slug":"portaaviones-eeuu-derriba-dron-irani-petrolero-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/","title":{"rendered":"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense"},"content":{"rendered":"<p>Un portaaviones de EE.UU. derrib\u00f3 un dron iran\u00ed que \u201cse acerc\u00f3 de manera agresiva\u201d al buque en el mar Ar\u00e1bigo el martes, horas antes de que dos botes armados operados por el Cuerpo de la Guardia Revolucionaria Isl\u00e1mica de Ir\u00e1n se acercaran a un petrolero con bandera estadounidense en el estrecho de Ormuz y amenazaran con abordar y apoderarse de la nave, seg\u00fan un portavoz militar de EE.UU.<\/p>\n<p>Los dos incidentes ocurren d\u00edas antes de que funcionarios de EE.UU. e Ir\u00e1n <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-administration-news-02-02-26?post-id=cml5jgbqj00003b6pty0ikaqc\">se re\u00fanan el viernes<\/a> para negociaciones diplom\u00e1ticas destinadas a evitar un enfrentamiento militar.<\/p>\n<p>En el primer incidente del martes, fuerzas estadounidenses derribaron un dron iran\u00ed \u201ccuando la aeronave no tripulada se acerc\u00f3 de manera agresiva\u201d al portaaviones USS Abraham Lincoln, que transitaba el mar Ar\u00e1bigo a unos 800 kil\u00f3metros de la costa sur de Ir\u00e1n, dijo el capit\u00e1n Tim Hawkins, portavoz del Comando Central de EE.UU.<\/p>\n<p>\u201cEl dron iran\u00ed continu\u00f3 volando hacia el buque a pesar de las medidas de desescalada tomadas por las fuerzas estadounidenses que operaban en aguas internacionales\u201d, dijo Hawkins. Un caza F-35C del Lincoln derrib\u00f3 el dron para proteger al portaaviones y a su personal, a\u00f1adi\u00f3.<\/p>\n<p>\u201cNing\u00fan miembro del servicio estadounidense result\u00f3 herido durante el incidente, y ning\u00fan equipo estadounidense fue impactado\u201d, dijo Hawkins.<\/p>\n<p>Horas despu\u00e9s, dos botes armados iran\u00edes se acercaron al M\/V Stena Imperative \u2014un petrolero qu\u00edmico operado por estadounidenses bajo bandera de EE.UU. en el estrecho de Ormuz\u2014 pasando junto al buque tres veces a alta velocidad mientras un dron iran\u00ed Mohajer tambi\u00e9n sobrevolaba la zona, se\u00f1al\u00f3 Hawkins. Durante una de sus pasadas, los iran\u00edes amenazaron por radio con abordar y apoderarse del petrolero. El buque se encontraba en aguas internacionales, indic\u00f3 Hawkins.<\/p>\n<p>Fuerzas militares estadounidenses que operaban en la zona respondieron al enterarse de las amenazas iran\u00edes. El destructor USS McFaul escolt\u00f3 al petrolero fuera del \u00e1rea junto con apoyo a\u00e9reo defensivo de la Fuerza A\u00e9rea de EE.UU., agreg\u00f3 Hawkins. Como resultado, la situaci\u00f3n se desescal\u00f3.<\/p>\n<p>Hawkins dijo que el comportamiento iran\u00ed era un ejemplo de la \u201cfalta de profesionalismo y conducta agresiva\u201d de los iran\u00edes, lo que incrementa el riesgo de errores de c\u00e1lculo para los buques que operan en la zona, y afirm\u00f3 que su \u201chostigamiento\u201d en aguas internacionales no ser\u00e1 tolerado por EE.UU.<\/p>\n<p>Los incidentes se producen mientras el presidente Donald Trump sopesa un <a href=\"https:\/\/www.cnn.com\/2026\/01\/28\/politics\/trump-threats-iran-nuclear-program-military-strike\">ataque<\/a> importante contra Ir\u00e1n en medio de las estancadas discusiones sobre la limitaci\u00f3n del programa nuclear y la producci\u00f3n de misiles bal\u00edsticos de ese pa\u00eds.<\/p>\n<p>En la \u00faltima semana, las Fuerzas Armadas de EE.UU. han acelerado el despliegue de material militar en el Medio Oriente, y envi\u00f3 el grupo de ataque del portaaviones Lincoln a la regi\u00f3n junto con tres destructores lanzamisiles y el ala a\u00e9rea del portaaviones, que incluye escuadrones de cazas F\/A-18E Super Hornet, F-35C Lightning II y aviones de guerra electr\u00f3nica EA-18G Growler.<\/p>\n<p>La Marina tambi\u00e9n cuenta con tres destructores \u2014el USS McFaul, el USS Delbert D. Black y el USS Mitscher\u2014 en la regi\u00f3n, aparte del grupo de ataque del portaaviones.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un portaaviones de EE.UU. derrib\u00f3 un dron iran\u00ed que \u201cse acerc\u00f3 de manera agresiva\u201d al buque en el mar Ar\u00e1bigo el martes, horas antes de que dos botes armados operados por el Cuerpo de la Guardia Revolucionaria Isl\u00e1mica de Ir\u00e1n se acercaran a un petrolero con bandera estadounidense en el estrecho de Ormuz y amenazaran [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1470816","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un portaaviones de EE.UU. derrib\u00f3 un dron iran\u00ed que \u201cse acerc\u00f3 de manera agresiva\u201d al buque en el mar Ar\u00e1bigo el martes, horas antes de que dos botes armados operados por el Cuerpo de la Guardia Revolucionaria Isl\u00e1mica de Ir\u00e1n se acercaran a un petrolero con bandera estadounidense en el estrecho de Ormuz y amenazaran [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T20:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense\",\"datePublished\":\"2026-02-03T20:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/\"},\"wordCount\":583,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/\",\"name\":\"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-02-03T20:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense - Noticias","og_description":"Un portaaviones de EE.UU. derrib\u00f3 un dron iran\u00ed que \u201cse acerc\u00f3 de manera agresiva\u201d al buque en el mar Ar\u00e1bigo el martes, horas antes de que dos botes armados operados por el Cuerpo de la Guardia Revolucionaria Isl\u00e1mica de Ir\u00e1n se acercaran a un petrolero con bandera estadounidense en el estrecho de Ormuz y amenazaran [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/","og_site_name":"Noticias","article_published_time":"2026-02-03T20:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/"},"author":{"name":"","@id":""},"headline":"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense","datePublished":"2026-02-03T20:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/"},"wordCount":583,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/","url":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/","name":"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-02-03T20:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Portaaviones de EE.UU. derriba dron iran\u00ed y ataca botes armados que amenazaban un petrolero estadounidense","url":"http:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/san-diego\/2026\/02\/03\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-02-03T20:03:48Z","datePublished":"2026-02-03T20:03:48Z","dateModified":"2026-02-03T20:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Portaaviones de EE.UU. derriba dron iran\\u00ed y ataca botes armados que amenazaban un petrolero estadounidense\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/02\\\/03\\\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/san-diego\\\/2026\\\/02\\\/03\\\/portaaviones-eeuu-derriba-dron-irani-petrolero-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-02-03T20:03:48Z\",\"datePublished\":\"2026-02-03T20:03:48Z\",\"dateModified\":\"2026-02-03T20:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1470841,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/04\/5-cosas-4-de-febrero-orix\/","url_meta":{"origin":1470816,"position":0},"title":"Las 5 cosas que debes saber este 4 de febrero","author":"","date":"febrero 4, 2026","format":false,"excerpt":"Delcy Rodr\u00edguez y Donald Trump se acercan cada vez m\u00e1s. Portaaviones de EE.UU. derriba dron iran\u00ed. \u00bfQui\u00e9nes son las figuras p\u00fablicas que aparecen en los archivos de Epstein? Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir el newsletter cada ma\u00f1ana en tu\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445472,"url":"https:\/\/noticiasya.com\/san-diego\/2024\/02\/15\/asi-se-ve-la-lucha-en-primera-linea-de-la-marina-de-estados-unidos-contra-los-huties-en-el-mar-rojo\/","url_meta":{"origin":1470816,"position":1},"title":"As\u00ed se ve la lucha en primera l\u00ednea de la Marina de Estados Unidos contra los hut\u00edes en el mar Rojo","author":"","date":"febrero 15, 2024","format":false,"excerpt":"A bordo del USS Dwight D. Eisenhower (CNN) -- Las alarmas sonaron en el portaaviones USS Dwight D. Eisenhower en el mar Rojo a las 4 de la ma\u00f1ana del martes, advirtiendo al personal que se preparara para posibles operaciones de vuelo contra un dron hut\u00ed que estaba sobrevolando los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471195,"url":"https:\/\/noticiasya.com\/san-diego\/2026\/02\/13\/eeuu-segundo-portaaviones-iran-trax\/","url_meta":{"origin":1470816,"position":2},"title":"EE.UU. env\u00eda un segundo grupo de portaaviones a Medio Oriente, seg\u00fan fuentes","author":"","date":"febrero 13, 2026","format":false,"excerpt":"El Pent\u00e1gono enviar\u00e1 a Medio Oriente un segundo grupo de portaaviones, el USS Gerald Ford, seg\u00fan un alto funcionario de la administraci\u00f3n y una fuente familiarizada con el asunto. Esta medida suma presi\u00f3n a Ir\u00e1n, incluso cuando el presidente Donald Trump ha declarado que las conversaciones con Teher\u00e1n contin\u00faan.El grupo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442574,"url":"https:\/\/noticiasya.com\/san-diego\/2023\/12\/24\/un-avion-cisterna-fue-atacado-por-un-dron-irani-en-el-oceano-indico-asegura-el-pentagono\/","url_meta":{"origin":1470816,"position":3},"title":"Un avi\u00f3n cisterna fue atacado por un dron iran\u00ed en el Oc\u00e9ano \u00cdndico, asegura el Pent\u00e1gono","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"(CNN) --\u00a0Un avi\u00f3n cisterna para productos qu\u00edmicos que operaba en el Oc\u00e9ano \u00cdndico fue atacado el s\u00e1bado por un dron de ataque iran\u00ed, dijo un funcionario del Departamento de Defensa de Estados Unidos. Se trata del s\u00e9ptimo ataque iran\u00ed contra transporte mar\u00edtimo comercial desde 2021.\u201cEl buque a motor CHEM PLUTO,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442576,"url":"https:\/\/noticiasya.com\/san-diego\/2023\/12\/24\/un-avion-cisterna-fue-atacado-por-un-dron-irani-en-el-oceano-indico-asegura-el-pentagono-2\/","url_meta":{"origin":1470816,"position":4},"title":"Un avi\u00f3n cisterna fue atacado por un dron iran\u00ed en el Oc\u00e9ano \u00cdndico, asegura el Pent\u00e1gono","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"(CNN) --\u00a0Un avi\u00f3n cisterna para productos qu\u00edmicos que operaba en el Oc\u00e9ano \u00cdndico fue atacado el s\u00e1bado por un dron de ataque iran\u00ed, dijo un funcionario del Departamento de Defensa de Estados Unidos. Se trata del s\u00e9ptimo ataque iran\u00ed contra transporte mar\u00edtimo comercial desde 2021.\u201cEl buque a motor CHEM PLUTO,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442578,"url":"https:\/\/noticiasya.com\/san-diego\/2023\/12\/24\/un-avion-cisterna-fue-atacado-por-un-dron-irani-en-el-oceano-indico-asegura-el-pentagono-3\/","url_meta":{"origin":1470816,"position":5},"title":"Un avi\u00f3n cisterna fue atacado por un dron iran\u00ed en el Oc\u00e9ano \u00cdndico, asegura el Pent\u00e1gono","author":"","date":"diciembre 24, 2023","format":false,"excerpt":"(CNN) --\u00a0Un avi\u00f3n cisterna para productos qu\u00edmicos que operaba en el Oc\u00e9ano \u00cdndico fue atacado el s\u00e1bado por un dron de ataque iran\u00ed, dijo un funcionario del Departamento de Defensa de Estados Unidos. Se trata del s\u00e9ptimo ataque iran\u00ed contra transporte mar\u00edtimo comercial desde 2021.\u201cEl buque a motor CHEM PLUTO,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/san-diego\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/comments?post=1470816"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/posts\/1470816\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/media?parent=1470816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/categories?post=1470816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/san-diego\/wp-json\/wp\/v2\/tags?post=1470816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}