{"id":1445560,"date":"2024-02-17T11:33:38","date_gmt":"2024-02-17T19:33:38","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445560"},"modified":"2024-02-17T11:33:38","modified_gmt":"2024-02-17T19:33:38","slug":"japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/","title":{"rendered":"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural"},"content":{"rendered":"<p>(CNN) &#8212; La agencia espacial japonesa afirma que lanz\u00f3 con \u00e9xito su cohete espacial insignia H3, un a\u00f1o despu\u00e9s de que su primer intento acabara en fracaso.<\/p>\n<p>El H3 parti\u00f3 del Centro Espacial de Tanegashima, en el sur de Jap\u00f3n, a las 9.22 hora local del s\u00e1bado, inform\u00f3 la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n (JAXA) en un comunicado.<\/p>\n<p>El organismo espacial dijo que hab\u00eda confirmado que la combusti\u00f3n del motor de la segunda etapa se hab\u00eda completado y que el cohete hab\u00eda alcanzado la \u00f3rbita seg\u00fan lo previsto.<\/p>\n<p>Seg\u00fan la JAXA, el H3, sucesor de los cohetes japoneses H-2A y H-2B, est\u00e1 dise\u00f1ado para ser m\u00e1s econ\u00f3mico gracias al uso de productos comerciales disponibles en el mercado en lugar de componentes aeroespaciales exclusivos.<\/p>\n<p>JAXA espera que el H3 pueda lanzar misiones tanto gubernamentales como comerciales en el futuro y, si tiene \u00e9xito, la agencia espacial tiene previsto lanzarlo hasta seis veces al a\u00f1o durante las pr\u00f3ximas dos d\u00e9cadas.<\/p>\n<p>El lanzamiento inaugural del H3 acab\u00f3 en fracaso el pasado mes de marzo, cuando su segunda etapa no se encendi\u00f3 y sus controladores emitieron una orden de destrucci\u00f3n apenas 15 minutos despu\u00e9s del despegue. Este fue solo uno de los muchos problemas que tuvo el lanzamiento inaugural, que ya hab\u00eda sido pospuesto tras los fallos de ignici\u00f3n que afectaron a dos de los motores secundarios del cohete.<\/p>\n<p>El \u00e9xito del lanzamiento del s\u00e1bado es la segunda victoria de JAXA en tan solo dos meses, despu\u00e9s de que su explorador rob\u00f3tico &#171;francotirador lunar&#187; aterrizara en la superficie de la Luna en enero.<\/p>\n<p>JAXA calific\u00f3 ese momento de &#171;logro significativo para la futura exploraci\u00f3n lunar y planetaria&#187;, a pesar de los contratiempos t\u00e9cnicos que dejaron inoperativo el Smart Lander for Investigating Moon (SLIM) durante varios d\u00edas tras el aterrizaje.<\/p>\n<p>La nave aterriz\u00f3 orientada en la direcci\u00f3n equivocada, lo que impidi\u00f3 que sus c\u00e9lulas solares generaran energ\u00eda. Sin embargo, 10 d\u00edas despu\u00e9s despert\u00f3.<\/p>\n<p>JAXA tambi\u00e9n hab\u00eda utilizado una nueva tecnolog\u00eda de precisi\u00f3n para demostrar un aterrizaje &#171;milim\u00e9trico&#187; a menos de 100 metros del objetivo del SLIM.<\/p>\n<p>Jap\u00f3n es el quinto pa\u00eds que pone una nave espacial en la Luna de forma segura, tras el \u00e9xito de India con su Chandrayaan-3 el pasado agosto. Estados Unidos, la antigua Uni\u00f3n Sovi\u00e9tica y China tambi\u00e9n han llevado naves espaciales hasta la Luna.<\/p>\n<p>La nueva carrera espacial est\u00e1 impulsada en parte por el deseo de los pa\u00edses de acceder al agua atrapada en forma de hielo en las regiones permanentemente ensombrecidas del polo sur lunar. Seg\u00fan los expertos, esta agua podr\u00eda utilizarse como agua potable o como combustible cuando la humanidad ampl\u00ede los l\u00edmites de la exploraci\u00f3n espacial en el futuro.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La agencia espacial japonesa afirma que lanz\u00f3 con \u00e9xito su cohete espacial insignia H3, un a\u00f1o despu\u00e9s de que su primer intento acabara en fracaso. El H3 parti\u00f3 del Centro Espacial de Tanegashima, en el sur de Jap\u00f3n, a las 9.22 hora local del s\u00e1bado, inform\u00f3 la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445560","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La agencia espacial japonesa afirma que lanz\u00f3 con \u00e9xito su cohete espacial insignia H3, un a\u00f1o despu\u00e9s de que su primer intento acabara en fracaso. El H3 parti\u00f3 del Centro Espacial de Tanegashima, en el sur de Jap\u00f3n, a las 9.22 hora local del s\u00e1bado, inform\u00f3 la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-17T19:33:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural\",\"datePublished\":\"2024-02-17T19:33:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/\"},\"wordCount\":521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/\",\"name\":\"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-17T19:33:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/","og_locale":"es_ES","og_type":"article","og_title":"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural - Noticias","og_description":"(CNN) &#8212; La agencia espacial japonesa afirma que lanz\u00f3 con \u00e9xito su cohete espacial insignia H3, un a\u00f1o despu\u00e9s de que su primer intento acabara en fracaso. El H3 parti\u00f3 del Centro Espacial de Tanegashima, en el sur de Jap\u00f3n, a las 9.22 hora local del s\u00e1bado, inform\u00f3 la Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/","og_site_name":"Noticias","article_published_time":"2024-02-17T19:33:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/"},"author":{"name":"","@id":""},"headline":"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural","datePublished":"2024-02-17T19:33:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/"},"wordCount":521,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/","name":"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-17T19:33:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jap\u00f3n lanza su segundo cohete insignia H3 un a\u00f1o despu\u00e9s del fallido intento inaugural","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/17\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-17T19:33:38Z","datePublished":"2024-02-17T19:33:38Z","dateModified":"2024-02-17T19:33:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jap\\u00f3n lanza su segundo cohete insignia H3 un a\\u00f1o despu\\u00e9s del fallido intento inaugural\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/17\\\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/17\\\/japon-lanza-su-segundo-cohete-insignia-h3-un-ano-despues-del-fallido-intento-inaugural\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-17T19:33:38Z\",\"datePublished\":\"2024-02-17T19:33:38Z\",\"dateModified\":\"2024-02-17T19:33:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1444074,"url":"https:\/\/noticiasya.com\/springfield\/2024\/01\/18\/la-agencia-de-exploracion-aeroespacial-de-japon-se-prepara-para-20-minutos-de-terror-por-intento-de-alunizaje-de-su-nave-slim\/","url_meta":{"origin":1445560,"position":0},"title":"La Agencia de Exploraci\u00f3n Aeroespacial de Jap\u00f3n se prepara para &#171;20 minutos de terror&#187; por intento de alunizaje de su nave SLIM","author":"","date":"enero 18, 2024","format":false,"excerpt":"(CNN) -- Mientras la primera misi\u00f3n estadounidense de alunizaje en d\u00e9cadas finaliza sin alcanzar su objetivo, una nave espacial lanzada por Jap\u00f3n se acerca a la Luna y se prepara para un intento hist\u00f3rico de alunizaje.Se espera que el Smart Lander for Investigating Moon (SLIM) de la Agencia de Exploraci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468920,"url":"https:\/\/noticiasya.com\/springfield\/2025\/12\/03\/cohete-chino-reutilizable-explota-durante-primera-prueba-orbital-trax\/","url_meta":{"origin":1445560,"position":1},"title":"Cohete chino reutilizable explota durante su primera prueba orbital, en un intento fallido de alcanzar a SpaceX","author":"","date":"diciembre 3, 2025","format":false,"excerpt":"Una empresa espacial privada china envi\u00f3 con \u00e9xito su cohete Zhuque-3 a \u00f3rbita, pero fracas\u00f3 en su intento hist\u00f3rico de volver a aterrizar el veh\u00edculo propulsor el mi\u00e9rcoles.Este fue el primer intento de este tipo realizado por una empresa china mientras el creciente sector espacial comercial del pa\u00eds se apresura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471593,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/24\/nasa-artemis-ii-viaje-luna-trax\/","url_meta":{"origin":1445560,"position":2},"title":"La NASA vuelve a retrasar la misi\u00f3n Artemis II: un nuevo problema pone en riesgo el viaje a la Luna","author":"","date":"febrero 24, 2026","format":false,"excerpt":"Los esfuerzos para lograr que la hist\u00f3rica misi\u00f3n de la NASA a la Luna despegue han fracasado una vez m\u00e1s, luego de que los ingenieros enfrentaran un nuevo problema con el cohete que deb\u00eda impulsar a cuatro astronautas en una trayectoria sin precedentes.La agencia anunci\u00f3 el s\u00e1bado que detect\u00f3 un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470787,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/02\/nasa-problemas-prueba-crucial-historica-mision-lunar-trax\/","url_meta":{"origin":1445560,"position":3},"title":"La NASA resuelve problemas en una prueba crucial antes del lanzamiento de la hist\u00f3rica misi\u00f3n lunar","author":"","date":"febrero 2, 2026","format":false,"excerpt":"Una prueba crucial del imponente cohete del Sistema de Lanzamiento Espacial de la NASA est\u00e1 en marcha, lo que marca uno de los pasos finales antes de que el veh\u00edculo impulse a cuatro astronautas al espacio profundo por primera vez desde que finaliz\u00f3 el programa Apolo hace m\u00e1s de cinco\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457243,"url":"https:\/\/noticiasya.com\/springfield\/2025\/01\/05\/cohete-desafiar-dominio-spacex-despegar-trax\/","url_meta":{"origin":1445560,"position":4},"title":"El cohete que podr\u00eda desafiar el dominio de SpaceX est\u00e1 listo para despegar","author":"","date":"enero 5, 2025","format":false,"excerpt":"En una plataforma de lanzamiento de Florida, que ha estado inactiva durante casi dos d\u00e9cadas, un nuevo cohete de aproximadamente 98 metros desarrollado por Blue Origin, la empresa de Jeff Bezos, est\u00e1 listo para su vuelo inaugural.El veh\u00edculo de lanzamiento sin tripulaci\u00f3n, llamado New Glenn, marcar\u00e1 el primer intento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449987,"url":"https:\/\/noticiasya.com\/springfield\/2024\/06\/03\/starliner-nasa-lanzamiento-5-de-mayo-trax\/","url_meta":{"origin":1445560,"position":5},"title":"El Starliner de Boeing realizar\u00e1 su pr\u00f3ximo intento de lanzamiento el mi\u00e9rcoles","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN) -- El nuevo intento de lanzamiento inaugural con tripulaci\u00f3n de la nave espacial Starliner de Boeing est\u00e1 previsto para el mi\u00e9rcoles, despu\u00e9s de que un problema inform\u00e1tico detuviera la cuenta atr\u00e1s momentos antes del despegue del s\u00e1bado.La hist\u00f3rica misi\u00f3n, llamada Crew Flight Test, se lanzar\u00e1 a las 10:52 a.m.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445560"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445560\/revisions"}],"predecessor-version":[{"id":1445578,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445560\/revisions\/1445578"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}