{"id":1445684,"date":"2024-02-19T23:33:43","date_gmt":"2024-02-20T07:33:43","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/?p=1445684"},"modified":"2024-02-19T23:33:43","modified_gmt":"2024-02-20T07:33:43","slug":"cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/","title":{"rendered":"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Est\u00e1 en curso una b\u00fasqueda de cuatro pescadores que no regresaron de un viaje en bote el s\u00e1bado frente a la costa del Golfo de Florida, dicen las autoridades locales.<\/p>\n<p>\u00c1ngel Hern\u00e1ndez Mu\u00f1oz, de 38 a\u00f1os, Rub\u00e9n Mora Sr., de 54 a\u00f1os, Julio C\u00e9sar Cordero Briones, de 37 a\u00f1os, y Vargas Parra, de 35, partieron de Venice, Florida, aproximadamente a las 8 a.m. del s\u00e1bado por la ma\u00f1ana, dijo el Departamento de Polic\u00eda de Venice en una publicaci\u00f3n del domingo en Facebook.<\/p>\n<p>Se esperaba que el grupo regresara esa noche, seg\u00fan un miembro de la familia, dijo la polic\u00eda.<\/p>\n<p>El mar no estaba &#171;demasiado agitado&#187; cuando el grupo de pescadores experimentados parti\u00f3, pero surgi\u00f3 una densa niebla que podr\u00eda haber sido &#171;un factor&#187; en su desaparici\u00f3n, dijo el capit\u00e1n del Departamento de Polic\u00eda de Venecia, Andy Leisenring, en una conferencia de prensa el lunes.<\/p>\n<p>M\u00e1s tarde el s\u00e1bado el tiempo empeor\u00f3.<\/p>\n<p>&#171;Al pasar la noche y el domingo, el viento se levant\u00f3, el mar se levant\u00f3 y, por supuesto, ha estado lloviendo la mayor parte del tiempo&#187;, dijo Leisenring. &#171;Incluso ahora, las condiciones son de mares de aproximadamente 4 a 6 pies (1,2 a 1,8 metros), por lo que no es muy seguro estar all\u00ed para una embarcaci\u00f3n peque\u00f1a&#187;.<\/p>\n<p>Alrededor de 13 barcos policiales locales han continuado la b\u00fasqueda del barco hoy a 16 kil\u00f3metros de la costa entre Longboat Pass y la isla Captiva, dijo Leisenring. La Guardia Costera de Estados Unidos ha estado buscando a 130 kil\u00f3metros de distancia y hasta ahora ha cubierto 11.900 kil\u00f3metros cuadrados, a\u00f1adi\u00f3.<\/p>\n<p>\u201cLa b\u00fasqueda a\u00fan est\u00e1 en curso con @USCG y los activos a\u00e9reos y de superficie de las agencias asociadas\u201d, dijo el Distrito Siete de la Guardia Costera el lunes X.<\/p>\n<p>El barco es un SportCraft blanco de 1975 de 23 pies (7 metros), seg\u00fan Leisenring.<\/p>\n<p>Los pescadores no dejaron un plan de navegaci\u00f3n \u2013 que indica el destino previsto y el plazo del viaje \u2013 con sus familias, por lo que no est\u00e1 claro hasta d\u00f3nde lleg\u00f3 el grupo, dijo el capit\u00e1n de la polic\u00eda.<\/p>\n<p>La polic\u00eda confirm\u00f3 que el veh\u00edculo y el remolque del barco todav\u00eda estaban estacionados en la rampa para botes de Marina Park, donde parti\u00f3 el grupo. Instaron a cualquier persona que tenga conocimiento sobre el barco perdido a que se comunique con el Departamento de Polic\u00eda de Venecia.<\/p>\n<p>The-CNN-Wire<br \/>\u2122 &amp; \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Est\u00e1 en curso una b\u00fasqueda de cuatro pescadores que no regresaron de un viaje en bote el s\u00e1bado frente a la costa del Golfo de Florida, dicen las autoridades locales. \u00c1ngel Hern\u00e1ndez Mu\u00f1oz, de 38 a\u00f1os, Rub\u00e9n Mora Sr., de 54 a\u00f1os, Julio C\u00e9sar Cordero Briones, de 37 a\u00f1os, y Vargas Parra, de 35, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445684","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Est\u00e1 en curso una b\u00fasqueda de cuatro pescadores que no regresaron de un viaje en bote el s\u00e1bado frente a la costa del Golfo de Florida, dicen las autoridades locales. \u00c1ngel Hern\u00e1ndez Mu\u00f1oz, de 38 a\u00f1os, Rub\u00e9n Mora Sr., de 54 a\u00f1os, Julio C\u00e9sar Cordero Briones, de 37 a\u00f1os, y Vargas Parra, de 35, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-20T07:33:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado\",\"datePublished\":\"2024-02-20T07:33:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/\"},\"wordCount\":459,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/\",\"name\":\"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-20T07:33:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/","og_locale":"es_ES","og_type":"article","og_title":"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado - Noticias","og_description":"(CNN) &#8212;\u00a0Est\u00e1 en curso una b\u00fasqueda de cuatro pescadores que no regresaron de un viaje en bote el s\u00e1bado frente a la costa del Golfo de Florida, dicen las autoridades locales. \u00c1ngel Hern\u00e1ndez Mu\u00f1oz, de 38 a\u00f1os, Rub\u00e9n Mora Sr., de 54 a\u00f1os, Julio C\u00e9sar Cordero Briones, de 37 a\u00f1os, y Vargas Parra, de 35, [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/","og_site_name":"Noticias","article_published_time":"2024-02-20T07:33:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/"},"author":{"name":"","@id":""},"headline":"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado","datePublished":"2024-02-20T07:33:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/"},"wordCount":459,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/","name":"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-20T07:33:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/19\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-20T07:33:43Z","datePublished":"2024-02-20T07:33:43Z","dateModified":"2024-02-20T07:33:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cuatro pescadores emprendieron un viaje en bote frente a la costa del Golfo de Florida el s\\u00e1bado por la ma\\u00f1ana. Todav\\u00eda no han regresado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/19\\\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/19\\\/cuatro-pescadores-emprendieron-un-viaje-en-bote-frente-a-la-costa-del-golfo-de-florida-el-sabado-por-la-manana-todavia-no-han-regresado\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-20T07:33:43Z\",\"datePublished\":\"2024-02-20T07:33:43Z\",\"dateModified\":\"2024-02-20T07:33:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445893,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/21\/pescadores-desaparecidos-venice-florida-trax\/","url_meta":{"origin":1445684,"position":0},"title":"Cuatro pescadores salieron en un bote frente a la costa del Golfo de Florida el s\u00e1bado por la ma\u00f1ana. Todav\u00eda no han regresado","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) --\u00a0Est\u00e1 en curso una b\u00fasqueda de cuatro pescadores que no regresaron de un viaje en bote el s\u00e1bado frente a la costa del Golfo de Florida, dicen las autoridades locales.\u00c1ngel Hern\u00e1ndez Mu\u00f1oz, de 38 a\u00f1os, Rub\u00e9n Mora Sr., de 54 a\u00f1os, Julio C\u00e9sar Cordero Briones, de 37 a\u00f1os, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462148,"url":"https:\/\/noticiasya.com\/springfield\/2025\/05\/08\/derrame-pemex-tabasco-petroleo-pescadores-orix\/","url_meta":{"origin":1445684,"position":1},"title":"Derrame de Pemex ti\u00f1e de negro la costa de Tabasco afectando a comunidades pesqueras","author":"","date":"mayo 8, 2025","format":false,"excerpt":"Una mancha negra invadi\u00f3 las aguas del golfo de M\u00e9xico en al menos siete kil\u00f3metros de la costa de la terminal mar\u00edtima de Dos Bocas debido a dos fugas en un ducto que transporta aceite, report\u00f3 Petr\u00f3leos Mexicanos (Pemex) el mi\u00e9rcoles.La presidenta de M\u00e9xico, Claudia Sheinbaum, dijo este jueves durante\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445904,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/21\/china-intensifica-patrullas-islas-perifericas-taiwan-muerte-pescadores-chinos-trax\/","url_meta":{"origin":1445684,"position":2},"title":"China intensifica las patrullas cerca de las islas perif\u00e9ricas de Taiw\u00e1n tras la muerte de pescadores chinos","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- China est\u00e1 aumentando las patrullas en aguas cercanas a un grupo de islas de primera l\u00ednea controladas por Taiw\u00e1n, a medida que aumentan las tensiones despu\u00e9s de que dos pescadores chinos se ahogaran durante una persecuci\u00f3n por parte de la guardia costera de Taiw\u00e1n, que los acus\u00f3 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445655,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/19\/china-intensifica-las-patrullas-cerca-de-las-islas-perifericas-de-taiwan-tras-la-muerte-de-pescadores-chinos\/","url_meta":{"origin":1445684,"position":3},"title":"China intensifica las patrullas cerca de las islas perif\u00e9ricas de Taiw\u00e1n tras la muerte de pescadores chinos","author":"","date":"febrero 19, 2024","format":false,"excerpt":"(CNN) -- China est\u00e1 aumentando las patrullas en aguas cercanas a un grupo de islas de primera l\u00ednea controladas por Taiw\u00e1n, a medida que aumentan las tensiones despu\u00e9s de que dos pescadores chinos se ahogaran durante una persecuci\u00f3n por parte de la guardia costera de Taiw\u00e1n, que los acus\u00f3 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451580,"url":"https:\/\/noticiasya.com\/springfield\/2024\/08\/03\/florida-depresion-tropical-tormenta-debby-huracan-sabado-trax\/","url_meta":{"origin":1445684,"position":4},"title":"Se emite alerta de hurac\u00e1n para partes de Florida mientras los meteor\u00f3logos prev\u00e9n que Debby se fortalezca en el Golfo","author":"","date":"agosto 3, 2024","format":false,"excerpt":"(CNN) -- Algunas partes de Florida est\u00e1n bajo una alerta de hurac\u00e1n, ya que aumenta la posibilidad de que la futura tormenta tropical Debby se convierta en hurac\u00e1n cuando toque tierra en los pr\u00f3ximos d\u00edas.Se pronostica que la tormenta, que ahora es la depresi\u00f3n tropical Cuatro, se desacelerar\u00e1 significativamente despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468550,"url":"https:\/\/noticiasya.com\/springfield\/2025\/11\/20\/trump-aguas-florida-california-exploracion-petrolera-trax\/","url_meta":{"origin":1445684,"position":5},"title":"Trump habilita aguas de Florida y California para la perforaci\u00f3n petrolera tras d\u00e9cadas de prohibici\u00f3n","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"El Gobierno de Trump propone abrir aguas federales frente a toda la costa de California para perforaci\u00f3n petrolera, as\u00ed como una zona frente a la costa de Florida. Las aguas de ninguno de esos estados han estado abiertas a nueva perforaci\u00f3n desde hace d\u00e9cadas.El Departamento del Interior del presidente Donald\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445684"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445684\/revisions"}],"predecessor-version":[{"id":1445701,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445684\/revisions\/1445701"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}