{"id":1445840,"date":"2024-02-21T18:04:11","date_gmt":"2024-02-22T02:04:11","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/"},"modified":"2024-02-21T18:04:11","modified_gmt":"2024-02-22T02:04:11","slug":"thomas-tuchel-deja-bayern-munich-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/","title":{"rendered":"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada"},"content":{"rendered":"<p>(CNN) &#8212; Thomas Tuchel dejar\u00e1 su cargo de entrenador del Bayern Munich al final de la temporada, seg\u00fan anunci\u00f3 el club este mi\u00e9rcoles.<\/p>\n<p>Tuchel, que fue contratado como entrenador del poderoso equipo alem\u00e1n en marzo de 2023, dejar\u00e1 el cargo un a\u00f1o antes de la fecha original de finalizaci\u00f3n de su contrato, junio de 2025.<\/p>\n<p>La noticia llega en medio de una racha reciente de resultados decepcionantes para el Bayern, que ha visto al club quedar a ocho puntos del l\u00edder de la Bundesliga, el Bayer Leverkusen. Adem\u00e1s, los b\u00e1varos perdieron 1-0 ante el Lazio en la ida de los octavos de final de la Liga de Campeones.<\/p>\n<p>Noticia en desarrollo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Thomas Tuchel dejar\u00e1 su cargo de entrenador del Bayern Munich al final de la temporada, seg\u00fan anunci\u00f3 el club este mi\u00e9rcoles. Tuchel, que fue contratado como entrenador del poderoso equipo alem\u00e1n en marzo de 2023, dejar\u00e1 el cargo un a\u00f1o antes de la fecha original de finalizaci\u00f3n de su contrato, junio de 2025. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445840","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Thomas Tuchel dejar\u00e1 su cargo de entrenador del Bayern Munich al final de la temporada, seg\u00fan anunci\u00f3 el club este mi\u00e9rcoles. Tuchel, que fue contratado como entrenador del poderoso equipo alem\u00e1n en marzo de 2023, dejar\u00e1 el cargo un a\u00f1o antes de la fecha original de finalizaci\u00f3n de su contrato, junio de 2025. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-22T02:04:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada\",\"datePublished\":\"2024-02-22T02:04:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/\"},\"wordCount\":148,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/\",\"name\":\"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-22T02:04:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada - Noticias","og_description":"(CNN) &#8212; Thomas Tuchel dejar\u00e1 su cargo de entrenador del Bayern Munich al final de la temporada, seg\u00fan anunci\u00f3 el club este mi\u00e9rcoles. Tuchel, que fue contratado como entrenador del poderoso equipo alem\u00e1n en marzo de 2023, dejar\u00e1 el cargo un a\u00f1o antes de la fecha original de finalizaci\u00f3n de su contrato, junio de 2025. [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/","og_site_name":"Noticias","article_published_time":"2024-02-22T02:04:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/"},"author":{"name":"","@id":""},"headline":"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada","datePublished":"2024-02-22T02:04:11+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/"},"wordCount":148,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/","name":"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-22T02:04:11+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/21\/thomas-tuchel-deja-bayern-munich-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-22T02:04:11Z","datePublished":"2024-02-22T02:04:11Z","dateModified":"2024-02-22T02:04:11Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Thomas Tuchel dejar\\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/21\\\/thomas-tuchel-deja-bayern-munich-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/21\\\/thomas-tuchel-deja-bayern-munich-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-22T02:04:11Z\",\"datePublished\":\"2024-02-22T02:04:11Z\",\"dateModified\":\"2024-02-22T02:04:11Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445765,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/21\/thomas-tuchel-dejara-el-cargo-de-entrenador-del-bayern-munich-al-final-de-la-temporada\/","url_meta":{"origin":1445840,"position":0},"title":"Thomas Tuchel dejar\u00e1 el cargo de entrenador del Bayern Munich al final de la temporada","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Thomas Tuchel dejar\u00e1 su cargo de entrenador del Bayern Munich al final de la temporada, seg\u00fan anunci\u00f3 el club este mi\u00e9rcoles.Noticia en desarrollo.The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455135,"url":"https:\/\/noticiasya.com\/springfield\/2024\/10\/16\/thomas-tuchel-nuevo-entrenador-seleccion-masculina-fputbol-inglaterra-orix\/","url_meta":{"origin":1445840,"position":1},"title":"Thomas Tuchel es el nuevo entrenador de la selecci\u00f3n masculina de f\u00fatbol de Inglaterra","author":"","date":"octubre 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Asociaci\u00f3n de F\u00fatbol de Inglaterra (FA) anunci\u00f3 este mi\u00e9rcoles el fichaje del alem\u00e1n Thomas Tuchel como nuevo entrenador de la selecci\u00f3n masculina.El director de la FA, Mark Bullingham, y su director deportivo, John McDermott, firmaron el contrato por 18 meses con el exentrenador de Chelsea el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448109,"url":"https:\/\/noticiasya.com\/springfield\/2024\/04\/15\/tecnico-del-barcelona-xavi-anuncia-que-dejara-el-gigante-espanol-al-final-de-la-temporada-trax\/","url_meta":{"origin":1445840,"position":2},"title":"El t\u00e9cnico del Barcelona, \u200b\u200bXavi, anuncia que dejar\u00e1 el gigante espa\u00f1ol al final de la temporada","author":"","date":"abril 15, 2024","format":false,"excerpt":"(CNN) --\u00a0 El t\u00e9cnico del Barcelona, \u200b\u200bXavi, anunci\u00f3 este s\u00e1bado que dejar\u00e1 el Club al final de la temporada.Hablando despu\u00e9s de la derrota del equipo en casa por 5-3 ante el Villarreal, Xavi dijo que partir\u00e1 el 30 de junio tras la conclusi\u00f3n de la temporada de La Liga.\"Creo que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462782,"url":"https:\/\/noticiasya.com\/springfield\/2025\/05\/25\/xabi-alonso-nuevo-tecnico-real-madrid-orix\/","url_meta":{"origin":1445840,"position":3},"title":"Xabi Alonso, el hijo pr\u00f3digo que se espera ponga orden en el Real Madrid","author":"","date":"mayo 25, 2025","format":false,"excerpt":"Una vez culminada la temporada del f\u00fatbol europeo, los equipos hacen ajustes y toman decisiones para mejorar el rendimiento de la pr\u00f3xima campa\u00f1a.El Real Madrid no ha sido la excepci\u00f3n y a cuando faltaban dos semanas para que terminara el calendario de LaLiga se conoci\u00f3 que el director t\u00e9cnico Carlo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473248,"url":"https:\/\/noticiasya.com\/springfield\/2026\/04\/16\/camavinga-roja-bayern-madrid-champions-trax\/","url_meta":{"origin":1445840,"position":4},"title":"El &#171;momento de locura&#187; que acab\u00f3 con el sue\u00f1o del Real Madrid en la Champions League","author":"","date":"abril 16, 2026","format":false,"excerpt":"Al principio, parec\u00eda un momento intrascendente en una noche de Champions League que promet\u00eda ser emocionante.El Real Madrid le ganaba al Bayern Munich por 3-2 en el partido de vuelta de los cuartos de final. El marcador global estaba empatado y la pr\u00f3rroga parec\u00eda inevitable a falta de menos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461966,"url":"https:\/\/noticiasya.com\/springfield\/2025\/05\/04\/bayern-munich-campeon-bundesliga-harry-kane-trax\/","url_meta":{"origin":1445840,"position":5},"title":"Un trofeo de campe\u00f3n para Harry Kane: el Bayern M\u00fanich gana la Bundesliga","author":"","date":"mayo 4, 2025","format":false,"excerpt":"El Bayern M\u00fanich se coron\u00f3 campe\u00f3n de la Bundesliga por 33.\u00aa vez, un r\u00e9cord, a falta de dos jornadas para el final, despu\u00e9s de que su rival m\u00e1s cercano, el Bayer Leverkusen, empatara 2-2 con el SC Friburgo el domingo por la tarde.Perdiendo 2-1 en la pr\u00f3rroga, Jonathan Tah, del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445840"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445840\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}