{"id":1445907,"date":"2024-02-21T18:34:10","date_gmt":"2024-02-22T02:34:10","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/"},"modified":"2024-02-21T18:34:10","modified_gmt":"2024-02-22T02:34:10","slug":"hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/","title":{"rendered":"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota"},"content":{"rendered":"<p>(CNN) &#8212; Un hombre de Colorado muri\u00f3 despu\u00e9s de que lo mordiera un gran lagarto venenoso, llamado monstruo de Gila, que ten\u00eda ilegalmente como mascota, seg\u00fan las autoridades de la ciudad de Lakewood.<\/p>\n<p>Christopher Ward, de 34 a\u00f1os, ten\u00eda dos de los reptiles y enferm\u00f3 despu\u00e9s de que uno de los animales lo mordiera en la mano, seg\u00fan muestra un informe de incidentes del Departamento de Polic\u00eda de Lakewood (LPD, por sus siglas en ingl\u00e9s). Lakewood es un suburbio de Denver.<\/p>\n<p>La novia de Ward llam\u00f3 al 911 justo antes de la medianoche del 12 de febrero despu\u00e9s de entrar en la habitaci\u00f3n donde estaban los reptiles y encontrar que uno de ellos estaba &#171;aferrado a la mano de Ward&#187;, escribi\u00f3 en el informe Leesha Crookston, agente de Control de Animales de la LPD. Ward comenz\u00f3 inmediatamente a mostrar s\u00edntomas, vomit\u00f3 varias veces antes de desmayarse, y su respiraci\u00f3n se detuvo, seg\u00fan el informe.<\/p>\n<p>Con drones aumentan la vigilancia de tiburones en Long Island, Nueva York, luego de que 5 personas fueran mordidas en 2 d\u00edas<\/p>\n<p>La novia de Ward dijo a Crookston que su novia no sab\u00eda exactamente c\u00f3mo ocurri\u00f3 el incidente de la mordida porque ella estaba en otra habitaci\u00f3n en ese momento, pero relat\u00f3 que escuch\u00f3 a Ward decir algo que &#171;no estaba bien&#187;, seg\u00fan el informe.<\/p>\n<p>Ward fue trasladado a un hospital local, donde se le conect\u00f3 a un respirador artificial y posteriormente fue &#171;declarado con muerte cerebral&#187;, seg\u00fan el informe. Falleci\u00f3 el 16 de febrero, declar\u00f3 este mi\u00e9rcoles a CNN John Romero, agente de informaci\u00f3n p\u00fablica de la Polic\u00eda de Lakewood. No se revel\u00f3 la causa de la muerte.<\/p>\n<p>Crookston dijo a la novia de Ward que es ilegal tener monstruos de Gila en la ciudad de Lakewood, seg\u00fan el informe. Los lagartos fueron retirados de la casa de Ward la semana pasada por Crookston y funcionarios de Parques y Vida Silvestre de Colorado y del Departamento de Recursos Naturales.<\/p>\n<p>Los funcionarios planean trasladar los lagartos a un parque de animales en Dakota del Sur, seg\u00fan el informe. 26 ara\u00f1as de diferentes especies que Ward ten\u00eda en terrarios tambi\u00e9n fueron retiradas de la casa.<\/p>\n<p>La novia de Ward dice que el lagarto que mordi\u00f3 a Ward se llamaba Winston y que Ward lo compr\u00f3 en una exposici\u00f3n de reptiles en Denver en octubre, cuando el animal ten\u00eda un a\u00f1o.<\/p>\n<p>Mujer envenen\u00f3 con acetona a una ni\u00f1a de un a\u00f1o, hija de su novio, dice el fiscal general de Pensilvania<\/p>\n<p>Los monstruos de Gila son los lagartos m\u00e1s grandes de Estados Unidos y pueden medir hasta 55 cent\u00edmetros de largo, seg\u00fan el Zool\u00f3gico Nacional del Smithsonian. Viven principalmente en el norte de M\u00e9xico y en varios estados del suroeste de Estados Unidos, como Arizona, California y Nuevo M\u00e9xico.<\/p>\n<p>Seg\u00fan el Smithsonian, el veneno del monstruo de Gila es tan t\u00f3xico como el de la serpiente de cascabel occidental. Aunque estos reptiles pueden mantener su mordedura durante m\u00e1s de 10 minutos, cuando lo hacen producen una &#171;cantidad relativamente peque\u00f1a de veneno&#187;.<\/p>\n<p>&#171;No existe ning\u00fan ant\u00eddoto para las mordidas de monstruo de Gila&#187;, afirma el Zool\u00f3gico de San Diego, que se\u00f1ala que la mordedura de un monstruo de Gila es dolorosa pero rara vez causa la muerte.<\/p>\n<p>&#171;La mordida de un monstruo de Gila es muy fuerte, y el lagarto puede no aflojar su agarre durante varios segundos&#187;, dice el Zool\u00f3gico de San Diego. &#171;Puede incluso masticar para que el veneno penetre m\u00e1s profundamente en la herida&#187;.<\/p>\n<p>La Oficina del Forense del Condado de Jefferson no ha respondido a la solicitud de comentarios de CNN sobre la causa de la muerte de Ward y si falleci\u00f3 por el veneno del reptil.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un hombre de Colorado muri\u00f3 despu\u00e9s de que lo mordiera un gran lagarto venenoso, llamado monstruo de Gila, que ten\u00eda ilegalmente como mascota, seg\u00fan las autoridades de la ciudad de Lakewood. Christopher Ward, de 34 a\u00f1os, ten\u00eda dos de los reptiles y enferm\u00f3 despu\u00e9s de que uno de los animales lo mordiera en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445907","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un hombre de Colorado muri\u00f3 despu\u00e9s de que lo mordiera un gran lagarto venenoso, llamado monstruo de Gila, que ten\u00eda ilegalmente como mascota, seg\u00fan las autoridades de la ciudad de Lakewood. Christopher Ward, de 34 a\u00f1os, ten\u00eda dos de los reptiles y enferm\u00f3 despu\u00e9s de que uno de los animales lo mordiera en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-22T02:34:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota\",\"datePublished\":\"2024-02-22T02:34:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/\"},\"wordCount\":689,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/\",\"name\":\"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-22T02:34:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota - Noticias","og_description":"(CNN) &#8212; Un hombre de Colorado muri\u00f3 despu\u00e9s de que lo mordiera un gran lagarto venenoso, llamado monstruo de Gila, que ten\u00eda ilegalmente como mascota, seg\u00fan las autoridades de la ciudad de Lakewood. Christopher Ward, de 34 a\u00f1os, ten\u00eda dos de los reptiles y enferm\u00f3 despu\u00e9s de que uno de los animales lo mordiera en [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/","og_site_name":"Noticias","article_published_time":"2024-02-22T02:34:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/"},"author":{"name":"","@id":""},"headline":"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota","datePublished":"2024-02-22T02:34:10+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/"},"wordCount":689,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/","name":"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-22T02:34:10+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\u00eda ilegalmente como mascota","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/21\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-22T02:34:10Z","datePublished":"2024-02-22T02:34:10Z","dateModified":"2024-02-22T02:34:10Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un hombre de Colorado muere tras la mordida de un monstruo de Gila que ten\\u00eda ilegalmente como mascota\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/21\\\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/21\\\/hombre-colorado-muere-mordido-monstruo-gila-ilegalmente-mascota-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-22T02:34:10Z\",\"datePublished\":\"2024-02-22T02:34:10Z\",\"dateModified\":\"2024-02-22T02:34:10Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469313,"url":"https:\/\/noticiasya.com\/springfield\/2025\/12\/16\/gary-zootopia-2-china-viboras-venenosas-trax\/","url_meta":{"origin":1445907,"position":0},"title":"Gary, de &#171;Zootopia 2&#187;, es un \u00e9xito en China. Ahora, los j\u00f3venes est\u00e1n comprando v\u00edboras venenosas","author":"","date":"diciembre 16, 2025","format":false,"excerpt":"Qi Weihao recientemente dio la bienvenida a un nuevo miembro de la familia: una hermosa y altamente venenosa serpiente azul.El joven, de 21 a\u00f1os, originario de la provincia central de Jiangxi, compr\u00f3 la v\u00edbora de fosa indonesia por 1.850 yuanes (US$ 260) dos d\u00edas despu\u00e9s del estreno del \u00e9xito animado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445317,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/12\/dos-heridos-incluido-un-nino-despues-de-un-tiroteo-en-la-iglesia-lakewood-en-houston-la-atacante-murio-dice-la-policia\/","url_meta":{"origin":1445907,"position":1},"title":"Dos heridos, incluido un ni\u00f1o, despu\u00e9s de un tiroteo en la iglesia Lakewood en Houston; la atacante muri\u00f3, dice la Polic\u00eda","author":"","date":"febrero 12, 2024","format":false,"excerpt":"(CNN) --\u00a0Una mujer vestida con una gabardina y armada con un rifle largo -acompa\u00f1ada por un ni\u00f1o peque\u00f1o- ingres\u00f3 a la iglesia Lakewood del pastor Joel Osteen el domingo por la tarde y comenz\u00f3 a disparar, dijo el jefe de polic\u00eda de Houston, Troy Finner.Dos agentes del orden fuera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461600,"url":"https:\/\/noticiasya.com\/springfield\/2025\/04\/24\/titans-tennessee-cam-ward-primera-eleccion-draft-nfl-trax\/","url_meta":{"origin":1445907,"position":2},"title":"Los Titans de Tennessee seleccionan al quarterback Cam Ward en la primera elecci\u00f3n del draft de la NFL 2025","author":"","date":"abril 24, 2025","format":false,"excerpt":"En la primera elecci\u00f3n del draft de la NFL 2025, los Titans de Tennessee seleccionaron al quarterback Cam Ward.Ward, de la Universidad de Miami, fue finalista del Trofeo Heisman la temporada pasada despu\u00e9s de terminar con 4.313 yardas por pase y 39 touchdowns.El jugador de 22 a\u00f1os, quien al salir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448683,"url":"https:\/\/noticiasya.com\/springfield\/2024\/04\/29\/caso-sussan-morphew-causa-muerte-homicidio-coctel-drogas-trax\/","url_meta":{"origin":1445907,"position":3},"title":"Una mujer de Colorado que desapareci\u00f3 durante un paseo en bicicleta muri\u00f3 por homicidio y ten\u00eda un c\u00f3ctel de drogas en su organismo, seg\u00fan el forense","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN) -- La autopsia realizada a los restos de una mujer de Colorado que desapareci\u00f3 mientras daba un paseo en bicicleta en 2020 y fue hallada muerta tres a\u00f1os despu\u00e9s determin\u00f3 que muri\u00f3 por homicidio y que ten\u00eda en su organismo un c\u00f3ctel de drogas que se utilizan para inmovilizar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1420455,"url":"https:\/\/noticiasya.com\/springfield\/2022\/08\/21\/advierten-que-perros-pueden-contraer-viruela-de-mono-tras-primer-caso-detectado-en-francia\/","url_meta":{"origin":1445907,"position":4},"title":"Advierten que perros pueden contraer viruela del mono","author":"agomez","date":"agosto 21, 2022","format":false,"excerpt":"Los CDC actualizaron la gu\u00eda tras el primer caso de un perro galgo italiano.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/springfield\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445342,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/13\/la-atacante-del-tiroteo-en-iglesia-de-houston-tenia-un-largo-historial-criminal-segun-la-policia-quien-era-genesse-ivonne-moreno\/","url_meta":{"origin":1445907,"position":5},"title":"La atacante del tiroteo en iglesia de Houston ten\u00eda un largo historial criminal, seg\u00fan la Polic\u00eda: \u00bfqui\u00e9n era Genesse Ivonne Moreno?","author":"agomez","date":"febrero 13, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 La mujer que abri\u00f3 fuego en una gran iglesia de Houston, Texas, la tarde de este domingo, luego de entrar con su hijo de 7 a\u00f1os, fue identificada como Genesse Ivonne Moreno, de 36 a\u00f1os, en una orden de registro.Poco despu\u00e9s de que Moreno comenzara a disparar en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445907"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445907\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}