{"id":1445938,"date":"2024-02-22T19:52:07","date_gmt":"2024-02-23T03:52:07","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/"},"modified":"2024-02-22T19:52:07","modified_gmt":"2024-02-23T03:52:07","slug":"wendy-williams-afasia-demencia-diagnostico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/","title":{"rendered":"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Wendy Williams, expresentadora de programas de entrevistas, fue diagnosticada con afasia progresiva y demencia frontotemporal, seg\u00fan sus representantes.<\/p>\n<p>La noticia se comparti\u00f3 en un comunicado de prensa este jueves para \u201ccorregir rumores inexactos e hirientes sobre su salud\u201d, escribi\u00f3 un equipo de atenci\u00f3n de Williams.<\/p>\n<p>&#171;Como los fans de Wendy saben, anteriormente ella ha sido abierta con el p\u00fablico sobre sus luchas m\u00e9dicas con la enfermedad de Graves y el linfedema, as\u00ed como con otros desaf\u00edos importantes relacionados a su salud&#187;, se\u00f1ala el comunicado de prensa. \u201cEn los \u00faltimos a\u00f1os, en ocasiones se han planteado preguntas sobre la capacidad de Wendy para procesar informaci\u00f3n y muchos han especulado sobre la condici\u00f3n de Wendy, especialmente cuando comenz\u00f3 a olvidar palabras, a actuar de manera err\u00e1tica en ocasiones y a tener dificultades para comprender las transacciones financieras\u201d.<\/p>\n<p>En 2023, Williams recibi\u00f3 su diagn\u00f3stico de afasia y demencia en el Weill Cornell Medicine, seg\u00fan sus representantes.<\/p>\n<p>\u00bfQu\u00e9 es la afasia?<\/p>\n<p>Esta condici\u00f3n afecta la comunicaci\u00f3n, la personalidad y la capacidad de comprender el lenguaje, seg\u00fan la Cl\u00ednica Mayo.<\/p>\n<p>&#171;La decisi\u00f3n de compartir esta noticia fue dif\u00edcil y se tom\u00f3 despu\u00e9s de una cuidadosa consideraci\u00f3n, no solo para abogar por la comprensi\u00f3n y la compasi\u00f3n hacia Wendy, sino tambi\u00e9n para crear conciencia sobre la afasia y la demencia frontotemporal&#187;.<\/p>\n<p>CNN se ha puesto en contacto con el equipo de atenci\u00f3n de Williams para obtener m\u00e1s comentarios.<\/p>\n<p>Williams se encuentra actualmente bajo una tutela que orden\u00f3 un tribunal. Este fin de semana se estrenar\u00e1 un documental de Lifetime sobre Williams, que produjo ella misma, con la participaci\u00f3n de su familia.<\/p>\n<p>CNN se comunic\u00f3 con la familia de Williams y con Lifetime para solicitar declaraciones.<\/p>\n<p>Williams fue la presentadora de su programa \u201cThe Wendy Williams Show\u201d hasta 2022, cuando Sherri Shepherd tom\u00f3 el horario de emisi\u00f3n. Antes del final del programa, Williams hab\u00eda estado ausente como presentadora desde el estreno de la temporada 13, que termin\u00f3 siendo la \u00faltima. En ese momento, el programa atribuy\u00f3 su ausencia a la recuperaci\u00f3n de Williams del covid-19 y luego dijo que estaba luchando contra la enfermedad de Graves, un trastorno autoinmune.<\/p>\n<p>\u201cThe Wendy Williams Show\u201d fue creado por Williams y debut\u00f3 en 2008 en estudios de la ciudad de Nueva York. Comenz\u00f3 su carrera en la radio y desarroll\u00f3 una reputaci\u00f3n por su ingenio r\u00e1pido y sus entrevistas sin filtros. Era conocida por su franqueza, lo que tambi\u00e9n alter\u00f3 algunas plumas entre aquellos en el entretenimiento a lo largo del camino.<\/p>\n<p>A menudo, Williams tambi\u00e9n se enorgullec\u00eda de ser sincera con sus espectadores. Ella ha sido abierta sobre la lucha que vivi\u00f3 contra la adicci\u00f3n. En 2019, habl\u00f3 en el programa sobre vivir en una casa sobria despu\u00e9s de buscar tratamiento por consumo de drogas. Solicit\u00f3 el divorcio de su marido, Kevin Hunter, el mismo a\u00f1o.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Wendy Williams, expresentadora de programas de entrevistas, fue diagnosticada con afasia progresiva y demencia frontotemporal, seg\u00fan sus representantes. La noticia se comparti\u00f3 en un comunicado de prensa este jueves para \u201ccorregir rumores inexactos e hirientes sobre su salud\u201d, escribi\u00f3 un equipo de atenci\u00f3n de Williams. &#171;Como los fans de Wendy saben, anteriormente ella [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445938","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Wendy Williams, expresentadora de programas de entrevistas, fue diagnosticada con afasia progresiva y demencia frontotemporal, seg\u00fan sus representantes. La noticia se comparti\u00f3 en un comunicado de prensa este jueves para \u201ccorregir rumores inexactos e hirientes sobre su salud\u201d, escribi\u00f3 un equipo de atenci\u00f3n de Williams. &#171;Como los fans de Wendy saben, anteriormente ella [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-23T03:52:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia\",\"datePublished\":\"2024-02-23T03:52:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/\"},\"wordCount\":527,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/\",\"name\":\"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-23T03:52:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia - Noticias","og_description":"(CNN) \u2013\u2013 Wendy Williams, expresentadora de programas de entrevistas, fue diagnosticada con afasia progresiva y demencia frontotemporal, seg\u00fan sus representantes. La noticia se comparti\u00f3 en un comunicado de prensa este jueves para \u201ccorregir rumores inexactos e hirientes sobre su salud\u201d, escribi\u00f3 un equipo de atenci\u00f3n de Williams. &#171;Como los fans de Wendy saben, anteriormente ella [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/","og_site_name":"Noticias","article_published_time":"2024-02-23T03:52:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/"},"author":{"name":"","@id":""},"headline":"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia","datePublished":"2024-02-23T03:52:07+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/"},"wordCount":527,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/","name":"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-23T03:52:07+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/22\/wendy-williams-afasia-demencia-diagnostico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-23T03:52:07Z","datePublished":"2024-02-23T03:52:07Z","dateModified":"2024-02-23T03:52:07Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"A Wendy Williams, expresentadora de TV, le diagnosticaron afasia y demencia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/22\\\/wendy-williams-afasia-demencia-diagnostico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/22\\\/wendy-williams-afasia-demencia-diagnostico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-23T03:52:07Z\",\"datePublished\":\"2024-02-23T03:52:07Z\",\"dateModified\":\"2024-02-23T03:52:07Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445941,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/22\/afasia-que-es-enfermedad-causas-sintomas-orix\/","url_meta":{"origin":1445938,"position":0},"title":"\u00bfQu\u00e9 es la afasia, la enfermedad que padecen Bruce Willis y Wendy Williams?","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La afasia es una enfermedad que impide que una persona se comunique, pues \"afecta la capacidad de hablar, escribir y comprender el lenguaje tanto verbal como escrito\", explica la Cl\u00ednica Mayo en su p\u00e1gina web. Esta es la condici\u00f3n que padece el actor Bruce Willis y que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460143,"url":"https:\/\/noticiasya.com\/springfield\/2025\/03\/19\/hija-bruce-willis-bien-cumplir-70-anos-trax\/","url_meta":{"origin":1445938,"position":1},"title":"La hija de Bruce Willis, Rumer, dice que su padre &#171;est\u00e1 muy bien&#187; al cumplir 70 a\u00f1os","author":"","date":"marzo 19, 2025","format":false,"excerpt":"Rumer Willis, hija de Bruce Willis y Demi Moore, comparti\u00f3 una actualizaci\u00f3n sobre la salud de su padre mientras la estrella de \u201cDie Hard\u201d celebra un cumplea\u00f1os importante.El martes, antes de que Bruce Willis celebrara su cumplea\u00f1os n\u00famero 70, Rumer Willis respondi\u00f3 a algunas preguntas de sus seguidores en una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451364,"url":"https:\/\/noticiasya.com\/springfield\/2024\/07\/23\/brain-care-score-herramienta-predecir-riesgo-demencia-depresion-trax\/","url_meta":{"origin":1445938,"position":2},"title":"Una sencilla herramienta puede predecir el riesgo de demencia y depresi\u00f3n, seg\u00fan un estudio","author":"","date":"julio 23, 2024","format":false,"excerpt":"(CNN) -- Cient\u00edficos anunciaron en diciembre la creaci\u00f3n con \u00e9xito del Brain Care Score, una herramienta para evaluar el riesgo de demencia o ictus sin necesidad de procedimientos m\u00e9dicos.Seg\u00fan un nuevo estudio, esta puntuaci\u00f3n, que tambi\u00e9n ayuda a pacientes y m\u00e9dicos a identificar cambios beneficiosos en el estilo de vida,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466693,"url":"https:\/\/noticiasya.com\/springfield\/2025\/09\/22\/trump-autismo-analgesico-vitaminas-trax\/","url_meta":{"origin":1445938,"position":3},"title":"Trump anticipa &#171;asombroso&#187; anuncio sobre autismo en el que se espera aborde analg\u00e9sico y vitaminas","author":"","date":"septiembre 22, 2025","format":false,"excerpt":"El discurso del presidente de EE.UU., Donald Trump, en el funeral de Charlie Kirk este domingo dio un giro para adelantar un anuncio que planea hacer el lunes desde la Oficina Oval sobre el autismo.\u201cCreo que les parecer\u00e1 asombroso\u201d, dijo. \u201cCreo que encontramos una respuesta al autismo\u201d.Aunque no ofreci\u00f3 detalles,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463618,"url":"https:\/\/noticiasya.com\/springfield\/2025\/06\/17\/familia-bruce-willis-mensajes-familia-enfermedad-trax\/","url_meta":{"origin":1445938,"position":4},"title":"La familia de Bruce Willis comparte conmovedores mensajes sobre los padres que &#171;viven con una discapacidad o enfermedad&#187;","author":"","date":"junio 17, 2025","format":false,"excerpt":"La familia de Bruce Willis lo celebr\u00f3 el D\u00eda del Padre, aunque reconoci\u00f3 que los d\u00edas festivos pueden resultar \u201cdif\u00edciles\u201d porque vive con demencia .\u201cFeliz D\u00eda del Padre a todos los pap\u00e1s que viven con discapacidades o enfermedades, que se muestran siempre presentes y a los ni\u00f1os que los apoyan\u201d,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457119,"url":"https:\/\/noticiasya.com\/springfield\/2025\/01\/01\/cuba-revolucion-edad-retiro-wendy-guerra\/","url_meta":{"origin":1445938,"position":5},"title":"Cuba, 66 a\u00f1os despu\u00e9s: la revoluci\u00f3n entr\u00f3 en edad de retiro","author":"","date":"enero 1, 2025","format":false,"excerpt":"Cuba vive un total desgarramiento. El divorcio entre pueblo y gobierno se hace cada vez m\u00e1s evidente. Las noticias de los familiares y amigos, videos, fotos y evidencias que nos llegan desde la isla, hablan de insalubridad, apagones, abandono a los adultos mayores, hambre, indefensi\u00f3n, escasez y p\u00e9rdida total de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445938"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445938\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}