{"id":1445960,"date":"2024-02-23T13:21:55","date_gmt":"2024-02-23T21:21:55","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/"},"modified":"2024-02-23T13:21:55","modified_gmt":"2024-02-23T21:21:55","slug":"fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/","title":{"rendered":"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere &#171;evitar y frustrar&#187; investigaciones a altos funcionarios"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0Juan Carlos Villena, fiscal de la Naci\u00f3n interino de Per\u00fa, quien asumi\u00f3 el cargo en diciembre tras la suspensi\u00f3n de Patricia Benavides, invoc\u00f3 a la ciudadan\u00eda a \u201cmantenerse alerta\u201d ante un proyecto de ley, iniciativa del congresista Jorge Montoya, del partido Renovaci\u00f3n Popular.<\/p>\n<p>Durante un video difundido este jueves a trav\u00e9s de la red social X, Villena denunci\u00f3 que el proyecto busca \u201cevitar y frustrar las investigaciones de los altos funcionarios que vienen llev\u00e1ndose a cabo\u201d as\u00ed como las investigaciones de los equipos especiales de fiscales, Lava Jato y otros, como los casos de \u201cv\u00edctimas durante las protestas y corrupci\u00f3n en el poder\u2026\u201d, refiri\u00e9ndose, a las muertes ocurridas durante las manifestaciones tras el intento de disoluci\u00f3n inconstitucional del Congreso por parte del expresidente Pedro Castillo en diciembre de 2022, luego de lo cual la presidenta Dina Boluarte asumi\u00f3 la presidencia de Per\u00fa.<\/p>\n<p>CNN ha comunicado con el Ministerio P\u00fablico para conocer c\u00f3mo accedi\u00f3 al proyecto de ley pero a\u00fan no ha obtenido respuesta.<\/p>\n<p>Ministerio P\u00fablico de Per\u00fa abre investigaciones contra sus propios funcionarios. \u00bfQu\u00e9 ocurre en la instituci\u00f3n?<\/p>\n<p>\u00bfQu\u00e9 dice el proyecto de ley?<\/p>\n<p>Tras el pronunciamiento del fiscal de la Naci\u00f3n interino, el congresista Jorge Montoya dijo en su cuenta de la red social X que el proyecto de ley que fue \u201cdesafortunadamente filtrado de manera maliciosa a los medios\u201d no busca obstaculizar las investigaciones en curso, sino \u201crestaurar la confianza erosionada en la justicia\u201d y que es \u201cuna respuesta necesaria ante las preocupantes declaraciones que vinculan a altos funcionarios del Ministerio P\u00fablico en situaciones comprometedoras\u201d.<\/p>\n<p>CNN se comunic\u00f3 con Montoya, quien dijo que el proyecto lleva el t\u00edtulo de \u201cLey que declara en emergencia y reorganizaci\u00f3n al Ministerio P\u00fablico\u201d y que investigan c\u00f3mo se filtr\u00f3: \u201cSomos conscientes de lo que estamos haciendo con un proyecto de ese tipo, pero estamos en una grave crisis en el Ministerio P\u00fablico\u201d dijo. Agreg\u00f3 que, si bien, el texto filtrado no es el final \u201cpodr\u00eda haber cambios en algunos detalles pero no el fondo, que implica reformar el sistema\u201d.<\/p>\n<p>En su pronunciamiento en X (antes Twitter), Montoya se refiri\u00f3 a las recientes declaraciones de Jaime Villanueva, exasesor de la suspendida Fiscal de la Naci\u00f3n, Patricia Benavides, y que recientemente motivaron a la Fiscal\u00eda a abrir investigaciones a varios de sus propios integrantes. Villanueva fue acusado de organizaci\u00f3n criminal y tr\u00e1fico de influencias en una investigaci\u00f3n que busca comprobar la posible existencia de una red criminal en el Ministerio P\u00fablico. Fue liberado en diciembre tras aceptar su colaboraci\u00f3n con la pesquisa.<\/p>\n<p>Seg\u00fan el fiscal interino, el documento \u201cpretender\u00eda declarar en emergencia y reorganizaci\u00f3n el Ministerio P\u00fablico y destituir sistem\u00e1ticamente a los fiscales de todas las instancias\u201d.<\/p>\n<p>Villena dijo que \u201cse plantea que luego de destituir a los fiscales supremos titulares en 180 d\u00edas, se les debe someter a una evaluaci\u00f3n por la junta de fiscales supremos reconformada y separarlos por considerarlos no id\u00f3neos\u201d.<\/p>\n<p>El funcionario calific\u00f3 el proyecto de \u201cabiertamente inconstitucional y arbitrario\u201d y dijo que \u201cvulneraria el estado constitucional de derecho, la autonom\u00eda e independencia del Ministerio P\u00fablico y el equilibrio de poderes esencial en una verdadera democracia\u201d.<\/p>\n<p>Dijo que \u201cpretenden quebrantar el orden constitucional y democr\u00e1tico con el prop\u00f3sito de volver al inicio de los a\u00f1os 90 cuando se destituy\u00f3 a muchos fiscales titulares del Ministerio P\u00fablico\u201d. El fiscal de la Naci\u00f3n interino se pregunt\u00f3 \u201c\u00bfacaso ya se tienen listos los nombres de las personas que nos reemplazar\u00edan de inmediato como en los a\u00f1os 90?\u201d<\/p>\n<p>Sobre esta afirmaci\u00f3n, Montoya le dijo a CNN: \u201cNo tenemos nombres de nadie. Estamos hablando de c\u00f3mo reformular el sistema. Todo esto debe hacerse de manera meritocr\u00e1tica\u201d.<\/p>\n<p>\u00bfA qui\u00e9nes investiga el Ministerio P\u00fablico?<\/p>\n<p>La Fiscal\u00eda tiene a su cargo investigaciones a varios expresidentes de Per\u00fa como Pedro Castillo, Alejandro Toledo, Mart\u00edn Vizcarra, Ollanta Humala y Pedro Pablo Kuczynski. En el caso de Castillo, la investigaci\u00f3n se refiere a la disoluci\u00f3n inconstitucional del Congreso y a los presuntos actos de corrupci\u00f3n cometidos durante su gobierno. En el caso de los otros exmandatarios, est\u00e1n relacionadas con el caso Odebrecht, al igual que en el caso Keiko Fujimori, l\u00edder del partido Fuerza Popular. Todos se han declarado inocentes.<\/p>\n<p>Villena dijo que hasta ahora ha recibido 357 carpetas fiscales de investigaciones contra altos funcionarios, como &#171;expresidentes de la Rep\u00fablica, congresistas, ministros, jueces y fiscales supremos, miembros del Tribunal Constitucional y de la Junta Nacional de Justicia y del Contralor General de la Rep\u00fablica\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0Juan Carlos Villena, fiscal de la Naci\u00f3n interino de Per\u00fa, quien asumi\u00f3 el cargo en diciembre tras la suspensi\u00f3n de Patricia Benavides, invoc\u00f3 a la ciudadan\u00eda a \u201cmantenerse alerta\u201d ante un proyecto de ley, iniciativa del congresista Jorge Montoya, del partido Renovaci\u00f3n Popular. Durante un video difundido este jueves a trav\u00e9s de la red [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445960","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere &quot;evitar y frustrar&quot; investigaciones a altos funcionarios - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere &quot;evitar y frustrar&quot; investigaciones a altos funcionarios - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0Juan Carlos Villena, fiscal de la Naci\u00f3n interino de Per\u00fa, quien asumi\u00f3 el cargo en diciembre tras la suspensi\u00f3n de Patricia Benavides, invoc\u00f3 a la ciudadan\u00eda a \u201cmantenerse alerta\u201d ante un proyecto de ley, iniciativa del congresista Jorge Montoya, del partido Renovaci\u00f3n Popular. Durante un video difundido este jueves a trav\u00e9s de la red [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-23T21:21:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere &#171;evitar y frustrar&#187; investigaciones a altos funcionarios\",\"datePublished\":\"2024-02-23T21:21:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/\"},\"wordCount\":826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/\",\"name\":\"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere \\\"evitar y frustrar\\\" investigaciones a altos funcionarios - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-23T21:21:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere &#171;evitar y frustrar&#187; investigaciones a altos funcionarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere \"evitar y frustrar\" investigaciones a altos funcionarios - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere \"evitar y frustrar\" investigaciones a altos funcionarios - Noticias","og_description":"(CNN) &#8212;\u00a0Juan Carlos Villena, fiscal de la Naci\u00f3n interino de Per\u00fa, quien asumi\u00f3 el cargo en diciembre tras la suspensi\u00f3n de Patricia Benavides, invoc\u00f3 a la ciudadan\u00eda a \u201cmantenerse alerta\u201d ante un proyecto de ley, iniciativa del congresista Jorge Montoya, del partido Renovaci\u00f3n Popular. Durante un video difundido este jueves a trav\u00e9s de la red [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/","og_site_name":"Noticias","article_published_time":"2024-02-23T21:21:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/"},"author":{"name":"","@id":""},"headline":"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere &#171;evitar y frustrar&#187; investigaciones a altos funcionarios","datePublished":"2024-02-23T21:21:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/"},"wordCount":826,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/","name":"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere \"evitar y frustrar\" investigaciones a altos funcionarios - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-23T21:21:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere &#171;evitar y frustrar&#187; investigaciones a altos funcionarios"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fiscal interino de Per\u00fa denuncia que proyecto de ley del Congreso quiere &#171;evitar y frustrar&#187; investigaciones a altos funcionarios","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-23T21:21:55Z","datePublished":"2024-02-23T21:21:55Z","dateModified":"2024-02-23T21:21:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fiscal interino de Per\\u00fa denuncia que proyecto de ley del Congreso quiere &#171;evitar y frustrar&#187; investigaciones a altos funcionarios\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/23\\\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/23\\\/fiscal-interino-peru-denuncia-ley-evitar-y-frustrar-investigaciones-funcionarios-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-23T21:21:55Z\",\"datePublished\":\"2024-02-23T21:21:55Z\",\"dateModified\":\"2024-02-23T21:21:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450335,"url":"https:\/\/noticiasya.com\/springfield\/2024\/06\/13\/peru-instituciones-internacionales-critican-congreso-orix\/","url_meta":{"origin":1445960,"position":0},"title":"\u00bfPor qu\u00e9 instituciones internacionales critican al Congreso de Per\u00fa?","author":"","date":"junio 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El 48% de los peruanos considera que el Congreso es la instituci\u00f3n con mayor poder en el pa\u00eds, seg\u00fan la \u00faltima encuesta de AmericaTV-Ipsos difundida en junio. Muy por detr\u00e1s, en segundo lugar y con un 18%, se encuentra el Poder Judicial y, en tercer lugar con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446535,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/05\/peru-investiga-alberto-otarola-favorecer-vinculo-sentimental-orix\/","url_meta":{"origin":1445960,"position":1},"title":"Fiscal\u00eda peruana investiga al presidente del Consejo de Ministros por presuntamente favorecer a una persona con la que habr\u00eda tenido v\u00ednculo sentimental","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El Ministerio P\u00fablico peruano inform\u00f3 este lunes en X, antes Twitter, que \"inici\u00f3 diligencias preliminares\" contra el primer ministro Alberto Ot\u00e1rola, como \"presunto instigador del delito contra la administraci\u00f3n p\u00fablica y como presunto autor del delito contra la administraci\u00f3n p\u00fablica-patrocinio ilegal\", ambos en agravio del Estado. La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465333,"url":"https:\/\/noticiasya.com\/springfield\/2025\/08\/09\/analisis-campana-represalias-legales-trump-descarada-trax\/","url_meta":{"origin":1445960,"position":2},"title":"La campa\u00f1a de represalias legales de Trump se vuelve m\u00e1s descarada","author":"","date":"agosto 9, 2025","format":false,"excerpt":"En caso de que hubiera alguna duda de que el presidente Donald Trump y su Gobierno est\u00e1n en una campa\u00f1a de represalias legales, esto deber\u00eda dejarlo claro.Trump ha sido investigado con frecuencia durante su carrera pol\u00edtica, debido a sus constantes esfuerzos por superar los l\u00edmites. Pero, \u00bfquiz\u00e1s los cuatro ejemplos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450878,"url":"https:\/\/noticiasya.com\/springfield\/2024\/07\/04\/congreso-de-peru-aprueba-proyecto-de-ley-que-limita-el-alcance-de-los-delitos-de-lesa-humanidad\/","url_meta":{"origin":1445960,"position":3},"title":"Congreso de Per\u00fa aprueba proyecto de ley que limita el alcance de los delitos de lesa humanidad","author":"","date":"julio 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Comisi\u00f3n Permanente del Congreso peruano aprob\u00f3 este jueves, en una segunda votaci\u00f3n, el proyecto de ley que \"precisa la aplicaci\u00f3n y alcances del delito de lesa humanidad y cr\u00edmenes de guerra\" en Per\u00fa.El proyecto legislativo, que ya hab\u00eda sido aprobado en primera votaci\u00f3n el 6 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445538,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/17\/ministerio-publico-de-peru-abre-investigaciones-contra-sus-propios-funcionarios-que-ocurre-en-la-institucion\/","url_meta":{"origin":1445960,"position":4},"title":"Ministerio P\u00fablico de Per\u00fa abre investigaciones contra sus propios funcionarios. \u00bfQu\u00e9 ocurre en la instituci\u00f3n?","author":"","date":"febrero 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La detenci\u00f3n en el mes de noviembre y las posteriores declaraciones ante el Ministerio P\u00fablico de Jaime Villanueva, exasesor de la suspendida Fiscal de la Naci\u00f3n, Patricia Benavides, han salpicado a diversos personajes del \u00e1mbito p\u00fablico en supuestos actos de corrupci\u00f3n que se habr\u00edan cometido en la propia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464790,"url":"https:\/\/noticiasya.com\/springfield\/2025\/07\/23\/ucrania-protestas-gobierno-zelensky-trax\/","url_meta":{"origin":1445960,"position":5},"title":"Ucrania registra las primeras grandes protestas contra el Gobierno de Zelensky desde el inicio de la guerra","author":"","date":"julio 23, 2025","format":false,"excerpt":"Ucrania ha presenciado las primeras grandes protestas contra el Gobierno en Kyiv desde el inicio de la invasi\u00f3n rusa a gran escala hace m\u00e1s de tres a\u00f1os, tras la indignaci\u00f3n generalizada que gener\u00f3 una medida del presidente Volodymyr Zelensky para frenar las agencias anticorrupci\u00f3n.Multitudes desafiantes se congregaron el martes en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445960"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445960\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}