{"id":1445962,"date":"2024-02-23T15:52:10","date_gmt":"2024-02-23T23:52:10","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/23\/fosil-dragon-240-millones-trax\/"},"modified":"2024-02-23T15:52:10","modified_gmt":"2024-02-23T23:52:10","slug":"fosil-dragon-240-millones-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fosil-dragon-240-millones-trax\/","title":{"rendered":"Cient\u00edficos revelan un f\u00f3sil de &#171;drag\u00f3n&#187; de 240 millones de a\u00f1os"},"content":{"rendered":"<p>(CNN) \u2014 F\u00f3siles reci\u00e9n descubiertos permitieron a los cient\u00edficos revelar por completo el de un \u201cdrag\u00f3n\u201d de 240 millones de a\u00f1os, informaron los Museos Nacionales de Escocia (NMS, por sus siglas en ingl\u00e9s) en un comunicado este viernes.<\/p>\n<p>El reptil de cinco metros de largo, perteneciente al per\u00edodo Tri\u00e1sico en China, se identific\u00f3 por primera vez en 2003. Sin embargo, despu\u00e9s de estudiar cinco espec\u00edmenes m\u00e1s recientes durante diez a\u00f1os, los cient\u00edficos pudieron al fin retratar la criatura completa, que lleva el nombre de Dinocephalosaurus orientalis.<\/p>\n<p>Un nido fosilizado de 29 millones de a\u00f1os descubierto en Oregon podr\u00eda ser \u00fanico en su especie<\/p>\n<p>Un f\u00f3sil completamente articulado, el \u00faltimo en salir a la luz, ofreci\u00f3 un &#171;hermoso esp\u00e9cimen completo desde la punta de la nariz hasta la punta de la cola&#187;, dijo el Dr. Nick Fraser, encargado de Ciencias Nacionales en los NMS y uno de los investigadores, en conversaci\u00f3n con CNN.<\/p>\n<p>&#171;Est\u00e1 enrollado en una especie de figura de ocho y&#8230; recuerda mucho a un drag\u00f3n chino&#187;, detall\u00f3.<\/p>\n<p>Ese f\u00f3sil ayud\u00f3 a dar luz sobre esta misteriosa criatura, y un equipo internacional de investigadores de Escocia, Alemania, Estados Unidos y China publicaron sus hallazgos en la revista Earth and Environmental Science Transactions de la Royal Society de Edimburgo.<\/p>\n<p>Hallan en la Patagonia argentina f\u00f3siles de uno de los \u00faltimos dinosaurios de cuello largo y pico de pato<\/p>\n<p>El profesor Li Chun del Instituto de Paleontolog\u00eda y Paleoantropolog\u00eda de Vertebrados de Beijing fue el primero en descubrir los f\u00f3siles en 2003. Estaba visitando un peque\u00f1o pueblo en la provincia de Guizhou, en el sur de China, cuando not\u00f3 una peque\u00f1a v\u00e9rtebra en una losa de piedra caliza, seg\u00fan su colega Fraser.<\/p>\n<p>Luego, los agricultores locales llevaron a Chun a otro lugar donde hab\u00eda otros pedazos de ese tipo de roca, y comenz\u00f3 a encontrar fragmentos de huesos y los uni\u00f3 para descubrir esta nueva especie, agreg\u00f3 Fraser.<\/p>\n<p>Una interpretaci\u00f3n art\u00edstica de la antigua criatura marina. (Cr\u00e9dito: Marlene Donelly)<\/p>\n<p>Ahora, f\u00f3siles m\u00e1s recientes indican que la criatura ten\u00eda 32 v\u00e9rtebras, las cuales formaban un cuello extremadamente largo que probablemente le ayud\u00f3 a pescar, aunque los cient\u00edficos a\u00fan no est\u00e1n seguros de su funci\u00f3n precisa.<\/p>\n<p>&#171;Todav\u00eda estoy desconcertado por la funci\u00f3n del cuello largo&#187;, dijo Fraser. \u201cLo \u00fanico que se me ocurre es que se estaban alimentando en aguas que ten\u00edan rocas y tal vez grietas. Y estaban usando sus largos cuellos para sondear y moverse hacia algunas de estas grietas y tal vez capturar presas de esa manera\u201d, indic\u00f3.<\/p>\n<p>Encuentran en Chile el f\u00f3sil de un elasmosaurio, un reptil marino que vivi\u00f3 hace 70 millones de a\u00f1os<\/p>\n<p>Todav\u00eda se conservan peces en la regi\u00f3n del est\u00f3mago de un f\u00f3sil, lo que indica que estaba bien adaptado al ambiente marino, y sus extremidades con aletas refuerzan esa hip\u00f3tesis, explicaron los investigadores en su art\u00edculo.<\/p>\n<p>Agregaron que el largo cuello del Dinocephalosaurus se parec\u00eda a otro antiguo e igualmente desconcertante reptil marino, el Tanystropheus hydroides.<\/p>\n<p>\u201cComo paleont\u00f3logos, utilizamos an\u00e1logos modernos para comprender la vida en el pasado. Para Dinocephalosaurus y Tanystropheus, no existe un an\u00e1logo moderno\u201d, dijo Fraser. Tambi\u00e9n que los investigadores pueden comparar criaturas como los ictiosaurios con sus contrapartes modernas como el at\u00fan y los delfines.<\/p>\n<p>\u201cAs\u00ed que todav\u00eda estamos teniendo algunos obst\u00e1culos, como ocurre con muchos animales en el Tri\u00e1sico, porque realmente es un mundo extra\u00f1o y maravilloso de todo tipo de animales extra\u00f1os que hacen cosas que los animales de hoy no parecen hacer&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2014 F\u00f3siles reci\u00e9n descubiertos permitieron a los cient\u00edficos revelar por completo el de un \u201cdrag\u00f3n\u201d de 240 millones de a\u00f1os, informaron los Museos Nacionales de Escocia (NMS, por sus siglas en ingl\u00e9s) en un comunicado este viernes. El reptil de cinco metros de largo, perteneciente al per\u00edodo Tri\u00e1sico en China, se identific\u00f3 por primera [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445962","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cient\u00edficos revelan un f\u00f3sil de &quot;drag\u00f3n&quot; de 240 millones de a\u00f1os - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cient\u00edficos revelan un f\u00f3sil de &quot;drag\u00f3n&quot; de 240 millones de a\u00f1os - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2014 F\u00f3siles reci\u00e9n descubiertos permitieron a los cient\u00edficos revelar por completo el de un \u201cdrag\u00f3n\u201d de 240 millones de a\u00f1os, informaron los Museos Nacionales de Escocia (NMS, por sus siglas en ingl\u00e9s) en un comunicado este viernes. El reptil de cinco metros de largo, perteneciente al per\u00edodo Tri\u00e1sico en China, se identific\u00f3 por primera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-23T23:52:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cient\u00edficos revelan un f\u00f3sil de &#171;drag\u00f3n&#187; de 240 millones de a\u00f1os\",\"datePublished\":\"2024-02-23T23:52:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/\"},\"wordCount\":660,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/\",\"name\":\"Cient\u00edficos revelan un f\u00f3sil de \\\"drag\u00f3n\\\" de 240 millones de a\u00f1os - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-23T23:52:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cient\u00edficos revelan un f\u00f3sil de &#171;drag\u00f3n&#187; de 240 millones de a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cient\u00edficos revelan un f\u00f3sil de \"drag\u00f3n\" de 240 millones de a\u00f1os - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cient\u00edficos revelan un f\u00f3sil de \"drag\u00f3n\" de 240 millones de a\u00f1os - Noticias","og_description":"(CNN) \u2014 F\u00f3siles reci\u00e9n descubiertos permitieron a los cient\u00edficos revelar por completo el de un \u201cdrag\u00f3n\u201d de 240 millones de a\u00f1os, informaron los Museos Nacionales de Escocia (NMS, por sus siglas en ingl\u00e9s) en un comunicado este viernes. El reptil de cinco metros de largo, perteneciente al per\u00edodo Tri\u00e1sico en China, se identific\u00f3 por primera [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/","og_site_name":"Noticias","article_published_time":"2024-02-23T23:52:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/"},"author":{"name":"","@id":""},"headline":"Cient\u00edficos revelan un f\u00f3sil de &#171;drag\u00f3n&#187; de 240 millones de a\u00f1os","datePublished":"2024-02-23T23:52:10+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/"},"wordCount":660,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/","name":"Cient\u00edficos revelan un f\u00f3sil de \"drag\u00f3n\" de 240 millones de a\u00f1os - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-23T23:52:10+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/23\/fosil-dragon-240-millones-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cient\u00edficos revelan un f\u00f3sil de &#171;drag\u00f3n&#187; de 240 millones de a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fosil-dragon-240-millones-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cient\u00edficos revelan un f\u00f3sil de &#171;drag\u00f3n&#187; de 240 millones de a\u00f1os","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fosil-dragon-240-millones-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fosil-dragon-240-millones-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-23T23:52:10Z","datePublished":"2024-02-23T23:52:10Z","dateModified":"2024-02-23T23:52:10Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cient\\u00edficos revelan un f\\u00f3sil de &#171;drag\\u00f3n&#187; de 240 millones de a\\u00f1os\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/23\\\/fosil-dragon-240-millones-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/23\\\/fosil-dragon-240-millones-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-23T23:52:10Z\",\"datePublished\":\"2024-02-23T23:52:10Z\",\"dateModified\":\"2024-02-23T23:52:10Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469590,"url":"https:\/\/noticiasya.com\/springfield\/2025\/12\/26\/misterio-evolucion-humana-2025-trax\/","url_meta":{"origin":1445962,"position":0},"title":"El mayor misterio de la evoluci\u00f3n humana empieza a despejarse: un avance en 2025 fue clave","author":"","date":"diciembre 26, 2025","format":false,"excerpt":"El mayor misterio de la evoluci\u00f3n humana, que surgi\u00f3 hace 15 a\u00f1os a partir de un hueso del me\u00f1ique de unos 60.000 a\u00f1os de antig\u00fcedad, finalmente comenz\u00f3 a desvelarse en 2025.El an\u00e1lisis del ADN extra\u00eddo del f\u00f3sil conmocion\u00f3 a la comunidad cient\u00edfica en 2010, cuando revel\u00f3 la existencia de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458304,"url":"https:\/\/noticiasya.com\/springfield\/2025\/02\/05\/descubren-antartida-fosil-ave-moderna-antigua-trax\/","url_meta":{"origin":1445962,"position":1},"title":"Descubren en la Ant\u00e1rtida el f\u00f3sil del ave moderna m\u00e1s antigua conocida","author":"","date":"febrero 5, 2025","format":false,"excerpt":"Un f\u00f3sil de cr\u00e1neo casi completo encontrado en la Ant\u00e1rtida revel\u00f3 el ave moderna m\u00e1s antigua conocida: una criatura del tama\u00f1o de un pato real emparentada con las aves acu\u00e1ticas que hoy viven cerca de lagos y oc\u00e9anos, seg\u00fan ha descubierto un nuevo estudio.El f\u00f3sil de 68 millones de a\u00f1os\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467884,"url":"https:\/\/noticiasya.com\/springfield\/2025\/10\/30\/dinosaurios-fosil-nanotyrannus-tyrannosaurus-rex-trax\/","url_meta":{"origin":1445962,"position":2},"title":"El f\u00f3sil de los &#171;dinosaurios en duelo&#187; obliga a replantear radicalmente los restos de T. rex","author":"","date":"octubre 30, 2025","format":false,"excerpt":"Un f\u00f3sil legendario alojado en el Museo de Ciencias Naturales de Carolina del Norte en Raleigh presenta esqueletos aparentemente atrapados en un combate prehist\u00f3rico: un \u00e9pico encuentro entre dos de los dinosaurios favoritos del mundo, Triceratops y Tyrannosaurus rex. O al menos eso pensaban los paleont\u00f3logos.Investigadores que pasaron los \u00faltimos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451139,"url":"https:\/\/noticiasya.com\/springfield\/2024\/07\/15\/fosil-antiguo-tiburon-dinosaurios-misterio-siglos-trax\/","url_meta":{"origin":1445962,"position":3},"title":"El f\u00f3sil de un antiguo tibur\u00f3n de la era de los dinosaurios resuelve un misterio de siglos","author":"","date":"julio 15, 2024","format":false,"excerpt":"(CNN) --\u00a0Durante el per\u00edodo Cret\u00e1cico, un g\u00e9nero de tiburones navegaba por el mar con hileras de dientes inusuales. Estos dientes, en su mayor\u00eda grandes y redondeados, no ten\u00edan como funci\u00f3n cortar a sus presas, sino triturar criaturas con caparaz\u00f3n.Sin embargo, desde su descubrimiento en el siglo XVIII, los cient\u00edficos han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451936,"url":"https:\/\/noticiasya.com\/springfield\/2024\/08\/17\/colmillo-mamut-arroyo-mississippi-primer-descubrimiento-trax\/","url_meta":{"origin":1445962,"position":4},"title":"Se top\u00f3 con un gran colmillo en un arroyo de Mississippi. Result\u00f3 ser el primer descubrimiento de su tipo","author":"","date":"agosto 17, 2024","format":false,"excerpt":"(CNN) -- Eddie Templeton, un cazador de f\u00f3siles aficionado, suele saber cu\u00e1ndo ha dado con algo. Desde que era un ni\u00f1o recorre las orillas de los arroyos de Mississippi y ha encontrado varios mam\u00edferos extintos asombrosos, incluyendo una mand\u00edbula de mastodonte, numerosos huesos de un pariente del armadillo gigante e\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445762,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/21\/el-fosil-famoso-en-realidad-es-solo-pintura-rocas-y-un-par-de-huesos-dicen-los-investigadores\/","url_meta":{"origin":1445962,"position":5},"title":"El f\u00f3sil famoso en realidad es solo pintura, rocas y un par de huesos, dicen los investigadores","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Seg\u00fan una nueva investigaci\u00f3n, un f\u00f3sil de 280 millones de a\u00f1os que se cree que es un esp\u00e9cimen bien conservado de un reptil antiguo es en gran medida una falsificaci\u00f3n.El f\u00f3sil, descubierto inicialmente en los Alpes italianos en 1931, tiene el nombre cient\u00edfico de Tridentinosaurus antiquus. Los cient\u00edficos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445962"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445962\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}