{"id":1445967,"date":"2024-02-23T18:46:56","date_gmt":"2024-02-24T02:46:56","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/"},"modified":"2024-02-23T18:46:56","modified_gmt":"2024-02-24T02:46:56","slug":"mina-venezuela-colapso-oro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/","title":{"rendered":"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela?"},"content":{"rendered":"<p>(CNN) \u2013\u2013 El colapso de una mina de extracci\u00f3n de oro en el estado Bol\u00edvar, Venezuela, ocurrido el martes, dej\u00f3 al menos 16 muertos, de acuerdo con las cifras oficiales que difundi\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro, el cual califica de ilegales a esas operaciones extractivas.<\/p>\n<p>Tragedia en Venezuela por derrumbe de una mina de oro<\/p>\n<p>\u00bfD\u00f3nde ocurri\u00f3 el colapso de la mina?<\/p>\n<p>El colapso ocurri\u00f3 en la localidad de La Paragua, una regi\u00f3n cercana a la frontera entre Venezuela y Brasil. \u201cEn el sitio de Bulla Loca hay una intensa actividad de extracci\u00f3n irregular de oro\u201d, explic\u00f3 a CNN el periodista Fritz S\u00e1nchez, especializado en medio ambiente y quien trabaj\u00f3 en la regi\u00f3n de Bol\u00edvar durante m\u00e1s de 20 a\u00f1os. \u201cEl socavamiento del terreno para la extracci\u00f3n en busca del oro gener\u00f3 el deslave y toda esta tragedia\u201d.<\/p>\n<p>De acuerdo con S\u00e1nchez, se trata de una zona \u201cboscosa y de dif\u00edcil acceso\u201d, y para llegar al sitio de la mina es necesario hacer un recorrido a trav\u00e9s del r\u00edo tambi\u00e9n llamado La Paragua.<\/p>\n<p>\u201cSolo hay una forma de llegar que es una traves\u00eda fluvial, que puede implicar dos horas y media\u201d, describi\u00f3 S\u00e1nchez, quien a\u00f1adi\u00f3 que, en \u00e9pocas de calor, el nivel bajo del r\u00edo puede alargar a\u00fan m\u00e1s la llegada de equipos de ayuda.<\/p>\n<p>\u00bfQu\u00e9 se sabe de las v\u00edctimas?<\/p>\n<p>Maduro anunci\u00f3 el mi\u00e9rcoles que 15 personas murieron en la mina, cifra que aument\u00f3 el jueves despu\u00e9s del anuncio del viceministro para la Gesti\u00f3n de Riesgo y Protecci\u00f3n Civil venezolano, Carlos P\u00e9rez Ampueda. Las autoridades dijeron tambi\u00e9n que hab\u00eda al menos 16 personas heridas.<\/p>\n<p>Aumenta a 16 el n\u00famero de fallecidos por el colapso de una mina en Venezuela<\/p>\n<p>Seg\u00fan un comunicado de la ONG venezolana Kap\u00e9 Kap\u00e9 difundido este viernes, al menos tres de las v\u00edctimas son miembros de comunidades ind\u00edgenas que habitan en la zona.<\/p>\n<p>CNN est\u00e1 intentando contactar a las autoridades venezolanas en busca de comentarios sobre esos reportes, sin haber obtenido una respuesta hasta ahora.<\/p>\n<p>\u00bfHay precedentes de este colapso?<\/p>\n<p>Sat\u00e9lites revelan la expansi\u00f3n de la mina de oro ilegal donde ocurri\u00f3 el accidente en Venezuela 0:46<\/p>\n<p>Un informe de la OCDE difundido en 2021 alerta que en la zona donde ocurri\u00f3 el derrumbe se producen numerosos actos ilegales que ponen en riesgo a la poblaci\u00f3n. El reporte se\u00f1ala: \u201cGraves abusos de los derechos humanos asociados con la extracci\u00f3n, el transporte o el comercio de minerales, como las peores formas de trabajo infantil, el trabajo forzoso, tratos degradantes, tortura y la violencia sexual generalizada\u201d.<\/p>\n<p>\u00bfQu\u00e9 ayuda ha prestado el gobierno venezolano hasta ahora?<\/p>\n<p>El gobierno venezolano difundi\u00f3 este jueves im\u00e1genes de un helic\u00f3ptero que us\u00f3 para rescatar a algunas de las v\u00edctimas, pero no ha dado m\u00e1s detalles hasta este viernes.<\/p>\n<p>\u00c1ngel Marcano, gobernador de Bol\u00edvar, asegur\u00f3 mediante una publicaci\u00f3n en la red social X que el gobierno venezolano se encontraba realizando labores de rescate: \u201cPresidente Nicol\u00e1s Maduro, aqu\u00ed est\u00e1 el gobierno bolivariano, como usted lo orden\u00f3, atendiendo personalmente junto a la FANB y al Poder Popular a las v\u00edctimas y familiares de este lamentable suceso en la Mina Bulla Loca\u201d.<\/p>\n<p>Manuel Cobela e Iv\u00e1n P\u00e9rez Sarmenti contribuyeron a este reporte.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 El colapso de una mina de extracci\u00f3n de oro en el estado Bol\u00edvar, Venezuela, ocurrido el martes, dej\u00f3 al menos 16 muertos, de acuerdo con las cifras oficiales que difundi\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro, el cual califica de ilegales a esas operaciones extractivas. Tragedia en Venezuela por derrumbe de una mina [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445967","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 El colapso de una mina de extracci\u00f3n de oro en el estado Bol\u00edvar, Venezuela, ocurrido el martes, dej\u00f3 al menos 16 muertos, de acuerdo con las cifras oficiales que difundi\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro, el cual califica de ilegales a esas operaciones extractivas. Tragedia en Venezuela por derrumbe de una mina [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-24T02:46:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela?\",\"datePublished\":\"2024-02-24T02:46:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/\",\"name\":\"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-24T02:46:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela? - Noticias","og_description":"(CNN) \u2013\u2013 El colapso de una mina de extracci\u00f3n de oro en el estado Bol\u00edvar, Venezuela, ocurrido el martes, dej\u00f3 al menos 16 muertos, de acuerdo con las cifras oficiales que difundi\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro, el cual califica de ilegales a esas operaciones extractivas. Tragedia en Venezuela por derrumbe de una mina [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/","og_site_name":"Noticias","article_published_time":"2024-02-24T02:46:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela?","datePublished":"2024-02-24T02:46:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/","url":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/","name":"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-24T02:46:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-paso\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela?","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/23\/mina-venezuela-colapso-oro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-24T02:46:56Z","datePublished":"2024-02-24T02:46:56Z","dateModified":"2024-02-24T02:46:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfQu\\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/23\\\/mina-venezuela-colapso-oro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/23\\\/mina-venezuela-colapso-oro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-24T02:46:56Z\",\"datePublished\":\"2024-02-24T02:46:56Z\",\"dateModified\":\"2024-02-24T02:46:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446482,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/04\/mina-venezuela-colapso-oro-orix-2\/","url_meta":{"origin":1445967,"position":0},"title":"\u00bfQu\u00e9 se sabe del colapso de la mina de oro Bulla Loca en Venezuela?","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 El colapso de una mina de extracci\u00f3n de oro en el estado Bol\u00edvar, Venezuela, ocurrido el martes, dej\u00f3 al menos 16 muertos, de acuerdo con las cifras oficiales que difundi\u00f3 el Gobierno del presidente Nicol\u00e1s Maduro, el cual califica de ilegales a esas operaciones extractivas.Tragedia en Venezuela por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446481,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/04\/800-evacuadas-mina-ilegal-oro-venezuela-derrumbe-orix-2\/","url_meta":{"origin":1445967,"position":1},"title":"Ya son m\u00e1s de 800 las personas evacuadas de la mina ilegal de oro en Venezuela tras derrumbe","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00a0La cifra de evacuados de la zona cercana a la mina de oro Bulla Loca en Venezuela aument\u00f3 a 864, inform\u00f3 este jueves el comandante estrat\u00e9gico operacional de la Fuerza Armada Nacional Bolivariana (FANB), Domingo Hern\u00e1ndez Lares.\u201cHasta el d\u00eda de hoy se han evacuado voluntariamente la cantidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446151,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/01\/800-evacuadas-mina-ilegal-oro-venezuela-derrumbe-orix\/","url_meta":{"origin":1445967,"position":2},"title":"Ya son m\u00e1s de 800 las personas evacuadas de la mina ilegal de oro en Venezuela tras derrumbe","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u00a0La cifra de evacuados de la zona cercana a la mina de oro Bulla Loca en Venezuela aument\u00f3 a 864, inform\u00f3 este jueves el comandante estrat\u00e9gico operacional de la Fuerza Armada Nacional Bolivariana (FANB), Domingo Hern\u00e1ndez Lares.\u201cHasta el d\u00eda de hoy se han evacuado voluntariamente la cantidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446016,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/26\/500-evacuados-mina-venezuela-bulla-loca-orix\/","url_meta":{"origin":1445967,"position":3},"title":"M\u00e1s de 500 personas han sido evacuadas de la zona donde ocurri\u00f3 el colapso de la mina Bulla Loca, en Venezuela","author":"","date":"febrero 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0M\u00e1s de 500 personas han sido evacuadas de la zona donde ocurri\u00f3 el colapso de la mina Bulla Loca, en el estado Bol\u00edvar, en el sur de Venezuela y fronterizo con Brasil, dijo este lunes en su cuenta oficial de X, antes Twitter, el comandante estrat\u00e9gico de operaciones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445988,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/24\/venezuela-evacua-384-personas-mina-bulla-loca-orix\/","url_meta":{"origin":1445967,"position":4},"title":"Ej\u00e9rcito de Venezuela evac\u00faa a m\u00e1s de 300 personas de mina ilegal de oro tras derrumbe que dej\u00f3 al menos 16 muertos","author":"","date":"febrero 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Ej\u00e9rcito de Venezuela evac\u00faa a 384 personas de la mina Bulla Loca, tres d\u00edas despu\u00e9s del derrumbe que dej\u00f3 al menos 16 muertos.La Fuerza Armada Nacional Bolivariana de Venezuela (FANB) inici\u00f3 este viernes la evacuaci\u00f3n de la mina ilegal de Bulla Loca, ubicada en la localidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455032,"url":"https:\/\/noticiasya.com\/springfield\/2024\/10\/10\/accidente-mina-colorado-muerto-personas-atrapadas-trax\/","url_meta":{"origin":1445967,"position":5},"title":"Accidente en una mina tur\u00edstica de Colorado deja un muerto. 23 personas fueron rescatadas","author":"","date":"octubre 10, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Una persona muri\u00f3 y 23 fueron rescatadas despu\u00e9s de quedar atrapadas a cientos de metros bajo tierra en la mina de oro Mollie Kathleen, una mina tur\u00edstica en Cripple Creek, Colorado, dijeron las autoridades este jueves.Once personas fueron rescatadas m\u00e1s temprano este jueves y una docena m\u00e1s quedaron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445967"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445967\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}