{"id":1445986,"date":"2024-02-24T18:32:16","date_gmt":"2024-02-25T02:32:16","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/"},"modified":"2024-02-24T18:32:16","modified_gmt":"2024-02-25T02:32:16","slug":"sag-awards-2024-lista-ganadores-sindicato-de-actores-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/","title":{"rendered":"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0La 30\u00aa edici\u00f3n anual de los premios Screen Actors Guild (SAG), que honra a los actores de la cosecha de pel\u00edculas y proyectos televisivos del a\u00f1o pasado nominados y votados por otros actores, se lleva a cabo este s\u00e1bado en el Shrine Auditorium &#038; Expo Hall de Los \u00c1ngeles.<\/p>\n<p>Si bien la ceremonia de este a\u00f1o no cuenta con un presentador, hubo una serie de animadores animados que subieron al escenario como presentadores, incluidos Idris Elba, Billie Eilish, Jessica Chastain, America Ferrera, Robert Downey Jr. y la presidenta de SAG-AFTRA, Fran Drescher, entre otros.<\/p>\n<p>Adem\u00e1s, Jennifer Aniston entreg\u00f3 a Barbra Streisand el premio SAG Lifetime Achievement.<\/p>\n<p>El primer premio de la noche fue un placer para los fans de &#171;El diablo viste de Prada&#187;, ya que las estrellas de la pel\u00edcula de 2006 \u2013Meryl Streep, Anne Hathaway y Emily Blunt\u2013 se reunieron para presentarlo juntas.<\/p>\n<p>El elenco de &#171;Succession&#187; lider\u00f3 las nominaciones entre las categor\u00edas televisivas con cinco. &#171;Barbie&#187; y &#171;Oppenheimer&#187; obtuvieron cada una cuatro nominaciones en las categor\u00edas de pel\u00edculas, incluido el reconocimiento en la codiciada categor\u00eda de reparto coral.<\/p>\n<p>Estos son los primeros premios SAG desde la prolongada huelga de actores en Hollywood del a\u00f1o pasado, que ocurri\u00f3 al mismo tiempo que la huelga de guionistas de la WGA. Tambi\u00e9n es el \u00faltimo gran evento de premios de entretenimiento antes de la ceremonia de los Oscar del pr\u00f3ximo mes.<\/p>\n<p>Los Premios SAG se transmiten en vivo a nivel mundial en Netflix, una novedad para el programa y el transmisor, a las 8 p.m., hora del Este.<\/p>\n<p>A continuaci\u00f3n las categor\u00edas y los nominados, con los ganadores indicados en negrita:<\/p>\n<p>Categor\u00edas de pel\u00edculas<\/p>\n<p>Mejor actor masculino en un papel principal<\/p>\n<p>Bradley Cooper, &#171;Maestro&#187;<\/p>\n<p>Colm\u00e1n Domingo, &#171;Rusti&#187;<\/p>\n<p>Paul Giamatti, &#171;Los restos&#187;<\/p>\n<p>Cillian Murphy, &#171;Oppenheimer&#187;<\/p>\n<p>Jeffrey Wright, &#171;American Fiction&#187;<\/p>\n<p>Mejor actriz en un papel protag\u00f3nico<\/p>\n<p>Annette Bening, &#171;Nyad&#187;<\/p>\n<p>Lily Gladstone, &#171;Killers of the Flower Moon&#187;<\/p>\n<p>Carey Mulligan, &#171;Maestro&#187;<\/p>\n<p>Margot Robbie, &#171;Barbie&#187;<\/p>\n<p>Emma Stone, &#171;Poor Things&#187;<\/p>\n<p>Mejor actor masculino en un papel secundario<\/p>\n<p>Sterling K. Brown, American Fiction&#187;<\/p>\n<p>Willem Dafoe, &#171;Poor things&#187;<\/p>\n<p>Robert De Niro, &#171;Killers of the Flower Moon&#187;<\/p>\n<p>Robert Downey Jr., &#171;Oppenheimer&#187;<\/p>\n<p>Ryan Gosling, &#171;Barbie&#187;<\/p>\n<p>Mejor actriz en un papel secundario<\/p>\n<p>Emily Blunt, &#171;Oppenheimer&#187;<\/p>\n<p>Danielle Brooks, &#171;El color p\u00farpura&#187;<\/p>\n<p>Pen\u00e9lope Cruz, &#171;Ferrari&#187;<\/p>\n<p>Jodie Foster, &#171;Nyad&#187;<\/p>\n<p>Da&#8217;Vine Joy Randolph, &#171;The Holdovers&#187;<\/p>\n<p>Mejor elenco en una pel\u00edcula<\/p>\n<p>&#171;American Fiction&#187;<\/p>\n<p>&#171;Barbie&#187;<\/p>\n<p>&#171;El color morado&#187;<\/p>\n<p>&#171;Killers of the Flower Moon&#187;<\/p>\n<p>&#171;Oppenheimer&#187;<\/p>\n<p>Categor\u00edas de televisi\u00f3n<\/p>\n<p>Mejor actor masculino en televisi\u00f3n o miniserie<\/p>\n<p>Matt Bomer, &#171;Fellow Travelers&#187;<\/p>\n<p>Jon Hamm, &#171;Fargo&#187;<\/p>\n<p>David Oyelowo, &#171;Lawmen: Bass Reeves&#187;<\/p>\n<p>Tony Shalhoub, &#171;Mr. Monk\u2019s Last Case: A Monk Movie&#187;<\/p>\n<p>Steven Yeun, &#171;Beef&#187;<\/p>\n<p>Mejor actriz en un televisi\u00f3n o miniserie<\/p>\n<p>Uzo Aduba, &#171;Painkiller&#187;<\/p>\n<p>Kathryn Hahn, &#171;Tiny Beautiful Things&#187;<\/p>\n<p>Brie Larson, &#171;Lessons in Chemistry&#187;<\/p>\n<p>Bel Powley, &#171;A Small Light&#187;<\/p>\n<p>Ali Wong, &#171;Beef&#187; *GANADORA<\/p>\n<p>Mejor actuaci\u00f3n de un actor en una serie dram\u00e1tica<\/p>\n<p>Brian Cox, &#171;Sucession&#187;<\/p>\n<p>Billy Crudup, &#171;The Morning Show&#187;<\/p>\n<p>Kieran Culkin, &#171;Sucession&#187;<\/p>\n<p>Matthew Macfadyen, &#171;Sucession&#187;<\/p>\n<p>Pedro Pascal, &#171;The Last of Us&#187;\u00a0*GANADOR<\/p>\n<p>Mejor actuaci\u00f3n de una actriz en una serie dram\u00e1tica<\/p>\n<p>Jennifer Aniston, &#171;The Morning Show&#187;<\/p>\n<p>Elizabeth Debicki, &#171;The Crown&#187;<\/p>\n<p>Bella Ramsey, &#171;The Last of Us&#187;<\/p>\n<p>Keri Russell, &#171;The Diplomat&#187;<\/p>\n<p>Sarah Snook, &#171;Sucession&#187;<\/p>\n<p>Mejor actuaci\u00f3n de un actor en una serie de comedia<\/p>\n<p>Brett Goldstein, &#171;Ted Lasso&#187;<\/p>\n<p>Bill Hader, &#171;Barry&#187;<\/p>\n<p>Ebon Moss-Bachrach, &#171;The Bear&#187;<\/p>\n<p>Jason Sudeikis, &#171;Ted Lasso&#187;<\/p>\n<p>Jeremy Allen White, &#171;The Bear&#187; *GANADOR<\/p>\n<p>Mejor actuaci\u00f3n de una actriz en una serie de comedia<\/p>\n<p>Alex Borstein, &#171;The Marvelous Mrs. Maisel&#187;<\/p>\n<p>Rachel Brosnahan, &#171;The Marvelous Mrs. Maisel&#187;<\/p>\n<p>Quinta Brunson, &#171;Abbott Elementary&#187;<\/p>\n<p>Ayo Edebiri, &#171;The Bear&#187; *GANADORA<\/p>\n<p>Hannah Waddingham, &#171;Ted Lasso&#187;<\/p>\n<p>Mejor reparto en una serie dram\u00e1tica<\/p>\n<p>&#171;The Crown&#187;<\/p>\n<p>&#171;The Gilded Age&#187;<\/p>\n<p>&#171;The Last of Us&#187;<\/p>\n<p>&#171;The Morning Show&#187;<\/p>\n<p>&#171;Sucession&#187;<\/p>\n<p>Mejor reparto en una serie de comedia<\/p>\n<p>&#171;Abbott Elementary&#187;<\/p>\n<p>&#171;Barry&#187;<\/p>\n<p>&#171;The Bear&#187;<\/p>\n<p>&#171;Only Murders in the Building&#187;<\/p>\n<p>&#171;Ted Lasso&#187;<\/p>\n<p>Honores al conjunto<\/p>\n<p>Mejor actuaci\u00f3n de acci\u00f3n de un equipo de especialistas en una pel\u00edcula<\/p>\n<p>&#171;Barbie&#187;<\/p>\n<p>&#171;Guardians of the Galaxy Vol. 3&#187;<\/p>\n<p>&#171;Indiana Jones and the Dial of Destiny&#187;<\/p>\n<p>&#171;John Wick: Chapter 4&#187;<\/p>\n<p>&#171;Mission: Impossible &#8211; Dead Reckoning Part One&#187; *GANADOR<\/p>\n<p>Mejor actuaci\u00f3n de acci\u00f3n de un equipo de especialistas en una serie de televisi\u00f3n<\/p>\n<p>&#171;Ahsoka&#187;<\/p>\n<p>&#171;Barry&#187;<\/p>\n<p>&#171;Beef&#187;<\/p>\n<p>&#171;The Last of Us&#187; *GANADOR<\/p>\n<p>&#171;Mandalorian&#187;<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0La 30\u00aa edici\u00f3n anual de los premios Screen Actors Guild (SAG), que honra a los actores de la cosecha de pel\u00edculas y proyectos televisivos del a\u00f1o pasado nominados y votados por otros actores, se lleva a cabo este s\u00e1bado en el Shrine Auditorium &#038; Expo Hall de Los \u00c1ngeles. Si bien la ceremonia de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1445986","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0La 30\u00aa edici\u00f3n anual de los premios Screen Actors Guild (SAG), que honra a los actores de la cosecha de pel\u00edculas y proyectos televisivos del a\u00f1o pasado nominados y votados por otros actores, se lleva a cabo este s\u00e1bado en el Shrine Auditorium &#038; Expo Hall de Los \u00c1ngeles. Si bien la ceremonia de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-25T02:32:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores\",\"datePublished\":\"2024-02-25T02:32:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/\"},\"wordCount\":760,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/\",\"name\":\"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-25T02:32:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/","og_locale":"es_ES","og_type":"article","og_title":"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores - Noticias","og_description":"(CNN) &#8212;\u00a0La 30\u00aa edici\u00f3n anual de los premios Screen Actors Guild (SAG), que honra a los actores de la cosecha de pel\u00edculas y proyectos televisivos del a\u00f1o pasado nominados y votados por otros actores, se lleva a cabo este s\u00e1bado en el Shrine Auditorium &#038; Expo Hall de Los \u00c1ngeles. Si bien la ceremonia de [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/","og_site_name":"Noticias","article_published_time":"2024-02-25T02:32:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/"},"author":{"name":"","@id":""},"headline":"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores","datePublished":"2024-02-25T02:32:16+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/"},"wordCount":760,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/","name":"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-25T02:32:16+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/24\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-25T02:32:16Z","datePublished":"2024-02-25T02:32:16Z","dateModified":"2024-02-25T02:32:16Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"SAG Awards 2024: esta es la lista completa de ganadores de los Premios del Sindicato de Actores\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/24\\\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/24\\\/sag-awards-2024-lista-ganadores-sindicato-de-actores-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-25T02:32:16Z\",\"datePublished\":\"2024-02-25T02:32:16Z\",\"dateModified\":\"2024-02-25T02:32:16Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457363,"url":"https:\/\/noticiasya.com\/springfield\/2025\/01\/08\/sag-awards-2025-lista-nominaciones-premios-sindicato-actores-trax\/","url_meta":{"origin":1445986,"position":0},"title":"SAG Awards 2025: esta es la lista completa de nominaciones a los premios del Sindicato de Actores","author":"","date":"enero 8, 2025","format":false,"excerpt":"Las nominaciones a la 31\u00aa edici\u00f3n de los premios anuales del Sindicato de Actores (SAG, por sus siglas en ingl\u00e9s) se dieron a conocer este mi\u00e9rcoles por la ma\u00f1ana.Wicked y Sh\u014dgun lideran las nominaciones con cinco menciones cada una. El evento honra algunas de las mejores actuaciones del a\u00f1o en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445989,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/24\/pedro-pascal-dijo-estaba-borracho-al-aceptar-el-premio-sag-por-the-last-of-us-trax\/","url_meta":{"origin":1445986,"position":1},"title":"Pedro Pascal dijo que estaba &#8216;un poco borracho&#8217; al aceptar el premio SAG por &#8216;The Last of Us&#8217;","author":"","date":"febrero 24, 2024","format":false,"excerpt":"(CNN) -- Pedro Pascal no es alguien que pronuncie un discurso de aceptaci\u00f3n de premios en una entrega de premios status quo, y no podr\u00edamos estar m\u00e1s felices por ello.Fiel a su estilo, cuando gan\u00f3 el premio al actor destacado en una serie dram\u00e1tica por \u201cThe Last of Us\u201d de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459111,"url":"https:\/\/noticiasya.com\/springfield\/2025\/02\/23\/sag-awards-2025-lista-ganadores-trax\/","url_meta":{"origin":1445986,"position":2},"title":"SAG Awards 2025: lista completa de ganadores de los Premios del Sindicato de Actores","author":"","date":"febrero 23, 2025","format":false,"excerpt":"Los Premios del Sindicato de Actores de Cine de 2025 est\u00e1n en marcha en el Shrine Auditorium and Exposition Hall de Los \u00c1ngeles.El evento rinde homenaje a algunas de las mejores actuaciones del a\u00f1o en cine y televisi\u00f3n, seleccionadas por los miembros de SAG-AFTRA, los propios actores.\u201cWicked\u201d y \u201cSh\u014dgun\u201d encabezan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445987,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/24\/billie-eilish-firmo-rostro-melissa-mccarthy-sag-trax\/","url_meta":{"origin":1445986,"position":3},"title":"Billie Eilish literalmente firm\u00f3 el rostro de Melissa McCarthy durante los SAG Awards","author":"","date":"febrero 24, 2024","format":false,"excerpt":"(CNN) --\u00a0 Melissa McCarthy fue la fan\u00e1tica n\u00famero uno de los SAG Awards este s\u00e1bado cuando le pidi\u00f3 un aut\u00f3grafo a Billie Eilish en el escenario.Pero no quer\u00eda un aut\u00f3grafo cualquiera.Eilish termin\u00f3 firmando su nombre, con marcador permanente, justo en la frente de McCarthy mientras ambas presentaban el premio a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472234,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/15\/one-battle-after-another-gana-oscar-mejor-pelicula-orix\/","url_meta":{"origin":1445986,"position":4},"title":"&#171;One Battle After Another&#187; gana el premio Oscar a mejor pel\u00edcula y lidera la gala de 2026","author":"","date":"marzo 15, 2026","format":false,"excerpt":"La cinta \u201cOne Battle After Another\u201d se convirti\u00f3 este domingo en la cinta m\u00e1s premiada de la edici\u00f3n 98 de los premios Oscar. Obtuvo seis estatuillas, entre ellas la m\u00e1s importante de la gala, la de mejor pel\u00edcula.Adem\u00e1s, su director, Paul Thomas Anderson obtuvo personalmente dos premios, a mejor director\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457490,"url":"https:\/\/noticiasya.com\/springfield\/2025\/01\/13\/grammy-oscar-se-celebraran-incendios-los-angeles-trax\/","url_meta":{"origin":1445986,"position":5},"title":"Los Grammy y los Oscar se llevar\u00e1n a cabo a seg\u00fan lo planeado y tendr\u00e1n un componente ben\u00e9fico tras incendios de Los \u00c1ngeles","author":"","date":"enero 13, 2025","format":false,"excerpt":"Como dicen en Hollywood, el espect\u00e1culo debe continuar.Este lunes se anunci\u00f3 que los premios Grammy y los Oscar se realizar\u00e1n seg\u00fan lo planeado el 2 de febrero y el 2 de marzo, respectivamente, respondiendo una pregunta que ha sido debatida detr\u00e1s de escena por los tomadores de decisiones encargados de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1445986"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1445986\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1445986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1445986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1445986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}