{"id":1446012,"date":"2024-02-26T06:47:09","date_gmt":"2024-02-26T14:47:09","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/"},"modified":"2024-02-26T06:47:09","modified_gmt":"2024-02-26T14:47:09","slug":"analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/","title":{"rendered":"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos"},"content":{"rendered":"<p>(CNN) &#8212; La cifra me llam\u00f3 la atenci\u00f3n en cuanto la vi.<\/p>\n<p>En un nuevo informe del Pew Research Center sobre la situaci\u00f3n en la frontera entre M\u00e9xico y Estados Unidos, el 57% de los estadounidenses dice que el gran n\u00famero de migrantes que buscan entrar al pa\u00eds genera m\u00e1s delincuencia.<\/p>\n<p>En otras palabras, la mayor\u00eda de los estadounidenses relacionan ahora la delincuencia con el reciente aumento de la migraci\u00f3n.<\/p>\n<p>Esto me llam\u00f3 la atenci\u00f3n porque contradice a\u00f1os de estudios sobre lo que realmente ha ocurrido tras la llegada de inmigrantes a las comunidades de Estados Unidos. Muchos investigadores han llegado a la conclusi\u00f3n de que no hay relaci\u00f3n entre inmigraci\u00f3n y delincuencia. Algunos han llegado incluso a la conclusi\u00f3n de que los inmigrantes tienen menos probabilidades de delinquir que los nacidos en Estados Unidos.<\/p>\n<p>Estudiantes latinos en Georgia lidian con &#171;comentarios de odio&#187; tras muerte de Laken Riley<\/p>\n<p>La delincuencia no fue el tema central de la reciente encuesta de Pew, seg\u00fan la cual los estadounidenses culpan mayoritariamente al gobierno por su gesti\u00f3n de la situaci\u00f3n en la frontera y ofrecen a los encuestados la oportunidad de opinar sobre posibles soluciones pol\u00edticas.<\/p>\n<p>Pero cuando se pregunt\u00f3 a los encuestados espec\u00edficamente sobre el impacto de la afluencia de inmigrantes en la delincuencia, se observaron marcadas diferencias entre los distintos partidos: el 85% de los republicanos vincularon la afluencia de inmigrantes con la delincuencia, frente al 31% de los dem\u00f3cratas.<\/p>\n<p>La encuesta tambi\u00e9n revel\u00f3 que el 39% de los estadounidenses no cree que la afluencia de inmigrantes tenga un gran impacto en la delincuencia.<\/p>\n<p>El informe de Pew se basa en una encuesta a 5.140 adultos realizada entre el 16 y el 21 de enero.<\/p>\n<p>Arrestan a siete inmigrantes sospechosos despu\u00e9s de m\u00e1s de 60 incidentes de robo en Nueva York<\/p>\n<p>Su publicaci\u00f3n se produce tras varios casos delictivos de gran repercusi\u00f3n en la ciudad de Nueva York en los que presuntamente est\u00e1n implicados inmigrantes recientes, entre ellos una agresi\u00f3n a agentes de polic\u00eda en Times Square y una serie de robos de tel\u00e9fonos m\u00f3viles que llevaron al comisario de polic\u00eda a declarar en una reciente rueda de prensa que &#171;una ola de delincuencia de inmigrantes&#187; hab\u00eda &#171;arrasado&#187; la ciudad.<\/p>\n<p>El alcalde Eric Adams ha subrayado que la mayor\u00eda de los inmigrantes llegados recientemente a Nueva York no est\u00e1n cometiendo delitos.<\/p>\n<p>&#171;La abrumadora mayor\u00eda de los m\u00e1s de 170.000 inmigrantes y solicitantes de asilo est\u00e1n intentando continuar la siguiente etapa de su viaje en busca del sue\u00f1o americano. Pero aquellos que cometan un delito ser\u00e1n tratados como cualquier otro delincuente en esta ciudad&#187;, afirm\u00f3.<\/p>\n<p>&#171;Este peque\u00f1o n\u00famero de personas est\u00e1 infringiendo la ley y teniendo un enorme impacto en nuestra seguridad p\u00fablica, y por eso nos centramos en ellos&#187;.<\/p>\n<p>Dos hermanos de Nueva York enfrentan 130 cargos luego de que se encontrara un &#171;arsenal&#187; de armas fantasma y explosivos caseros en su apartamento, dicen los fiscales<\/p>\n<p>Todo esto plantea algunas preguntas clave: \u00bfestamos asistiendo a un aumento de la delincuencia vinculado a la inmigraci\u00f3n o existe una brecha entre la percepci\u00f3n p\u00fablica y la realidad? \u00bfY qu\u00e9 puede ocurrir cuando nos centramos en incidentes individuales y no tenemos en cuenta el panorama general?<\/p>\n<p>Para hacerme una mejor idea de lo que est\u00e1 pasando, habl\u00e9 con varios crimin\u00f3logos antes de que se publicara el informe de Pew. Esto es lo que me dijeron (editado en extensi\u00f3n y claridad):<\/p>\n<p>Migrantes solicitantes de asilo esperan a ser procesados en un campamento improvisado tras cruzar la frontera con M\u00e9xico el 2 de febrero de 2024, cerca de Jacumba Hot Springs, California. Cr\u00e9dito: Gregory Bull\/AP<\/p>\n<p>Estos expertos han analizado cientos de estudios sobre inmigraci\u00f3n y delincuencia. Esto es lo que han aprendido<\/p>\n<p>Charis Kubrin y Graham Ousey escribieron literalmente el libro b\u00e1sico sobre inmigraci\u00f3n y delincuencia. Llevan d\u00e9cadas investigando estos temas y analizaron numerosos estudios para su libro de 2023, &#171;Immigration and Crime: Taking Stock&#187;. Kubrin es profesor de Criminolog\u00eda, Derecho y Sociedad en la Universidad de California en Irvine, y Ousey es profesor de Sociolog\u00eda y Criminolog\u00eda en el College of William and Mary de Virginia.<\/p>\n<p>Uno de los motivos por los que me puse en contacto con ustedes es que recientemente se han producido algunos incidentes de gran repercusi\u00f3n en Nueva York que han llamado la atenci\u00f3n.<\/p>\n<p>Kubrin: Cuando me enter\u00e9 del incidente de Nueva York, lo primero que hice al o\u00edrlo en las noticias es decir: &#171;Oh, Dios, ya empezamos&#187;. Porque estos casos anecd\u00f3ticos, sin minimizar nunca la gravedad, pero los raros sucesos en los que individuos nacidos en el extranjero, y mucho menos indocumentados, cometen delitos, y salen en las noticias, me preocupan por el efecto cascada de estos incidentes que eclipsan lo que sabemos en el contexto m\u00e1s amplio sobre inmigraci\u00f3n y delincuencia. Porque se trata de temas candentes. Tocan la fibra sensible.<\/p>\n<p>Ousey: Los seres humanos cometen delitos en casi todas las sociedades del mundo. Pero lo que se pierde en esas historias anecd\u00f3ticas es que llevan a un punto m\u00e1ximo de negatividad en el que se ignoran todas las cosas potencialmente buenas que los inmigrantes aportan a nuestra sociedad. Y es frustrante intentar aportar pruebas y contextualizar las cosas y ponerlas en t\u00e9rminos estad\u00edsticos cuando est\u00e1s argumentando en contra de este punto cr\u00edtico que permite a la gente ignorar m\u00e1s o menos todo lo dem\u00e1s.<\/p>\n<p>Hay tanta gente que responder\u00e1 a esas encuestas de opini\u00f3n p\u00fablica y reconocer\u00e1 que los inmigrantes han contribuido enormemente de forma beneficiosa a la sociedad. Entonces, \u00bfcu\u00e1les son las fuerzas que perpet\u00faan esa asociaci\u00f3n (entre inmigraci\u00f3n y delincuencia)? \u00bfY por qu\u00e9 tiene tanto poder? \u00bfPor qu\u00e9 tiene tanta influencia en la forma en que pensamos sobre los inmigrantes en general o sobre los inmigrantes indocumentados en particular? No estoy seguro de las respuestas, pero es una de las cosas que m\u00e1s me intrigan.<\/p>\n<p>\u00bfQu\u00e9 es lo que quieren que la gente se lleve de su libro?<\/p>\n<p>Kubrin: A trav\u00e9s de una variedad de estudios que utilizan diferentes a\u00f1os de datos que se centran en diferentes \u00e1reas de Estados Unidos, con algunas excepciones, hay algunos matices all\u00ed. No quiero negar el matiz: en general, por t\u00e9rmino medio, no encontramos una conexi\u00f3n entre inmigraci\u00f3n y delincuencia, como se afirma tan a menudo.<\/p>\n<p>La conclusi\u00f3n m\u00e1s com\u00fan en todos estos tipos de estudios es que la inmigraci\u00f3n en una zona o bien no est\u00e1 asociada con la delincuencia en esa zona, o bien est\u00e1 negativamente asociada con la delincuencia en esa zona. Es decir, que m\u00e1s inmigraci\u00f3n equivale a menos delincuencia. Es raro encontrar estudios que demuestren que la delincuencia se produce tras un aumento de la inmigraci\u00f3n o con un mayor porcentaje de poblaci\u00f3n inmigrante.<\/p>\n<p>Ousey: Mucha gente cuando dice eso dir\u00e1, &#171;Oh, bueno, pero \u00bfqu\u00e9 pasa con los inmigrantes indocumentados?&#187;. Y hay menos investigaci\u00f3n sobre ese tema. Pero el corpus de investigaci\u00f3n est\u00e1 creciendo y llega m\u00e1s o menos a la misma conclusi\u00f3n.<\/p>\n<p>Alambre de p\u00faas cerca del r\u00edo Grande el 3 de febrero de 2024 en Shelby Park en Eagle Pass, Texas. Cr\u00e9dito: Sergio Flores\/AFP\/Getty Images<\/p>\n<p>La gente est\u00e1 muy centrada ahora mismo en los migrantes que han llegado recientemente. \u00bfExisten estudios que analicen alguna de estas ciudades que han visto una afluencia?<\/p>\n<p>Kubrin: No conozco ninguno (todav\u00eda).<\/p>\n<p>Bas\u00e1ndose en su experiencia, que les ha permitido analizar numerosos estudios a lo largo de muchos a\u00f1os, \u00bfcreen que es razonable plantear la hip\u00f3tesis o extrapolar que este tipo de tendencias a largo plazo se observar\u00edan tambi\u00e9n en este grupo en t\u00e9rminos de inmigraci\u00f3n y delincuencia? \u00bfCu\u00e1l ser\u00eda su teor\u00eda?<\/p>\n<p>Kubrin: Aqu\u00ed es donde tenemos que tener cuidado. Porque creo que se trata de una poblaci\u00f3n y un contexto \u00fanicos. Los inmigrantes son un grupo muy diverso. Hablamos de los inmigrantes como si fueran un bloque, \u00bfverdad? Pero var\u00edan en todo, incluida su motivaci\u00f3n para venir a Estados Unidos.<\/p>\n<p>S\u00ed creo que con algunas de las llegadas recientes tenemos ciertas situaciones en las que los inmigrantes vienen con muy poco en la mano, habiendo escapado de acontecimientos extremadamente traum\u00e1ticos, llegando como refugiados en muchos casos a lugares que no son particularmente acogedores, y no tienen los recursos para ayudarles. Seamos realistas. No son las condiciones ideales.<\/p>\n<p>Al mismo tiempo, me parece interesante que con todos estos miles de individuos, los titulares hasta ahora hayan sido dos o tres (incidentes). La cuesti\u00f3n no es por qu\u00e9 estos inmigrantes cometen estos delitos contra los agentes de polic\u00eda. Es \u00bfc\u00f3mo es posible que miles y miles y miles de inmigrantes en estas condiciones vengan y no cometan delitos? Ese es el titular para m\u00ed.<\/p>\n<p>\u00bfCu\u00e1les son las consecuencias en el mundo real de este tipo de declaraciones generalizadas que o\u00edmos en las que se tacha a los inmigrantes de delincuentes?<\/p>\n<p>Kubrin: Las consecuencias de esos estereotipos y de equivocarnos es que estamos impulsando y apoyando pol\u00edticas que parten del supuesto de que los inmigrantes traen delincuencia. Y esas pol\u00edticas no solo no funcionan, sino que tienen consecuencias colaterales que afectan no solo a los propios inmigrantes, sino a la sociedad estadounidense en general&#8230; As\u00ed que hablar de esto no es solo un ejercicio acad\u00e9mico de opini\u00f3n p\u00fablica. Las consecuencias, lo que est\u00e1 en juego, son muy importantes.<\/p>\n<p>Si realmente queremos acabar con la delincuencia o reducirla en la sociedad, nuestra conclusi\u00f3n es&#8230; que una pol\u00edtica de inmigraci\u00f3n restrictiva, dura y excluyente no lo va a conseguir. Y hay muchos da\u00f1os colaterales, tanto si hablamos de los da\u00f1os a la familia o a los ni\u00f1os con las pol\u00edticas de deportaci\u00f3n, o las pol\u00edticas de separaci\u00f3n familiar, o los cr\u00edmenes de odio cometidos como resultado de las afirmaciones de que los inmigrantes son criminales.<\/p>\n<p>\u00bfHay una &#171;oleada de delitos cometidos por inmigrantes&#187; en Nueva York? Este experto dice que es demasiado pronto para afirmarlo<\/p>\n<p>Christopher Herrmann es un antiguo supervisor de an\u00e1lisis criminal del Departamento de Polic\u00eda de Nueva York. Ahora es profesor adjunto del Departamento de Derecho y Ciencias Policiales del John Jay College of Criminal Justice de la CUNY.<\/p>\n<p>El comisario de Polic\u00eda de Nueva York, Edward Caban, describi\u00f3 recientemente una &#171;oleada de delincuencia de inmigrantes&#187; en la ciudad al anunciar la detenci\u00f3n de una banda de ladrones de tel\u00e9fonos celulares. \u00bfEs eso lo que est\u00e1 ocurriendo?<\/p>\n<p>Hay un aumento de los robos. \u00bfEs el aumento suficiente para llamarlo ola de delincuencia? No. \u00bfSeguro que los inmigrantes son los responsables del aumento de robos? No. \u00bfSabemos si las v\u00edctimas tambi\u00e9n eran inmigrantes?<\/p>\n<p>No&#8230; Es dif\u00edcil calificarla de ola de delincuencia migrante cuando no sabemos todas estas cosas.<\/p>\n<p>Esta captura de pantalla de un video del Departamento de Polic\u00eda de Nueva York muestra a un grupo de presuntos migrantes asaltando a dos agentes del Departamento de Polic\u00eda de Nueva York cerca de Times Square a finales de enero. Cr\u00e9dito: Departamento de Polic\u00eda de Nueva York<\/p>\n<p>\u00bfExiste alg\u00fan dato global que te permita pensar en el impacto que puede tener este gran n\u00famero de reci\u00e9n llegados a la ciudad?<\/p>\n<p>Cuando una periodista del New York Daily News me pregunt\u00f3 recientemente sobre este tema, le di lo que me pareci\u00f3 una buena f\u00f3rmula: \u00bfPor qu\u00e9 no coges las comisar\u00edas de polic\u00eda que tienen albergues y te fijas en esa muestra? \u00bfHa aumentado la delincuencia? \u00bfHa bajado?<\/p>\n<p>Ese informe de New York Daily News acab\u00f3 descubriendo que, en los lugares que analizaron donde hay refugios, la delincuencia ha bajado este a\u00f1o en comparaci\u00f3n con el mismo periodo del a\u00f1o pasado en la mayor\u00eda de las categor\u00edas.<\/p>\n<p>S\u00ed, la mayor\u00eda de la gente te dir\u00e1 que los inmigrantes indocumentados son mejores que los ciudadanos estadounidenses en lo que respecta a la delincuencia. Tienen miedo de ser deportados.<\/p>\n<p>\u00bfEs una tendencia que observaste cuando estaba en la polic\u00eda de Nueva York?<\/p>\n<p>El problema es, y esto es sin duda una cuesti\u00f3n de estados dem\u00f3cratas y republicanos, que en muchos de los estados dem\u00f3cratas ni siquiera registramos la situaci\u00f3n de inmigraci\u00f3n. Realmente no nos preocupamos por eso. Si cometes un delito, te arrestamos. Te vamos a meter en la c\u00e1rcel. Si resulta que no eres ciudadano y nos molestamos contigo, quiz\u00e1 te entreguemos al ICE. Pero la realidad es que, muchas veces, simplemente te metemos en nuestro sistema y te tratamos como a cualquier otro delincuente.<\/p>\n<p>\u00bfAs\u00ed que realmente no se sabe?<\/p>\n<p>S\u00ed, no hay una manera f\u00e1cil de profundizar en esto y realmente averiguar, \u00bfes un problema de inmigrantes?, \u00bfno es un problema de inmigrantes? Pero yo casi lo equiparar\u00eda a&#8230; como, el metro de Nueva York. Cada vez que hay un incidente de gran repercusi\u00f3n en el metro de Nueva York, salen a la luz todas estas historias y todo el mundo tiene miedo del metro. E hice las cuentas y fueron como ocho delitos graves violentos con como medio mill\u00f3n de personas viajando en el metro. A la gente le gusta centrarse en estos incidentes de alto perfil medi\u00e1tico. No estoy diciendo que los incidentes de alto perfil no sucedieron. Solo digo que no son la norma, son la excepci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La cifra me llam\u00f3 la atenci\u00f3n en cuanto la vi. En un nuevo informe del Pew Research Center sobre la situaci\u00f3n en la frontera entre M\u00e9xico y Estados Unidos, el 57% de los estadounidenses dice que el gran n\u00famero de migrantes que buscan entrar al pa\u00eds genera m\u00e1s delincuencia. En otras palabras, la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446012","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La cifra me llam\u00f3 la atenci\u00f3n en cuanto la vi. En un nuevo informe del Pew Research Center sobre la situaci\u00f3n en la frontera entre M\u00e9xico y Estados Unidos, el 57% de los estadounidenses dice que el gran n\u00famero de migrantes que buscan entrar al pa\u00eds genera m\u00e1s delincuencia. En otras palabras, la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-26T14:47:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos\",\"datePublished\":\"2024-02-26T14:47:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/\"},\"wordCount\":2344,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/\",\"name\":\"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-26T14:47:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos - Noticias","og_description":"(CNN) &#8212; La cifra me llam\u00f3 la atenci\u00f3n en cuanto la vi. En un nuevo informe del Pew Research Center sobre la situaci\u00f3n en la frontera entre M\u00e9xico y Estados Unidos, el 57% de los estadounidenses dice que el gran n\u00famero de migrantes que buscan entrar al pa\u00eds genera m\u00e1s delincuencia. En otras palabras, la [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/","og_site_name":"Noticias","article_published_time":"2024-02-26T14:47:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/"},"author":{"name":"","@id":""},"headline":"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos","datePublished":"2024-02-26T14:47:09+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/"},"wordCount":2344,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/","name":"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-26T14:47:09+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Preguntas sobre inmigraci\u00f3n y crimen en Estados Unidos, respondidas por crimin\u00f3logos","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/26\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-26T14:47:09Z","datePublished":"2024-02-26T14:47:09Z","dateModified":"2024-02-26T14:47:09Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Preguntas sobre inmigraci\\u00f3n y crimen en Estados Unidos, respondidas por crimin\\u00f3logos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/26\\\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/26\\\/analisis-criminologos-inmigracion-delincuencia-estados-unidos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-26T14:47:09Z\",\"datePublished\":\"2024-02-26T14:47:09Z\",\"dateModified\":\"2024-02-26T14:47:09Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1445483,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/15\/analisis-pregunte-a-criminologos-sobre-inmigracion-y-delincuencia-en-estados-unidos-sus-respuestas-pueden-sorprenderte\/","url_meta":{"origin":1446012,"position":0},"title":"AN\u00c1LISIS | Pregunt\u00e9 a crimin\u00f3logos sobre inmigraci\u00f3n y delincuencia en Estados Unidos. Sus respuestas pueden sorprenderte","author":"","date":"febrero 15, 2024","format":false,"excerpt":"(CNN) -- La cifra me llam\u00f3 la atenci\u00f3n en cuanto la vi.En un nuevo informe del Pew Research Center sobre la situaci\u00f3n en la frontera entre M\u00e9xico y Estados Unidos, el 57% de los estadounidenses dice que el gran n\u00famero de migrantes que buscan entrar al pa\u00eds genera m\u00e1s delincuencia.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448751,"url":"https:\/\/noticiasya.com\/springfield\/2024\/05\/01\/analisis-trump-plan-deportar-15-20-millones-inmigrantes-trax\/","url_meta":{"origin":1446012,"position":1},"title":"AN\u00c1LISIS | Trump explica su plan de corte militarista para deportar a entre 15 y 20 millones de personas","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN) -- No es habitual que los principales candidatos presidenciales, de cualquier lado del espectro pol\u00edtico, salgan de los confines de los comentarios preparados, los discursos de campa\u00f1a y las audiencias afines, por lo que merece la pena prestar atenci\u00f3n cuando realmente responden a preguntas detalladas.El expresidente Donald Trump concedi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445510,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/16\/juez-federal-cuestiona-la-controvertida-ley-de-inmigracion-de-texas\/","url_meta":{"origin":1446012,"position":2},"title":"Juez federal cuestiona la controvertida ley de inmigraci\u00f3n de Texas","author":"","date":"febrero 16, 2024","format":false,"excerpt":"(CNN) -- Un juez federal expres\u00f3 el jueves su preocupaci\u00f3n y escepticismo sobre una controvertida ley que convierte en delito estatal la entrada ilegal en Texas, mientras escuchaba los argumentos orales sobre una moci\u00f3n para una orden judicial preliminar que bloquee la normativa.La medida SB4, que entrar\u00e1 en vigor el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471192,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/13\/trump-inmigracion-empleo-contratacion-trax\/","url_meta":{"origin":1446012,"position":3},"title":"Por qu\u00e9 la ofensiva inmigratoria de Trump no impulsa la contrataci\u00f3n","author":"","date":"febrero 13, 2026","format":false,"excerpt":"A primera vista, la apuesta de la administraci\u00f3n Trump con la inmigraci\u00f3n y el empleo parece una simple cuesti\u00f3n matem\u00e1tica: si una franja de trabajadores es expulsada del pa\u00eds, los empresarios tendr\u00e1n que recurrir a los recursos humanos que todav\u00eda est\u00e1n en Estados Unidos para cubrir esos puestos.Pero eso no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451207,"url":"https:\/\/noticiasya.com\/springfield\/2024\/07\/17\/ted-cruz-venezuela-inmigracion-carceles-criminales-verificacion-orix\/","url_meta":{"origin":1446012,"position":4},"title":"CNN verifica: Ted Cruz dijo que Venezuela \u201cvac\u00eda sus c\u00e1rceles\u201d para enviar criminales a EE.UU. Esto es falso","author":"","date":"julio 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Desde la Convenci\u00f3n Nacional Republicana, Ted Cruz, senador por Texas, realiz\u00f3 declaraciones falsas sobre supuestos v\u00ednculos de la inmigraci\u00f3n con la delincuencia en Estados Unidos. Puntualmente, acus\u00f3 al gobierno de Venezuela de \u201cvaciar sus c\u00e1rceles\u201d y enviar criminales al pa\u00eds.\u201cCreo que el gobierno de Venezuela deliberadamente est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466767,"url":"https:\/\/noticiasya.com\/springfield\/2025\/09\/24\/ofensiva-administracion-trump-contra-migracion-legal-trax\/","url_meta":{"origin":1446012,"position":5},"title":"Dentro de la amplia ofensiva de la administraci\u00f3n Trump contra la inmigraci\u00f3n legal","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"La administraci\u00f3n Trump est\u00e1 haciendo que sea mucho m\u00e1s dif\u00edcil venir a Estados Unidos legalmente y m\u00e1s complicado para los inmigrantes legales actuales quedarse, una restricci\u00f3n que tendr\u00e1 profundos efectos domin\u00f3 en la econom\u00eda y la sociedad.En ocho meses, los funcionarios del Gobierno han implementado una serie de medidas que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1446012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1446012"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1446012\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1446012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1446012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1446012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}