{"id":1446014,"date":"2024-02-26T07:37:03","date_gmt":"2024-02-26T15:37:03","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/26\/zelensky-trump-putin-trax\/"},"modified":"2024-02-26T07:37:03","modified_gmt":"2024-02-26T15:37:03","slug":"zelensky-trump-putin-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/26\/zelensky-trump-putin-trax\/","title":{"rendered":"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia"},"content":{"rendered":"<p>(CNN) &#8212; El expresidente de EE.UU. Donald Trump estar\u00e1 \u201ccontra los estadounidenses\u201d si decide apoyar a Rusia en lugar de a Ucrania, dijo el domingo el presidente de ese pa\u00eds devastado por la guerra, Volodymyr Zelensky.<\/p>\n<p>En declaraciones a Kaitlan Collins de CNN en Kyiv, Zelensky dijo que \u201cno puede entender c\u00f3mo Donald Trump puede estar del lado de (el presidente de Rusia Vladimir) Putin\u201d.<\/p>\n<p>&#171;Es incre\u00edble&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Guerra de Rusia en Ucrania y noticias tras la muerte de Navalny, en vivo<\/p>\n<p>Trump, que est\u00e1 a punto de convertirse en el candidato presidencial republicano tras ganar las primarias republicanas de Carolina del Sur, se ha negado en el pasado a decir si quiere que Rusia o Ucrania ganen la guerra.<\/p>\n<p>Zelensky dijo que cre\u00eda que Trump \u2014quien tambi\u00e9n afirm\u00f3 que pondr\u00eda fin al conflicto en un d\u00eda si es elegido\u2014 no entend\u00eda los objetivos de Putin.<\/p>\n<p>&#171;Creo que Donald Trump no conoce a Putin&#187;, dijo Zelensky. \u201cS\u00e9 que lo conoci\u00f3\u2026 pero nunca pele\u00f3 contra Putin. (El) ej\u00e9rcito estadounidense nunca luch\u00f3 con el ej\u00e9rcito de Rusia. Nunca\u2026 yo lo entiendo mejor\u201d, dijo.<\/p>\n<p>&#171;No creo que comprenda que Putin nunca se detendr\u00e1&#187;, dijo.<\/p>\n<p>Zelensky dijo a CNN que Rusia est\u00e1 gastando \u201cmiles de millones\u201d en difundir informaci\u00f3n falsa sobre la guerra y que ha logrado utilizar la desinformaci\u00f3n como arma e influir en el debate en Estados Unidos.<\/p>\n<p>\u201cMe sorprendi\u00f3 que sean fuertes incluso en Estados Unidos, en la UE (Uni\u00f3n Europea), en todo el mundo. Invirtieron mucho dinero en esto\u201d, dijo.<\/p>\n<p>Inflar el n\u00famero de v\u00edctimas ucranianas es solo un ejemplo de c\u00f3mo Rusia est\u00e1 difundiendo narrativas falsas, dijo el presidente. M\u00e1s temprano el domingo, Zelensky revel\u00f3 por primera vez el n\u00famero de soldados ucranianos muertos en el conflicto hasta el momento: 31.000.<\/p>\n<p>Dijo que era importante compartir la cifra porque \u201cya estamos hartos de mentiras\u201d, y a\u00f1adi\u00f3 que incluso algunos pol\u00edticos estadounidenses han estado compartiendo cifras muy inexactas.<\/p>\n<p>Los bomberos trabajan para apagar las llamas en la estaci\u00f3n de tren de Kostiantynivka en la regi\u00f3n de Donbass en Ucrania el 25 de febrero. Laurel Chor\/SOPA Images\/LightRocket\/Getty Images<\/p>\n<p>CNN no puede verificar de forma independiente las cifras, que llegaron el fin de semana en que Ucrania cumpli\u00f3 dos a\u00f1os desde la invasi\u00f3n a gran escala de Rusia. Los funcionarios estadounidenses estiman que unos 70.000 soldados han muerto y casi el doble han resultado heridos.<\/p>\n<p>Zelensky: &#171;Millones morir\u00e1n&#187;<\/p>\n<p>Ucrania ha tenido un comienzo de a\u00f1o dif\u00edcil. Sufri\u00f3 una gran derrota a principios de este mes cuando las tropas ucranianas se retiraron de Avdiivka, una ciudad oriental que ocuparon durante una d\u00e9cada.<\/p>\n<p>Zelensky y otros funcionarios ucranianos y occidentales dijeron que Avdiivka se perdi\u00f3 porque las tropas no ten\u00edan suficientes municiones para defenderla.<\/p>\n<p>Sin embargo, a pesar de las terribles consecuencias de esta escasez, el Congreso de Estados Unidos sigue estancando el paquete de ayuda militar de US$ 60.000 millones de d\u00f3lares del presidente Joe Biden para Ucrania.<\/p>\n<p>Zelensky dijo que sin la ayuda de Estados Unidos, Ucrania no s\u00f3lo tendr\u00e1 dificultades para lograr nuevos avances en el campo de batalla, sino que tambi\u00e9n le resultar\u00e1 dif\u00edcil seguir defendi\u00e9ndose este a\u00f1o.<\/p>\n<p>AN\u00c1LISIS | Por qu\u00e9 la petici\u00f3n de Zelensky caer\u00e1 en o\u00eddos sordos de los republicanos<\/p>\n<p>\u201cLa gente estar\u00e1 preparada, pero no habr\u00e1 municiones y las brigadas no estar\u00e1n listas&#8230; no solo para nuestra contraofensiva, sino que no estar\u00e1n listas para defenderse, para mantenerse fuertes. Ser\u00e1 muy dif\u00edcil\u201d, afirm\u00f3.<\/p>\n<p>El momento es crucial, ya que Zelensky dijo el domingo que Rusia podr\u00eda intentar una nueva ofensiva a finales de mayo.<\/p>\n<p>El nuevo jefe del ej\u00e9rcito de Ucrania, Oleksandr Syrskyi, est\u00e1 elaborando actualmente dos versiones de un plan sobre qu\u00e9 hacer a continuaci\u00f3n, dijo. Si Kyiv obtiene la ayuda de Estados Unidos, podr\u00e1 empezar a contraatacar a Rusia. Si no es as\u00ed, tendr\u00e1 que centrarse \u00fanicamente en defender.<\/p>\n<p>Zelensky dijo que habl\u00f3 con el presidente de la C\u00e1mara de Representantes, Mike Johnson, sobre el paquete de ayuda y que se sent\u00eda optimista despu\u00e9s de esa conversaci\u00f3n.<\/p>\n<p>&#171;Dijo que har\u00e1 todo lo posible para apoyar a Ucrania, est\u00e1 de nuestro lado y comprende lo heroicos que son nuestro pueblo, nuestros soldados y civiles&#187;, dijo.<\/p>\n<p>Zelensky a\u00f1adi\u00f3 que, si bien entiende que Estados Unidos se acerca a las elecciones, espera que se pueda llegar a un acuerdo.<\/p>\n<p>&#171;Si cambian de opini\u00f3n, ser\u00e1 un gran problema para nosotros&#187;, afirm\u00f3.<\/p>\n<p>\u201cLe ped\u00ed al presidente (Biden)\u2026 &#8216;por favor, presidente, le pido que me ayude y que ayude al pueblo ucraniano\u2026 por favor, tengan una reuni\u00f3n entre ellos, dem\u00f3cratas y republicanos, y, por favor, \u00bfpueden llegar a un acuerdo?'&#187;, dijo.<\/p>\n<p>Cuando Collins le pregunt\u00f3 sobre la afirmaci\u00f3n del senador estadounidense JD Vance de que el resultado de la guerra no cambiar\u00e1 incluso si Ucrania recibe el dinero, Zelensky dijo que Vance \u201cno entiende lo que est\u00e1 pasando aqu\u00ed\u201d.<\/p>\n<p>\u201cEntenderlo es estar en primera l\u00ednea para ver qu\u00e9 est\u00e1 pasando&#8230; sin este apoyo. Y comprender\u00e1 que millones de personas morir\u00e1n\u201d, a\u00f1adi\u00f3.<\/p>\n<p>\u201c\u00c9l no lo entiende, por supuesto, Dios los bendijo y no tienen la guerra en su territorio\u201d.<\/p>\n<p>Con informaci\u00f3n de Andy Carey, Madalena Araujo y Victoria Butenko de CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El expresidente de EE.UU. Donald Trump estar\u00e1 \u201ccontra los estadounidenses\u201d si decide apoyar a Rusia en lugar de a Ucrania, dijo el domingo el presidente de ese pa\u00eds devastado por la guerra, Volodymyr Zelensky. En declaraciones a Kaitlan Collins de CNN en Kyiv, Zelensky dijo que \u201cno puede entender c\u00f3mo Donald Trump puede [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446014","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El expresidente de EE.UU. Donald Trump estar\u00e1 \u201ccontra los estadounidenses\u201d si decide apoyar a Rusia en lugar de a Ucrania, dijo el domingo el presidente de ese pa\u00eds devastado por la guerra, Volodymyr Zelensky. En declaraciones a Kaitlan Collins de CNN en Kyiv, Zelensky dijo que \u201cno puede entender c\u00f3mo Donald Trump puede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-26T15:37:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia\",\"datePublished\":\"2024-02-26T15:37:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/\"},\"wordCount\":936,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/\",\"name\":\"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-26T15:37:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia - Noticias","og_description":"(CNN) &#8212; El expresidente de EE.UU. Donald Trump estar\u00e1 \u201ccontra los estadounidenses\u201d si decide apoyar a Rusia en lugar de a Ucrania, dijo el domingo el presidente de ese pa\u00eds devastado por la guerra, Volodymyr Zelensky. En declaraciones a Kaitlan Collins de CNN en Kyiv, Zelensky dijo que \u201cno puede entender c\u00f3mo Donald Trump puede [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/","og_site_name":"Noticias","article_published_time":"2024-02-26T15:37:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/"},"author":{"name":"","@id":""},"headline":"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia","datePublished":"2024-02-26T15:37:03+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/"},"wordCount":936,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/","name":"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-26T15:37:03+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/zelensky-trump-putin-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/26\/zelensky-trump-putin-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/26\/zelensky-trump-putin-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/26\/zelensky-trump-putin-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-26T15:37:03Z","datePublished":"2024-02-26T15:37:03Z","dateModified":"2024-02-26T15:37:03Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Zelensky dice que Trump no entiende a Putin porque nunca ha luchado contra Rusia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/26\\\/zelensky-trump-putin-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/26\\\/zelensky-trump-putin-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-26T15:37:03Z\",\"datePublished\":\"2024-02-26T15:37:03Z\",\"dateModified\":\"2024-02-26T15:37:03Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471653,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/25\/trump-llamada-zelensky-guerra-ucrania-trax\/","url_meta":{"origin":1446014,"position":0},"title":"Trump tiene una llamada con Zelensky mientras la guerra en Ucrania se alarga m\u00e1s de 4 a\u00f1os y se estancan negociaciones de paz","author":"","date":"febrero 25, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, habl\u00f3 este mi\u00e9rcoles con su hom\u00f3logo de Ucrania, Volodymyr Zelensky, mientras la guerra de Rusia en Ucrania se ha extendido m\u00e1s de cuatro a\u00f1os, seg\u00fan una persona familiarizada con la conversaci\u00f3n.La llamada se produjo mientras Zelensky anima p\u00fablicamente a Trump a seguir apoyando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462559,"url":"https:\/\/noticiasya.com\/springfield\/2025\/05\/20\/ucrania-rusia-ataques-drones-trump-putin-trax\/","url_meta":{"origin":1446014,"position":1},"title":"Ucrania y Rusia afirman que contin\u00faan los ataques con drones tras la llamada de Trump a Putin","author":"","date":"mayo 20, 2025","format":false,"excerpt":"Ucrania y Rusia se acusaron mutuamente de lanzar drones de ataque uno contra el otro durante la noche de este lunes, horas despu\u00e9s de que el presidente de Rusia, Vladimir Putin, hablara por tel\u00e9fono con su hom\u00f3logo de Estados Unidos, Donald Trump, y nuevamente rechazara un alto el fuego inmediato.Rusia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471571,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/23\/zelensky-peticion-trump-guerra-ucrania-entrevista-trax\/","url_meta":{"origin":1446014,"position":2},"title":"La s\u00faplica de Zelensky a Trump: Qu\u00e9dese de nuestro lado","author":"","date":"febrero 23, 2026","format":false,"excerpt":"El presidente de Ucrania Volodymyr Zelensky hizo una s\u00faplica a Donald Trump el lunes, diciendo a CNN que quiere que el presidente de Estados Unidos \u201cse quede de nuestro lado\u201d.Hablando en el Palacio Presidencial en Kyiv en la v\u00edspera del cuarto aniversario de la invasi\u00f3n a gran escala de Rusia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462799,"url":"https:\/\/noticiasya.com\/springfield\/2025\/05\/26\/trump-putin-loco-ataque-rusia-ucrania-trax\/","url_meta":{"origin":1446014,"position":3},"title":"Trump dice que Putin &#171;se ha vuelto absolutamente loco&#187; tras ataque de gran escala de Rusia a Ucrania","author":"","date":"mayo 26, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump dijo el domingo que Vladimir Putin \u201cse ha vuelto absolutamente LOCO\u201d, despu\u00e9s de que el l\u00edder ruso lanzara durante la noche el mayor ataque a\u00e9reo de los tres a\u00f1os de guerra de Mosc\u00fa contra Ucrania.\u201cSiempre he tenido una muy buena relaci\u00f3n con Vladimir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465474,"url":"https:\/\/noticiasya.com\/springfield\/2025\/08\/13\/trump-promete-consecuencias-putin-no-acepta-fin-guerra-trax\/","url_meta":{"origin":1446014,"position":4},"title":"Trump promete &#171;consecuencias muy severas&#187; para Rusia si Putin no acepta poner fin a la guerra","author":"","date":"agosto 13, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, prometi\u00f3 \u201cconsecuencias muy severas\u201d para Rusia si su presidente, Vladimir Putin, no acepta poner fin a su guerra en Ucrania durante la reuni\u00f3n de ambos l\u00edderes el viernes.\u201cHabr\u00e1 consecuencias\u201d, declar\u00f3 Trump durante un evento en el Centro Kennedy de Washington.Al pregunt\u00e1rsele si eso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462267,"url":"https:\/\/noticiasya.com\/springfield\/2025\/05\/13\/trump-asistiria-conversaciones-ucrania-rusia-turquia-trax\/","url_meta":{"origin":1446014,"position":5},"title":"Trump considera asistir a las conversaciones entre Ucrania y Rusia en Turqu\u00eda","author":"","date":"mayo 13, 2025","format":false,"excerpt":"El presidente Donald Trump dijo que est\u00e1 abierto a asistir a las posibles conversaciones de paz entre Rusia y Ucrania en Turqu\u00eda este jueves, mientras Estados Unidos aumenta la presi\u00f3n sobre Mosc\u00fa y Kyiv para poner fin al conflicto de tres a\u00f1os.Trump visitar\u00e1 el Golfo esta semana, con escalas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1446014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1446014"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1446014\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1446014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1446014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1446014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}