{"id":1446027,"date":"2024-02-26T18:52:08","date_gmt":"2024-02-27T02:52:08","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/"},"modified":"2024-02-26T18:52:08","modified_gmt":"2024-02-27T02:52:08","slug":"turistas-rusos-corea-del-norte-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/","title":{"rendered":"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron"},"content":{"rendered":"<p>(CNN) &#8212; Lena Bychcova no pod\u00eda creerlo cuando recibi\u00f3 su visa de turista norcoreana.<\/p>\n<p>Muchos turistas rusos se han visto excluidos de los destinos tur\u00edsticos. Pero Corea del Norte, como aliado clave de Rusia, ofrec\u00eda una rara oportunidad de viajar.<\/p>\n<p>La profesional de mercadeo fue una de los aproximadamente 100 ciudadanos rusos a quienes se les permiti\u00f3 viajar a Corea del Norte este mes en lo que se cree que es el primer viaje tur\u00edstico internacional desde la pandemia de coronavirus.<\/p>\n<p>El turismo en Corea del Norte est\u00e1 estrictamente controlado. No se permite la entrada al pa\u00eds a viajeros individuales y los grupos van acompa\u00f1ados de cuidadores. Los ingresos del turismo se utilizan para apoyar al r\u00e9gimen del dictador Kim Jong Un.<\/p>\n<p>Viajar al \u201creino ermita\u00f1o\u201d no est\u00e1 exento de riesgos importantes. El estudiante universitario estadounidense Otto Warmbier fue detenido en un viaje a Corea del Norte en 2016, supuestamente por robar un cartel de propaganda. Fue devuelto a Estados Unidos 17 meses despu\u00e9s en estado vegetativo y muri\u00f3 poco despu\u00e9s.<\/p>\n<p>Las vacaciones de esqu\u00ed m\u00e1s inusuales del mundo<\/p>\n<p>Bychcova y el resto del grupo llegaron a Pyongyang el 9 de febrero, viajando en un avi\u00f3n de Air Koryo de propiedad norcoreana desde Vladivostok.<\/p>\n<p>Si bien Bychcova admite que estaba ansiosa por el viaje, dice que gan\u00f3 la curiosidad y que no pod\u00eda dejar pasar la oportunidad de ver un pa\u00eds que pocos turistas tienen la oportunidad de explorar.<\/p>\n<p>El bloguero de viajes Ilya Voskresensky, que tambi\u00e9n se uni\u00f3 a la gira, se sinti\u00f3 igualmente tenso: mencion\u00f3 su trabajo a tiempo parcial, vendiendo platos antiguos, como su profesi\u00f3n en lugar de revelar que era un creador de contenidos. A pesar de sus dudas, admite que una de las razones para seguir adelante con el viaje fue descubrir si la Corea del Norte actual se comparar\u00eda con la Rusia sovi\u00e9tica de la que le hablaron sus familiares.<\/p>\n<p>&#171;Cuando miras a Corea del Norte, te das cuenta de que tu abuela y tu abuelo viv\u00edan como lo hacen aqu\u00ed&#187;, le dice Voskresensky a CNN. \u201cEs un teletransporte al pasado. No hay absolutamente ning\u00fan anuncio en la ciudad. Lo \u00fanico que se exhibe son lemas del partido, banderas, etc.\u201d.<\/p>\n<p>Miembros del grupo tur\u00edstico ruso fotografiados poco despu\u00e9s de llegar a Pyongyang. Cr\u00e9dito: Kim Won Jin\/AFP\/Getty Images<\/p>\n<p>El viaje de cuatro d\u00edas le cost\u00f3 a cada visitante unos US$ 750. El grupo contaba con gu\u00edas y traductores de habla rusa en todo momento. El itinerario incluy\u00f3 una visita a las estatuas de bronce de los difuntos l\u00edderes Kim Il Sung y Kim Jong Il en la colina Mansu, el Palacio de los Ni\u00f1os Mangyongdae, donde los ni\u00f1os presentaron un espect\u00e1culo de m\u00fasica y danza, y tres d\u00edas en la estaci\u00f3n de esqu\u00ed Masikryong.<\/p>\n<p>A los rusos tambi\u00e9n se les impusieron reglas estrictas a seguir, especialmente cuando se trataba de tomar fotograf\u00edas y videos.<\/p>\n<p>\u201cNos pidieron que no fotografi\u00e1ramos a los militares ni a la gente uniformada en general, que no fotografi\u00e1ramos las obras ni los edificios en construcci\u00f3n\u201d, explica Bychcova. \u201cY hab\u00eda reglas sobre c\u00f3mo tomar fotograf\u00edas y, en general, tratar los retratos o esculturas de l\u00edderes. Si tienes un peri\u00f3dico o una revista con una foto del l\u00edder, entonces no puedes doblar el peri\u00f3dico de manera que el retrato quede arrugado\u201d.<\/p>\n<p>Estos peri\u00f3dicos se convirtieron en algunos de sus souvenirs favoritos de Corea del Norte. Bychcova dice que no hab\u00eda mucho que comprar, pero hab\u00eda dos tiendas \u2013una en el aeropuerto y otra en la capital\u2013 donde ella y otros turistas pod\u00edan conseguir imanes, mu\u00f1ecas, juegos de Lego y otros peque\u00f1os obsequios.<\/p>\n<p>Lena Bychcova mira por la ventana de su habitaci\u00f3n en la estaci\u00f3n de esqu\u00ed Masikryong. Cortes\u00eda de Elena Bychcova<\/p>\n<p>La relaci\u00f3n entre Rusia y Corea del Norte<\/p>\n<p>Antes de la pandemia, la mayor fuente de turistas entrantes a Corea del Norte no era Rusia, sino China.<\/p>\n<p>Los esquiadores rusos fueron los primeros turistas a los que se permiti\u00f3 la entrada desde la pandemia, una se\u00f1al de la creciente popularidad de Rusia en Corea del Norte.<\/p>\n<p>Con sanciones globales y un n\u00famero cada vez menor de aliados, el creciente inter\u00e9s mutuo de Rusia y Corea del Norte ha hecho sonar la alarma entre los funcionarios de inteligencia de Estados Unidos.<\/p>\n<p>Corea del Norte ha suministrado a Rusia misiles para utilizarlos contra Ucrania.<\/p>\n<p>En febrero, el presidente de Rusia, Vladimir Putin, regal\u00f3 un veh\u00edculo a su hom\u00f3logo norcoreano, Kim Jong Un. El acto fue una posible violaci\u00f3n de las sanciones de las Naciones Unidas impuestas contra el pa\u00eds por su programa de armas nucleares.<\/p>\n<p>Tanto Voskresensky como Bychcova dicen que su decisi\u00f3n de viajar no fue por pol\u00edtica: fueron a Corea del Norte deseosos de conocer a la gente local y entablar relaciones.<\/p>\n<p>Sin embargo, despu\u00e9s de regresar, Bychcova no cree que algo as\u00ed sea realmente posible en el sistema norcoreano.<\/p>\n<p>\u201cUnos 200 ni\u00f1os \u2013 \u00a1los contamos en el escenario! \u2013 hab\u00eda preparado especialmente para nosotros un concierto de una hora de duraci\u00f3n. Y \u00e9ramos s\u00f3lo 97\u201d, dice.<\/p>\n<p>\u201cAs\u00ed que hab\u00eda m\u00e1s gente en el escenario que espectadores. Pod\u00edamos sentir que estaban tratando de crear una cierta imagen de c\u00f3mo es Corea del Norte para nosotros. Pero algunos detalles revelaron que no era del todo cierto, que hay otra vida\u201d.<\/p>\n<p>Si bien los rusos pudieron discutir libremente su viaje a Corea del Norte y sus pensamientos sobre el r\u00e9gimen de Kim, ese mismo privilegio no se aplica en su propio pa\u00eds.<\/p>\n<p>Las cr\u00edticas a Putin, a las pol\u00edticas de Rusia y al ej\u00e9rcito son delitos penales en Rusia.<\/p>\n<p>Un destacado exfuncionario de la KGB convertido en bloguero promilitar que apoy\u00f3 abiertamente la guerra en Ucrania fue arrestado y acusado de \u201cactividad extremista\u201d el verano pasado por comentarios cr\u00edticos hacia Putin.<\/p>\n<p>La semana pasada, una mujer de 33 a\u00f1os con doble ciudadan\u00eda rusa y estadounidense fue arrestada en Ekaterimburgo y acusada de \u201cbrindar asistencia financiera a un Estado extranjero en actividades dirigidas contra la seguridad de Rusia\u201d. \u00bfLa raz\u00f3n? Seg\u00fan los informes, don\u00f3 US$ 51 a una organizaci\u00f3n ben\u00e9fica ucraniana.<\/p>\n<p>Si bien tanto Voskresensky como Bychcova estaban conscientes de los abusos a los derechos humanos en Corea del Norte, ambos le dijeron a CNN que esperaban que el viaje valiera la pena para conectarse con civiles norcoreanos comunes y corrientes.<\/p>\n<p>Ahora, ambos dicen que considerar\u00edan volver a Corea del Norte alg\u00fan d\u00eda, pero s\u00f3lo si la situaci\u00f3n pol\u00edtica cambia.<\/p>\n<p>\u201cEl mensaje principal de mi contenido es que en cualquier lugar, sin importar el pa\u00eds o la nacionalidad, all\u00ed vive gente com\u00fan y corriente, y en todas partes hay que tratar a la gente con amor\u201d, dice Voskresensky. &#171;Espero que viajar salve el mundo&#187;.<\/p>\n<p>Otro viaje de esqu\u00ed ruso a Corea del Norte est\u00e1 previsto para marzo de 2024.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Lena Bychcova no pod\u00eda creerlo cuando recibi\u00f3 su visa de turista norcoreana. Muchos turistas rusos se han visto excluidos de los destinos tur\u00edsticos. Pero Corea del Norte, como aliado clave de Rusia, ofrec\u00eda una rara oportunidad de viajar. La profesional de mercadeo fue una de los aproximadamente 100 ciudadanos rusos a quienes se [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446027","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Lena Bychcova no pod\u00eda creerlo cuando recibi\u00f3 su visa de turista norcoreana. Muchos turistas rusos se han visto excluidos de los destinos tur\u00edsticos. Pero Corea del Norte, como aliado clave de Rusia, ofrec\u00eda una rara oportunidad de viajar. La profesional de mercadeo fue una de los aproximadamente 100 ciudadanos rusos a quienes se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-27T02:52:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron\",\"datePublished\":\"2024-02-27T02:52:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/\"},\"wordCount\":1240,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/\",\"name\":\"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-27T02:52:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron - Noticias","og_description":"(CNN) &#8212; Lena Bychcova no pod\u00eda creerlo cuando recibi\u00f3 su visa de turista norcoreana. Muchos turistas rusos se han visto excluidos de los destinos tur\u00edsticos. Pero Corea del Norte, como aliado clave de Rusia, ofrec\u00eda una rara oportunidad de viajar. La profesional de mercadeo fue una de los aproximadamente 100 ciudadanos rusos a quienes se [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/","og_site_name":"Noticias","article_published_time":"2024-02-27T02:52:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/"},"author":{"name":"","@id":""},"headline":"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron","datePublished":"2024-02-27T02:52:08+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/"},"wordCount":1240,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/","name":"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-27T02:52:08+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/26\/turistas-rusos-corea-del-norte-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-27T02:52:08Z","datePublished":"2024-02-27T02:52:08Z","dateModified":"2024-02-27T02:52:08Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los turistas regresaron a Corea del Norte por primera vez desde la pandemia. Esto es lo que vieron\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/26\\\/turistas-rusos-corea-del-norte-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/26\\\/turistas-rusos-corea-del-norte-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-27T02:52:08Z\",\"datePublished\":\"2024-02-27T02:52:08Z\",\"dateModified\":\"2024-02-27T02:52:08Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451854,"url":"https:\/\/noticiasya.com\/springfield\/2024\/08\/14\/corea-norte-turismo-internacional-trax\/","url_meta":{"origin":1446027,"position":0},"title":"Corea del Norte reabrir\u00e1 sus puertas al turismo internacional este invierno, afirman operadores tur\u00edsticos","author":"","date":"agosto 14, 2024","format":false,"excerpt":"(CNN) -- Corea del Norte reabrir\u00e1 el turismo internacional limitado a fines de 2024, casi cinco a\u00f1os despu\u00e9s de cerrar por completo las fronteras del pa\u00eds debido a la pandemia de covid-19, seg\u00fan anunciaron dos compa\u00f1\u00edas de viajes con conexiones con el pa\u00eds aislado.Koryo Tours, con sede en Beijing, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456160,"url":"https:\/\/noticiasya.com\/springfield\/2024\/11\/29\/starbucks-nueva-sucursal-corea-norte-trax\/","url_meta":{"origin":1446027,"position":1},"title":"Starbucks abre una sucursal con vistas a Corea del Norte","author":"","date":"noviembre 29, 2024","format":false,"excerpt":"Se\u00fal, Corea del Norte (CNN) -- Los amantes del caf\u00e9 que est\u00e9n interesados en vislumbrar la vida en la naci\u00f3n m\u00e1s reclusa del mundo deber\u00edan prepararse para viajar: Starbucks tiene el lugar perfecto para ellos.El \u00faltimo establecimiento de la cadena estadounidense en Corea del Sur est\u00e1 situado en una torre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458876,"url":"https:\/\/noticiasya.com\/springfield\/2025\/02\/18\/turistas-estadounidenses-corea-del-norte-seis-cifras-segundo-pasaporte-trax\/","url_meta":{"origin":1446027,"position":2},"title":"Los turistas de EE.UU. no pueden visitar Corea del Norte: uno pag\u00f3 una suma de seis cifras por otro pasaporte para poder ir","author":"","date":"febrero 18, 2025","format":false,"excerpt":"Para la mayor parte del mundo, los d\u00edas oscuros del covid-19 parecen un recuerdo lejano, pero no es as\u00ed en Corea del Norte, dijo Justin Martell, quien acaba de convertirse en el primer estadounidense conocido en poner un pie en el misterioso pa\u00eds desde el inicio de la pandemia, hace\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466111,"url":"https:\/\/noticiasya.com\/springfield\/2025\/09\/03\/corea-del-norte-wonsan-kalma-turismo-trax\/","url_meta":{"origin":1446027,"position":3},"title":"Hoteles, playas y parques acu\u00e1ticos, pero \u00bfy los turistas? As\u00ed es el vasto y casi vac\u00edo nuevo complejo de Corea del Norte","author":"","date":"septiembre 3, 2025","format":false,"excerpt":"Kil\u00f3metros de arena blanca, aguas de color turquesa e hileras de hoteles impecables frente al mar dibujan la costa del reci\u00e9n construido complejo Wonsan-Kalma. El l\u00edder norcoreano Kim Jong Un espera que el desarrollo sea algo equivalente a Waikiki.Pero hay un problema: no hay turistas.Cuando CNN revis\u00f3 las im\u00e1genes del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447480,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/27\/television-corea-norte-censura-pantalones-presentador-trax\/","url_meta":{"origin":1446027,"position":4},"title":"La televisi\u00f3n de Corea del Norte censura los pantalones del presentador de un programa brit\u00e1nico de jardiner\u00eda","author":"","date":"marzo 27, 2024","format":false,"excerpt":"(CNN) -- La cadena \u200b\u200bestatal de Corea del Norte, KCTV, hizo borrosos los jeans del veterano presentador de televisi\u00f3n brit\u00e1nico Alan Titchmarsh, como parte de la censura del pa\u00eds a la moda y la cultura extranjeras.KCTV transmiti\u00f3 este lunes un episodio del programa de Titchmarsh \"Garden Secrets\", emitido originalmente en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455417,"url":"https:\/\/noticiasya.com\/springfield\/2024\/10\/29\/soldados-norcoreanos-comandos-rusos-frente-ucrania-trax\/","url_meta":{"origin":1446027,"position":5},"title":"Los soldados norcoreanos aprenden comandos rusos y podr\u00edan ser enviados al frente de Ucrania, dicen legisladores surcoreanos","author":"","date":"octubre 29, 2024","format":false,"excerpt":"(CNN) -- Los soldados norcoreanos podr\u00edan estar siendo preparados para un traslado al frente de la guerra de Rusia contra Ucrania despu\u00e9s de que se les ense\u00f1aron comandos rusos b\u00e1sicos, dijeron este martes legisladores surcoreanos a la agencia de noticias Yonhap, citando a funcionarios de inteligencia del pa\u00eds.Unos 10.000 soldados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1446027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1446027"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1446027\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1446027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1446027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1446027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}