{"id":1446041,"date":"2024-02-27T06:56:59","date_gmt":"2024-02-27T14:56:59","guid":{"rendered":"https:\/\/wordpress-vip.entravision.com\/noticias\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/"},"modified":"2024-02-27T06:56:59","modified_gmt":"2024-02-27T14:56:59","slug":"mapa-politico-mexico-pri-morena-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","title":{"rendered":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0En apenas una d\u00e9cada, el mapa electoral de M\u00e9xico ha pasado de la hegemon\u00eda del Partido Revolucionario Institucional (PRI) al dominio de Morena, el partido fundado por el actual presidente, Andr\u00e9s Manuel L\u00f3pez Obrador.<\/p>\n<p>En seis a\u00f1os, Morena logr\u00f3 posicionarse como la primera fuerza pol\u00edtica. Los datos hablan por s\u00ed solos: el partido conquist\u00f3 la presidencia del pa\u00eds y la mayor\u00eda parlamentaria en el Congreso en 2018 y actualmente gobierna 21 de los 32 estados que conforman el pa\u00eds.<\/p>\n<p>El PRI, fundado el 18 de enero de 1946, domin\u00f3 durante d\u00e9cadas el mapa pol\u00edtico. Hasta 1989, el Revolucionario Institucional gobernaba todos los estados del pa\u00eds.<\/p>\n<p>En ese a\u00f1o, el conservador Partido Acci\u00f3n Nacional (PAN) logr\u00f3 obtener el primer Gobierno estatal de oposici\u00f3n con la victoria de Ernesto Ruffo Appel en Baja California. A partir de su triunfo, comenzaron a surgir los Gobiernos de oposici\u00f3n, tal como recuerda el libro &#171;Alternancia y transici\u00f3n pol\u00edtica: \u00bfC\u00f3mo gobierna la oposici\u00f3n en M\u00e9xico?&#187;, editado por El Colegio de la Frontera Norte.<\/p>\n<p>En los siguientes a\u00f1os, el PAN sumar\u00eda m\u00e1s estados: en 1991 conquistar\u00eda Guanajuato; en 1992, Chihuahua; en 1995 vuelve a ganar Baja California y Guanajuato y se suma Jalisco. Para 1997, gana Quer\u00e9taro y Nuevo Le\u00f3n. Ese a\u00f1o, el izquierdista Partido de la Revoluci\u00f3n Democr\u00e1tica (PRD) conquista el entonces Distrito Federal, hoy Ciudad de M\u00e9xico.<\/p>\n<p>El PRI gobern\u00f3 al menos 5 entidades por m\u00e1s de 80 a\u00f1os: Durango, Hidalgo, Quintana Roo, Tamaulipas y Veracruz. Adem\u00e1s cumplir\u00e1 un siglo de gobierno en Coahuila, en el norte de M\u00e9xico.<\/p>\n<p>El PRI tambi\u00e9n estuvo casi un siglo -94 a\u00f1os- al frente de una gobernaci\u00f3n, la del Estado de M\u00e9xico. Su presencia estuvo ininterrumpida dese 1929, con Filiberto G\u00f3mez, primer gobernador, hasta 2023, con Alfredo del Mazo Maza.<\/p>\n<p>Coahuila solo ha conocido gobernadores pri\u00edstas. En 2023, el PRI volvi\u00f3 a ganar la gobernaci\u00f3n de la mano de Manolo Jim\u00e9nez para el periodo 2023-2029, con lo que cumplir\u00e1 un siglo de gobernar ese estado. De sus dos bastiones, en las elecciones de 2023 el PRI perdi\u00f3 el Estado de M\u00e9xico, a manos de Morena, pero conserv\u00f3 Coahuila.<\/p>\n<p>La debacle del PRI y la llegada de Morena<\/p>\n<p>El Movimiento de Regeneraci\u00f3n Nacional (Morena) naci\u00f3 como partido el 1 de agosto de 2014. Particip\u00f3 en elecciones locales y federales por primera vez en 2015 y se coloc\u00f3 como cuarta fuerza pol\u00edtica nacional, por detr\u00e1s del PRI, PAN y PRD.<\/p>\n<p>En 2016, el PRI sufri\u00f3 su mayor derrota electoral en los estados cuando perdi\u00f3 siete de las 12 gobernaciones que estaban en juego en esas elecciones. Entonces dej\u00f3 ir cuatro de sus bastiones: Durango, Tamaulipas, Veracruz y Quintana Roo. Tambi\u00e9n perdi\u00f3 en Chihuahua, Aguascalientes y Puebla.<\/p>\n<p>Ese a\u00f1o, el PRI gan\u00f3 cinco (perdi\u00f3 cuatro respecto a 2010); el PAN gan\u00f3 cuatro; la alianza PRD-PAN gan\u00f3 en tres, igual que seis a\u00f1os atr\u00e1s.<\/p>\n<p>En 2018, Morena gan\u00f3 la presidencia del pa\u00eds con Andr\u00e9s Manuel L\u00f3pez Obrador, adem\u00e1s de la mayor\u00eda parlamentaria en ambas c\u00e1maras del Congreso. Logr\u00f3 tambi\u00e9n sus primeros Gobiernos estatales: la Ciudad de M\u00e9xico, con Claudia Sheinbaum; Tabasco, con Ad\u00e1n Augusto L\u00f3pez; Chiapas, con Rutilio Escand\u00f3n; Veracruz, con Cuitl\u00e1huac Garc\u00eda; y Morelos con el exfutbolista Cuauht\u00e9moc Blanco, en este caso en coalici\u00f3n con PT y PES.<\/p>\n<p>En 2021, hubo elecciones intermedias y se renovaron 17 gobernaciones, de las que Morena gan\u00f3 11: Baja California, Baja California Sur, Campeche, Colima, Guerrero, Michoac\u00e1n, Nayarit, Sinaloa, Sonora, Zacatecas y Tlaxcala. Baja California ya lo gobernaba Morena, pero el resto de los estados se los arrebat\u00f3 al PRI, PAN y PRD.<\/p>\n<p>Tras esas victorias, Morena gobernaba 16 estados; el PAN, ocho; el PRI cuatro; Movimiento Ciudadano, dos; el Partido Verde, uno; y Encuentro Social, uno.<\/p>\n<p>En las elecciones de junio de 2022, Morena volvi\u00f3 a sumar estados, ahora con las victorias en Hidalgo, Oaxaca, Tamaulipas y Quintana Roo.<\/p>\n<p>Para ese a\u00f1o el mapa pol\u00edtico se encontraba as\u00ed: Morena gobernaba 20 estados; el PAN, cinco; el PRI, tres; Movimiento Ciudadano, dos; el Partido Verde Ecologista de M\u00e9xico, uno; y Encuentro Social, uno.<\/p>\n<p>Finalmente en 2023, estuvieron en juego las gobernaciones de Coahuila y Estado de M\u00e9xico. El PRI retuvo el primero, pero Morena logr\u00f3 quitarle el basti\u00f3n mexiquense.<\/p>\n<p>El mapa pol\u00edtico de 2024<\/p>\n<p>Actualmente, Morena gobierna 21 estados: Baja California, Baja California Sur, Colima, Chiapas, Campeche, Ciudad de M\u00e9xico, Estado de M\u00e9xico, Hidalgo, Guerrero, Michoac\u00e1n, Nayarit, Oaxaca, Puebla, Quintana Roo, Sonora, Sinaloa, Tamaulipas, Tlaxcala, Tabasco, Veracruz y Zacatecas.<\/p>\n<p>A estos se suman dos, que gobierna con sus aliados: Morelos (PES) y San Luis Potos\u00ed (PVEM). Con esto, Morena tiene bajo su poder un 71.8% de los Gobiernos estatales del pa\u00eds.<\/p>\n<p>En tanto, la oposici\u00f3n se reparte el resto de la siguiente forma: cinco para el PAN; dos para el PRI y dos para Movimiento Ciudadano.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0En apenas una d\u00e9cada, el mapa electoral de M\u00e9xico ha pasado de la hegemon\u00eda del Partido Revolucionario Institucional (PRI) al dominio de Morena, el partido fundado por el actual presidente, Andr\u00e9s Manuel L\u00f3pez Obrador. En seis a\u00f1os, Morena logr\u00f3 posicionarse como la primera fuerza pol\u00edtica. Los datos hablan por s\u00ed solos: el partido [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446041","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0En apenas una d\u00e9cada, el mapa electoral de M\u00e9xico ha pasado de la hegemon\u00eda del Partido Revolucionario Institucional (PRI) al dominio de Morena, el partido fundado por el actual presidente, Andr\u00e9s Manuel L\u00f3pez Obrador. En seis a\u00f1os, Morena logr\u00f3 posicionarse como la primera fuerza pol\u00edtica. Los datos hablan por s\u00ed solos: el partido [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-27T14:56:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico\",\"datePublished\":\"2024-02-27T14:56:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/\"},\"wordCount\":875,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/\",\"url\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/\",\"name\":\"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-02-27T14:56:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","og_locale":"es_ES","og_type":"article","og_title":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0En apenas una d\u00e9cada, el mapa electoral de M\u00e9xico ha pasado de la hegemon\u00eda del Partido Revolucionario Institucional (PRI) al dominio de Morena, el partido fundado por el actual presidente, Andr\u00e9s Manuel L\u00f3pez Obrador. En seis a\u00f1os, Morena logr\u00f3 posicionarse como la primera fuerza pol\u00edtica. Los datos hablan por s\u00ed solos: el partido [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","og_site_name":"Noticias","article_published_time":"2024-02-27T14:56:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/"},"author":{"name":"","@id":""},"headline":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico","datePublished":"2024-02-27T14:56:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/"},"wordCount":875,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","url":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","name":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-02-27T14:56:59+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"De la hegemon\u00eda del PRI al dominio de Morena: as\u00ed ha cambiado el mapa electoral en M\u00e9xico","url":"http:\/\/noticiasya.com\/springfield\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/02\/27\/mapa-politico-mexico-pri-morena-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-02-27T14:56:59Z","datePublished":"2024-02-27T14:56:59Z","dateModified":"2024-02-27T14:56:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"De la hegemon\\u00eda del PRI al dominio de Morena: as\\u00ed ha cambiado el mapa electoral en M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/27\\\/mapa-politico-mexico-pri-morena-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/02\\\/27\\\/mapa-politico-mexico-pri-morena-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-02-27T14:56:59Z\",\"datePublished\":\"2024-02-27T14:56:59Z\",\"dateModified\":\"2024-02-27T14:56:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1450985,"url":"https:\/\/noticiasya.com\/springfield\/2024\/07\/09\/pri-perpetuara-alejandro-moreno-orix\/","url_meta":{"origin":1446041,"position":0},"title":"Renovaci\u00f3n del PRI: \u00bfse perpetuar\u00e1 la presencia de Alejandro Moreno?","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Partido Revolucionario Institucional (PRI) se prepara para renovar su dirigencia. Este proceso inici\u00f3 con un pol\u00e9mico cambio a los estatutos internos: este domingo, la Asamblea Nacional del partido aprob\u00f3 reformas que permitir\u00e1n a su actual presidente, Alejandro \u2018Alito\u2019 Moreno, reelegirse, si as\u00ed lo busca, hasta por tres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450989,"url":"https:\/\/noticiasya.com\/springfield\/2024\/07\/09\/morena-10-anios-existencia-predominio-politica-mexico-orix\/","url_meta":{"origin":1446041,"position":1},"title":"Morena cumple 10 a\u00f1os de existencia con predominio de la pol\u00edtica en M\u00e9xico","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El oficialista partido Morena cumple 10 a\u00f1os de existencia convertido en la principal fuerza pol\u00edtica en M\u00e9xico, gracias a que en este per\u00edodo es en el que m\u00e1s ha logrado \u201cconectar\u201d con la ciudadan\u00eda y superar la oferta de la oposici\u00f3n, dicen analistas consultados por CNN.El Movimiento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446480,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/04\/quienes-candidatos-gobernador-elecciones-jalisco-mexico-orix\/","url_meta":{"origin":1446041,"position":2},"title":"\u00bfQui\u00e9nes son los candidatos a gobernador en las elecciones de Jalisco en 2024?","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Comenz\u00f3 la campa\u00f1a electoral de los aspirantes a gobernador de Jalisco, uno de los tres estados m\u00e1s importantes de M\u00e9xico, junto con Nuevo Le\u00f3n y la capital, Ciudad de M\u00e9xico. Este estado es gobernado por el partido Movimiento Ciudadano, que tambi\u00e9n gobierna en Nuevo Le\u00f3n.Estos son los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451822,"url":"https:\/\/noticiasya.com\/springfield\/2024\/08\/13\/pri-mexico-crisis-alianzas-orix\/","url_meta":{"origin":1446041,"position":3},"title":"Crisis y alianzas: \u00bfQu\u00e9 le espera en el futuro al PRI?","author":"","date":"agosto 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Partido Revolucionario Institucional (PRI), una fuerza pol\u00edtica hist\u00f3rica en M\u00e9xico, se enfrenta a la peor crisis de su historia, coinciden especialistas.Adem\u00e1s de quedar como la tercera fuerza pol\u00edtica \u2014debajo del ahora hegem\u00f3nico Morena y del derechista Partido Acci\u00f3n Nacional (PAN) \u2014 luego de las elecciones del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446165,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/01\/quienes-candidatos-gobernador-yucatan-elecciones-mexico-orix\/","url_meta":{"origin":1446041,"position":4},"title":"\u00bfQui\u00e9nes son los candidatos a gobernador en las elecciones de Yucat\u00e1n en 2024?","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En Yucat\u00e1n, estado ubicado en el sureste de M\u00e9xico y un polo tur\u00edstico importante, la gubernatura podr\u00eda cambiar de la alternancia pol\u00edtica de d\u00e9cadas de dos partidos. El estado es gobernado por Mauricio Vila Dosal del Partido Acci\u00f3n Nacional (PAN), quien le arrebat\u00f3 el gobierno al PRI:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446472,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/04\/quienes-candidatos-gobernador-yucatan-elecciones-mexico-orix-2\/","url_meta":{"origin":1446041,"position":5},"title":"\u00bfQui\u00e9nes son los candidatos a gobernador en las elecciones de Yucat\u00e1n en 2024?","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En Yucat\u00e1n, estado ubicado en el sureste de M\u00e9xico y un polo tur\u00edstico importante, la gubernatura podr\u00eda cambiar de la alternancia pol\u00edtica de d\u00e9cadas de dos partidos. El estado es gobernado por Mauricio Vila Dosal del Partido Acci\u00f3n Nacional (PAN), quien le arrebat\u00f3 el gobierno al PRI:\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1446041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1446041"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1446041\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1446041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1446041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1446041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}