{"id":1447751,"date":"2024-04-04T22:03:42","date_gmt":"2024-04-05T05:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/"},"modified":"2024-04-04T22:03:42","modified_gmt":"2024-04-05T05:03:42","slug":"gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/","title":{"rendered":"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario"},"content":{"rendered":"<p>(CNN) &#8212; El gabinete de seguridad de Israel aprob\u00f3 la reapertura del paso fronterizo de Erez, entre Israel y el norte de Gaza, por primera vez desde los ataques de Hamas del 7 de octubre, seg\u00fan inform\u00f3 el jueves un funcionario israel\u00ed a CNN.<\/p>\n<p>El funcionario israel\u00ed dijo que el cruce se abrir\u00eda para permitir la entrada de m\u00e1s ayuda humanitaria en Gaza. El gabinete tambi\u00e9n aprob\u00f3 el uso del puerto israel\u00ed de Ashdod para ayudar a transferir m\u00e1s ayuda al enclave.<\/p>\n<p>El anuncio se produce en medio de la creciente furia internacional por los ataques israel\u00edes que mataron a siete trabajadores humanitarios de la World Central Kitchen en Gaza. Israel ha reconocido su responsabilidad en las muertes, pero mantiene que el ataque no fue deliberado.<\/p>\n<p>El presidente de Estados Unidos, Joe Biden, declar\u00f3 el jueves que la situaci\u00f3n humanitaria general en Gaza es inaceptable en una llamada con el primer ministro de Israel, Benjamin Netanyahu, y advirti\u00f3 a Israel que tome medidas para abordar la crisis o se enfrentar\u00e1 a las consecuencias.<\/p>\n<p>El cruce de Erez, un paso peatonal, fue uno de los puntos fronterizos violados por los combatientes de Hamas el 7 de octubre cuando lanzaron su sangriento ataque contra Israel, matando a 1.200 personas y tomando a otras 250 como rehenes.<\/p>\n<p>Sigue sin estar claro c\u00f3mo se llevar\u00e1 a cabo la reapertura; los vol\u00famenes de entregas de ayuda que se han permitido hasta ahora a trav\u00e9s de los cruces de la frontera sur de Gaza han sido insuficientes en comparaci\u00f3n con la magnitud del sufrimiento humano en el territorio.<\/p>\n<p>Las Naciones Unidas acogieron con cautela la noticia de la reapertura. &#171;Es una noticia positiva pero, por supuesto, tendremos que ver c\u00f3mo se implementa. Necesitamos un alto el fuego humanitario y una afluencia masiva de ayuda&#187;, declar\u00f3 el jueves el portavoz del secretario general de la ONU, St\u00e9phane Dujarric.<\/p>\n<p>La principal agencia de la ONU en Gaza, la UNRWA, ha sido marginada por Israel y su presencia sigue restringida en algunas partes del enclave, especialmente en el norte, donde el riesgo de hambruna es mayor y se han registrado casos de muerte por inanici\u00f3n.<\/p>\n<p>Desde enero, los habitantes del norte de Gaza se han visto obligados a sobrevivir con una media de solo 245 calor\u00edas al d\u00eda, seg\u00fan Oxfam.<\/p>\n<p>Biden le advierte a Netanyahu que proteja a los civiles en Gaza o enfrente las consecuencias<\/p>\n<p>Desde los ataques terroristas del 7 de octubre, el asedio israel\u00ed a Gaza ha causado la muerte de m\u00e1s de 32.916 personas, seg\u00fan el Ministerio de Sanidad de Gaza, y ha provocado una espiral de crisis humanitaria en la que casi tres cuartas partes de la poblaci\u00f3n del norte de Gaza padece niveles catastr\u00f3ficos de hambre, seg\u00fan un informe respaldado por Naciones Unidas.<\/p>\n<p>Los puntos de ingreso a Gaza<\/p>\n<p>Los pasos fronterizos terrestres de Gaza, por los que tradicionalmente ha entrado en el territorio la mayor parte de la ayuda vital, siguen estando fuertemente restringidos por Israel. Las agencias de ayuda han acusado a Israel de estrangular la entrada de ayuda en el territorio devastado por la guerra, aunque Israel ha dicho que no tiene &#171;ning\u00fan l\u00edmite&#187; en la cantidad de ayuda que puede entrar.<\/p>\n<p>Antes de que comenzara la guerra, Israel restringi\u00f3 todos los accesos a Gaza por mar y aire, y mantuvo los pasos terrestres bajo estricto control. Dispon\u00eda de dos cruces funcionales con el enclave: Erez, destinado a la circulaci\u00f3n de personas, y Kerem Shalom, para mercanc\u00edas.<\/p>\n<p>Gaza tambi\u00e9n tiene un paso fronterizo con Egipto, en Rafah, gestionado por las autoridades egipcias. Aunque Israel no tiene control directo sobre este paso, vigila toda la actividad en el sur de Gaza.<\/p>\n<p>Ataque israel\u00ed que mat\u00f3 a trabajadores humanitarios en Gaza es consistente con un bombardeo de precisi\u00f3n, seg\u00fan muestra un an\u00e1lisis<\/p>\n<p>El ministro de Defensa de Israel, Yoav Gallant, prometi\u00f3 interrumpir el suministro de electricidad, alimentos, agua y combustible al enclave palestino despu\u00e9s de que combatientes de Hamas mataron a 1.200 personas en Israel y tomaron m\u00e1s de 250 rehenes el 7 de octubre.<\/p>\n<p>A finales de octubre empez\u00f3 a entrar ayuda a trav\u00e9s de Rafah y, tras la presi\u00f3n de Estados Unidos, Israel empez\u00f3 a permitir el paso de camiones de ayuda a trav\u00e9s de Kerem Shalom a finales de diciembre, pero a un ritmo muy inferior al de los 500 camiones comerciales y de ayuda diarios que hab\u00eda antes de la guerra.<\/p>\n<p>Nota del editor: esta noticia ha sido actualizada con desarrollos de la informaci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El gabinete de seguridad de Israel aprob\u00f3 la reapertura del paso fronterizo de Erez, entre Israel y el norte de Gaza, por primera vez desde los ataques de Hamas del 7 de octubre, seg\u00fan inform\u00f3 el jueves un funcionario israel\u00ed a CNN. El funcionario israel\u00ed dijo que el cruce se abrir\u00eda para permitir [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447751","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El gabinete de seguridad de Israel aprob\u00f3 la reapertura del paso fronterizo de Erez, entre Israel y el norte de Gaza, por primera vez desde los ataques de Hamas del 7 de octubre, seg\u00fan inform\u00f3 el jueves un funcionario israel\u00ed a CNN. El funcionario israel\u00ed dijo que el cruce se abrir\u00eda para permitir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T05:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario\",\"datePublished\":\"2024-04-05T05:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/\"},\"wordCount\":815,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/\",\"name\":\"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-05T05:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario - Noticias","og_description":"(CNN) &#8212; El gabinete de seguridad de Israel aprob\u00f3 la reapertura del paso fronterizo de Erez, entre Israel y el norte de Gaza, por primera vez desde los ataques de Hamas del 7 de octubre, seg\u00fan inform\u00f3 el jueves un funcionario israel\u00ed a CNN. El funcionario israel\u00ed dijo que el cruce se abrir\u00eda para permitir [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-05T05:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/"},"author":{"name":"","@id":""},"headline":"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario","datePublished":"2024-04-05T05:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/"},"wordCount":815,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/","name":"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-05T05:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\u00fan un funcionario","url":"http:\/\/noticiasya.com\/springfield\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2024\/04\/04\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-05T05:03:42Z","datePublished":"2024-04-05T05:03:42Z","dateModified":"2024-04-05T05:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gabinete de seguridad de Israel aprueba la reapertura del paso fronterizo del norte de Gaza por primera vez desde el 7 de octubre, seg\\u00fan un funcionario\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/04\\\/04\\\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2024\\\/04\\\/04\\\/gabinete-seguridad-israel-reapertura-paso-fronterizo-gaza-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-05T05:03:42Z\",\"datePublished\":\"2024-04-05T05:03:42Z\",\"dateModified\":\"2024-04-05T05:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1470754,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/02\/reabre-cruce-fronterizo-gaza-egipto-trax\/","url_meta":{"origin":1447751,"position":0},"title":"Se reabre el cruce fronterizo de Rafah entre Gaza y Egipto casi dos a\u00f1os despu\u00e9s de que Israel lo cerrara, dice funcionario","author":"","date":"febrero 2, 2026","format":false,"excerpt":"El \u00fanico cruce fronterizo de Gaza con Egipto se reabri\u00f3 parcialmente la ma\u00f1ana del lunes, despu\u00e9s de que Israel lo cerrara hace casi dos a\u00f1os, seg\u00fan un funcionario de seguridad israel\u00ed, lo que permiti\u00f3 que un peque\u00f1o n\u00famero de palestinos entrara y saliera del enclave devastado por la guerra.La Uni\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461981,"url":"https:\/\/noticiasya.com\/springfield\/2025\/05\/05\/gabinete-seguridad-israel-gaza-ayuda-trax\/","url_meta":{"origin":1447751,"position":1},"title":"El gabinete de seguridad de Israel aprueba plan ampliado para ocupar el territorio de Gaza y entregar ayuda, dice una fuente","author":"","date":"mayo 5, 2025","format":false,"excerpt":"El gabinete de seguridad de Israel vot\u00f3 este domingo a favor de ampliar las operaciones militares en Gaza y establecer un nuevo marco para la entrega de ayuda, seg\u00fan dos funcionarios israel\u00edes.La votaci\u00f3n se produjo horas despu\u00e9s de que el ej\u00e9rcito dijera que movilizar\u00eda a decenas de miles de reservistas,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457623,"url":"https:\/\/noticiasya.com\/springfield\/2025\/01\/18\/acuerdo-alto-fuego-rehenes-gaza-trax\/","url_meta":{"origin":1447751,"position":2},"title":"El acuerdo de alto el fuego y liberaci\u00f3n de rehenes entrar\u00e1 en vigor el domingo, poniendo un freno a meses de enfrentamientos","author":"","date":"enero 18, 2025","format":false,"excerpt":"El largamente esperado acuerdo de alto el fuego y liberaci\u00f3n de rehenes entre el Gobierno de Israel y Hamas entrar\u00e1 en vigor el domingo, lo que podr\u00eda marcar un nuevo cap\u00edtulo en un sangriento conflicto de 15 meses que ha inflamado Medio Oriente.El acuerdo, que consta de tres fases, entrar\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457486,"url":"https:\/\/noticiasya.com\/springfield\/2025\/01\/13\/hamas-libere-33-rehenes-acuerdo-funcionario-israeli-trax\/","url_meta":{"origin":1447751,"position":3},"title":"Se espera que Hamas libere a 33 rehenes en la primera fase de un acuerdo emergente, dice funcionario israel\u00ed","author":"","date":"enero 13, 2025","format":false,"excerpt":"Se espera que Hamas libere a 33 rehenes durante la primera fase de un acuerdo de alto el fuego emergente que se est\u00e1 ultimando por negociadores en Doha, dijeron dos funcionarios israel\u00edes.Israel cree que la mayor\u00eda de los 33 rehenes est\u00e1n vivos, dijo un alto funcionario israel\u00ed a los reporteros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465249,"url":"https:\/\/noticiasya.com\/springfield\/2025\/08\/08\/netanyahu-plan-guerra-gaza-trax\/","url_meta":{"origin":1447751,"position":4},"title":"\u00bfCu\u00e1l es el plan de Netanyahu para escalar la guerra de Israel en Gaza? Lo que sabemos","author":"","date":"agosto 8, 2025","format":false,"excerpt":"El gabinete de seguridad de Israel vot\u00f3 este viernes para expandir la guerra en Gaza, lo que marca una importante escalada en un momento en que enfrenta una intensa presi\u00f3n tanto interna como internacional para poner fin al conflicto.El gabinete aprob\u00f3 planes para tomar el control de la Ciudad de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465219,"url":"https:\/\/noticiasya.com\/springfield\/2025\/08\/07\/netanyahu-israel-busca-ocupacion-total-gaza-trax\/","url_meta":{"origin":1447751,"position":5},"title":"Israel pretende tomar el control de toda Gaza, dice Netanyahu antes de la reuni\u00f3n del gabinete de seguridad","author":"","date":"agosto 7, 2025","format":false,"excerpt":"El gabinete de seguridad de Israel est\u00e1 listo para decidir sobre una reocupaci\u00f3n total de Gaza, una medida que marcar\u00eda una importante escalada del conflicto tras casi dos a\u00f1os de guerra en el territorio.A pesar de la presi\u00f3n internacional, oposici\u00f3n de las fuerzas israel\u00edes y el temor interno de que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1447751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1447751"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1447751\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1447751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1447751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1447751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}