{"id":1468980,"date":"2025-12-04T16:03:43","date_gmt":"2025-12-05T00:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/"},"modified":"2025-12-04T16:03:43","modified_gmt":"2025-12-05T00:03:43","slug":"facebook-metaverso-wall-street-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/","title":{"rendered":"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz"},"content":{"rendered":"<p>Parece que Meta finalmente est\u00e1 lista para poner fin al sufrimiento del metaverso.<\/p>\n<p>Las acciones de la compa\u00f1\u00eda antes conocida como Facebook subieron un 7 % la ma\u00f1ana del jueves tras un <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2025-12-04\/meta-s-zuckerberg-plans-deep-cuts-for-metaverse-efforts?srnd=homepage-americas\">informe de Bloomberg<\/a> que se\u00f1ala que el CEO, Mark Zuckerberg, recortar\u00e1 el presupuesto del equipo del metaverso hasta en un 30 %. CNN no ha confirmado el informe y Meta no respondi\u00f3 a una solicitud de comentarios.<\/p>\n<p>La acci\u00f3n termin\u00f3 el d\u00eda con una subida del 3,4 %.<\/p>\n<p>No es dif\u00edcil ver por qu\u00e9 Wall Street est\u00e1 tan entusiasmado. Despu\u00e9s de cuatro a\u00f1os y miles de millones de d\u00f3lares desperdiciados, el metaverso \u2014una funci\u00f3n en la que Zuckerberg cre\u00eda tan profundamente que <a href=\"https:\/\/www.cnn.com\/2022\/10\/30\/tech\/meta-metaverse-transition\">renombr\u00f3<\/a> la compa\u00f1\u00eda en su honor\u2014 est\u00e1, m\u00e1s o menos, acabado.<\/p>\n<p>La idea nunca tuvo mucho sentido, incluso cuando Zuckerberg declar\u00f3 dram\u00e1ticamente que el metaverso ser\u00eda \u201cel sucesor de internet m\u00f3vil\u201d. La compa\u00f1\u00eda inicialmente se fij\u00f3 el objetivo de alcanzar 500.000 usuarios activos mensuales en <a href=\"https:\/\/www.cnn.com\/2021\/12\/09\/tech\/meta-launches-horizon-worlds\">Horizons Worlds<\/a>, un espacio de realidad virtual, para finales de 2022. Seg\u00fan el <a href=\"https:\/\/www.wsj.com\/articles\/meta-metaverse-horizon-worlds-zuckerberg-facebook-internal-documents-11665778961?mod=hp_lead_pos1\">Wall Street Journal<\/a>, Meta revis\u00f3 ese objetivo a casi la mitad m\u00e1s tarde ese mismo a\u00f1o.<\/p>\n<p>Para ser claros, a\u00fan no sabemos qu\u00e9 pasar\u00e1 con el metaverso, que forma parte de la divisi\u00f3n Reality Labs de Meta, encargada de sus visores de realidad virtual. Y Zuckerberg ha dicho que todav\u00eda cree que alg\u00fan d\u00eda la gente pasar\u00e1 cantidades significativas de tiempo en mundos virtuales.<\/p>\n<p>Pero todo el proyecto est\u00e1, por decir lo menos, muy lejos del vasto idilio digital del sue\u00f1o febril de Zuckerberg durante la pandemia, y est\u00e1 siendo relegado al fondo del armario como tantos otros proyectos bien intencionados de la \u00e9poca de la pandemia de covid-19.<\/p>\n<p>Los inversionistas (y la mayor\u00eda de las personas que usan internet) fueron esc\u00e9pticos desde el principio.<\/p>\n<p>El metaverso era un <a href=\"https:\/\/www.cnn.com\/2021\/10\/28\/business\/meta-facebook-name-nightcap\">concepto difuso<\/a>, presentado a una poblaci\u00f3n que acababa de salir de los confinamientos por el covid-19 y que no quer\u00eda nada m\u00e1s que estar cerca de otros humanos fuera de l\u00ednea, en la vida real. Meta nos dec\u00eda que el futuro de las redes sociales ser\u00eda inmersivo, como una gran videollamada de Zoom poblada por alter egos digitales que pueden interactuar, jugar y comprarse cosas unos a otros por\u2026 \u00bfdiversi\u00f3n? En realidad no estaba claro cu\u00e1l era el objetivo, y de todas formas, para llegar ah\u00ed se necesitaba acceso a un visor voluminoso de US$ 400.<\/p>\n<p>Por supuesto, el momento de la renovaci\u00f3n de marca de Meta tambi\u00e9n fue importante.<br \/>Facebook intentaba desesperadamente arrastrarse fuera de un pantano de titulares negativos vinculados a la denunciante <a href=\"https:\/\/www.cnn.com\/2021\/10\/04\/tech\/facebook-whistleblower-frances-haugen-what-we-know\">Frances Haugen<\/a>, quien filtr\u00f3 documentos internos al Wall Street Journal detallando c\u00f3mo la gigante de las redes sociales repetidamente no abord\u00f3 problemas en sus plataformas que los ejecutivos sab\u00edan que estaban perjudicando a los usuarios (especialmente adolescentes).<\/p>\n<p>La empresa, bajo todo tipo de escrutinio y a\u00fan resentida por haberse perdido el cambio hacia los tel\u00e9fonos inteligentes, necesitaba un cambio de narrativa.<\/p>\n<p>Pero cuanto m\u00e1s la gente pudo ver del metaverso, menos atractivo resultaba. Aproximadamente un a\u00f1o despu\u00e9s del giro de Meta, una imagen del propio Zuckerberg, con un rostro cuadrado y sin vida dentro del metaverso, se volvi\u00f3 viral debido a lo sorprendentemente mediocres que segu\u00edan siendo los gr\u00e1ficos tras un a\u00f1o de trabajo y miles de millones de d\u00f3lares invertidos en su desarrollo. En ese momento, escrib\u00ed sobre lo que ve\u00eda como el mayor problema del metaverso de Meta: <a href=\"https:\/\/www.cnn.com\/2022\/08\/25\/business\/nightcap-metaverse-mark-zuckerberg\">simplemente no se ve <em>cool<\/em><\/a>.<\/p>\n<p>El atractivo inicial de Facebook resid\u00eda en parte en c\u00f3mo permit\u00eda a las personas mostrarse como <em>cool<\/em>, fuera lo que eso significara para ellas.<\/p>\n<p>Pod\u00edas ser gracioso, atractivo o misterioso en tu foto de perfil. Pod\u00edas escribir un estado ingenioso mencionando alguna banda indie poco conocida. Creabas toda una vibra con tus listas de pel\u00edculas, m\u00fasica y libros favoritos. Y pod\u00edas conectar con personas de una manera que dejaba el significado de esa conexi\u00f3n en la ambig\u00fcedad: \u201cagregar como amigo\u201d pod\u00eda significar mucho, o muy poco, sin presi\u00f3n, lo que sea, solo s\u00e9 <em>cool<\/em>.<\/p>\n<p>Ese factor <em>cool<\/em> claramente falta en el metaverso. Pero Zuckerberg puede que haya aprendido al menos una lecci\u00f3n del desastre: la est\u00e9tica importa, por eso Meta est\u00e1 fichando al <a href=\"https:\/\/www.bloomberg.com\/news\/articles\/2025-12-03\/apple-design-executive-alan-dye-poached-by-meta-in-major-coup\">principal dise\u00f1ador de Apple<\/a>, Alan Dye, para dirigir un nuevo estudio de integraci\u00f3n de hardware, software e IA.<\/p>\n<p>Los ahorros provenientes de los recortes en el metaverso, dijeron personas familiarizadas con los planes a Bloomberg, se espera que se desv\u00eden a otros proyectos, incluidos lentes de inteligencia artificial y otros dispositivos vestibles, donde Meta busca consolidar su dominio. Este a\u00f1o, la empresa mantuvo una gran ventaja sobre sus rivales, capturando el 61 % del mercado de lentes inteligentes y dispositivos AR\/VR, <a href=\"https:\/\/www.idc.com\/promo\/arvr\/\">seg\u00fan IDC Global<\/a>.<\/p>\n<p>Sin embargo, al igual que el metaverso, el retorno financiero de la inteligencia artificial est\u00e1 lejos de ser seguro, y Wall Street ha expresado preocupaci\u00f3n por la disposici\u00f3n de Zuckerberg a gastar sumas astron\u00f3micas en tecnolog\u00eda no comprobada, incluso en una tan popular como la inteligencia artificial.<\/p>\n<p>Zuckerberg, como es caracter\u00edstico, no se deja intimidar. \u201cSi terminamos malgastando un par de cientos de miles de millones de d\u00f3lares, creo que eso ser\u00eda muy desafortunado, obviamente\u201d, dijo en septiembre en el <a href=\"https:\/\/www.youtube.com\/watch?v=23FyskyFoP8\">p\u00f3dcast \u201cAccess\u201d<\/a>. \u201cPero lo que dir\u00eda es que en realidad creo que el riesgo es mayor del otro lado\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parece que Meta finalmente est\u00e1 lista para poner fin al sufrimiento del metaverso. Las acciones de la compa\u00f1\u00eda antes conocida como Facebook subieron un 7 % la ma\u00f1ana del jueves tras un informe de Bloomberg que se\u00f1ala que el CEO, Mark Zuckerberg, recortar\u00e1 el presupuesto del equipo del metaverso hasta en un 30 %. CNN [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1468980","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz - Noticias\" \/>\n<meta property=\"og:description\" content=\"Parece que Meta finalmente est\u00e1 lista para poner fin al sufrimiento del metaverso. Las acciones de la compa\u00f1\u00eda antes conocida como Facebook subieron un 7 % la ma\u00f1ana del jueves tras un informe de Bloomberg que se\u00f1ala que el CEO, Mark Zuckerberg, recortar\u00e1 el presupuesto del equipo del metaverso hasta en un 30 %. CNN [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-05T00:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz\",\"datePublished\":\"2025-12-05T00:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/\"},\"wordCount\":975,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/\",\"name\":\"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-12-05T00:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz - Noticias","og_description":"Parece que Meta finalmente est\u00e1 lista para poner fin al sufrimiento del metaverso. Las acciones de la compa\u00f1\u00eda antes conocida como Facebook subieron un 7 % la ma\u00f1ana del jueves tras un informe de Bloomberg que se\u00f1ala que el CEO, Mark Zuckerberg, recortar\u00e1 el presupuesto del equipo del metaverso hasta en un 30 %. CNN [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/","og_site_name":"Noticias","article_published_time":"2025-12-05T00:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/"},"author":{"name":"","@id":""},"headline":"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz","datePublished":"2025-12-05T00:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/"},"wordCount":975,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/","url":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/","name":"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-12-05T00:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El metaverso est\u00e1 acabado y Wall Street no podr\u00eda estar m\u00e1s feliz","url":"http:\/\/noticiasya.com\/springfield\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2025\/12\/04\/facebook-metaverso-wall-street-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-12-05T00:03:43Z","datePublished":"2025-12-05T00:03:43Z","dateModified":"2025-12-05T00:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El metaverso est\\u00e1 acabado y Wall Street no podr\\u00eda estar m\\u00e1s feliz\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2025\\\/12\\\/04\\\/facebook-metaverso-wall-street-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2025\\\/12\\\/04\\\/facebook-metaverso-wall-street-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-12-05T00:03:43Z\",\"datePublished\":\"2025-12-05T00:03:43Z\",\"dateModified\":\"2025-12-05T00:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1458849,"url":"https:\/\/noticiasya.com\/springfield\/2025\/02\/17\/meta-intentando-inventar-futuro-trax\/","url_meta":{"origin":1468980,"position":0},"title":"Meta sigue intentando inventar el futuro; pero sin \u00e9xito todav\u00eda","author":"","date":"febrero 17, 2025","format":false,"excerpt":"Con Facebook se inici\u00f3 la era moderna de las redes sociales a principios de la d\u00e9cada de 2000, pero las ambiciones de expansi\u00f3n de su empresa matriz, Meta, durante la \u00faltima d\u00e9cada no han tenido el mismo \u00e9xito. De todos modos, al parecer sigue intent\u00e1ndolo de nuevo con su \u00faltimo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466568,"url":"https:\/\/noticiasya.com\/springfield\/2025\/09\/17\/mark-zuckerberg-presenta-nuevas-gafas-inteligentes-meta-ia-trax\/","url_meta":{"origin":1468980,"position":1},"title":"Mark Zuckerberg presenta las nuevas gafas inteligentes de Meta impulsadas por inteligencia artificial","author":"","date":"septiembre 17, 2025","format":false,"excerpt":"El CEO de Meta, Mark Zuckerberg, subi\u00f3 al escenario este mi\u00e9rcoles para presentar la pr\u00f3xima generaci\u00f3n de dispositivos port\u00e1tiles impulsados por inteligencia artificial de la compa\u00f1\u00eda: unas gafas inteligentes con una peque\u00f1a pantalla dentro de la lente.Representan el siguiente paso de la empresa hacia un futuro en el que todos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459894,"url":"https:\/\/noticiasya.com\/springfield\/2025\/03\/13\/nicolas-garcia-hume-y-el-reestreno-de-reverso-es-casi-algo-hipnotico\/","url_meta":{"origin":1468980,"position":2},"title":"Nicol\u00e1s Garc\u00eda Hume y el reestreno de Reverso: &#171;Es casi algo hipn\u00f3tico&#187;","author":"","date":"marzo 13, 2025","format":false,"excerpt":"El actor y director Nicol\u00e1s Garc\u00eda Hume convers\u00f3 con B\u00e1rbara Arroyo en el programa Cine Argentina CNN, que se emite todos los s\u00e1bados desde las 17, sobre el reestreno de la obra Reverso (los martes 20 hs en Paseo la Plaza) y la emoci\u00f3n por haber finalizado la filmaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457511,"url":"https:\/\/noticiasya.com\/springfield\/2025\/01\/14\/meta-despide-empleados-peor-desempeno-trax\/","url_meta":{"origin":1468980,"position":3},"title":"Meta despedir\u00e1 al 5% de sus empleados con peor desempe\u00f1o","author":"","date":"enero 14, 2025","format":false,"excerpt":"Meta tiene el objetivo recortar alrededor del 5% de lo que llama sus \u201cempleados con menor desempe\u00f1o\u201d, mientras planea volver a cubrir esos puestos a finales de este a\u00f1o, confirm\u00f3 la compa\u00f1\u00eda este martes.Estos recortes de empleo podr\u00edan afectar a unos 3.600 trabajadores, seg\u00fan el \u00faltimo informe trimestral de Meta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456509,"url":"https:\/\/noticiasya.com\/springfield\/2024\/12\/12\/meta-dona-millon-dolares-fondo-trump-reparar-relacion-trax\/","url_meta":{"origin":1468980,"position":4},"title":"Meta dona US$ 1 mill\u00f3n al fondo inaugural de Trump en el \u00faltimo paso para reparar la relaci\u00f3n","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"Meta don\u00f3 US$ 1 mill\u00f3n al fondo inaugural del presidente electo Donald Trump, confirm\u00f3 la compa\u00f1\u00eda a CNN.La noticia llega dos semanas despu\u00e9s de que el CEO de Meta, Mark Zuckerberg, se reuniera en privado con Trump en Mar-a-Lago. La donaci\u00f3n fue reportada primero por The Wall Street Journal.CNN inform\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461175,"url":"https:\/\/noticiasya.com\/springfield\/2025\/04\/14\/meta-antimonopolio-instagram-whatsapp-trax\/","url_meta":{"origin":1468980,"position":5},"title":"Si Meta pierde en un caso antimonopolio, podr\u00eda verse obligada a dividirse y vender Instagram y WhatsApp","author":"","date":"abril 14, 2025","format":false,"excerpt":"Meta va a juicio a partir del lunes.El gobierno estadounidense est\u00e1 impulsando un caso antimonopolio de gran envergadura, alegando que la empresa de Mark Zuckerberg construy\u00f3 ilegalmente un \u201cmonopolio de redes sociales\u201d mediante a\u00f1os de \u201cconducta anticompetitiva\u201d.Si el juez se pone del lado del gobierno, Meta podr\u00eda verse obligada a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1468980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1468980"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1468980\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1468980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1468980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1468980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}