{"id":1472337,"date":"2026-03-19T06:03:50","date_gmt":"2026-03-19T13:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/"},"modified":"2026-03-19T06:03:50","modified_gmt":"2026-03-19T13:03:50","slug":"padre-deportado-familia-separada-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/","title":{"rendered":"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental"},"content":{"rendered":"<p>Hace dos meses, la vida de la familia Mart\u00ednez en la ciudad costera de Huntington Beach, California, era ajetreada, pero normal. Mam\u00e1 y pap\u00e1 trabajaban para pagar las cuentas, viendo con orgullo c\u00f3mo sus hijas prosperaban: una se uni\u00f3 a la Marina de Estados Unidos y la otra estudia en Cal State Fullerton.<\/p>\n<p>Ahora, el padre ha sido deportado a M\u00e9xico, la aviadora de la Marina ha sido desplegada en Medio Oriente como parte de la guerra con Ir\u00e1n, y la estudiante universitaria de Administraci\u00f3n de Empresas est\u00e1 tratando de mantener unida a su familia.<\/p>\n<p>\u201cNo se siente como una familia\u201d, dijo Ana Mart\u00ednez sobre su vida actual. \u201cSiento que nos han separado\u201d.<\/p>\n<p>Se han visto atrapados en dos pol\u00edticas clave del Gobierno de Trump este a\u00f1o: el control de la inmigraci\u00f3n y la guerra contra Ir\u00e1n. Tambi\u00e9n representan una cruda realidad de los temores de millones de familias con estatus inmigratorio mixto, compuestas por inmigrantes indocumentados y ciudadanos estadounidenses.<\/p>\n<p>\u201cPude salir sin miedo con mi familia. Pero ahora camino con un peso enorme sobre mis hombros\u201d, dijo Ana, la hermana menor, de 19 a\u00f1os, a CNN.<\/p>\n<p>Los Mart\u00ednez eran una familia orgullosa de su tradici\u00f3n militar. Fotograf\u00edas de su hija Jessica con uniforme adornan una pared de su sala, celebrando los logros de las ni\u00f1as. Humberto sol\u00eda usar su sudadera que dec\u00eda \u201cPap\u00e1 de una hija en la Marina\u201d, aunque \u00e9l y su esposa Nancy estaban demasiado nerviosos para pasar por los controles permanentes de la I-5 para visitarla en la base de San Diego.<\/p>\n<p>Ana y Humberto acababan de salir de su casa, en Huntington Beach, la ma\u00f1ana del 31 de enero, camino a recoger el coche del mec\u00e1nico, cuando \u00e9l se gir\u00f3 hacia ella y le dijo que no se asustara.<\/p>\n<p>Se percat\u00f3 de que la polic\u00eda los segu\u00eda y orill\u00f3 su camioneta. Ana grab\u00f3 con su tel\u00e9fono mientras los agentes federales le dec\u00edan a Humberto que deb\u00eda regresar a su M\u00e9xico natal, a pesar de que ella les gritaba que \u00e9l hab\u00eda solicitado la regularizaci\u00f3n de su estatus. El video registr\u00f3 sus gritos de \u201c\u00a1Papi, papi!\u201d mientras lo esposaban y se lo llevaban.<\/p>\n<p>Un comunicado del Departamento de Seguridad Nacional confirm\u00f3 la acci\u00f3n: \u201cEl 31 de enero, ICE arrest\u00f3 a Humberto Mart\u00ednez, un delincuente indocumentado mexicano con antecedentes penales por conducir bajo los efectos del alcohol y uso no autorizado de un veh\u00edculo. Hab\u00eda sido deportado de Estados Unidos cuatro veces y opt\u00f3 por cometer m\u00faltiples delitos graves reingresando ilegalmente a nuestro pa\u00eds en numerosas ocasiones. Se le emiti\u00f3 una orden final de deportaci\u00f3n en 2013 y fue deportado a M\u00e9xico por quinta vez tras ser puesto bajo custodia de ICE\u201d.<\/p>\n<p>\u201cBajo la presidencia de Trump [\u2026] si infringes la ley, enfrentar\u00e1s las consecuencias. Los inmigrantes ilegales con antecedentes penales no son bienvenidos en Estados Unidos.\u201d<\/p>\n<p>Humberto reconoce haber entrado ilegalmente a Estados Unidos en varias ocasiones, tras llegar solo por primera vez en septiembre de 1999. \u201cComo todo inmigrante, vine a este pa\u00eds buscando un futuro mejor, una vida mejor\u201d, declar\u00f3 a CNN desde Tijuana, M\u00e9xico. Afirm\u00f3 que lo llevaron en coche hacia el sur el mismo d\u00eda que fue detenido en enero y enviado a cruzar la frontera.<\/p>\n<p>Humberto, quien se dedicaba a instalar pisos de madera, se declar\u00f3 culpable de conducir bajo los efectos del alcohol y sin licencia v\u00e1lida en 2004. Cumpli\u00f3 ocho d\u00edas de servicio comunitario en lugar de una multa y tres a\u00f1os de libertad condicional, seg\u00fan consta en los registros judiciales obtenidos por CNN. Afirm\u00f3 que no fue deportado. El nacimiento de sus hijas, a finales de esa d\u00e9cada, le dio m\u00e1s motivos para querer estar en California.<\/p>\n<p>\u201cM\u00e1s que nada, no quer\u00eda que mis hijas se desviaran del buen camino ni que perdieran el control, que estuvieran sin su padre. Y, sobre todo, quer\u00eda que fueran buenas mujeres, y ya lo est\u00e1n logrando\u201d, dijo.<\/p>\n<p>Ana recuerda que, durante su infancia, su familia era muy unida, iban juntos a la iglesia cat\u00f3lica de San Joaqu\u00edn y las invitaban a tomar yogur helado en una tienda del barrio.<\/p>\n<p>Dijo que ten\u00eda cinco a\u00f1os cuando se enter\u00f3 de que sus padres eran indocumentados, durante la campa\u00f1a de deportaci\u00f3n del Gobierno de Obama. Aquello gener\u00f3 un temor constante en su vida, aunque nunca imagin\u00f3 que las leyes de inmigraci\u00f3n separar\u00edan a su familia.<\/p>\n<p>La pariente que ella sent\u00eda que abandonar\u00eda el pa\u00eds era su hermana Jessica, quien hablaba de alistarse en la Marina incluso cuando era ni\u00f1a.<\/p>\n<p>\u201cMe dio un poco de tristeza porque sab\u00eda que iba a estar m\u00e1s lejos de m\u00ed, pero aun as\u00ed estaba orgullosa de ella porque encontr\u00f3 algo que realmente quer\u00eda hacer\u201d, dijo Ana.<\/p>\n<p>Jessica quer\u00eda servir a su pa\u00eds y sab\u00eda que unirse a las Fuerza Armadas les dar\u00eda a sus padres la oportunidad de solicitar el permiso de permanencia temporal, que puede aplazar la deportaci\u00f3n de familiares de militares en servicio activo, entre otros, y puede conducir a la residencia permanente legal. Jessica decor\u00f3 su birrete de graduaci\u00f3n de la escuela secundaria con banderas estadounidenses y mexicanas y una dedicatoria: \u201cA mis padres, que llegaron sin nada y me lo dieron todo\u201d.<\/p>\n<p>Jessica se uni\u00f3 a la tripulaci\u00f3n del USS Abraham Lincoln, donde trabajaba en los misiles y el armamento del enorme portaviones. Se encontraba a bordo del Lincoln, en Asia, cuando Ana tuvo que comunicarle la noticia de la deportaci\u00f3n de su padre.<\/p>\n<p>\u201cEstaba dolida, estaba decepcionada al saber que se hab\u00edan llevado a mi padre y que ella estaba sirviendo a nuestro pa\u00eds y a nuestras Fuerzas Armadas\u201d, dijo Ana. \u201cEstaba en estado de shock. Estaba llorando\u201d.<\/p>\n<p>D\u00edas despu\u00e9s de la deportaci\u00f3n, un dron iran\u00ed fue derribado cuando volaba hacia el Lincoln, que hab\u00eda zarpado hacia el mar Ar\u00e1bigo mientras Estados Unidos continuaba las negociaciones con Ir\u00e1n.<\/p>\n<p>Tras los ataques coordinados entre Estados Unidos e Israel, Ir\u00e1n afirm\u00f3 haber alcanzado el Lincoln. Los comandantes estadounidenses pronto <a href=\"https:\/\/x.com\/CENTCOM\/status\/2028124242273767557?s=20\">desmintieron<\/a> la afirmaci\u00f3n, pero el mundo de Ana cambi\u00f3 para siempre. \u201cPerder a mi hermana es ahora mi mayor temor\u201d.<\/p>\n<p>A bordo del Lincoln, Jessica sigue respetando los valores familiares de respeto y responsabilidad, dijo Ana, pase lo que pase.<\/p>\n<p>\u201cNos coment\u00f3 que hab\u00eda ganado alg\u00fan tipo de certificado por ser la mejor empleada. Pero se dio cuenta de que no se sent\u00eda tan orgullosa porque su padre no estaba all\u00ed y no se encontraba en casa\u201d, dijo Ana.<\/p>\n<p>En Tijuana, Humberto se emociona al hablar de lo que le gustar\u00eda decirle al presidente Donald Trump. \u201c\u00bfPuede darme la oportunidad de recibir a mi hija cuando regrese y luego decidir?\u201d, pregunt\u00f3. \u201cQuiero ver a mi marinera, eso es todo lo que quiero\u201d.<\/p>\n<p>El abogado de inmigraci\u00f3n Eric Price, quien se hizo cargo del caso de Humberto despu\u00e9s de que fuera enviado de regreso a M\u00e9xico, critic\u00f3 la decisi\u00f3n del Gobierno de deportarlo.<\/p>\n<p>\u201cLa valiente hija de Humberto no solo tiene que preocuparse por su misi\u00f3n con la Marina de Estados Unidos, sino tambi\u00e9n por la seguridad de su padre, quien ha sido separado de su familia debido al insensible aparato de deportaci\u00f3n del Gobierno de Trump\u201d, dijo. \u201cNuestra esperanza es que podamos reunir a Humberto con su hija en unos a\u00f1os mediante el proceso de reunificaci\u00f3n familiar\u201d.<\/p>\n<p>En Huntington Beach, Ana ahora lleva a su madre al trabajo en un minimercado y la trae de vuelta, lo que ayuda a limitar su contacto con los agentes de inmigraci\u00f3n.<\/p>\n<p>\u201cEncontr\u00e9 una rutina en la que paso un rato con mi pap\u00e1, otro con mi hermana, otro con mi mam\u00e1, y luego voy y vengo con la escuela y el trabajo\u201d, dijo. \u201cHay momentos en que se complica\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace dos meses, la vida de la familia Mart\u00ednez en la ciudad costera de Huntington Beach, California, era ajetreada, pero normal. Mam\u00e1 y pap\u00e1 trabajaban para pagar las cuentas, viendo con orgullo c\u00f3mo sus hijas prosperaban: una se uni\u00f3 a la Marina de Estados Unidos y la otra estudia en Cal State Fullerton. Ahora, el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472337","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hace dos meses, la vida de la familia Mart\u00ednez en la ciudad costera de Huntington Beach, California, era ajetreada, pero normal. Mam\u00e1 y pap\u00e1 trabajaban para pagar las cuentas, viendo con orgullo c\u00f3mo sus hijas prosperaban: una se uni\u00f3 a la Marina de Estados Unidos y la otra estudia en Cal State Fullerton. Ahora, el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T13:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental\",\"datePublished\":\"2026-03-19T13:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/\"},\"wordCount\":1396,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/\",\"name\":\"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-19T13:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental - Noticias","og_description":"Hace dos meses, la vida de la familia Mart\u00ednez en la ciudad costera de Huntington Beach, California, era ajetreada, pero normal. Mam\u00e1 y pap\u00e1 trabajaban para pagar las cuentas, viendo con orgullo c\u00f3mo sus hijas prosperaban: una se uni\u00f3 a la Marina de Estados Unidos y la otra estudia en Cal State Fullerton. Ahora, el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-19T13:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental","datePublished":"2026-03-19T13:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/"},"wordCount":1396,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/","name":"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-19T13:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Padre deportado, hija enviada a un operativo militar: c\u00f3mo una familia de California se separ\u00f3 por la pol\u00edtica gubernamental","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/19\/padre-deportado-familia-separada-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-19T13:03:50Z","datePublished":"2026-03-19T13:03:50Z","dateModified":"2026-03-19T13:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Padre deportado, hija enviada a un operativo militar: c\\u00f3mo una familia de California se separ\\u00f3 por la pol\\u00edtica gubernamental\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/19\\\/padre-deportado-familia-separada-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/19\\\/padre-deportado-familia-separada-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-19T13:03:50Z\",\"datePublished\":\"2026-03-19T13:03:50Z\",\"dateModified\":\"2026-03-19T13:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1463290,"url":"https:\/\/noticiasya.com\/springfield\/2025\/06\/06\/quien-es-kilmar-abrego-garcia-el-salvador-deportado-eeuu-orix\/","url_meta":{"origin":1472337,"position":0},"title":"\u00bfQui\u00e9n es Kilmar \u00c1brego Garc\u00eda, el hombre devuelto a EE.UU. tras ser deportado a El Salvador?","author":"","date":"junio 6, 2025","format":false,"excerpt":"Kilmar \u00c1brego Garc\u00eda, de 29 a\u00f1os, padre de tres hijos con discapacidades, es un ciudadano salvadore\u00f1o que entr\u00f3 a Estados Unidos de forma irregular alrededor de 2011, cuando era adolescente, huyendo de la violencia de las pandillas, seg\u00fan asegura su familia.En 2019 un tribunal de inmigraci\u00f3n suspendi\u00f3 su remoci\u00f3n y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463017,"url":"https:\/\/noticiasya.com\/springfield\/2025\/05\/30\/familia-indocumentado-pide-dhs-retracte-trax\/","url_meta":{"origin":1472337,"position":1},"title":"Familia de inmigrante indocumentado acusado de amenazar a Trump dice que recibi\u00f3 amenazas y pide al DHS que se retracte","author":"","date":"mayo 30, 2025","format":false,"excerpt":"Abogados y activistas locales llevaron a cabo una conferencia de prensa este viernes en Milwaukee, Wisconsin, en la que solicitaron al Departamento de Seguridad Nacional (DHS, por sus siglas ingl\u00e9s) que emita una rectificaci\u00f3n sobre las afirmaciones de que un inmigrante indocumentado envi\u00f3 una carta amenazando al presidente Donald Trump.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467087,"url":"https:\/\/noticiasya.com\/springfield\/2025\/10\/03\/periodista-mario-guevara-deportado-el-salvador-ice-trax\/","url_meta":{"origin":1472337,"position":2},"title":"El periodista salvadore\u00f1o Mario Guevara es deportado a El Salvador tras meses bajo custodia de ICE","author":"","date":"octubre 3, 2025","format":false,"excerpt":"Mario Guevara, el periodista salvadore\u00f1o que gan\u00f3 popularidad documentando redadas de inmigraci\u00f3n en Estados Unidos, fue deportado este viernes despu\u00e9s de pasar meses bajo custodia federal.Guevara fue deportado a su natal El Salvador la madrugada del viernes, confirm\u00f3 a CNN el Comit\u00e9 para la Protecci\u00f3n de los Periodistas (CPJ), m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465917,"url":"https:\/\/noticiasya.com\/springfield\/2025\/08\/27\/pesadilla-inmigrante-connecticut-mexico-entrevista-orix\/","url_meta":{"origin":1472337,"position":3},"title":"&#171;Es una pesadilla que no me deja dormir&#187;, inmigrante detenido en Connecticut habla tras su deportaci\u00f3n a M\u00e9xico","author":"","date":"agosto 27, 2025","format":false,"excerpt":"En las \u00faltimas semanas, la vida de Leonel Ch\u00e1vez dio un vuelco del que todav\u00eda intenta recuperarse. Este inmigrante mexicano de 42 a\u00f1os, que viv\u00eda en Estados Unidos desde hace d\u00e9cadas, fue separado de su familia al ser detenido a mediados de agosto junto a su hermano en Norwalk, Connecticut,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460942,"url":"https:\/\/noticiasya.com\/springfield\/2025\/04\/08\/cronologia-deportacion-kilmar-abrego-el-salvador-trax\/","url_meta":{"origin":1472337,"position":4},"title":"Cronolog\u00eda de la batalla legal por la deportaci\u00f3n err\u00f3nea de Kilmar \u00c1brego a El Salvador","author":"","date":"abril 8, 2025","format":false,"excerpt":"El lunes, la Corte Suprema suspendi\u00f3 temporalmente el plazo impuesto por un tribunal inferior para devolver a Estados Unidos a un hombre de Maryland deportado por error a El Salvador, lo que le otorga al gobierno de Trump tiempo adicional para revisar el caso.Kilmar Armando \u00c1brego Garc\u00eda, trabajador metal\u00fargico y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468420,"url":"https:\/\/noticiasya.com\/springfield\/2025\/11\/17\/refugiado-union-sovietica-deportado-ucrania-trax\/","url_meta":{"origin":1472337,"position":5},"title":"Lleg\u00f3 a EE.UU. siendo un ni\u00f1o refugiado de la antigua Uni\u00f3n Sovi\u00e9tica. Ahora es padre y se enfrenta a deportaci\u00f3n a Ucrania","author":"","date":"noviembre 17, 2025","format":false,"excerpt":"Roman Surovtsev era puntual en recoger a sus dos hijas del colegio todas las tardes.Para \u00e9l es importante estar ah\u00ed para sus sonrientes hijas de 3 y 5 a\u00f1os, haci\u00e9ndoles un mont\u00f3n de preguntas sobre lo que aprendieron y con qui\u00e9n jugaron.En casa, junto a su esposa Samantha, siempre se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472337"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472337\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}