{"id":1472359,"date":"2026-03-19T16:03:53","date_gmt":"2026-03-19T23:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/"},"modified":"2026-03-19T16:03:53","modified_gmt":"2026-03-19T23:03:53","slug":"spinosaurus-mirabilis-nueva-especie-dinosaurio-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/","title":{"rendered":"Spinosaurus mirabilis: una &#171;garza infernal&#187; que suma evidencia en un debate de larga data sobre estos dinosaurios"},"content":{"rendered":"<p>Un cr\u00e1neo fosilizado y mand\u00edbulas hallados en N\u00edger pertenec\u00edan a una criatura que ten\u00eda una gran cresta \u00f3sea sobre la cabeza y vivi\u00f3 hace unos 95 millones de a\u00f1os. Nombrada <em>Spinosaurus mirabilis<\/em>, es la primera especie de Spinosaurus identificada en m\u00e1s de un siglo.<\/p>\n<p>Los hallazgos, publicados el 19 de febrero en la revista <a href=\"https:\/\/www.science.org\/doi\/10.1126\/science.adx5486\">Science<\/a>, sugieren que la criatura prehist\u00f3rica es un pariente cercano de Spinosaurus aegyptiacus, un <a href=\"https:\/\/www.cnn.com\/science\/unearthed\/paleontology\">dinosaurio<\/a> gigante comedor de peces con una vela a lo largo del lomo, descrito por primera vez en 1915 por el paleont\u00f3logo alem\u00e1n Ernst Stromer von Reichenbach.<\/p>\n<p>Este descubrimiento podr\u00eda responder una pregunta largamente debatida entre los cient\u00edficos sobre las especies de Spinosaurus: \u00bferan depredadores de persecuci\u00f3n marina \u2014animales que se zambull\u00edan y nadaban tras sus presas\u2014 o se parec\u00edan m\u00e1s a las garzas, vadeando en la l\u00ednea de costa y atacando peces de manera estrat\u00e9gica en aguas poco profundas?<\/p>\n<p>Paul Sereno, autor principal del estudio y profesor de biolog\u00eda y anatom\u00eda de los organismos en la Universidad de Chicago, dijo que la nueva investigaci\u00f3n apunta a que Spinosaurus era lo que \u00e9l llama una \u201cgarza infernal\u201d: un cazador semiaqu\u00e1tico de la l\u00ednea de costa con similitudes f\u00edsicas con un ave zancuda, pero a una escala aterradora.<\/p>\n<p>Seg\u00fan los f\u00f3siles reci\u00e9n identificados, la criatura probablemente ten\u00eda un hocico largo y estrecho para atrapar peces, un cuello capaz de impulsar la cabeza hacia abajo en un movimiento de estocada y patas lo suficientemente largas como para cazar en aguas poco profundas.<\/p>\n<p>Cuando los investigadores compararon las proporciones de la cabeza, el cuello y las extremidades posteriores de los huesos fosilizados con las de una garza azul adulta, las similitudes sugirieron que el Spinosaurus estaba adaptado para acechar y atacar a lo largo de costas abiertas y bordes de r\u00edos.<\/p>\n<p>Pero la \u201cprueba irrefutable\u201d, seg\u00fan Sereno, fue que los f\u00f3siles se encontraron muy tierra adentro, lo que sugiere que la criatura viv\u00eda y cazaba a lo largo de sistemas fluviales y otras v\u00edas de agua poco profundas, en lugar del mar. Encontrar un depredador gigante adaptado al medio marino en el centro del continente, dijo, ser\u00eda tan improbable como \u201cencontrar una ballena azul en Chicago\u201d.<\/p>\n<p>Al igual que Spinosaurus aegyptiacus, Spinosaurus mirabilis ten\u00eda una cresta \u00f3sea en la cabeza, pero en S. mirabilis la estructura era m\u00e1s pronunciada y dram\u00e1tica en comparaci\u00f3n con sus parientes.<\/p>\n<p>Es una \u201ccresta \u00f3sea llamativa que sobresale de su cabeza, como el peinado tipo tup\u00e9 de Elvis\u201d, coment\u00f3 en un correo electr\u00f3nico Steve Brusatte, paleont\u00f3logo de la Universidad de Edimburgo. No particip\u00f3 en el estudio.<\/p>\n<p>Es \u201cun arma muy mala\u201d, dijo Sereno sobre la cresta de la cabeza de la criatura.<br \/>Est\u00e1 ubicada de manera inc\u00f3moda, es algo fr\u00e1gil y asim\u00e9trica; rasgos que apuntan a que no se usaba para el combate y s\u00ed para exhibici\u00f3n y se\u00f1alizaci\u00f3n, quiz\u00e1 incluso se\u00f1alizaci\u00f3n sexual, a\u00f1adi\u00f3.<\/p>\n<p>La diferencia en las crestas de la cabeza de los f\u00f3siles reci\u00e9n identificados y otros restos de Spinosaurus ayud\u00f3 a los investigadores a confirmar que se trataba de una especie distinta dentro del g\u00e9nero Spinosaurus.<\/p>\n<p>En comparaci\u00f3n con Spinosaurus aegyptiacus, Spinosaurus mirabilis tambi\u00e9n ten\u00eda una mand\u00edbula m\u00e1s baja y dientes entrelazados, una configuraci\u00f3n que, seg\u00fan Sereno, es muy adecuada para sujetar peces resbaladizos.<\/p>\n<p>El estudio tambi\u00e9n arroja luz sobre la evoluci\u00f3n del Spinosaurus, que pudo haberse desarrollado en tres fases. Durante el Jur\u00e1sico, surgi\u00f3 su cr\u00e1neo para atrapar peces; en el Cret\u00e1cico temprano, el Spinosaurus se convirti\u00f3 en un depredador dominante alrededor del antiguo mar de Tetis; y justo antes del Cret\u00e1cico tard\u00edo, a medida que se abr\u00eda el oc\u00e9ano Atl\u00e1ntico, el Spinosaurus alcanz\u00f3 sus mayores tama\u00f1os y se convirti\u00f3 en un especialista en emboscadas en aguas poco profundas en el norte de \u00c1frica y Sudam\u00e9rica.<\/p>\n<p>\u201cDurante mucho tiempo ha sido un dinosaurio misterioso, pero con cada nuevo hallazgo f\u00f3sil el verdadero Spinosaurus va tomando forma lentamente\u201d, dijo Brusatte.<\/p>\n<p>Sereno destac\u00f3 c\u00f3mo las herramientas modernas aceleraron la investigaci\u00f3n. El equipo tom\u00f3 cientos de fotos y cre\u00f3 modelos 3D de S. mirabilis, lo que permiti\u00f3 a los investigadores manipular digitalmente la cresta y los fragmentos de la mand\u00edbula, y comenzar a reconstruir el cr\u00e1neo.<\/p>\n<p>El nuevo hallazgo f\u00f3sil representa un \u201crenacimiento\u201d en la investigaci\u00f3n sobre dinosaurios depredadores gigantes, coment\u00f3 por correo electr\u00f3nico Matteo Fabbri, profesor adjunto del Centro de Anatom\u00eda Funcional y Evoluci\u00f3n de la Facultad de Medicina de la Universidad Johns Hopkins. Fabbri no particip\u00f3 en la investigaci\u00f3n.<\/p>\n<p>Pero tambi\u00e9n se\u00f1al\u00f3 que es dif\u00edcil establecer una nueva especie a partir de fragmentos f\u00f3siles. La naturaleza fragmentaria de los f\u00f3siles no ofrece \u201cmucho con qu\u00e9 trabajar, lo que deja muchas dudas sobre la anatom\u00eda real del animal\u201d, afirm\u00f3.<\/p>\n<p>Una r\u00e9plica del cr\u00e1neo de Spinosaurus est\u00e1 en exhibici\u00f3n en el Children\u2019s Museum de Chicago, brindando a los ni\u00f1os la oportunidad de verlo.<\/p>\n<p>Para Sereno, los f\u00f3siles no son solo un importante hallazgo cient\u00edfico, sino una invitaci\u00f3n para que la pr\u00f3xima generaci\u00f3n se involucre con el asombro del descubrimiento.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un cr\u00e1neo fosilizado y mand\u00edbulas hallados en N\u00edger pertenec\u00edan a una criatura que ten\u00eda una gran cresta \u00f3sea sobre la cabeza y vivi\u00f3 hace unos 95 millones de a\u00f1os. Nombrada Spinosaurus mirabilis, es la primera especie de Spinosaurus identificada en m\u00e1s de un siglo. Los hallazgos, publicados el 19 de febrero en la revista Science, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472359","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Spinosaurus mirabilis: una &quot;garza infernal&quot; que suma evidencia en un debate de larga data sobre estos dinosaurios - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spinosaurus mirabilis: una &quot;garza infernal&quot; que suma evidencia en un debate de larga data sobre estos dinosaurios - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un cr\u00e1neo fosilizado y mand\u00edbulas hallados en N\u00edger pertenec\u00edan a una criatura que ten\u00eda una gran cresta \u00f3sea sobre la cabeza y vivi\u00f3 hace unos 95 millones de a\u00f1os. Nombrada Spinosaurus mirabilis, es la primera especie de Spinosaurus identificada en m\u00e1s de un siglo. Los hallazgos, publicados el 19 de febrero en la revista Science, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-19T23:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Spinosaurus mirabilis: una &#171;garza infernal&#187; que suma evidencia en un debate de larga data sobre estos dinosaurios\",\"datePublished\":\"2026-03-19T23:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/\"},\"wordCount\":948,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/\",\"name\":\"Spinosaurus mirabilis: una \\\"garza infernal\\\" que suma evidencia en un debate de larga data sobre estos dinosaurios - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-19T23:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spinosaurus mirabilis: una &#171;garza infernal&#187; que suma evidencia en un debate de larga data sobre estos dinosaurios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spinosaurus mirabilis: una \"garza infernal\" que suma evidencia en un debate de larga data sobre estos dinosaurios - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Spinosaurus mirabilis: una \"garza infernal\" que suma evidencia en un debate de larga data sobre estos dinosaurios - Noticias","og_description":"Un cr\u00e1neo fosilizado y mand\u00edbulas hallados en N\u00edger pertenec\u00edan a una criatura que ten\u00eda una gran cresta \u00f3sea sobre la cabeza y vivi\u00f3 hace unos 95 millones de a\u00f1os. Nombrada Spinosaurus mirabilis, es la primera especie de Spinosaurus identificada en m\u00e1s de un siglo. Los hallazgos, publicados el 19 de febrero en la revista Science, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-19T23:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/"},"author":{"name":"","@id":""},"headline":"Spinosaurus mirabilis: una &#171;garza infernal&#187; que suma evidencia en un debate de larga data sobre estos dinosaurios","datePublished":"2026-03-19T23:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/"},"wordCount":948,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/","name":"Spinosaurus mirabilis: una \"garza infernal\" que suma evidencia en un debate de larga data sobre estos dinosaurios - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-19T23:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Spinosaurus mirabilis: una &#171;garza infernal&#187; que suma evidencia en un debate de larga data sobre estos dinosaurios"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Spinosaurus mirabilis: una &#171;garza infernal&#187; que suma evidencia en un debate de larga data sobre estos dinosaurios","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/19\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-19T23:03:53Z","datePublished":"2026-03-19T23:03:53Z","dateModified":"2026-03-19T23:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Spinosaurus mirabilis: una &#171;garza infernal&#187; que suma evidencia en un debate de larga data sobre estos dinosaurios\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/19\\\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/19\\\/spinosaurus-mirabilis-nueva-especie-dinosaurio-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-19T23:03:53Z\",\"datePublished\":\"2026-03-19T23:03:53Z\",\"dateModified\":\"2026-03-19T23:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446169,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/01\/timothee-chalamet-y-zendaya-vieron-a-criatura-austin-butler-dune-parte-dos-trax\/","url_meta":{"origin":1472359,"position":0},"title":"Timoth\u00e9e Chalamet y Zendaya recuerdan la primera vez que vieron a la &#8216;criatura aterradora&#8217; (Austin Butler) en el set de &#171;Dune: Parte Dos&#187;","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN) -- En el drama \u00e9pico de ciencia ficci\u00f3n \"Dune: Parte Dos\", a Timoth\u00e9e Chalamet y Zendaya se les unen nuevos personajes clave, interpretados por Christopher Walken, Florence Pugh, L\u00e9a Seydoux, Anya Taylor-Joy y Austin Butler, quien interpreta al villano y \"psic\u00f3tico\" (como le describe el personaje de Pugh en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446466,"url":"https:\/\/noticiasya.com\/springfield\/2024\/03\/04\/timothee-chalamet-y-zendaya-vieron-a-criatura-austin-butler-dune-parte-dos-trax-2\/","url_meta":{"origin":1472359,"position":1},"title":"Timoth\u00e9e Chalamet y Zendaya recuerdan la primera vez que vieron a la &#8216;criatura aterradora&#8217; (Austin Butler) en el set de &#171;Dune: Parte Dos&#187;","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- En el drama \u00e9pico de ciencia ficci\u00f3n \"Dune: Parte Dos\", a Timoth\u00e9e Chalamet y Zendaya se les unen nuevos personajes clave, interpretados por Christopher Walken, Florence Pugh, L\u00e9a Seydoux, Anya Taylor-Joy y Austin Butler, quien interpreta al villano y \"psic\u00f3tico\" (como le describe el personaje de Pugh en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455241,"url":"https:\/\/noticiasya.com\/springfield\/2024\/10\/18\/fosiles-antropodo-mas-grande-mundo-trax\/","url_meta":{"origin":1472359,"position":2},"title":"F\u00f3siles muestran c\u00f3mo era realmente el artr\u00f3podo m\u00e1s grande del mundo, que vivi\u00f3 hace 300 millones de a\u00f1os","author":"","date":"octubre 18, 2024","format":false,"excerpt":"(CNN) -- Durante casi dos siglos, los cient\u00edficos han intentado resolver un misterio persistente sobre un animal gigante parecido a un milpi\u00e9s llamado Arthropleura, que usaba sus m\u00faltiples patas para deambular por la Tierra hace m\u00e1s de 300 millones de a\u00f1os.Ahora, dos f\u00f3siles bien conservados de la criatura desenterrados en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445962,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/23\/fosil-dragon-240-millones-trax\/","url_meta":{"origin":1472359,"position":3},"title":"Cient\u00edficos revelan un f\u00f3sil de &#171;drag\u00f3n&#187; de 240 millones de a\u00f1os","author":"","date":"febrero 23, 2024","format":false,"excerpt":"(CNN) \u2014 F\u00f3siles reci\u00e9n descubiertos permitieron a los cient\u00edficos revelar por completo el de un \u201cdrag\u00f3n\u201d de 240 millones de a\u00f1os, informaron los Museos Nacionales de Escocia (NMS, por sus siglas en ingl\u00e9s) en un comunicado este viernes.El reptil de cinco metros de largo, perteneciente al per\u00edodo Tri\u00e1sico en China,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1406713,"url":"https:\/\/noticiasya.com\/springfield\/2022\/06\/16\/instalan-mas-camaras-en-zoologico-de-amarillo-tras-aparicion-de-criatura\/","url_meta":{"origin":1472359,"position":4},"title":"Instalan m\u00e1s c\u00e1maras en Zool\u00f3gico de Amarillo tras aparicion de criatura","author":"agomez","date":"junio 16, 2022","format":false,"excerpt":"Los funcionarios del zool\u00f3gico emitieron un comunicado agradeciendo a Wyze por su generosa donaci\u00f3n.","rel":"","context":"In &quot;Comunidad&quot;","block_context":{"text":"Comunidad","link":"https:\/\/noticiasya.com\/springfield\/categoria\/comunidad"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469272,"url":"https:\/\/noticiasya.com\/springfield\/2025\/12\/15\/peliculas-iberoamericanas-premios-oscar-orix\/","url_meta":{"origin":1472359,"position":5},"title":"Estas son las pel\u00edculas iberoamericanas que aspiran a ser nominadas a los premios Oscar","author":"agomez","date":"diciembre 15, 2025","format":false,"excerpt":"Este a\u00f1o, 16 pel\u00edculas de Iberoam\u00e9rica fueron admitidas por la academia del cine de Hollywood, que esta semana publicar\u00e1 una lista preliminar de 15 aspirantes para ser consideradas a una nominaci\u00f3n al Oscar 2026 en la categor\u00eda de mejor pel\u00edcula internacional.Estas son las producciones que representan a la regi\u00f3n.Una abogada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472359"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472359\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}