{"id":1472364,"date":"2026-03-19T18:03:45","date_gmt":"2026-03-20T01:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/"},"modified":"2026-03-19T18:03:45","modified_gmt":"2026-03-20T01:03:45","slug":"march-madness-baloncesto-primera-ronda-ncaa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/","title":{"rendered":"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber"},"content":{"rendered":"<p>La locura (<em>madness<\/em>, en ingl\u00e9s) se ha desatado por completo.<\/p>\n<p>Los primeros 16 partidos del torneo masculino se est\u00e1n disputando a lo largo del jueves y hasta las primeras horas de la madrugada del viernes; y ya hemos vivido un encuentro de infarto y un resultado hist\u00f3rico.<\/p>\n<p>Esto es todo lo que necesitas saber sobre la primera jornada del torneo de la NCAA.<\/p>\n<p>El primer partido del torneo siempre enfrenta a los cabezas de serie octavo y noveno, y, por lo general, resulta un encuentro muy parejo. Durante unos 25 minutos del jueves, pareci\u00f3 que TCU pondr\u00eda fin a una temporada dif\u00edcil para Ohio State.<\/p>\n<p>Eso hasta que los Buckeyes recordaron que hab\u00eda llegado la hora de la verdad: ganar o irse a casa.<\/p>\n<p>Una contundente racha en la segunda mitad puso a los Buckeyes por delante, y los minutos finales del encuentro transcurrieron con el liderato cambiando de manos en un ajustado partido decidido por una sola posesi\u00f3n.<\/p>\n<p>El partido inaugural se decidi\u00f3 en el \u00faltimo minuto: TCU tom\u00f3 una ventaja de tres puntos, a la que Ohio State respondi\u00f3 cuando solo quedaban 30 segundos de juego.<\/p>\n<p>Los Horned Frogs agotaron todo el reloj de posesi\u00f3n en su siguiente ataque. Xavier Edmonds logr\u00f3 ejecutar un tiro complicado desde la pintura a falta de apenas cuatro segundos, encestando la canasta de la ventaja ante la marca de dos defensores.<\/p>\n<p>Ohio State tuvo la oportunidad de realizar un \u00faltimo tiro \u2014un lanzamiento desesperado sobre la bocina\u2014, pero el bal\u00f3n rebot\u00f3 en el centro del tablero y los Buckeyes se convirtieron en la primera v\u00edctima del torneo de este a\u00f1o.<\/p>\n<p>El marcador final: TCU 66, Ohio State 64.<\/p>\n<p>No pas\u00f3 mucho tiempo antes de que se hiciera historia por primera vez en el torneo de este a\u00f1o.<\/p>\n<p>Nebraska, cuarto cabeza de serie en la regi\u00f3n Sur, logr\u00f3 algo que la universidad nunca antes hab\u00eda conseguido: ganar un partido del torneo.<\/p>\n<p>Los Cornhuskers acumulaban un balance de 0-8 en el torneo antes del jueves. Sin embargo, este equipo de Nebraska era muy diferente al de a\u00f1os anteriores. Hab\u00edan iniciado la temporada con un r\u00e9cord de 20-0 y terminaron en segundo lugar en la conferencia Big Ten durante la temporada regular.<\/p>\n<p>Los Troy Trojans comenzaron el encuentro con gran acierto desde el campo y dieron un peque\u00f1o susto al equipo de Fred Hoiberg en los primeros compases. Sin embargo, una gran racha anotadora en la primera mitad puso a los Cornhuskers c\u00f3modamente por delante, permiti\u00e9ndoles controlar el partido con total tranquilidad. Oklahoma City se transform\u00f3 en una extensi\u00f3n del sur de Lincoln ante la gran cantidad de aficionados vestidos de rojo que realizaron el viaje, mientras los c\u00e1nticos de \u201c\u00a1Go Big Red!\u201d resonaban, impulsando a los Huskers hacia la victoria.<\/p>\n<p>Pryce Sandfort lider\u00f3 la ofensiva de Nebraska, desat\u00e1ndose desde el per\u00edmetro. Anot\u00f3 siete triples y finaliz\u00f3 el encuentro con 23 puntos, al tiempo que los Cornhuskers se encaminaban hacia una c\u00f3moda victoria por 76-47.<\/p>\n<p>Jugar\u00e1n contra el ganador del encuentro entre Vanderbilt y McNeese, quienes juegan m\u00e1s tarde este jueves.<\/p>\n<ul>\n<li><strong>TCU<\/strong> 66-64 Ohio State<\/li>\n<li><strong>Nebraska<\/strong> 76-47 Troy<\/li>\n<li><strong>Louisville<\/strong> 83-79 South Florida<\/li>\n<li>Wisconsin 82-83 <strong>High Point<\/strong><\/li>\n<li><strong>Duke<\/strong> 71-65 Siena<\/li>\n<li><strong>Vanderbilt<\/strong> 78-68 McNeese<\/li>\n<li><strong>Michigan State<\/strong> 92-67 North Dakota State<\/li>\n<li><strong>Arkansas<\/strong> 97-78 Hawai<\/li>\n<li>North Carolina vs. VCU (televisa TNT)<\/li>\n<li>Michigan vs. Howard (televisa CBS)<\/li>\n<li>BYU vs. Texas (televisa TBS)<\/li>\n<li>Saint Mary\u2019s vs. Texas A&#038;M (televisa truTV)<\/li>\n<li>Illinois vs. University of Pennsylvania (televisa TNT)<\/li>\n<li>Georgia vs. Saint Louis (televisa CBS)<\/li>\n<li>Gonzaga vs. Kennesaw State (televisa TBS)<\/li>\n<li>Houston vs. Idaho (televisa truTV)<\/li>\n<\/ul>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La locura (madness, en ingl\u00e9s) se ha desatado por completo. Los primeros 16 partidos del torneo masculino se est\u00e1n disputando a lo largo del jueves y hasta las primeras horas de la madrugada del viernes; y ya hemos vivido un encuentro de infarto y un resultado hist\u00f3rico. Esto es todo lo que necesitas saber sobre [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472364","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber - Noticias\" \/>\n<meta property=\"og:description\" content=\"La locura (madness, en ingl\u00e9s) se ha desatado por completo. Los primeros 16 partidos del torneo masculino se est\u00e1n disputando a lo largo del jueves y hasta las primeras horas de la madrugada del viernes; y ya hemos vivido un encuentro de infarto y un resultado hist\u00f3rico. Esto es todo lo que necesitas saber sobre [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T01:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber\",\"datePublished\":\"2026-03-20T01:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/\"},\"wordCount\":641,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/\",\"name\":\"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-20T01:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber - Noticias","og_description":"La locura (madness, en ingl\u00e9s) se ha desatado por completo. Los primeros 16 partidos del torneo masculino se est\u00e1n disputando a lo largo del jueves y hasta las primeras horas de la madrugada del viernes; y ya hemos vivido un encuentro de infarto y un resultado hist\u00f3rico. Esto es todo lo que necesitas saber sobre [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-20T01:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/"},"author":{"name":"","@id":""},"headline":"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber","datePublished":"2026-03-20T01:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/"},"wordCount":641,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/","name":"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-20T01:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El March Madness comenz\u00f3 de manera fren\u00e9tica y ya se hizo historia: esto es lo que necesitas saber","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/19\/march-madness-baloncesto-primera-ronda-ncaa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-20T01:03:45Z","datePublished":"2026-03-20T01:03:45Z","dateModified":"2026-03-20T01:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El March Madness comenz\\u00f3 de manera fren\\u00e9tica y ya se hizo historia: esto es lo que necesitas saber\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/19\\\/march-madness-baloncesto-primera-ronda-ncaa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/19\\\/march-madness-baloncesto-primera-ronda-ncaa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-20T01:03:45Z\",\"datePublished\":\"2026-03-20T01:03:45Z\",\"dateModified\":\"2026-03-20T01:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472396,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/20\/march-madness-terminos-conocer-orix\/","url_meta":{"origin":1472364,"position":0},"title":"March Madness, explicado: los t\u00e9rminos que debes conocer","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Ya est\u00e1 en marcha el torneo nacional de la primera divisi\u00f3n del b\u00e1squetbol universitario de la NCAA, competencia que es conocida como el \u201cMarch Madness\u201d, o \u201cLocura de Marzo\u201d, en espa\u00f1ol.A\u00f1o tras a\u00f1o, los equipos m\u00e1s destacados de la temporada compiten por ver cu\u00e1l es el mejor programa de Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472593,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/26\/sweet-16-march-madness-partidos-ncaa-trax\/","url_meta":{"origin":1472364,"position":1},"title":"Llega el &#171;Sweet 16&#187; del March Madness: as\u00ed se definen los clasificados al Final Four de la NCAA","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Durante los \u00faltimos d\u00edas, los aficionados de 16 equipos de baloncesto universitario masculino no han podido sacarse una idea de la cabeza: dos victorias m\u00e1s para llegar al Final Four.Tras sobrevivir al arduo desaf\u00edo que representan las rondas iniciales del March Madness, alcanzar el Sweet 16 constituye, de por s\u00ed,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472550,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/25\/favoritos-march-madness-sweet-16-ncaa-orix\/","url_meta":{"origin":1472364,"position":2},"title":"Llega el &#171;Sweet 16&#187; del March Madness: estos son los favoritos al t\u00edtulo","author":"","date":"marzo 25, 2026","format":false,"excerpt":"Ya est\u00e1 aqu\u00ed el \u201cSweet 16\u201d, o los octavos de final del torneo nacional de baloncesto universitario de la primera divisi\u00f3n de la NCAA. Una competencia conocida popularmente como el \u201cMarch Madness\u201d, o la \u201cLocura de Marzo\u201d.Hasta el momento, el mayor batacazo lo dio la Universidad de Iowa, que elimin\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472339,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/march-madness-calendario-horarios-bracket-baloncesto-orix\/","url_meta":{"origin":1472364,"position":3},"title":"March Madness: calendario, horarios y bracket del baloncesto universitario en EE.UU.","author":"","date":"marzo 19, 2026","format":false,"excerpt":"El torneo universitario de baloncesto de la NCAA en Estados Unidos comienza. El conocido March Madness es uno de los eventos deportivos m\u00e1s seguidos en el pa\u00eds.La edici\u00f3n de 2026 contar\u00e1 con una destacada presencia de talento espa\u00f1ol y latinoamericano.Entre los espa\u00f1oles sobresalen el base malague\u00f1o Mario Saint-Supery, de Gonzaga,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445449,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/15\/messi-y-su-frenetica-agenda-le-permitira-estar-presente-en-los-juegos-olimpicos\/","url_meta":{"origin":1472364,"position":4},"title":"Messi y su fren\u00e9tica agenda, \u00bfle permitir\u00e1 estar presente en los Juegos Ol\u00edmpicos?","author":"","date":"febrero 15, 2024","format":false,"excerpt":"(CNN) -- \"Vamos\", suscribi\u00f3 Lionel Messi en el posteo que la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) realiz\u00f3 a los pocos minutos que la Albiceleste consigui\u00f3 el boleto a Par\u00eds 2024.El s\u00edmbolo m\u00e1ximo de la Albiceleste se sum\u00f3 al festejo de la selecci\u00f3n de Argentina sub-23, que este domingo venci\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445451,"url":"https:\/\/noticiasya.com\/springfield\/2024\/02\/15\/messi-y-su-frenetica-agenda-le-permitira-estar-presente-en-los-juegos-olimpicos-2\/","url_meta":{"origin":1472364,"position":5},"title":"Messi y su fren\u00e9tica agenda, \u00bfle permitir\u00e1 estar presente en los Juegos Ol\u00edmpicos?","author":"","date":"febrero 15, 2024","format":false,"excerpt":"(CNN) -- \"Vamos\", suscribi\u00f3 Lionel Messi en el posteo que la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) realiz\u00f3 a los pocos minutos que la Albiceleste consigui\u00f3 el boleto a Par\u00eds 2024.El s\u00edmbolo m\u00e1ximo de la Albiceleste se sum\u00f3 al festejo de la selecci\u00f3n de Argentina sub-23, que este domingo venci\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472364"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472364\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}