{"id":1472394,"date":"2026-03-20T14:03:43","date_gmt":"2026-03-20T21:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/"},"modified":"2026-03-20T14:03:43","modified_gmt":"2026-03-20T21:03:43","slug":"gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/","title":{"rendered":"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &#171;no es objeto de negociaci\u00f3n&#187; con EE.UU."},"content":{"rendered":"<p>El Gobierno de Cuba afirm\u00f3 este viernes que el sistema pol\u00edtico de la isla, incluido el presidente Miguel D\u00edaz-Canel, \u201cno es objeto de negociaci\u00f3n\u201d con Estados Unidos.<\/p>\n<p>\u201cLo que s\u00ed puedo confirmar categ\u00f3ricamente, y est\u00e1 entre las l\u00edneas de lo que dijo el presidente (D\u00edaz-Canel), es que el sistema pol\u00edtico cubano no es objeto de negociaci\u00f3n y, por supuesto, ni el presidente ni el cargo de ning\u00fan directivo en Cuba es objeto de negociaci\u00f3n con Estados Unidos ni con el gobierno de ning\u00fan pa\u00eds\u201d, declar\u00f3 Carlos Fern\u00e1ndez de Coss\u00edo, viceministro de Relaciones Exteriores de Cuba, en conferencia de prensa desde La Habana.<\/p>\n<p>Hace una semana, D\u00edaz-Canel <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/13\/latinoamerica\/diaz-canel-cuba-conferencia-dialogo-eeuu-orix\">confirm\u00f3<\/a> que funcionarios de su Gobierno dialogaron con Estados Unidos para buscar soluciones al embargo impuesto en la isla, que los cubanos consideran un bloqueo.<\/p>\n<p>D\u00edaz-Canel agreg\u00f3 que los di\u00e1logos con EE.UU. eran parte \u201cde un proceso muy sensible que se aborda con responsabilidad y mucha sensibilidad\u2026 Hemos expresado nuestra voluntad de continuar el proceso bajo los principios de la igualdad y el respeto a los sistemas pol\u00edticos de ambos pa\u00edses, a la soberan\u00eda y a la autodeterminaci\u00f3n\u201d.<\/p>\n<p>Este viernes, Fern\u00e1ndez de Coss\u00edo recalc\u00f3 el tono del mensaje de D\u00edaz-Canel sobre el respeto a los sistemas pol\u00edticos, diciendo que \u201cel sistema pol\u00edtico de Estados Unidos tampoco forma parte de la negociaci\u00f3n\u201d.<\/p>\n<p>\u201cNosotros no hemos exigido ning\u00fan cambio constitucional en Estados Unidos, ni hemos pedido que despidan o que excluyan del gobierno a ning\u00fan funcionario\u201d, dijo el vicecanciller cubano. \u201cLas diferencias pol\u00edticas que tenemos con Estados Unidos se manejan de otra manera. Y en la negociaci\u00f3n no est\u00e1n exigencias de Cuba al sistema pol\u00edtico de Estados Unidos\u201d, agreg\u00f3.<\/p>\n<p>Las declaraciones de Fern\u00e1ndez de Coss\u00edo llegan en medio del momento m\u00e1s tenso entre Estados Unidos y Cuba en d\u00e9cadas.<\/p>\n<p>Cuba se encuentra atravesando una de las crisis econ\u00f3micas y sociales m\u00e1s graves de su historia, con<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/14\/latinoamerica\/cuba-petroleo-energia-afectaciones-presion-eeuu-orix\"> apagones recurrentes, protestas <\/a>y escasez de bienes b\u00e1sicos no vistos desde el llamado <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/27\/latinoamerica\/razones-crisis-cuba-economia-orix\">\u201cperiodo especial\u201d <\/a>de comienzos de la d\u00e9cada de 1990.<\/p>\n<p>La situaci\u00f3n empeor\u00f3 notablemente a partir del derrocamiento del presidente de Venezuela, Nicol\u00e1s Maduro, por parte de Estados Unidos en enero de este a\u00f1o, que llev\u00f3 a la suspensi\u00f3n de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/27\/latinoamerica\/razones-crisis-cuba-economia-orix\">los env\u00edos de petr\u00f3leo venezolano a Cuba<\/a>. Despu\u00e9s, Trump amenaz\u00f3 con imponer aranceles a todos los pa\u00edses que enviaran crudo a Cuba, por lo que M\u00e9xico, su segundo mejor proveedor de petr\u00f3leo, interrumpi\u00f3 los env\u00edos de combustible, aunque <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/17\/mexico\/embajadores-cuba-eeuu-chocan-llamado-ayudar-pueblo-orix\">mantiene sus entregas de ayuda humanitaria<\/a> para la isla.<\/p>\n<p>Sin el comustible de Venezuela y M\u00e9xico, y con el embargo econ\u00f3mico impuesto por EE.UU., Cuba vive una situaci\u00f3n <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/17\/latinoamerica\/cuba-apagon-recuperacion-lenta-energia-orix\">cr\u00edtica<\/a>. La crisis se enmarca en el contexto general de la tensa relaci\u00f3n que La Habana mantiene con Washington desde el triunfo de la Revoluci\u00f3n en 1959.<\/p>\n<p>Pese a la existencia de conversaciones actuales entre ambos gobiernos, Trump reiter\u00f3 esta semana su amenaza de \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/16\/eeuu\/video\/trump-eeuu-tomar-cuba\">tomar<\/a>\u201d Cuba, sin ofrecer m\u00e1s detalles. Ante las preguntas de periodistas, el presidente de EE.UU. dijo que en este momento Cuba es \u201cuna naci\u00f3n muy debilitada\u201d. Adem\u00e1s, tambi\u00e9n esta semana, el secretario de Estado, Marco Rubio, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/17\/eeuu\/video\/marco-rubio-embargo-cuba-trax\">asegur\u00f3<\/a> que el liderazgo de Cuba deber\u00eda \u201ctener personas diferentes\u201d.<\/p>\n<p>Previamente, Trump <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/11\/latinoamerica\/trump-cuba-acuerdo-ameneza-trax\">ha advertido<\/a> a Cuba que \u201chaga un trato antes de que sea demasiado tarde\u201d y <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/27\/eeuu\/trump-toma-control-amistosa-cuba-trax\">ha planteado<\/a> una posible \u201ctoma de control amistosa\u201d de la isla.<\/p>\n<p>En tanto, D\u00edaz-Canel ha respondido a estos planteamientos. Hace unos d\u00edas, el presidente de la isla <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/18\/mundo\/presidente-cuba-intento-ee-uu-controlar-resistencia-inexpugnable-trax\">dijo<\/a> que cualquier intento de Estados Unidos de tomar el control del pa\u00eds ser\u00e1 respondido con una \u201cresistencia inexpugnable\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Cuba afirm\u00f3 este viernes que el sistema pol\u00edtico de la isla, incluido el presidente Miguel D\u00edaz-Canel, \u201cno es objeto de negociaci\u00f3n\u201d con Estados Unidos. \u201cLo que s\u00ed puedo confirmar categ\u00f3ricamente, y est\u00e1 entre las l\u00edneas de lo que dijo el presidente (D\u00edaz-Canel), es que el sistema pol\u00edtico cubano no es objeto de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472394","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &quot;no es objeto de negociaci\u00f3n&quot; con EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &quot;no es objeto de negociaci\u00f3n&quot; con EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Gobierno de Cuba afirm\u00f3 este viernes que el sistema pol\u00edtico de la isla, incluido el presidente Miguel D\u00edaz-Canel, \u201cno es objeto de negociaci\u00f3n\u201d con Estados Unidos. \u201cLo que s\u00ed puedo confirmar categ\u00f3ricamente, y est\u00e1 entre las l\u00edneas de lo que dijo el presidente (D\u00edaz-Canel), es que el sistema pol\u00edtico cubano no es objeto de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T21:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &#171;no es objeto de negociaci\u00f3n&#187; con EE.UU.\",\"datePublished\":\"2026-03-20T21:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/\"},\"wordCount\":685,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/\",\"name\":\"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel \\\"no es objeto de negociaci\u00f3n\\\" con EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-20T21:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &#171;no es objeto de negociaci\u00f3n&#187; con EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel \"no es objeto de negociaci\u00f3n\" con EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel \"no es objeto de negociaci\u00f3n\" con EE.UU. - Noticias","og_description":"El Gobierno de Cuba afirm\u00f3 este viernes que el sistema pol\u00edtico de la isla, incluido el presidente Miguel D\u00edaz-Canel, \u201cno es objeto de negociaci\u00f3n\u201d con Estados Unidos. \u201cLo que s\u00ed puedo confirmar categ\u00f3ricamente, y est\u00e1 entre las l\u00edneas de lo que dijo el presidente (D\u00edaz-Canel), es que el sistema pol\u00edtico cubano no es objeto de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-20T21:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/"},"author":{"name":"","@id":""},"headline":"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &#171;no es objeto de negociaci\u00f3n&#187; con EE.UU.","datePublished":"2026-03-20T21:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/"},"wordCount":685,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/","name":"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel \"no es objeto de negociaci\u00f3n\" con EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-20T21:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &#171;no es objeto de negociaci\u00f3n&#187; con EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &#171;no es objeto de negociaci\u00f3n&#187; con EE.UU.","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-20T21:03:43Z","datePublished":"2026-03-20T21:03:43Z","dateModified":"2026-03-20T21:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gobierno de Cuba dice que el cargo del presidente Miguel D\\u00edaz-Canel &#171;no es objeto de negociaci\\u00f3n&#187; con EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/20\\\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/20\\\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-20T21:03:43Z\",\"datePublished\":\"2026-03-20T21:03:43Z\",\"dateModified\":\"2026-03-20T21:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472402,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/20\/cuba-regala-fusil-combate-silvio-rodriguez-orix\/","url_meta":{"origin":1472394,"position":0},"title":"Cuba le regala un fusil AKM al cantautor Silvio Rodr\u00edguez por su &#171;patri\u00f3tica disposici\u00f3n&#187; a defender el pa\u00eds","author":"","date":"marzo 20, 2026","format":false,"excerpt":"El Gobierno del presidente de Cuba, Miguel D\u00edaz-Canel, le regal\u00f3 este viernes un fusil AKM y una r\u00e9plica de la misma arma al cantautor cubano Silvio Rodr\u00edguez por su \u201cpatri\u00f3tica disposici\u00f3n\u201d para defender al pa\u00eds, que atraviesa una grave crisis que se ha profundizado en las \u00faltimas semanas por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472428,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","url_meta":{"origin":1472394,"position":1},"title":"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU.","author":"","date":"marzo 21, 2026","format":false,"excerpt":"El presidente de Cuba, Miguel D\u00edaz-Canel, habl\u00f3 este viernes sobre la presi\u00f3n que ejerce Estados Unidos sobre la isla y, en medio de las tensiones con el Gobierno de Donald Trump, reconoci\u00f3 que puede haber una agresi\u00f3n contra la isla y dijo que el pueblo cubano se prepara para defender\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472430,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/21\/lula-critica-eeuu-venezuela-cuba-petro-cuestiona-onu-conflictos-orix\/","url_meta":{"origin":1472394,"position":2},"title":"Lula critica acciones de EE.UU. sobre Venezuela y Cuba, mientras Petro cuestiona la capacidad de ONU para evitar conflictos","author":"","date":"marzo 21, 2026","format":false,"excerpt":"El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, critic\u00f3 este s\u00e1bado las acciones de Estados Unidos sobre Venezuela y Cuba, pa\u00edses que han visto en los \u00faltimos meses ataques militares en su territorio y amenazas de tomas de control, respectivamente.Durante el Foro de Alto Nivel de la Comunidad de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472340,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/cuba-miguel-diaz-canel-presidente-revolucion-quien-es-orix\/","url_meta":{"origin":1472394,"position":3},"title":"Miguel D\u00edaz-Canel, el presidente que prometi\u00f3 &#171;la continuidad de la revoluci\u00f3n&#187; en Cuba y hoy ve amenazado ese objetivo","author":"","date":"marzo 19, 2026","format":false,"excerpt":"Cuando asumi\u00f3 la presidencia de Cuba hace casi ocho a\u00f1os, Miguel D\u00edaz-Canel dijo tener claro cu\u00e1l deb\u00eda ser su principal objetivo: mantener viva la revoluci\u00f3n que comenz\u00f3 en 1959, dio forma al sistema de gobierno que desde entonces rige en la isla y se convirti\u00f3 en un s\u00edmbolo para la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470897,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/05\/diaz-canel-cuba-dispuesta-dialogo-eeuu-sin-presiones-orix\/","url_meta":{"origin":1472394,"position":4},"title":"D\u00edaz-Canel confirma que Cuba est\u00e1 dispuesta al di\u00e1logo con EE.UU., pero &#171;sin presiones&#187;","author":"","date":"febrero 5, 2026","format":false,"excerpt":"Miguel D\u00edaz-Canel, presidente de Cuba, dijo este jueves que su gobierno est\u00e1 dispuesto a dialogar con la administraci\u00f3n estadounidense de Donald Trump, siempre y cuando no haya \u201cpresiones\u201d.\u201cCuba est\u00e1 dispuesta a un di\u00e1logo con los Estados Unidos, a un di\u00e1logo sobre cualquiera de los temas que se quiera debatir o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472808,"url":"https:\/\/noticiasya.com\/springfield\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","url_meta":{"origin":1472394,"position":5},"title":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado","author":"","date":"abril 2, 2026","format":false,"excerpt":"Cuba parece estar al borde del colapso. Sin petr\u00f3leo desde la ca\u00edda de Nicol\u00e1s Maduro en Venezuela en enero, sin el apoyo pol\u00edtico de muchos de sus antiguos aliados y en medio de una perpetua crisis econ\u00f3mica, el pa\u00eds comunista atraviesa la que es posiblemente la crisis m\u00e1s importante desde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472394"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472394\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}