{"id":1472399,"date":"2026-03-20T16:03:51","date_gmt":"2026-03-20T23:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/"},"modified":"2026-03-20T16:03:51","modified_gmt":"2026-03-20T23:03:51","slug":"cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/","title":{"rendered":"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal"},"content":{"rendered":"<p>Se viene una nueva fecha FIFA de partidos amistosos internacionales y, como no, el repechaje mundialista que entrega los \u00faltimos seis cupos a la<a href=\"https:\/\/cnnespanol.cnn.com\/deportes\/mundial-2026\"> cita de Canad\u00e1, Estados Unidos y M\u00e9xico.<\/a> Pero tambi\u00e9n tendremos la reinauguraci\u00f3n del Estadio Azteca, que extra\u00f1ar\u00e1 a quien aparec\u00eda como invitado de lujo.<\/p>\n<p>Se trata de Cristiano Ronaldo, quien es el gran ausente en la \u00faltima convocatoria de Portugal para una doble fecha de preparaci\u00f3n ante dos de los anfitriones de la pr\u00f3xima Copa del Mundo: M\u00e9xico (28 de marzo) y Estados Unidos (31 de marzo).<\/p>\n<p>Cristiano era uno de los atractivos principales para la primera prueba del coloso de Santa \u00darsula antes del comienzo del Mundial 2026, e incluso su posible presencia ayud\u00f3 a catapultar los precios de las entradas para un partido con grandes expectativas futbol\u00edsticas y, al mismo tiempo, de log\u00edstica.<\/p>\n<p>Pero el p\u00fablico mexicano se quedar\u00e1 con ganas de ver a CR7, luego que el \u00eddolo portugu\u00e9s y m\u00e1ximo anotador de la historia del f\u00fatbol moderno tuviera que ausentarse por lesi\u00f3n.<\/p>\n<p>La lista de Roberto Mart\u00ednez dej\u00f3 aislados a Cristiano, R\u00faben Dias y N\u00e9lson Semedo, habituales de la selecci\u00f3n, pero que no est\u00e1n aptos para jugar.<\/p>\n<p>Sin embargo, el seleccionador desestim\u00f3 que Cristiano Ronaldo sufriera una lesi\u00f3n grave que ponga en peligro su futuro con el equipo, especialmente para el Mundial 2026.<\/p>\n<p>\u201cNo, no, no, no est\u00e1 en riesgo (Cristiano Ronaldo). Es una lesi\u00f3n leve, una lesi\u00f3n muscular, y una lesi\u00f3n de la que creemos que podr\u00eda recuperarse en una o dos semanas. No es un per\u00edodo muy largo. Creo que todo lo que Cristiano ha hecho f\u00edsicamente durante esta temporada demuestra que est\u00e1 en excelente condici\u00f3n y que no hay ning\u00fan problema f\u00edsico\u201d, asegur\u00f3 Mart\u00ednez al momento de entregar la lista.<\/p>\n<p>Adem\u00e1s, el t\u00e9cnico espa\u00f1ol a cargo de la selecci\u00f3n lusa asegur\u00f3 que es una buena etapa para la \u201cgesti\u00f3n f\u00edsica y oportunidad\u201d, pensando en las opciones para terminar de construir el equipo de cara al Mundial.<\/p>\n<p>Dentro de la lista de 27 jugadores tambi\u00e9n aparece como gran novedad la convocatoria del mediocampista Mateus Fernandes, del West Ham, y la ausencia de Bruno Fernandes, del Manchester City, por decisi\u00f3n t\u00e9cnica.<\/p>\n<p><strong>Arqueros:<\/strong> Diogo Costa (FC Porto), Jos\u00e9 S\u00e1 (Wolverhampton Wanderers), Rui Silva (Sporting CP)<\/p>\n<p><strong>Defensas: <\/strong>Matheus Nunes (Manchester City), Diogo Dalot (Manchester United), Jo\u00e3o Cancelo (FC Barcelona), Nuno Mendes (PSG), Gon\u00e7alo In\u00e1cio (Sporting CP), Renato Veiga (Villarreal), Ant\u00f3nio Silva (SL Benfica), Tom\u00e1s Ara\u00fajo (SL Benfica).<\/p>\n<p><strong>Mediocampistas:<\/strong> R\u00faben Neves (Al Hilal), Sam\u00fa Costa (Mallorca), Mateus Fernandes (West Ham), Jo\u00e3o Neves (PSG), Vitinha (PSG), Bruno Fernandes (Manchester United) y Rodrigo Mora (FC Porto);<\/p>\n<p><strong>Delanteros:<\/strong> Ricardo Horta (SC Braga), Pedro Gon\u00e7alves (Sporting CP), Jo\u00e3o F\u00e9lix (Al Nassr), Francisco Trinc\u00e3o (Sporting CP), Francisco Concei\u00e7\u00e3o (Juventus), Rafael Le\u00e3o (AC Milan), Pedro Neto (Chelsea), Gon\u00e7alo Guedes (Real Sociedad) y Gon\u00e7alo Ramos (PSG).<\/p>\n<p>Antes del inicio del Mundial 2026, el Estadio Azteca habr\u00eda contado con la presencia de Cristiano Ronaldo y Lionel Messi en menos de un mes, pero el astro argentino no visitar\u00e1 el inmueble de momento, tras la <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/18\/deportes\/messi-gol-900-inter-miami-eliminado-efe\">eliminaci\u00f3n del Inter Miami de<\/a> la Copa de Campeones de la Concacaf y lo que hubiese sido un potencial enfrentamiento contra las \u00c1guilas del Am\u00e9rica.<\/p>\n<p>Portugal comparte el grupo K del Mundial con Uzbekist\u00e1n, Colombia y un equipo por clasificar entre Rep\u00fablica Democr\u00e1tica del Congo, Jamaica y Nueva Caledonia.<\/p>\n<p>El debut ser\u00e1 el 17 de junio en Houston, justamente contra la selecci\u00f3n clasificada del <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/12\/deportes\/repechaje-mundial-2026-orix\">repechaje<\/a>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se viene una nueva fecha FIFA de partidos amistosos internacionales y, como no, el repechaje mundialista que entrega los \u00faltimos seis cupos a la cita de Canad\u00e1, Estados Unidos y M\u00e9xico. Pero tambi\u00e9n tendremos la reinauguraci\u00f3n del Estadio Azteca, que extra\u00f1ar\u00e1 a quien aparec\u00eda como invitado de lujo. Se trata de Cristiano Ronaldo, quien es [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472399","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal - Noticias\" \/>\n<meta property=\"og:description\" content=\"Se viene una nueva fecha FIFA de partidos amistosos internacionales y, como no, el repechaje mundialista que entrega los \u00faltimos seis cupos a la cita de Canad\u00e1, Estados Unidos y M\u00e9xico. Pero tambi\u00e9n tendremos la reinauguraci\u00f3n del Estadio Azteca, que extra\u00f1ar\u00e1 a quien aparec\u00eda como invitado de lujo. Se trata de Cristiano Ronaldo, quien es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-20T23:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal\",\"datePublished\":\"2026-03-20T23:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/\"},\"wordCount\":656,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/\",\"name\":\"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-20T23:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal - Noticias","og_description":"Se viene una nueva fecha FIFA de partidos amistosos internacionales y, como no, el repechaje mundialista que entrega los \u00faltimos seis cupos a la cita de Canad\u00e1, Estados Unidos y M\u00e9xico. Pero tambi\u00e9n tendremos la reinauguraci\u00f3n del Estadio Azteca, que extra\u00f1ar\u00e1 a quien aparec\u00eda como invitado de lujo. Se trata de Cristiano Ronaldo, quien es [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-20T23:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/"},"author":{"name":"","@id":""},"headline":"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal","datePublished":"2026-03-20T23:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/"},"wordCount":656,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/","name":"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-20T23:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-20T23:03:51Z","datePublished":"2026-03-20T23:03:51Z","dateModified":"2026-03-20T23:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cristiano Ronaldo se pierde la reinauguraci\\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/20\\\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/20\\\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-20T23:03:51Z\",\"datePublished\":\"2026-03-20T23:03:51Z\",\"dateModified\":\"2026-03-20T23:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472651,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/28\/aficionado-muere-caida-reinaguracion-estadio-azteca-orix\/","url_meta":{"origin":1472399,"position":0},"title":"Un aficionado muere tras una ca\u00edda durante la reinauguraci\u00f3n del Estadio Azteca de la Ciudad de M\u00e9xico de cara al Mundial","author":"","date":"marzo 28, 2026","format":false,"excerpt":"Un aficionado muri\u00f3 este s\u00e1bado tras caer de la zona de palcos del Estadio Azteca de la Ciudad de M\u00e9xico, que este d\u00eda fue reinaugurado de cara al Mundial de F\u00fatbol del que M\u00e9xico ser\u00e1 anfitri\u00f3n junto con Estados Unidos y Canad\u00e1, inform\u00f3 la Secretar\u00eda de Seguridad Ciudadana de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473565,"url":"https:\/\/noticiasya.com\/springfield\/2026\/04\/28\/mundial-futbol-mexico-quejas-precios-entradas-orix\/","url_meta":{"origin":1472399,"position":1},"title":"&#171;Este Mundial no es de M\u00e9xico&#187;: los precios de las entradas generan malestar entre los aficionados mexicanos","author":"","date":"abril 28, 2026","format":false,"excerpt":"M\u00e9xico har\u00e1 historia como el primer pa\u00eds en albergar tres Copas del Mundo este verano, pero la euforia por este r\u00e9cord no se refleja en los aficionados mexicanos.Francisco Javier Ferreira, de 70 a\u00f1os, recuerda las dos Copas del Mundo a las que asisti\u00f3 en su pa\u00eds natal, M\u00e9xico 1970 y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468363,"url":"https:\/\/noticiasya.com\/springfield\/2025\/11\/14\/podria-cristiano-ronaldo-perder-inicio-mundial-2026-orix\/","url_meta":{"origin":1472399,"position":2},"title":"\u00bfPodr\u00eda Cristiano Ronaldo perderse el inicio del Mundial 2026 si le dan una sanci\u00f3n severa?","author":"","date":"noviembre 14, 2025","format":false,"excerpt":"Cristiano Ronaldo asegur\u00f3 antes del partido contra Irlanda, por las eliminatorias europeas para la Copa Mundial 2026, que se iba a portar bien y que, aunque sab\u00eda del talante severo del p\u00fablico irland\u00e9s, mantendr\u00eda la compostura.Sin embargo, ir abajo en el marcador por 2 a 0, entrada la segunda parte,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468235,"url":"https:\/\/noticiasya.com\/springfield\/2025\/11\/11\/cristiano-ronaldo-mundial-portugal-retiro-trax\/","url_meta":{"origin":1472399,"position":3},"title":"Cristiano Ronaldo sobre el Mundial: Tendr\u00e9 41 a\u00f1os y creo que ese ser\u00e1 el momento clave","author":"","date":"noviembre 11, 2025","format":false,"excerpt":"El delantero estrella de Portugal, Cristiano Ronaldo, dijo que el Mundial de la FIFA 2026 ser\u00e1 \u201cdefinitivamente\u201d su \u00faltimo.\u201cTendr\u00e9 41 a\u00f1os y creo que ese ser\u00e1 el momento clave en la gran competici\u00f3n\u201d, dijo Ronaldo a Becky Anderson de CNN en una entrevista en la Cumbre de Turismo en Riad,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468462,"url":"https:\/\/noticiasya.com\/springfield\/2025\/11\/18\/cristiano-ronaldo-casa-blanca-trump-trax\/","url_meta":{"origin":1472399,"position":4},"title":"Cristiano Ronaldo se reunir\u00e1 con el presidente Donald Trump en la Casa Blanca el martes","author":"","date":"noviembre 18, 2025","format":false,"excerpt":"Se espera que la superestrella del f\u00fatbol Cristiano Ronaldo se re\u00fana con el presidente Donald Trump en la Casa Blanca el martes, el mismo d\u00eda en que el pr\u00edncipe heredero saud\u00ed, Mohammed bin Salman, estar\u00e1 all\u00ed para una jornada completa de eventos con el mandatario, seg\u00fan informaron dos funcionarios del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463346,"url":"https:\/\/noticiasya.com\/springfield\/2025\/06\/08\/nations-league-portugal-cristiano-ronaldo-espana-orix\/","url_meta":{"origin":1472399,"position":5},"title":"Portugal gana la Nations League en penaltis: Cristiano Ronaldo anot\u00f3 en una final vibrante","author":"","date":"junio 8, 2025","format":false,"excerpt":"Cristiano Ronaldo no gan\u00f3 la Copa del Mundo, pero en el ocaso de su carrera puede levantar otro t\u00edtulo importante: la Nations League. Adem\u00e1s, anot\u00f3 un gol decisivo.Portugal derrot\u00f3 en penaltis a Espa\u00f1a tras 2-2 en los 90 minutos y los tiempos extra que mantuvieron el empate.El espa\u00f1ol Zubimendi abri\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472399"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472399\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}