{"id":1472428,"date":"2026-03-21T13:03:41","date_gmt":"2026-03-21T20:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/"},"modified":"2026-03-21T13:03:41","modified_gmt":"2026-03-21T20:03:41","slug":"puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","title":{"rendered":"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU."},"content":{"rendered":"<p>El presidente de Cuba, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/19\/latinoamerica\/cuba-miguel-diaz-canel-presidente-revolucion-quien-es-orix\">Miguel D\u00edaz-Canel<\/a>, habl\u00f3 este viernes sobre la presi\u00f3n que ejerce Estados Unidos sobre la isla y, en medio de las tensiones con el Gobierno de Donald Trump, reconoci\u00f3 que puede haber una agresi\u00f3n contra la isla y dijo que el pueblo cubano se prepara para defender el territorio en caso de que eso ocurra.<\/p>\n<p>\u201cNo estamos cruzados de brazos. En primer lugar, reconocemos que puede haber una agresi\u00f3n a Cuba y hemos desatado un plan de preparaci\u00f3n para elevar la disposici\u00f3n para la defensa de nuestro pueblo\u201d, dijo D\u00edaz-Canel en un discuro ante grupos activistas que llevaron donaciones a la isla, que atraviesa una grave crisis econ\u00f3mica agravada por el embargo energ\u00e9tico que impuso Washington.<\/p>\n<p>El pueblo cubano, seg\u00fan D\u00edaz-Canel, \u201ctiene una concepci\u00f3n defensiva, no agresiva\u201d. El mismo d\u00eda, la Presidencia de Cuba <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/20\/latinoamerica\/cuba-regala-fusil-combate-silvio-rodriguez-orix?iid=cnn_buildContentRecirc_end_recirc&#038;recs_exp=lo-m%C3%A1s-le%C3%ADdo-article-end&#038;tenant_id=popular.es\">dio a conocer el regalo<\/a> que le hizo al cantautor cubano Silvio Rodr\u00edguez: un fusil AKM y una r\u00e9plica de la misma arma, por su \u201cpatri\u00f3tica disposici\u00f3n\u201d <a href=\"https:\/\/x.com\/PresidenciaCuba\/status\/2035047143384522935\">para defender al pa\u00eds<\/a>. \u201cComo \u00e9l, millones de cubanos no le fallar\u00e1n a la Patria\u201d, dijo el Gobierno cubano en un comunicado.<\/p>\n<p>La escasez de petr\u00f3leo afecta a Cuba desde que dej\u00f3 de recibir los env\u00edos de Venezuela, su principal proveedor, y tambi\u00e9n de M\u00e9xico, su segundo proveedor, por las <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/29\/eeuu\/trump-amenaza-aranceles-paises-petroleo-cuba-orix\">amenazas arancelarias<\/a> tras el operativo militar en el que Estados Unidos captur\u00f3 al presidente de Venezuela, Nicol\u00e1s Maduro.<\/p>\n<p>Si bien el Gobierno de Cuba confirm\u00f3 d\u00edas atr\u00e1s que funcionarios cubanos tuvieron di\u00e1logo con el Gobierno estadounidense para buscar soluciones al embargo, al que los cubanos consideran un bloqueo, el viernes las autoridades de Cuba dejaron en claro que el sistema pol\u00edtico de <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/20\/latinoamerica\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\">la isla \u201cno es objeto de negociaci\u00f3n\u201d<\/a>.<\/p>\n<p>\u201cEl presidente de los Estados Unidos, en una de sus expresiones de clamor, dice \u2018a Cuba le hemos aplicado toda la presi\u00f3n posible\u2019. Est\u00e1 reconociendo que nos han bloqueado, que han aplicado una pol\u00edtica de m\u00e1xima presi\u00f3n, \u00bfc\u00f3mo va a decir que lo del bloqueo es un invento nuestro, si ellos mismos lo est\u00e1n diciendo?\u201d, dijo D\u00edaz-Canel en su discurso.<\/p>\n<p>En palabras del presidente, Estados Unidos ha pasado a una \u201csegunda fase\u201d en la que dice: \u201cYa solo lo que nos queda es tomar el lugar (en referencia a la isla) y arrasarlo todo\u201d.<\/p>\n<p>La tensa relaci\u00f3n que La Habana mantiene con Washington es de larga data y se remonta a 1959 con el comienzo de la revoluci\u00f3n cubana, que inici\u00f3 el sistema de gobierno que a\u00fan rige en la isla y que <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/19\/latinoamerica\/cuba-miguel-diaz-canel-presidente-revolucion-quien-es-orix#:~:text=Cuando%20asumi%C3%B3%20la,en%20Am%C3%A9rica%20Latina.\">fue s\u00edmbolo de la izquierda en Am\u00e9rica Latina<\/a>.<\/p>\n<p>Esa tensi\u00f3n escal\u00f3 en los \u00faltimos meses despu\u00e9s del operativo militar estadounidense en Caracas y se profundiz\u00f3 en las \u00faltimas semanas, con el presidente Donald Trump <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/07\/eeuu\/video\/cuba-trump-ultimos-dias-cumbre-escudo-americas-sot\">hablando sobre \u201cun gran cambio\u201d<\/a> y tambi\u00e9n de \u201ctomar\u201d la isla, debido al debilitamiento y la situaci\u00f3n cr\u00edtica que atraviesa.<\/p>\n<p>El secretario de Estado de EE.UU., Marco Rubio, tambi\u00e9n declar\u00f3 p\u00fablicamente d\u00edas atr\u00e1s desde la Casa Blanca, junto a Trump, que considera que Cuba necesita un cambio con \u201cnueva gente al mando\u201d porque su econom\u00eda y su sistema de gobierno \u201cya no funciona\u201d.<\/p>\n<p>D\u00edaz-Canel pareci\u00f3 referirse este viernes a parte de esas declaraciones, cuando dijo que \u201cla direcci\u00f3n de la revoluci\u00f3n cubana est\u00e1 unida\u201d y que todas las decisiones en Cuba \u201cse toman de manera colectiva y colegiada, en las que est\u00e1 presente el l\u00edder hist\u00f3rico de la revoluci\u00f3n cubana\u201d, el expresidente Ra\u00fal Castro, quien este a\u00f1o cumplir\u00e1 95 a\u00f1os.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Cuba, Miguel D\u00edaz-Canel, habl\u00f3 este viernes sobre la presi\u00f3n que ejerce Estados Unidos sobre la isla y, en medio de las tensiones con el Gobierno de Donald Trump, reconoci\u00f3 que puede haber una agresi\u00f3n contra la isla y dijo que el pueblo cubano se prepara para defender el territorio en caso de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472428","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Reconocemos que puede haber una agresi\u00f3n a Cuba&quot;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Reconocemos que puede haber una agresi\u00f3n a Cuba&quot;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"El presidente de Cuba, Miguel D\u00edaz-Canel, habl\u00f3 este viernes sobre la presi\u00f3n que ejerce Estados Unidos sobre la isla y, en medio de las tensiones con el Gobierno de Donald Trump, reconoci\u00f3 que puede haber una agresi\u00f3n contra la isla y dijo que el pueblo cubano se prepara para defender el territorio en caso de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-21T20:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU.\",\"datePublished\":\"2026-03-21T20:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/\"},\"wordCount\":664,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/\",\"name\":\"\\\"Reconocemos que puede haber una agresi\u00f3n a Cuba\\\", dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-21T20:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Reconocemos que puede haber una agresi\u00f3n a Cuba\", dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\"Reconocemos que puede haber una agresi\u00f3n a Cuba\", dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU. - Noticias","og_description":"El presidente de Cuba, Miguel D\u00edaz-Canel, habl\u00f3 este viernes sobre la presi\u00f3n que ejerce Estados Unidos sobre la isla y, en medio de las tensiones con el Gobierno de Donald Trump, reconoci\u00f3 que puede haber una agresi\u00f3n contra la isla y dijo que el pueblo cubano se prepara para defender el territorio en caso de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-21T20:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/"},"author":{"name":"","@id":""},"headline":"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU.","datePublished":"2026-03-21T20:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/"},"wordCount":664,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","name":"\"Reconocemos que puede haber una agresi\u00f3n a Cuba\", dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-21T20:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Reconocemos que puede haber una agresi\u00f3n a Cuba&#187;, dice D\u00edaz-Canel en plena tensi\u00f3n con EE.UU.","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/21\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-21T20:03:41Z","datePublished":"2026-03-21T20:03:41Z","dateModified":"2026-03-21T20:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Reconocemos que puede haber una agresi\\u00f3n a Cuba&#187;, dice D\\u00edaz-Canel en plena tensi\\u00f3n con EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/21\\\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/21\\\/puede-haber-agresion-cuba-miguel-diaz-canel-eeuu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-21T20:03:41Z\",\"datePublished\":\"2026-03-21T20:03:41Z\",\"dateModified\":\"2026-03-21T20:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473736,"url":"https:\/\/noticiasya.com\/springfield\/2026\/05\/02\/trump-control-cuba-diaz-canel-agresor-rendicion-orix\/","url_meta":{"origin":1472428,"position":0},"title":"Trump insiste en tomar el control de Cuba. D\u00edaz-Canel responde que &#171;ning\u00fan agresor encontrar\u00e1 rendici\u00f3n&#187; en la isla","author":"","date":"mayo 2, 2026","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, reiter\u00f3 el viernes su comentario sobre la posibilidad de que EE.UU. tome \u201cel control\u201d de Cuba de inmediato, sugiriendo que las fuerzas militares estadounidenses podr\u00edan avanzar sobre la isla de camino de regreso de la guerra en Ir\u00e1n.\u201cY \u00e9l viene originalmente de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473244,"url":"https:\/\/noticiasya.com\/springfield\/2026\/04\/16\/cotidianidad-duele-cuba-diaz-canel-listos-agresion-mlitar-eeuu-orix\/","url_meta":{"origin":1472428,"position":1},"title":"&#171;La cotidianidad cubana duele&#187;: D\u00edaz-Canel llama a estar listos para una &#171;agresi\u00f3n militar&#187; de EE.UU.","author":"","date":"abril 16, 2026","format":false,"excerpt":"El presidente de Cuba, Miguel D\u00edaz-Canel, habl\u00f3 este jueves del \u201cmomento sumamente desafiante\u201d que vive la isla en medio del embargo econ\u00f3mico y energ\u00e9tico impuesto por Estados Unidos, y llam\u00f3 a los cubanos a estar listos para \u201cenfrentar serias amenazas\u201d, entre ellas una \u201cagresi\u00f3n militar\u201d.\u201cEl momento es sumamente desafiante y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470897,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/05\/diaz-canel-cuba-dispuesta-dialogo-eeuu-sin-presiones-orix\/","url_meta":{"origin":1472428,"position":2},"title":"D\u00edaz-Canel confirma que Cuba est\u00e1 dispuesta al di\u00e1logo con EE.UU., pero &#171;sin presiones&#187;","author":"","date":"febrero 5, 2026","format":false,"excerpt":"Miguel D\u00edaz-Canel, presidente de Cuba, dijo este jueves que su gobierno est\u00e1 dispuesto a dialogar con la administraci\u00f3n estadounidense de Donald Trump, siempre y cuando no haya \u201cpresiones\u201d.\u201cCuba est\u00e1 dispuesta a un di\u00e1logo con los Estados Unidos, a un di\u00e1logo sobre cualquiera de los temas que se quiera debatir o\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472475,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/23\/diaz-canel-dispuesto-vida-revolucion-cuba-presion-eeuu-orix\/","url_meta":{"origin":1472428,"position":3},"title":"D\u00edaz-Canel dice que en Cuba no quieren la guerra pero est\u00e1n dispuestos a &#171;dar la vida por la Revoluci\u00f3n&#187;","author":"","date":"marzo 23, 2026","format":false,"excerpt":"En medio de la creciente presi\u00f3n de Estados Unidos, el presidente de Cuba, Miguel D\u00edaz-Canel, asegur\u00f3 en una entrevista con el pol\u00edtico espa\u00f1ol Pablo Iglesias que su Gobierno apuesta por el di\u00e1logo, pero se prepara para \u201cel peor de los escenarios\u201d en defensa de la soberan\u00eda de la isla, que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472340,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/19\/cuba-miguel-diaz-canel-presidente-revolucion-quien-es-orix\/","url_meta":{"origin":1472428,"position":4},"title":"Miguel D\u00edaz-Canel, el presidente que prometi\u00f3 &#171;la continuidad de la revoluci\u00f3n&#187; en Cuba y hoy ve amenazado ese objetivo","author":"","date":"marzo 19, 2026","format":false,"excerpt":"Cuando asumi\u00f3 la presidencia de Cuba hace casi ocho a\u00f1os, Miguel D\u00edaz-Canel dijo tener claro cu\u00e1l deb\u00eda ser su principal objetivo: mantener viva la revoluci\u00f3n que comenz\u00f3 en 1959, dio forma al sistema de gobierno que desde entonces rige en la isla y se convirti\u00f3 en un s\u00edmbolo para la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472394,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/20\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\/","url_meta":{"origin":1472428,"position":5},"title":"Gobierno de Cuba dice que el cargo del presidente Miguel D\u00edaz-Canel &#171;no es objeto de negociaci\u00f3n&#187; con EE.UU.","author":"","date":"marzo 20, 2026","format":false,"excerpt":"El Gobierno de Cuba afirm\u00f3 este viernes que el sistema pol\u00edtico de la isla, incluido el presidente Miguel D\u00edaz-Canel, \u201cno es objeto de negociaci\u00f3n\u201d con Estados Unidos.\u201cLo que s\u00ed puedo confirmar categ\u00f3ricamente, y est\u00e1 entre las l\u00edneas de lo que dijo el presidente (D\u00edaz-Canel), es que el sistema pol\u00edtico cubano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472428"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472428\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}