{"id":1472433,"date":"2026-03-21T17:03:51","date_gmt":"2026-03-22T00:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/"},"modified":"2026-03-21T17:03:51","modified_gmt":"2026-03-22T00:03:51","slug":"cuba-segundo-apagon-nacional-una-semana-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/","title":{"rendered":"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana"},"content":{"rendered":"<p>El Ministerio de Energ\u00eda y Minas de Cuba anunci\u00f3 este s\u00e1bado que toda la isla ha sufrido otro apag\u00f3n el\u00e9ctrico.<\/p>\n<p>\u201cSe ha producido una desconexi\u00f3n total del Sistema El\u00e9ctrico Nacional\u201d, dijo el Ministerio <a href=\"https:\/\/x.com\/EnergiaMinasCub\/status\/2035487928378413423\">en una publicaci\u00f3n en X<\/a>. \u201cYa comienzan a implementarse los protocolos para el restablecimiento\u201d.<\/p>\n<p>Esto ocurre solo d\u00edas despu\u00e9s de que Cuba viviera el lunes <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/17\/latinoamerica\/cuba-apagon-recuperacion-lenta-energia-orix\">su primer colapso nacional de la red el\u00e9ctrica<\/a> desde que Estados Unidos comenz\u00f3 a bloquear los suministros de petr\u00f3leo procedentes de Venezuela a principios de este a\u00f1o.<\/p>\n<p>La Uni\u00f3n El\u00e9ctrica de Cuba, que pertenece al Ministerio de Energ\u00eda, prev\u00eda un d\u00e9ficit de 1.740 megawatts (MW) para la hora pico de esta noche, seg\u00fan <a href=\"https:\/\/x.com\/OSDE_UNE\/status\/2035336303982575765\">el reporte que public\u00f3 por la ma\u00f1ana en X<\/a>.<\/p>\n<p>De acuerdo con el gobierno de Cuba, los apagones en la isla \u2014que se hab\u00edan vuelto frecuentes en los \u00faltimos a\u00f1os\u2014 se han agravado durante los primeros meses de 2026 debido a la escasez de combustible para que las centrales el\u00e9ctricas puedan operar.<\/p>\n<p>La falta de petr\u00f3leo tambi\u00e9n ha impactado en otros aspectos, como los servicios p\u00fablicos y el transporte de alimentos, una situaci\u00f3n que ya ha generado algunas protestas en La Habana y otras ciudades.<\/p>\n<p>El presidente de Cuba, Miguel D\u00edaz-Canel, dijo recientemente que entiende el malestar que estos problemas generan, aunque asegur\u00f3 que las autoridades est\u00e1n trabajando para buscar v\u00edas de soluci\u00f3n.<\/p>\n<p>Dentro de este contexto, el canciller de Cuba, Bruno Rodr\u00edguez, se\u00f1al\u00f3 este s\u00e1bado que su pa\u00eds permanece abierto <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/21\/latinoamerica\/lula-critica-eeuu-venezuela-cuba-petro-cuestiona-onu-conflictos-orix\">a tener un di\u00e1logo serio y respetuoso con Estados Unidos<\/a>, que mantiene presiones sobre la isla y un embargo econ\u00f3mico desde la d\u00e9cada de 1960.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio de Energ\u00eda y Minas de Cuba anunci\u00f3 este s\u00e1bado que toda la isla ha sufrido otro apag\u00f3n el\u00e9ctrico. \u201cSe ha producido una desconexi\u00f3n total del Sistema El\u00e9ctrico Nacional\u201d, dijo el Ministerio en una publicaci\u00f3n en X. \u201cYa comienzan a implementarse los protocolos para el restablecimiento\u201d. Esto ocurre solo d\u00edas despu\u00e9s de que Cuba [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472433","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cuba anuncia segundo apag\u00f3n nacional en menos de una semana - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Ministerio de Energ\u00eda y Minas de Cuba anunci\u00f3 este s\u00e1bado que toda la isla ha sufrido otro apag\u00f3n el\u00e9ctrico. \u201cSe ha producido una desconexi\u00f3n total del Sistema El\u00e9ctrico Nacional\u201d, dijo el Ministerio en una publicaci\u00f3n en X. \u201cYa comienzan a implementarse los protocolos para el restablecimiento\u201d. Esto ocurre solo d\u00edas despu\u00e9s de que Cuba [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-22T00:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana\",\"datePublished\":\"2026-03-22T00:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/\"},\"wordCount\":328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/\",\"name\":\"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-22T00:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana - Noticias","og_description":"El Ministerio de Energ\u00eda y Minas de Cuba anunci\u00f3 este s\u00e1bado que toda la isla ha sufrido otro apag\u00f3n el\u00e9ctrico. \u201cSe ha producido una desconexi\u00f3n total del Sistema El\u00e9ctrico Nacional\u201d, dijo el Ministerio en una publicaci\u00f3n en X. \u201cYa comienzan a implementarse los protocolos para el restablecimiento\u201d. Esto ocurre solo d\u00edas despu\u00e9s de que Cuba [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-22T00:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/"},"author":{"name":"","@id":""},"headline":"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana","datePublished":"2026-03-22T00:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/"},"wordCount":328,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/","name":"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-22T00:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cuba anuncia segundo apag\u00f3n nacional en menos de una semana","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/21\/cuba-segundo-apagon-nacional-una-semana-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-22T00:03:51Z","datePublished":"2026-03-22T00:03:51Z","dateModified":"2026-03-22T00:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cuba anuncia segundo apag\\u00f3n nacional en menos de una semana\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/21\\\/cuba-segundo-apagon-nacional-una-semana-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/21\\\/cuba-segundo-apagon-nacional-una-semana-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-22T00:03:51Z\",\"datePublished\":\"2026-03-22T00:03:51Z\",\"dateModified\":\"2026-03-22T00:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466329,"url":"https:\/\/noticiasya.com\/springfield\/2025\/09\/10\/cuba-apagon-cuarto-orix\/","url_meta":{"origin":1472433,"position":0},"title":"Cuba sufre un nuevo apag\u00f3n en todo el pa\u00eds, el cuarto en menos de un a\u00f1o","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Cuba sufri\u00f3 este mi\u00e9rcoles un nuevo apag\u00f3n en todo el pa\u00eds, seg\u00fan inform\u00f3 en redes sociales la estatal Uni\u00f3n El\u00e9ctrica (UNE). Es el cuarto a nivel nacional en menos de un a\u00f1o.El corte el\u00e9ctrico general ocurri\u00f3 a las 9:14 a.m. hora local.\u201cSe ha producido una desconexi\u00f3n total del Sistema El\u00e9ctrico,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455222,"url":"https:\/\/noticiasya.com\/springfield\/2024\/10\/18\/cuba-apagon-toda-la-isla-fallo-planta-electrica-trax\/","url_meta":{"origin":1472433,"position":1},"title":"Cuba experimenta un apag\u00f3n en toda la isla tras falla en planta el\u00e9ctrica","author":"","date":"octubre 18, 2024","format":false,"excerpt":"(CNN) --\u00a0La red el\u00e9ctrica de Cuba sufri\u00f3 un apag\u00f3n este viernes, dejando al pa\u00eds a oscuras tras \"la falla\" de una de las principales plantas de energ\u00eda de la isla, seg\u00fan su ministerio de energ\u00eda.En un comunicado en X, el ministerio dijo que \"la falla\" de la Central Termoel\u00e9ctrica Antonio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472445,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/22\/cuba-recuperar-suministro-electrico-apagon-orix\/","url_meta":{"origin":1472433,"position":2},"title":"Cuba inicia labores para recuperar el suministro el\u00e9ctrico tras un nuevo apag\u00f3n total","author":"","date":"marzo 22, 2026","format":false,"excerpt":"Las autoridades de Cuba informaron este domingo el inicio de labores para restablecer el suministro el\u00e9ctrico, que sufri\u00f3 un colapso el s\u00e1bado por segunda vez en una semana, en medio de un bloqueo petrolero estadounidense.La red el\u00e9ctrica sufri\u00f3 \u201cuna desconexi\u00f3n total\u201d por un problema en la Unidad n\u00famero 6 de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458724,"url":"https:\/\/noticiasya.com\/springfield\/2025\/02\/13\/cuba-suspende-actividades-no-imprescindibles-crisis-electrica-orix\/","url_meta":{"origin":1472433,"position":3},"title":"Cuba suspende actividades docentes y laborales &#171;no imprescindibles&#187; el viernes y s\u00e1bado debido a la crisis el\u00e9ctrica","author":"","date":"febrero 13, 2025","format":false,"excerpt":"El Gobierno de Cuba anunci\u00f3 este jueves la suspensi\u00f3n de actividades laborales y docentes \u201cno imprescindibles\u201d el viernes y s\u00e1bado, debido a la crisis energ\u00e9tica que afecta a la isla, inform\u00f3 la ministra de Trabajo y Seguridad Social, Marta Elena Feito Cabrera.\u201cTeniendo en cuenta la situaci\u00f3n energ\u00e9tica que afronta el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472276,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/17\/cuba-apagon-recuperacion-lenta-energia-orix\/","url_meta":{"origin":1472433,"position":4},"title":"El suministro el\u00e9ctrico de Cuba comienza lentamente a restablecerse tras el apag\u00f3n total","author":"","date":"marzo 17, 2026","format":false,"excerpt":"El sistema el\u00e9ctrico de Cuba comienza a restablecerse tras el colapso total de este lunes. La recuperaci\u00f3n es lenta, como sucede cuando hay apagones de esta magnitud.Seg\u00fan el UNE, el operador de la red el\u00e9ctrica cubana, el servicio ya se restableci\u00f3 en las regiones occidental y centro-oriental de la isla\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456251,"url":"https:\/\/noticiasya.com\/springfield\/2024\/12\/04\/cuba-desconexion-sistema-electrico-orix\/","url_meta":{"origin":1472433,"position":5},"title":"Cuba bajo apag\u00f3n total tras &#171;desconexi\u00f3n&#187; del sistema el\u00e9ctrico","author":"","date":"diciembre 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Cuba enfrenta este mi\u00e9rcoles la \"desconexi\u00f3n total del Sistema El\u00e9ctrico Nacional SEN\", inform\u00f3 la Uni\u00f3n El\u00e9ctrica de Cuba a trav\u00e9s de un comunicado publicado en su p\u00e1gina de Facebook. El episodio ha dejado a millones sin electricidad, en el \u00faltimo en una serie de fallos en una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472433"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472433\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}