{"id":1472442,"date":"2026-03-22T05:03:46","date_gmt":"2026-03-22T12:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/"},"modified":"2026-03-22T05:03:46","modified_gmt":"2026-03-22T12:03:46","slug":"chile-cable-submarino-china-eeuu-minerales-raros-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/","title":{"rendered":"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington?"},"content":{"rendered":"<p>Apenas d\u00edas antes de asumir la presidencia, el ultraderechista Jos\u00e9 Antonio Kast y el exmandatario Gabriel Boric (de la izquierda progresista) rompieron relaciones y cancelaron reuniones entre ambos equipos. \u00bfEl motivo? El proyecto de construcci\u00f3n de un cable submarino chino de telecomunicaciones que unir\u00eda al pa\u00eds austral directamente con Hong Kong.<\/p>\n<p>No es un plan nuevo: tuvo su origen durante el Gobierno de Sebasti\u00e1n Pi\u00f1era, tras un ofrecimiento de China, y su concesi\u00f3n termin\u00f3 siendo aprobada v\u00eda decreto en la administraci\u00f3n de Boric, con la firma de su ministro de Transportes, Juan Mu\u00f1oz.<\/p>\n<p>El documento -al que accedi\u00f3 el medio local \u201cEl Mercurio\u201d- oficializaba la concesi\u00f3n del cable de fibra \u00f3ptica por al menos 30 a\u00f1os, detallaba que abarcar\u00eda m\u00e1s de 19 mil kil\u00f3metros y unir\u00eda las ciudades de Hong Kong (China) con Conc\u00f3n, en la regi\u00f3n chilena de Valpara\u00edso.<\/p>\n<p>Sin embargo, 48 horas despu\u00e9s de firmado el decreto, el propio Boric decidi\u00f3 frenar su avance, cuando los documentos ya iban de camino a la Contralor\u00eda. Seg\u00fan el exmandatario, el hecho motiv\u00f3 \u201camenazas expl\u00edcitas\u201d por parte de Estados Unidos, quien revoc\u00f3 la visa al ministro de Transportes de Boric y otros dos funcionarios p\u00fablicos. Kast, por su parte, acus\u00f3 en ese entonces \u201cfalta de transparencia\u201d por parte del Gobierno saliente.<\/p>\n<p>\u201cChile-China Express\u201d, nombre que recib\u00eda este proyecto, pertenec\u00eda a la empresa china Mobile International y buscaba mejorar la conectividad e intercambio de datos entre ambos pa\u00edses. D\u00edas antes de dejar el cargo, Boric afirm\u00f3 que este era un tema \u201ctan sensible, tan delicado\u201d que \u201crequer\u00eda una conversaci\u00f3n con el presidente electo (ahora actual presidente Kast)\u201d, pero que esto no pod\u00eda estar \u201csubordinado a las amenazas de un determinado pa\u00eds\u201d.<\/p>\n<p>Posteriormente, el propio embajador de Estados Unidos en Chile, Brandon Judd, sentenci\u00f3 el fin del proyecto chino. \u201cEl Gobierno todav\u00eda tiene que revisar los permisos, pero yo creo que ya est\u00e1 terminado\u201d, asegur\u00f3 en una improvisada rueda de prensa el 12 de marzo.<\/p>\n<p>\u201cCuando hablamos en temas de seguridad, siempre vamos a pensar que nosotros (Chile y Estados Unidos) somos socios, y compartimos informaci\u00f3n e inteligencia. Y si a\u00fan queremos compartir todo eso, nosotros tenemos que tener la confianza de que esta informaci\u00f3n que compartimos ser\u00e1 guardada. Con este proyecto, Chile no ser\u00e1 due\u00f1o de este cable, entonces no podemos tener la confianza de que esta informaci\u00f3n ser\u00e1 guardada. Si Chile fuera el due\u00f1o, podr\u00eda ser. Pero hasta ahora los \u00fanicos que ser\u00edan due\u00f1os ser\u00edan empresas chinas\u201d, afirm\u00f3 Judd, y reiter\u00f3 que el cable \u201cya se acab\u00f3\u201d y que la permanencia de Chile en el programa visa waiver \u201cno est\u00e1 en duda\u201d.<\/p>\n<p>Seg\u00fan expertos, en Chile quien construye proyectos de esta envergadura no siempre es el mismo que termina oper\u00e1ndolas, y ah\u00ed es clave la forma en que se negocian las concesiones. Pero el cable submarino chino \u201cya parece ser cosa del pasado\u201d. El problema, advierten, es lo que est\u00e1 por venir.<\/p>\n<p>Para el analista internacional Gilberto Aranda, Chile est\u00e1 entrando en una posici\u00f3n inc\u00f3moda: por un lado, tiene a China, su principal socio comercial -y principal comprador de cobre-, y por el otro a Estados Unidos, con la administraci\u00f3n Trump, donde Kast coincide en varios puntos pol\u00edticos y busca referencias, como la actual construcci\u00f3n de un muro para frenar la migraci\u00f3n irregular en la frontera norte con Per\u00fa y Bolivia.<\/p>\n<p>\u201cTengo la impresi\u00f3n de que el proyecto Cable Submarino Chino ya ha sido dejado de lado, pero la pregunta es: \u00bfqu\u00e9 viene despu\u00e9s?\u201d, se\u00f1ala Aranda, quien recuerda la importancia del rol de Chile como productor mundial de \u201cminerales cr\u00edticos\u201d como el cobre y el litio, los cuales adquieren esta denominaci\u00f3n al ser clasificados como esenciales en industrias de transici\u00f3n energ\u00e9tica y electromovilidad.<\/p>\n<p>\u201cSe hizo una declaraci\u00f3n conjunta (entre Chile y Estados Unidos) de minerales cr\u00edticos y otros recursos, firmada el mismo 12 de marzo\u201d, recuerda Aranda. Seg\u00fan este documento, ambas contrapartes consideran que \u201cel apoyo mutuo en el suministro de minerales cr\u00edticos resulta fundamental para la seguridad nacional y las industrias comerciales de ambos pa\u00edses\u201d, y establece un plazo de 15 d\u00edas para realizar consultas t\u00e9cnicas y presentar resultados.<\/p>\n<p>\u201cEsto nos dice que lo que le interesa (a Estados Unidos) es la infraestructura cr\u00edtica, pero en la \u00faltima estrategia de seguridad nacional tambi\u00e9n se habla de la importancia de los mercados, adem\u00e1s de la poblaci\u00f3n, espacios estrat\u00e9gicos, entre otros. Si pensamos en todo eso, el siguiente punto podr\u00eda ser una demanda o exigencia en torno a lo que es el cobre o el litio, donde Chile no solo tiene exportaciones hacia China, sino que hay acuerdos para explotar el litio con otras potencias\u201d, afirma Aranda a CNN.<\/p>\n<p>Luego de los \u00faltimos incendios forestales en la regi\u00f3n del Biob\u00edo, que afectaron especialmente a localidades como Penco y Tom\u00e9, China tambi\u00e9n se\u00f1al\u00f3 su inter\u00e9s en estas tierras, ahora expuestas por la quema de bosques y que son catalogadas como \u201ctierras raras\u201d: un conjunto de elementos qu\u00edmicos que, por su baja concentraci\u00f3n aprovechable en la corteza terrestre, se han vuelto \u201cesenciales en televisores de pantalla plana, bater\u00edas inteligentes, l\u00e1mparas fluorescentes compactas, tel\u00e9fonos m\u00f3viles, unidades de disco, veh\u00edculos el\u00e9ctricos y turbinas e\u00f3licas\u201d, explica el acad\u00e9mico Martin Reich, de la Facultad de Ciencias F\u00edsicas y Matem\u00e1ticas de la Universidad de Chile.<\/p>\n<p>En una visita en terreno a Tom\u00e9, el embajador de China en Chile, Niu Qingbao, se\u00f1al\u00f3: \u201cLa comuna tiene muchas necesidades en la mejora de la infraestructura y la construcci\u00f3n de una ciudad inteligente, as\u00ed que estoy dispuesto a ayudar a promover el establecimiento de hermanamiento entre Tom\u00e9 y alguna ciudad china, y tambi\u00e9n quiero promover la cooperaci\u00f3n m\u00e1s profunda entre Tom\u00e9 y las empresas chinas\u201d, dijo a trav\u00e9s de su traductora a Radio Biob\u00edo. Esta es la primera vez que el embajador chino visita un municipio en el pa\u00eds austral.<\/p>\n<p>En la actualidad, Chile mantiene una posici\u00f3n de liderazgo en la producci\u00f3n de varios minerales, destacando como primer productor mundial de cobre y renio, con participaciones de 23,0% y 46,8% respectivamente a nivel global, y registra una presencia relevante en litio y molibdeno, con cuotas de 20,4% y 14,6%. Las expectativas a futuro, eso s\u00ed, radican en el litio: SQM, la principal compa\u00f1\u00eda chilena exportadora de litio, estima un aumento del 25% de la demanda mundial para 2026.<\/p>\n<p>\u201cChile tiene un modelo de crecimiento basado en la apertura exterior y el libre comercio. El tema Chile-China y Chile-Estados Unidos nos obliga, por parte de Estados Unidos, a ir tomando posiciones a un alineamiento mucho m\u00e1s cerrado y eso por supuesto que coloca a Chile en una posici\u00f3n inc\u00f3moda\u201d, explica el acad\u00e9mico de la Universidad de Chile a CNN. \u201cHay recetas para salir de eso. Yo creo en el multi alineamiento y que se supere ese binomio de potencias, pero est\u00e1 complejo\u201d, dice Aranda.<\/p>\n<p>El 13 de marzo, el subsecretario de Estado de Estados Unidos, Christopher Landau, se\u00f1al\u00f3 a trav\u00e9s de su cuenta de X: \u201cSiento una afinidad especial con el presidente Jos\u00e9 Antonio Kast, quiz\u00e1s porque ambos crecimos en Chile en la misma \u00e9poca (\u00e9l es aproximadamente dos a\u00f1os menor que yo). Desde el primer momento se percibe que es un hombre de valores y de palabra, un \u2018hombre de confianza\u2019\u201d. Y agreg\u00f3: \u201cNo hace falta decir que tuvimos reuniones muy cordiales y constructivas en los \u00faltimos d\u00edas, y realmente creo que estamos entrando en una edad dorada de las relaciones entre Estados Unidos y Chile\u201d.<\/p>\n<p>Para Aranda, la situaci\u00f3n es clara: \u201cDefinitivamente Estados Unidos est\u00e1 intentando recuperar el control territorial de mercados e infraestructura cr\u00edtica en Latinoam\u00e9rica\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apenas d\u00edas antes de asumir la presidencia, el ultraderechista Jos\u00e9 Antonio Kast y el exmandatario Gabriel Boric (de la izquierda progresista) rompieron relaciones y cancelaron reuniones entre ambos equipos. \u00bfEl motivo? El proyecto de construcci\u00f3n de un cable submarino chino de telecomunicaciones que unir\u00eda al pa\u00eds austral directamente con Hong Kong. No es un plan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472442","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Apenas d\u00edas antes de asumir la presidencia, el ultraderechista Jos\u00e9 Antonio Kast y el exmandatario Gabriel Boric (de la izquierda progresista) rompieron relaciones y cancelaron reuniones entre ambos equipos. \u00bfEl motivo? El proyecto de construcci\u00f3n de un cable submarino chino de telecomunicaciones que unir\u00eda al pa\u00eds austral directamente con Hong Kong. No es un plan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-22T12:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington?\",\"datePublished\":\"2026-03-22T12:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/\"},\"wordCount\":1377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/\",\"name\":\"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-22T12:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington? - Noticias","og_description":"Apenas d\u00edas antes de asumir la presidencia, el ultraderechista Jos\u00e9 Antonio Kast y el exmandatario Gabriel Boric (de la izquierda progresista) rompieron relaciones y cancelaron reuniones entre ambos equipos. \u00bfEl motivo? El proyecto de construcci\u00f3n de un cable submarino chino de telecomunicaciones que unir\u00eda al pa\u00eds austral directamente con Hong Kong. No es un plan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-22T12:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/"},"author":{"name":"","@id":""},"headline":"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington?","datePublished":"2026-03-22T12:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/"},"wordCount":1377,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/","name":"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-22T12:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfPor qu\u00e9 el proyecto de un cable submarino enfrent\u00f3 a los chilenos y gener\u00f3 molestias en Washington?","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/22\/chile-cable-submarino-china-eeuu-minerales-raros-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-22T12:03:46Z","datePublished":"2026-03-22T12:03:46Z","dateModified":"2026-03-22T12:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfPor qu\\u00e9 el proyecto de un cable submarino enfrent\\u00f3 a los chilenos y gener\\u00f3 molestias en Washington?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/22\\\/chile-cable-submarino-china-eeuu-minerales-raros-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/22\\\/chile-cable-submarino-china-eeuu-minerales-raros-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-22T12:03:46Z\",\"datePublished\":\"2026-03-22T12:03:46Z\",\"dateModified\":\"2026-03-22T12:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455934,"url":"https:\/\/noticiasya.com\/springfield\/2024\/11\/19\/riesgo-internet-ecuador-telconet-orix\/","url_meta":{"origin":1472442,"position":0},"title":"Advierten riesgo en servicio de internet para gran parte de Ecuador tras cuestionada decisi\u00f3n gubernamental contra empresa Telconet","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La empresa privada ecuatoriana \u201cTelconet Latam\u201d advirti\u00f3 este martes que la provisi\u00f3n del servicio de internet a sus usuarios en el pa\u00eds est\u00e1 \u201cen riesgo\u201d, al informar que su proveedor \u201cCable Andino Corpandino\u201d fue notificado de una resoluci\u00f3n gubernamental de la Agencia de Regulaci\u00f3n y Control de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471964,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/06\/trump-doctrina-donroe-guerras-paz-analisis-orix\/","url_meta":{"origin":1472442,"position":1},"title":"La &#171;doctrina Donroe&#187; deja todo para Trump, incluyendo la guerra y la paz","author":"","date":"marzo 6, 2026","format":false,"excerpt":"El presidente y creador de la llamada \u201cJunta de Paz\u201d inici\u00f3 una guerra, de nuevo. Desde que Donald Trump inici\u00f3 su segundo mandato, ha ordenado el uso de la fuerza en 7 oportunidades, mientras que asegura haber resuelto 8 o m\u00e1s guerras. Antes del actual ataque contra Ir\u00e1n, el segundo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453017,"url":"https:\/\/noticiasya.com\/springfield\/2024\/09\/24\/boric-onu-crisis-venezuela-triunfo-oposicion-orix\/","url_meta":{"origin":1472442,"position":2},"title":"Boric reitera ante la ONU llamado para salida pol\u00edtica a la crisis en Venezuela que \u201creconozca el triunfo de la oposici\u00f3n\u201d","author":"","date":"septiembre 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El presidente de Chile, Gabriel Boric, dijo este martes que su pa\u00eds sigue con atenci\u00f3n \u201cla cr\u00edtica situaci\u00f3n\u201d que vive Venezuela y reiter\u00f3 su llamado a una salida pol\u00edtica de la crisis, que \u201creconozca el triunfo de la oposici\u00f3n\u201d.Durante su intervenci\u00f3n en la 79\u00b0 Asamblea General de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457211,"url":"https:\/\/noticiasya.com\/springfield\/2025\/01\/04\/gabriel-boric-chile-polo-sur-antartida-trax\/","url_meta":{"origin":1472442,"position":3},"title":"Gabriel Boric visita el Polo Sur en un viaje hist\u00f3rico","author":"","date":"enero 4, 2025","format":false,"excerpt":"El presidente de Chile, Gabriel Boric, viaj\u00f3 al Polo Sur de la Ant\u00e1rtida el viernes, un lugar donde ning\u00fan otro presidente latinoamericano ha puesto pie, seg\u00fan el gobierno chileno.Boric lider\u00f3 el hist\u00f3rico viaje de dos d\u00edas, llamado Operaci\u00f3n Estrella Polar III, para extender el monitoreo ambiental de contaminantes en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469277,"url":"https:\/\/noticiasya.com\/springfield\/2025\/12\/15\/boric-kast-palacio-moneda-elecciones-presidente-chile-efe\/","url_meta":{"origin":1472442,"position":4},"title":"Boric recibi\u00f3 a Kast en el Palacio de La Moneda para iniciar la transici\u00f3n que terminar\u00e1 en marzo","author":"","date":"diciembre 15, 2025","format":false,"excerpt":"El presidente de Chile, Gabriel Boric, y el presidente electo, Jos\u00e9 Antonio Kast, se reunieron este lunes en el palacio de Gobierno para empezar su transici\u00f3n entre ambos Gobiernos que culminar\u00e1 el 11 de marzo, cuando el ultraderechista asumir\u00e1 el poder.Kast, que gan\u00f3 las elecciones con un 58,1 % por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456106,"url":"https:\/\/noticiasya.com\/springfield\/2024\/11\/26\/denuncian-gabriel-boric-presunto-acoso-sexual-orix\/","url_meta":{"origin":1472442,"position":5},"title":"Denuncian a Gabriel Boric por presunto acoso sexual y difusi\u00f3n de im\u00e1genes \u00edntimas, la defensa alega completa inocencia","author":"","date":"noviembre 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Una mujer denunci\u00f3 al presidente de Chile, Gabriel Boric, por un presunto acoso sexual entre 2013 y 2014. La defensa del mandatario neg\u00f3 este martes tajantemente que tal cosa haya ocurrido y, en cambio, presenta otro relato.En una rueda de prensa, el abogado del mandatario, Jonatan Valenzuela,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472442"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472442\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}