{"id":1472565,"date":"2026-03-25T23:03:45","date_gmt":"2026-03-26T06:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/"},"modified":"2026-03-25T23:03:45","modified_gmt":"2026-03-26T06:03:45","slug":"maduro-regresa-tribunales-estados-unidos-defensa-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/","title":{"rendered":"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa"},"content":{"rendered":"<p><a href=\"https:\/\/www.cnn.com\/world\/americas\/nicolas-maduro-fast-facts\">Nicol\u00e1s Maduro,<\/a> el derrocado presidente de Venezuela, intentar\u00e1 convencer este jueves a un juez federal de que el Gobierno estadounidense est\u00e1 interfiriendo en su capacidad para defenderse de los cargos relacionados con el narcoterrorismo y que el caso debe ser desestimado.<\/p>\n<p>El juez Alvin Hellerstein fij\u00f3 inicialmente la audiencia para dar tiempo a los abogados de Maduro y su esposa, Cilia Flores de Maduro, a revisar las pruebas, elaborar un calendario para las mociones legales y, potencialmente, fijar una fecha para el juicio.<\/p>\n<p>En un giro inesperado dentro de este caso ya de por s\u00ed inusual, el abogado de Maduro, Barry Pollack, declar\u00f3 el mes pasado que tendr\u00e1 que retirarse si Estados Unidos no permite que el Gobierno de Venezuela pague sus honorarios legales.<\/p>\n<p>Maduro y su esposa fueron <a href=\"https:\/\/www.cnn.com\/2026\/01\/23\/americas\/venezuela-maduro-fort-tiuna-compound-operation-reconstruction-intl-invs\">capturados en su residencia presidencial en Caracas<\/a> a principios de enero en una sorprendente operaci\u00f3n nocturna llevada a cabo por las fuerzas militares y del orden estadounidenses, y trasladados a Nueva York para enfrentar cargos.<\/p>\n<p>Pollack afirm\u00f3 que la Oficina de Control de Activos Extranjeros del Departamento del Tesoro otorg\u00f3 y posteriormente revoc\u00f3 una licencia que permit\u00eda al Gobierno venezolano pagar sus honorarios legales.<\/p>\n<p>Tanto los Maduro como el Gobierno venezolano est\u00e1n sancionados por Estados Unidos, por lo que cualquier persona que solicite un pago debe obtener una licencia para evitar infringir las leyes de sanciones estadounidenses.<\/p>\n<p>Seg\u00fan el abogado, la revocaci\u00f3n viola el derecho constitucional de Maduro a defenderse de los cargos. El abogado de Flores de Maduro se sum\u00f3 a la moci\u00f3n. Si el juez no desestima el caso, solicitan una audiencia para analizar el proceso de toma de decisiones del Gobierno.<\/p>\n<p>Los fiscales afirmaron que la licencia inicial de la OFAC fue un \u201cerror administrativo\u201d y que a\u00fan permiten a los Maduro acceder a sus fondos personales en Venezuela para cubrir sus gastos legales.<\/p>\n<p>\u201cSin embargo, la OFAC ha denegado la solicitud de los acusados \u200b\u200bde una excepci\u00f3n adicional: permitirles pagar sus honorarios legales con fondos il\u00edcitos controlados por un Gobierno sancionado. Esto se debe a que las regulaciones de la OFAC proh\u00edben expresamente el uso de fondos de una <em>entidad sancionada<\/em> para pagar los honorarios de los abogados de otra persona sancionada\u201d, escribieron los fiscales en un documento judicial en el que se opon\u00edan al sobreseimiento de la acusaci\u00f3n.<\/p>\n<p>Los abogados afirman que Maduro tiene una batalla cuesta arriba por delante.<\/p>\n<p>\u201cDado a que no se le reconoce como l\u00edder de Venezuela y todo el r\u00e9gimen de sanciones tiene como objetivo aislarlo, es poco probable que el tribunal considere que tiene derecho a recibir dinero para financiar su defensa penal\u201d, opin\u00f3 Duncan Levin, un exfiscal especializado en derecho de sanciones.<\/p>\n<p>Maduro no se quedar\u00eda sin representaci\u00f3n legal. Seg\u00fan la ley estadounidense, tiene derecho a un abogado de oficio.<\/p>\n<p>Los Maduro se han declarado inocentes de los cargos de conspiraci\u00f3n para la importaci\u00f3n de armas y coca\u00edna que, seg\u00fan la fiscal\u00eda, abarcan m\u00e1s de 25 a\u00f1os, y se encuentran bajo custodia federal en el Centro de Detenci\u00f3n Metropolitano de Brooklyn.<\/p>\n<p>Pollack ya ha dado a entender que impugnar\u00e1 la legalidad del arresto de Maduro y argumentar\u00e1 que goza de inmunidad judicial porque la presunta conducta ilegal ocurri\u00f3 mientras era presidente.<\/p>\n<p>Maduro fue elegido presidente de Venezuela por primera vez en 2013. Sin embargo, el Gobierno estadounidense, junto con decenas de otros pa\u00edses, no lo ha reconocido como el l\u00edder leg\u00edtimo del pa\u00eds desde las elecciones presidenciales de 2018.<\/p>\n<p>Este a\u00f1o, tras la destituci\u00f3n de Maduro, el Departamento de Estado de Estados Unidos reconoci\u00f3 a Delcy Rodr\u00edguez como jefa de Estado de Venezuela.<\/p>\n<p>A principios de enero, las fuerzas estadounidenses irrumpieron en el complejo presidencial, se enfrentaron en un intenso tiroteo con las defensas a\u00e9reas venezolanas y capturaron a Maduro y a su esposa en su residencia fuertemente fortificada.<\/p>\n<p>Los abogados afirman que, si bien la captura y el arresto de Maduro fueron extraordinarios, la legislaci\u00f3n estadounidense est\u00e1 bien establecida.<\/p>\n<p>\u201cSeg\u00fan la Constituci\u00f3n de Estados Unidos, es el presidente quien decide a qui\u00e9n reconocer como jefe de Estado, y estoy completamente seguro de que un tribunal estadounidense no va a cuestionar la decisi\u00f3n de Estados Unidos de que Maduro ya no es jefe de Estado\u201d, declar\u00f3 William Dodge, profesor de derecho internacional en la facultad de derecho de la Universidad George Washington.<\/p>\n<p>\u201cSu secuestro fue ilegal seg\u00fan el derecho internacional\u201d, se\u00f1al\u00f3, pero agreg\u00f3: \u201cEn Estados Unidos est\u00e1 bastante claro que la ilegalidad de llevar a alguien ante un tribunal no afecta la jurisdicci\u00f3n del mismo\u201d.<\/p>\n<p>Dodge tambi\u00e9n se muestra esc\u00e9ptico ante las afirmaciones de Maduro de gozar de inmunidad por su conducta mientras estuvo al frente del pa\u00eds.<\/p>\n<p>\u201cEl narcotr\u00e1fico no es un delito oficial\u201d, afirm\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicol\u00e1s Maduro, el derrocado presidente de Venezuela, intentar\u00e1 convencer este jueves a un juez federal de que el Gobierno estadounidense est\u00e1 interfiriendo en su capacidad para defenderse de los cargos relacionados con el narcoterrorismo y que el caso debe ser desestimado. El juez Alvin Hellerstein fij\u00f3 inicialmente la audiencia para dar tiempo a los abogados [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472565","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nicol\u00e1s Maduro, el derrocado presidente de Venezuela, intentar\u00e1 convencer este jueves a un juez federal de que el Gobierno estadounidense est\u00e1 interfiriendo en su capacidad para defenderse de los cargos relacionados con el narcoterrorismo y que el caso debe ser desestimado. El juez Alvin Hellerstein fij\u00f3 inicialmente la audiencia para dar tiempo a los abogados [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T06:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa\",\"datePublished\":\"2026-03-26T06:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/\"},\"wordCount\":856,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/\",\"name\":\"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-26T06:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa - Noticias","og_description":"Nicol\u00e1s Maduro, el derrocado presidente de Venezuela, intentar\u00e1 convencer este jueves a un juez federal de que el Gobierno estadounidense est\u00e1 interfiriendo en su capacidad para defenderse de los cargos relacionados con el narcoterrorismo y que el caso debe ser desestimado. El juez Alvin Hellerstein fij\u00f3 inicialmente la audiencia para dar tiempo a los abogados [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-26T06:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/"},"author":{"name":"","@id":""},"headline":"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa","datePublished":"2026-03-26T06:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/"},"wordCount":856,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/","name":"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-26T06:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Nicol\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\u00e1 tratando de obstaculizar su defensa","url":"http:\/\/noticiasya.com\/springfield\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/03\/25\/maduro-regresa-tribunales-estados-unidos-defensa-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-26T06:03:45Z","datePublished":"2026-03-26T06:03:45Z","dateModified":"2026-03-26T06:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Nicol\\u00e1s Maduro regresa a los tribunales con el argumento de que Estados Unidos est\\u00e1 tratando de obstaculizar su defensa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/25\\\/maduro-regresa-tribunales-estados-unidos-defensa-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/03\\\/25\\\/maduro-regresa-tribunales-estados-unidos-defensa-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-26T06:03:45Z\",\"datePublished\":\"2026-03-26T06:03:45Z\",\"dateModified\":\"2026-03-26T06:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471866,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/04\/cilia-flores-nicolas-maduro-venezuela-desestimar-cargos-eeuu-orix\/","url_meta":{"origin":1472565,"position":0},"title":"Cilia Flores, esposa de Nicol\u00e1s Maduro, pide unirse a solicitud para desestimar cargos de narcoterrorismo en EE.UU.","author":"","date":"marzo 4, 2026","format":false,"excerpt":"La esposa del derrocado presidente de Venezuela, Cilia Flores de Maduro, pidi\u00f3 a un juez federal en Nueva York que le permita sumarse a la ofensiva legal de Nicol\u00e1s Maduro para desestimar la acusaci\u00f3n penal que ambos enfrentan en Estados Unidos.En documentos presentados ante la corte este martes, los abogados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472947,"url":"https:\/\/noticiasya.com\/springfield\/2026\/04\/07\/derrota-nicolas-maduro-tribunales-eeuu-juez-prohibe-pruebas-acusados-detenidos-orix\/","url_meta":{"origin":1472565,"position":1},"title":"Nueva derrota para Nicol\u00e1s Maduro en EE.UU.: juez proh\u00edbe compartir pruebas del caso con otros acusados","author":"","date":"abril 7, 2026","format":false,"excerpt":"El juez federal en el proceso penal contra Nicol\u00e1s Maduro en Nueva York dio este martes un nuevo golpe a la defensa del depuesto presidente venezolano al prohibir que sus abogados compartan pruebas del caso con otros acusados que siguen sin ser detenidos, seg\u00fan documentos judiciales.En una orden judicial, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472576,"url":"https:\/\/noticiasya.com\/springfield\/2026\/03\/26\/nicolas-maduro-cilia-flores-segunda-audiencia-eeuu-proceso-penal-orix\/","url_meta":{"origin":1472565,"position":2},"title":"\u00bfQu\u00e9 ha pasado en el proceso penal de Nicol\u00e1s Maduro y Cilia Flores hasta ahora?","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Nicol\u00e1s Maduro y Cilia Flores volver\u00e1n a la corte este jueves. A los 83 d\u00edas de su captura en un operativo militar de Estados Unidos, el derrocado presidente de Venezuela y su esposa tendr\u00e1n su segunda audiencia frente a la justicia estadounidense, ante la que son acusados de delitos relacionados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473606,"url":"https:\/\/noticiasya.com\/springfield\/2026\/04\/28\/juez-eeuu-acepta-licencias-pago-defensa-maduro-orix\/","url_meta":{"origin":1472565,"position":3},"title":"Juez de EE.UU. acepta licencias de la OFAC para que el Gobierno de Venezuela pague la defensa legal de Maduro y su esposa","author":"","date":"abril 28, 2026","format":false,"excerpt":"El juez Alvin K. Hellerstein, quien est\u00e1 a cargo del caso contra Nicol\u00e1s Maduro, acept\u00f3 la decisi\u00f3n del Gobierno de Estados Unidos de permitir que el Gobierno de Venezuela pague la defensa legal del derrocado presidente de Venezuela y de su esposa, la diputada Cilia Flores, quienes desde enero est\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473497,"url":"https:\/\/noticiasya.com\/springfield\/2026\/04\/25\/venezuela-maduro-defensa-legal-trax\/","url_meta":{"origin":1472565,"position":4},"title":"EE.UU. acepta que el Gobierno de Venezuela pague por la defensa de Maduro, lo que pone fin a la disputa legal","author":"","date":"abril 25, 2026","format":false,"excerpt":"Estados Unidos acept\u00f3 permitir que el Gobierno de Venezuela financie la defensa del presidente derrocado Nicol\u00e1s Maduro, lo que pone fin a un enfrentamiento legal.En una carta presentada a \u00faltima hora del viernes por la noche, los fiscales federales informaron al juez que supervisa el caso que el Departamento del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469802,"url":"https:\/\/noticiasya.com\/springfield\/2026\/01\/05\/hijo-maduro-padre-secuestrado-orix\/","url_meta":{"origin":1472565,"position":5},"title":"El hijo de Maduro dice que su padre est\u00e1 &#171;secuestrado&#187; y pide &#171;solidaridad internacional&#187; con \u00e9l","author":"","date":"enero 5, 2026","format":false,"excerpt":"Nicol\u00e1s Maduro Guerra, hijo del presidente Nicol\u00e1s Maduro y diputado del oficialista Partido Socialista Unido de Venezuela (PSUV), dijo este lunes que su padre fue \u201csecuestrado\u201d por Estados Unidos y pidi\u00f3 \u201csolidaridad internacional\u201d con \u00e9l para que regrese al pa\u00eds sudamericano.Maduro Guerra hizo estas declaraciones durante la sesi\u00f3n de instalaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472565"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472565\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}