{"id":1472909,"date":"2026-04-06T18:03:41","date_gmt":"2026-04-07T01:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/"},"modified":"2026-04-06T18:03:41","modified_gmt":"2026-04-07T01:03:41","slug":"minneapolis-tiroteo-ice-video-immigrante-venezolano-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/springfield\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/","title":{"rendered":"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara"},"content":{"rendered":"<p>Un video reci\u00e9n difundido de una c\u00e1mara municipal de Minneapolis arroja luz sobre los momentos previos a un tiroteo en el que estuvieron involucrados un agente de ICE y dos inmigrantes venezolanos en enero, y sobre por qu\u00e9 el relato inicial de la agencia sobre el incidente termin\u00f3 por derrumbarse.<\/p>\n<p>Julio Cesar Sosa-Celis, quien fue baleado por un agente federal, y su primo Alfredo A.<br \/>Aljorna enfrentaron cargos federales despu\u00e9s de que el Departamento de Seguridad Nacional dijo que hab\u00edan atacado violentamente al agente, lo que lo llev\u00f3 a disparar en defensa propia. Pero el Departamento de Justicia retir\u00f3 los cargos en febrero, y el ICE dijo que dos de sus agentes que hicieron declaraciones falsas sobre el incidente bajo juramento fueron puestos en licencia administrativa.<\/p>\n<p>El video de nueve minutos, que muestra un forcejeo de unos 12 segundos entre el agente federal y los dos hombres, parece contradecir el relato del agente de que estuvo involucrado en un forcejeo durante unos tres minutos antes del tiroteo.<br \/>Tambi\u00e9n parece contradecir las reiteradas afirmaciones del Departamento de Seguridad Nacional de que el agente fue golpeado violentamente con una pala para nieve o un palo de escoba. Uno de los hombres que aparecen en el video parece estar sosteniendo una pala, que suelta antes de que comience el forcejeo, y la pala puede verse en el suelo nevado durante todo el encuentro.<\/p>\n<p>La Fiscal\u00eda federal investiga, y los agentes que hicieron \u201cdeclaraciones falsas\u201d sobre el incidente podr\u00edan enfrentar un despido o un proceso penal, dijo a CNN un portavoz de ICE en un comunicado el lunes, en respuesta a preguntas sobre el video.<\/p>\n<p>\u201cEl video es evidencia en investigaciones federales y estatales en curso, as\u00ed que no puedo comentar\u201d, dijo a CNN la abogada de Sosa-Celis, Robin Wolpert. El abogado de Aljorna, Frederick J. Goetz, tambi\u00e9n declin\u00f3 comentar sobre el video.<\/p>\n<p>El incidente ocurri\u00f3 durante el despliegue de varios meses del Departamento de Seguridad Nacional en las llamadas Twin Cities conocido como Operaci\u00f3n Metro Surge, que apunt\u00f3 a inmigrantes indocumentados y deriv\u00f3 en la muerte de dos ciudadanos de EE.UU. a manos de agentes federales. M\u00e1s de 4.000 inmigrantes indocumentados fueron arrestados durante la operaci\u00f3n, dijo el Departamento de Seguridad Nacional.<\/p>\n<p>La exsecretaria del Departamento de Seguridad Nacional, Kristi Noem, describi\u00f3 en su momento las acciones de los hombres como \u201cun intento de homicidio de las fuerzas del orden federales\u201d.<\/p>\n<p>Pero el Departamento de Justicia present\u00f3 en febrero una moci\u00f3n para retirar los cargos contra los hombres, citando \u201cevidencia reci\u00e9n descubierta\u201d que contradice el relato previo de los agentes. Los fiscales federales proporcionaron informaci\u00f3n incorrecta al tribunal, indic\u00f3 el Departamento de Justicia.<\/p>\n<p>\u201cEl video deja absolutamente claro que, al igual que en otras situaciones durante la Operaci\u00f3n Metro Surge, el relato del Gobierno federal sobre lo ocurrido simplemente no coincide con los hechos\u201d, dijo a CNN el alcalde de Minneapolis, Jacob Frey, en un comunicado el lunes.<\/p>\n<p>Las agencias federales han ofrecido relatos contradictorios sobre el incidente.<\/p>\n<p>En su <a href=\"https:\/\/www.dhs.gov\/news\/2026\/01\/15\/dhs-releases-more-details-about-three-violent-criminal-illegal-aliens-who-violently\">relato inicial<\/a>, el 15 de enero, el Departamento de Seguridad Nacional dijo que agentes federales ten\u00edan como objetivo a Sosa-Celis en una detenci\u00f3n de tr\u00e1nsito cuando este huy\u00f3 primero en su veh\u00edculo y luego a pie, resisti\u00e9ndose y agrediendo violentamente al agente de polic\u00eda que intentaba detenerlo. La agencia afirm\u00f3 que otros dos hombres, incluido Aljorna, salieron de un apartamento cercano y atacaron al agente. Los tres hombres golpearon al agente con una pala para nieve o el mango de una escoba durante el incidente, seg\u00fan el comunicado, antes de que el agente disparara \u201cun tiro defensivo para defender su vida\u201d.<\/p>\n<p>Pero al d\u00eda siguiente, el Departamento de Justicia ofreci\u00f3 un relato diferente en una presentaci\u00f3n para respaldar los cargos penales contra Sosa-Celis y Aljorna.<br \/>Aljorna conduc\u00eda el veh\u00edculo que los agentes persegu\u00edan, dijeron los fiscales.<br \/>Aljorna huy\u00f3 del auto, y \u00e9l y Sosa-Celis golpearon al agente con una pala o una escoba, seg\u00fan la declaraci\u00f3n jurada.<\/p>\n<p>En febrero, Goetz dijo a CNN que las afirmaciones del Gobierno de Trump de que su cliente y Sosa-Celis atacaron a agentes federales con un palo de escoba o una pala \u201cnunca ocurrieron\u201d.<\/p>\n<p>Los agentes federales segu\u00edan a Aljorna mientras conduc\u00eda, dijo Goetz, y Aljorna perdi\u00f3 el control del auto debido al hielo en la calzada y choc\u00f3 contra un banco de nieve.<\/p>\n<p>Aljorna sali\u00f3 corriendo del auto, y un agente de ICE lo derrib\u00f3 a solo 3 metros de la casa donde Sosa-Celis estaba de pie, seg\u00fan su abogado. Aljorna pudo zafarse de su chaqueta, liber\u00e1ndose del agarre del agente, y corri\u00f3 hacia su primo. Ambos se pusieron detr\u00e1s de la puerta y la cerraron cuando se efectu\u00f3 el disparo, dijo el abogado.<\/p>\n<p>Despu\u00e9s del tiroteo, Sosa-Celis describi\u00f3 haber estado involucrado en un forcejeo con agentes federales mientras ayudaba a Aljorna a escapar del arresto.<\/p>\n<p>Los relatos de los dos hombres fueron reiterados por sus familiares y parejas en entrevistas y videos en vivo de sus llamadas al 911, que difer\u00edan de la declaraci\u00f3n inicial del Departamento de Seguridad Nacional.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un video reci\u00e9n difundido de una c\u00e1mara municipal de Minneapolis arroja luz sobre los momentos previos a un tiroteo en el que estuvieron involucrados un agente de ICE y dos inmigrantes venezolanos en enero, y sobre por qu\u00e9 el relato inicial de la agencia sobre el incidente termin\u00f3 por derrumbarse. Julio Cesar Sosa-Celis, quien fue [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1472909","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un video reci\u00e9n difundido de una c\u00e1mara municipal de Minneapolis arroja luz sobre los momentos previos a un tiroteo en el que estuvieron involucrados un agente de ICE y dos inmigrantes venezolanos en enero, y sobre por qu\u00e9 el relato inicial de la agencia sobre el incidente termin\u00f3 por derrumbarse. Julio Cesar Sosa-Celis, quien fue [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-07T01:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara\",\"datePublished\":\"2026-04-07T01:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/\"},\"wordCount\":907,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/\",\"name\":\"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-07T01:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara - Noticias","og_description":"Un video reci\u00e9n difundido de una c\u00e1mara municipal de Minneapolis arroja luz sobre los momentos previos a un tiroteo en el que estuvieron involucrados un agente de ICE y dos inmigrantes venezolanos en enero, y sobre por qu\u00e9 el relato inicial de la agencia sobre el incidente termin\u00f3 por derrumbarse. Julio Cesar Sosa-Celis, quien fue [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-07T01:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/"},"author":{"name":"","@id":""},"headline":"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara","datePublished":"2026-04-07T01:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/"},"wordCount":907,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/","name":"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-07T01:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/springfield\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\u00f3 antes de que un agente disparara","url":"http:\/\/noticiasya.com\/springfield\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/springfield\/2026\/04\/06\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-07T01:03:41Z","datePublished":"2026-04-07T01:03:41Z","dateModified":"2026-04-07T01:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Se cae una historia de ICE sobre un tiroteo en Minneapolis: un video muestra lo que ocurri\\u00f3 antes de que un agente disparara\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/04\\\/06\\\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/springfield\\\/2026\\\/04\\\/06\\\/minneapolis-tiroteo-ice-video-immigrante-venezolano-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-07T01:03:41Z\",\"datePublished\":\"2026-04-07T01:03:41Z\",\"dateModified\":\"2026-04-07T01:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471249,"url":"https:\/\/noticiasya.com\/springfield\/2026\/02\/15\/hombre-baleado-ice-minneapolis-confesion-trax\/","url_meta":{"origin":1472909,"position":0},"title":"Acusan de agresi\u00f3n a un hombre baleado por un agente de ICE en Minneapolis. Una sorprendente confesi\u00f3n puso fin al caso","author":"","date":"febrero 15, 2026","format":false,"excerpt":"Alfredo Alejandro Aljorna estaba trabajando en Minneapolis una noche de mi\u00e9rcoles del mes pasado, haciendo entregas como conductor de DoorDash, cuando se dio cuenta de que estaba siendo seguido por agentes de ICE, seg\u00fan su abogado.Condujo hasta su casa y fue derribado por un agente, pero logr\u00f3 zafarse y corri\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469910,"url":"https:\/\/noticiasya.com\/springfield\/2026\/01\/08\/que-paso-tiroteo-ice-muerte-mujer-minneapolis-trax\/","url_meta":{"origin":1472909,"position":1},"title":"\u00bfQu\u00e9 pas\u00f3 en el tiroteo en Minneapolis en el que un agente de ICE mat\u00f3 a una mujer? Esto sabemos","author":"","date":"enero 8, 2026","format":false,"excerpt":"El tiroteo mortal de una ciudadana estadounidense por parte de un agente del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Minneapolis este mi\u00e9rcoles podr\u00eda convertirse en un punto de inflexi\u00f3n en la ofensiva migratoria del presidente Donald Trump en las ciudades estadounidenses.Renee Nicole\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469949,"url":"https:\/\/noticiasya.com\/springfield\/2026\/01\/09\/incidente-junio-influir-agente-ice-tiroteo-minneapolis-trax\/","url_meta":{"origin":1472909,"position":2},"title":"Un incidente en junio pudo influir en el agente de ICE que dispar\u00f3 y mat\u00f3 a una mujer en Minneapolis, seg\u00fan expertos","author":"","date":"enero 9, 2026","format":false,"excerpt":"Mientras aumentan las preguntas sobre las circunstancias que llevaron a un agente del Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos (ICE, por sus siglas en ingl\u00e9s) a disparar y matar a una mujer de 37 a\u00f1os en su veh\u00edculo en Minneapolis esta semana, el posible historial traum\u00e1tico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469943,"url":"https:\/\/noticiasya.com\/springfield\/2026\/01\/09\/video-plantea-preguntas-tacticas-agente-ice-jonathan-ross-minneapolis-trax\/","url_meta":{"origin":1472909,"position":3},"title":"Un video plantea nuevas preguntas sobre las t\u00e1cticas del agente de ICE Jonathan Ross antes del mortal tiroteo de Minneapolis","author":"","date":"enero 9, 2026","format":false,"excerpt":"Mientras se acercaba al veh\u00edculo de Renee Good en una calle de Minneapolis el mi\u00e9rcoles, el agente de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) Jonathan Ross levant\u00f3 la c\u00e1mara de su tel\u00e9fono y grab\u00f3 un video.Menos de un minuto despu\u00e9s, todav\u00eda estaba grabando cuando sac\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470182,"url":"https:\/\/noticiasya.com\/springfield\/2026\/01\/17\/ice-tiroteo-minneapolis-renee-good-trax\/","url_meta":{"origin":1472909,"position":4},"title":"Transcripciones del 911, informes y videos muestran c\u00f3mo agente de ICE dispar\u00f3 a una madre de 3 hijos a &#171;quemarropa&#187;","author":"","date":"enero 17, 2026","format":false,"excerpt":"Los registros de llamadas de emergencia y los informes que detallan el tiroteo fatal de Renee Good la semana pasada por parte de un agente federal de inmigraci\u00f3n revelan una mayor sensaci\u00f3n de caos organizacional y gran conmoci\u00f3n en torno a sus momentos finales.Agentes del Servicio de Inmigraci\u00f3n y Control\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469900,"url":"https:\/\/noticiasya.com\/springfield\/2026\/01\/08\/tiroteo-minneapolis-ice-atropello-trax\/","url_meta":{"origin":1472909,"position":5},"title":"El DHS inform\u00f3 que una mujer intent\u00f3 atropellar a agentes de ICE en Minneapolis antes de ser baleada. Aqu\u00ed las im\u00e1genes","author":"","date":"enero 8, 2026","format":false,"excerpt":"Tras el incidente en el que un agente de ICE dispar\u00f3 y mat\u00f3 a una mujer en Minneapolis el mi\u00e9rcoles, el presidente Donald Trump afirm\u00f3 en una publicaci\u00f3n en l\u00ednea que el video del incidente mostraba a la mujer \u201catropellando de forma violenta, deliberada y cruel\u201d al agente.El Departamento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/springfield\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/comments?post=1472909"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/posts\/1472909\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/media?parent=1472909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/categories?post=1472909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/springfield\/wp-json\/wp\/v2\/tags?post=1472909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}