{"id":1447758,"date":"2024-04-05T02:03:41","date_gmt":"2024-04-05T09:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/"},"modified":"2024-04-05T02:03:41","modified_gmt":"2024-04-05T09:03:41","slug":"terremoto-taiwan-lecciones-prevencion-construccion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/","title":{"rendered":"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas"},"content":{"rendered":"<p>Hualien, Taiw\u00e1n (CNN) &#8212; Wu estaba preparando el desayuno para los hu\u00e9spedes del peque\u00f1o hotel que dirige en el condado taiwan\u00e9s de Hualien cuando las estanter\u00edas a su alrededor temblaron violentamente y la monta\u00f1a situada detr\u00e1s de su casa rugi\u00f3.<\/p>\n<p>Temiendo que el edificio se derrumbara, se apresur\u00f3 a poner a salvo a sus hu\u00e9spedes en el exterior. Al otro lado del r\u00edo, escarpadas laderas se desprend\u00edan de las monta\u00f1as, el aire estaba lleno de nubes de polvo.<\/p>\n<p>Pero la casa de Wu apenas sufri\u00f3 da\u00f1os por el terremoto de magnitud 7,4 del 3 de abril, el m\u00e1s potente de los \u00faltimos 25 a\u00f1os en Taiw\u00e1n, algo que \u00e9l atribuye a un esfuerzo m\u00e1s amplio por hacer la isla m\u00e1s resistente a los sismos.<\/p>\n<p>&#171;Tras el terremoto de 1999, nuestro Gobierno llev\u00f3 a cabo una revisi\u00f3n exhaustiva de los c\u00f3digos de construcci\u00f3n, y todos los edificios que se construyan deben utilizar nuevas tecnolog\u00edas que los hagan m\u00e1s resistentes a los sismos&#187;, explica.<\/p>\n<p>Hace 15 a\u00f1os, cuando empez\u00f3 a construir su casa de hu\u00e9spedes de dos plantas cerca de la entrada del desfiladero de Taroko \u2014un parque nacional famoso por sus escarpados ca\u00f1ones con paredes de m\u00e1rmol\u2014, Wu tuvo que obtener la aprobaci\u00f3n del Gobierno para prepararla contra terremotos.<\/p>\n<p>Y los expertos afirman que cambios como \u00e9ste han ayudado a la isla, propensa a los temblores, a evitar v\u00edctimas masivas en sismos como el del mi\u00e9rcoles.<\/p>\n<p>&#171;Me siento muy afortunado&#187;, dice Wu sobre los escasos da\u00f1os causados por el fuerte sismo. &#171;No es demasiado grave&#187;.<\/p>\n<p>C\u00f3mo resiste a los terremotos el Taipei 101, el rascacielos m\u00e1s alto de Taiw\u00e1n<\/p>\n<p>Un puesto de control a las afueras del desfiladero de Taroko, al norte de la ciudad de Hualien, en Taiw\u00e1n. (Cr\u00e9dito: Annabelle Chih\/Getty Images AsiaPac\/Getty Images)<\/p>\n<p>Un ni\u00f1o recibe atenci\u00f3n m\u00e9dica en un puesto de mando de rescate improvisado a las afueras del desfiladero de Taroko tras ser rescatado el 5 de abril de 2024. (Cr\u00e9dito: Annabelle Chih\/Getty Images)<\/p>\n<p>La situaci\u00f3n es similar en Hualien, una ciudad situada a s\u00f3lo 18 kil\u00f3metros del epicentro, que parec\u00eda sorprendentemente tranquila el d\u00eda siguiente del temblor.<\/p>\n<p>Las tiendas y restaurantes han reabierto, al igual que los puestos de frutas, verduras y aperitivos. Los servicios de trenes a la ciudad, suspendidos por precauci\u00f3n el mi\u00e9rcoles, se reanudaron y circulan seg\u00fan lo previsto.<\/p>\n<p>La se\u00f1al m\u00e1s potente del terremoto es una torre de ladrillo rojo de 10 pisos en el centro de la ciudad, que se inclina precariamente en un \u00e1ngulo de 45 grados tras el derrumbe de su planta baja. Las excavadoras han amontonado escombros en la base del edificio Uranus para reforzarlo.<\/p>\n<p>Los equipos de emergencia han empezado a reparar decenas de edificios da\u00f1ados y a demoler cuatro considerados imposibles de salvar. Pero en su mayor parte, la ciudad de 100.000 habitantes de la pintoresca costa oriental de Taiw\u00e1n ha salido indemne.<\/p>\n<p>No se trata de subestimar la fuerza del sismo. Los sism\u00f3logos taiwaneses describen el temblor con una energ\u00eda equivalente a 32 de las bombas at\u00f3micas lanzadas sobre Hiroshima. Sacudi\u00f3 toda la isla de Taiw\u00e1n y se sinti\u00f3 en lugares tan lejanos como Hong Kong y Shangh\u00e1i.<\/p>\n<p>Chong, una ama de casa de 52 a\u00f1os, dijo que hab\u00eda vivido muchos terremotos en Hualien. &#171;Pero la magnitud de este terremoto fue muy aterradora&#187;, dijo. &#171;Nunca hab\u00eda experimentado un terremoto tan grande en mis 50 a\u00f1os aqu\u00ed en Hualien&#187;.<\/p>\n<p>FOTOS | Un fuerte terremoto causa da\u00f1os y destrozos en Taiw\u00e1n<\/p>\n<p>Equipo pesado utilizado para demoler el edificio Uranus en Hualien. (Cr\u00e9dito: Yan Zhao\/AFP\/Getty Images)<\/p>\n<p>Trabajadores derriban un edificio da\u00f1ado tras el terremoto en el condado de Hualien, Taiw\u00e1n, el 4 de abril de 2024. (Cr\u00e9dito: Tyrone Siu\/Reuters)<\/p>\n<p>El terremoto del mi\u00e9rcoles sacudi\u00f3 m\u00e1s zonas de Taiw\u00e1n con mayor intensidad que ning\u00fan otro sismo desde 1999, cuando un temblor de magnitud 7,7 sacudi\u00f3 el centro de la isla, causando 2.400 muertos y 10.000 heridos.<\/p>\n<p>Pero esta vez, el n\u00famero de v\u00edctimas es mucho menor. Hasta este jueves, 10 personas hab\u00edan muerto y algo m\u00e1s de 1.000 estaban heridas, mientras que 25 permanec\u00edan desaparecidas, seg\u00fan las autoridades.<\/p>\n<p>&#171;Es un resultado bastante milagroso&#187;, dijo Daniel Aldrich, profesor de Ciencias Pol\u00edticas y Pol\u00edticas P\u00fablicas en la Universidad Northeastern que estudia la capacidad de recuperaci\u00f3n de las ciudades, calificando el balance de &#171;un n\u00famero muy bajo de muertos por un terremoto fuerte y potente cerca de un centro urbano&#187;.<\/p>\n<p>&#171;Las dem\u00e1s cat\u00e1strofes en torno a 7,5 (magnitud) han causado muchas m\u00e1s v\u00edctimas de las que hemos visto hasta ahora en Taiw\u00e1n&#187;, afirm\u00f3, citando las decenas de miles de muertos durante anteriores sismos en Hait\u00ed, India y China.<\/p>\n<p>Rescatan a un hombre inconsciente en Taiw\u00e1n tras el terremoto 0:31<\/p>\n<p>&#171;Crecimos con terremotos&#187;<\/p>\n<p>El sismo del mi\u00e9rcoles sacudi\u00f3 la costa este rural de Taiw\u00e1n. La mayor parte de la poblaci\u00f3n vive en el oeste de la isla, donde se encuentran las ciudades m\u00e1s grandes, una extensa red ferroviaria de alta velocidad y gran parte del coraz\u00f3n industrial.<\/p>\n<p>La mayor parte de la destrucci\u00f3n y de las muertes se produjeron en zonas rurales remotas del condado de Hualien.<\/p>\n<p>La mayor\u00eda de las v\u00edctimas murieron al aire libre por la ca\u00edda de rocas o corrimientos de tierra. Seg\u00fan las autoridades, cuatro de ellas estaban de excursi\u00f3n en el desfiladero de Taroko, otras cuatro murieron en carreteras de monta\u00f1a y otra estaba trabajando en una cantera remota.<\/p>\n<p>Hasta ahora, s\u00f3lo hab\u00eda muerto una persona en un edificio derrumbado: el edificio Uranus, en el centro de Hualien. En un principio escap\u00f3, pero regres\u00f3 para rescatar a su gato, inform\u00f3 la filial de CNN, SET.<\/p>\n<p>Enormes rocas cayeron en una carretera costera que conecta Hualien con el norte de Taiw\u00e1n tras el terremoto. (Cr\u00e9dito: Sam Yeh\/AFP\/Getty Images)<\/p>\n<p>Los equipos de rescate se preparan para entrar en el desfiladero de Taroko para buscar a los que siguen desaparecidos dentro del parque el 5 de abril de 2024. (Cr\u00e9dito: Annabelle Chih\/Getty Images)<\/p>\n<p>Seg\u00fan los expertos, el reciente impulso de Taiw\u00e1n en materia de preparaci\u00f3n se debe a las duras lecciones aprendidas del devastador sismo de hace 25 a\u00f1os.<\/p>\n<p>Cuando se produjo el sismo en 1999, Taiw\u00e1n no estaba preparada, afirma Aldrich, citando la corrupci\u00f3n en el sector de la construcci\u00f3n, la falta de normas de edificaci\u00f3n y la inadecuada coordinaci\u00f3n de las labores de rescate.<\/p>\n<p>Aquel sismo dej\u00f3 m\u00e1s de 100.000 edificios total o parcialmente derrumbados en todo Taiw\u00e1n, incluidas casi 300 escuelas. Tambi\u00e9n se derrumbaron edificios en la capital, Taipei, a unos 160 km del epicentro.<\/p>\n<p>&#171;Lo que hemos visto desde entonces son mejoras masivas en todos los \u00e1mbitos, lo que yo llamar\u00eda un conjunto de respuestas de arriba abajo sobre un conjunto de respuestas de abajo arriba&#187;, dijo Aldrich.<\/p>\n<p>De arriba abajo, el Gobierno ha reforzado las leyes de gesti\u00f3n de cat\u00e1strofes, ha mejorado la coordinaci\u00f3n de las operaciones de rescate y socorro y ha aplicado c\u00f3digos de construcci\u00f3n m\u00e1s estrictos para resistir los terremotos.<br \/>\n&#171;Se han impuesto multas y sanciones masivas a las empresas constructoras que han hecho alg\u00fan tipo de recorte en la construcci\u00f3n. Y se ha invertido mucho en todos los edificios nuevos&#187;, afirm\u00f3 Aldrich.<br \/>\nEl Gobierno de Taiw\u00e1n lanz\u00f3 una campa\u00f1a para evaluar, modernizar o reconstruir los edificios p\u00fablicos con el fin de mejorar su capacidad para resistir terremotos m\u00e1s fuertes, siendo las escuelas una de las prioridades. Desde entonces, la campa\u00f1a se ha extendido a edificios privados, como el de Wu.<br \/>\nEl 21 de septiembre \u2014fecha en que se produjo el mort\u00edfero terremoto de 1999\u2014 es ahora el d\u00eda designado para los simulacros de cat\u00e1strofe en Taiw\u00e1n, con el env\u00edo de mensajes de alerta a los tel\u00e9fonos m\u00f3viles de toda la isla y la realizaci\u00f3n de ejercicios de evacuaci\u00f3n en las escuelas.<\/p>\n<p>Rescatistas buscan a sobrevivientes entre los edificios derribados en Taiw\u00e1n tras el peligroso terremoto<\/p>\n<p>El alcalde de Hualien, Wei Chia-yen, atribuye el n\u00famero relativamente bajo de v\u00edctimas mortales en su ciudad a la preparaci\u00f3n anticipada.<br \/>\n&#171;Aqu\u00ed, en Hualien, hemos crecido con los terremotos&#187;, dijo en el interior de un gimnasio convertido en refugio de una escuela primaria, instalado pocas horas despu\u00e9s del sismo.<br \/>\nSe han levantado hileras de tiendas de campa\u00f1a para los residentes cuyas casas han resultado da\u00f1adas, o que temen regresar debido a las r\u00e9plicas, mientras en las mesas se extienden cajas de comida y bebida.<br \/>\nEl propio Wei result\u00f3 herido por la ca\u00edda de un armario sobre su pierna izquierda y utiliza muletas para desplazarse por el refugio.<br \/>\n&#171;Nuestros profesores y familiares siempre nos han ense\u00f1ado a reaccionar cuando se produce un terremoto&#187;, explica. &#171;As\u00ed que sab\u00edamos de esto desde que \u00e9ramos ni\u00f1os&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hualien, Taiw\u00e1n (CNN) &#8212; Wu estaba preparando el desayuno para los hu\u00e9spedes del peque\u00f1o hotel que dirige en el condado taiwan\u00e9s de Hualien cuando las estanter\u00edas a su alrededor temblaron violentamente y la monta\u00f1a situada detr\u00e1s de su casa rugi\u00f3. Temiendo que el edificio se derrumbara, se apresur\u00f3 a poner a salvo a sus hu\u00e9spedes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447758","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas - Noticias\" \/>\n<meta property=\"og:description\" content=\"Hualien, Taiw\u00e1n (CNN) &#8212; Wu estaba preparando el desayuno para los hu\u00e9spedes del peque\u00f1o hotel que dirige en el condado taiwan\u00e9s de Hualien cuando las estanter\u00edas a su alrededor temblaron violentamente y la monta\u00f1a situada detr\u00e1s de su casa rugi\u00f3. Temiendo que el edificio se derrumbara, se apresur\u00f3 a poner a salvo a sus hu\u00e9spedes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-05T09:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas\",\"datePublished\":\"2024-04-05T09:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/\"},\"wordCount\":1590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/\",\"name\":\"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-05T09:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas - Noticias","og_description":"Hualien, Taiw\u00e1n (CNN) &#8212; Wu estaba preparando el desayuno para los hu\u00e9spedes del peque\u00f1o hotel que dirige en el condado taiwan\u00e9s de Hualien cuando las estanter\u00edas a su alrededor temblaron violentamente y la monta\u00f1a situada detr\u00e1s de su casa rugi\u00f3. Temiendo que el edificio se derrumbara, se apresur\u00f3 a poner a salvo a sus hu\u00e9spedes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/","og_site_name":"Noticias","article_published_time":"2024-04-05T09:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/"},"author":{"name":"","@id":""},"headline":"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas","datePublished":"2024-04-05T09:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/"},"wordCount":1590,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/","url":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/","name":"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-05T09:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El mayor terremoto en d\u00e9cadas que sacudi\u00f3 Taiw\u00e1n no la dobleg\u00f3 y puso en relieve su preparaci\u00f3n. Estas son las lecciones aprendidas","url":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/05\/terremoto-taiwan-lecciones-prevencion-construccion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-05T09:03:41Z","datePublished":"2024-04-05T09:03:41Z","dateModified":"2024-04-05T09:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El mayor terremoto en d\\u00e9cadas que sacudi\\u00f3 Taiw\\u00e1n no la dobleg\\u00f3 y puso en relieve su preparaci\\u00f3n. Estas son las lecciones aprendidas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/04\\\/05\\\/terremoto-taiwan-lecciones-prevencion-construccion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/04\\\/05\\\/terremoto-taiwan-lecciones-prevencion-construccion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-05T09:03:41Z\",\"datePublished\":\"2024-04-05T09:03:41Z\",\"dateModified\":\"2024-04-05T09:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1447913,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/09\/roger-perro-estrella-rescates-terremoto-taiwan-trax\/","url_meta":{"origin":1447758,"position":0},"title":"\u201cRoger\u201d, un perro demasiado juguet\u00f3n que fracas\u00f3 en la academia de polic\u00eda, es una estrella en los rescates tras el terremoto de Taiw\u00e1n","author":"","date":"abril 9, 2024","format":false,"excerpt":"Taipei, Taiw\u00e1n (CNN) -- Un labrador que no logr\u00f3 convertirse en un perro detector de drogas porque era demasiado amigable y juguet\u00f3n se ganas corazones en todo Taiw\u00e1n por su trabajo en las operaciones de b\u00fasqueda despu\u00e9s del terremoto de magnitud 7,4 que sacudi\u00f3 la isla la semana pasada.Los perros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447665,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/02\/sismo-de-magnitud-75-sacude-taiwan-cerca-de-la-ciudad-de-hualien-reporta-usgs\/","url_meta":{"origin":1447758,"position":1},"title":"Sismo de magnitud 7,4 sacude la costa este de Taiw\u00e1n, reporta USGS: hay alerta de tsunami","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN) \u2013\u2013\u00a0 Un fuerte sismo de magnitud 7,4 sacudi\u00f3 la costa este de Taiw\u00e1n en la ma\u00f1ana de este mi\u00e9rcoles, hora local, report\u00f3 el Servicio Geol\u00f3gico de Estados Unidos (USGS, por sus siglas en ingl\u00e9s).El sismo tuvo una profundidad de 34,8 kil\u00f3metros, seg\u00fan la entidad. Su epicentro se ubic\u00f3 a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469604,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/12\/27\/terremoto-taiwan-trax\/","url_meta":{"origin":1447758,"position":2},"title":"Terremoto de magnitud 6,6 sacude a Taiw\u00e1n; no hay reportes inmediatos de v\u00edctimas ni da\u00f1os","author":"","date":"diciembre 27, 2025","format":false,"excerpt":"Taiw\u00e1n fue sacudido por un terremoto de magnitud 6,6 este s\u00e1bado por la noche, hora local, seg\u00fan el Servicio Geol\u00f3gico de Estados Unidos (USGS). Hasta ahora no se han reportado v\u00edctimas ni da\u00f1os.El terremoto ocurri\u00f3 a las 11:05 p.m. hora local, a 31 kil\u00f3metros al este de la costa de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466763,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/24\/tifon-ragasa-china-muertos-taiwan-trax\/","url_meta":{"origin":1447758,"position":3},"title":"El mortal tif\u00f3n Ragasa azota la costa densamente poblada del sur de China luego de dejar 14 muertos en Taiw\u00e1n","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"Un enorme tif\u00f3n que ya caus\u00f3 inundaciones fatales en Taiw\u00e1n, donde hay 14 muertos y 124 desaparecidos, est\u00e1 azotando una de las costas m\u00e1s densamente pobladas del mundo, causando vientos huracanados y fuertes lluvias a ciudades del sur de China, como Hong Kong y Shenzhen.El tif\u00f3n Ragasa, que hace unos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460582,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/03\/29\/voces-myanmar-devastada-terremoto-esto-escuchamos-trax\/","url_meta":{"origin":1447758,"position":4},"title":"Empiezan a surgir voces desde Myanmar, devastada por el terremoto. Esto es lo que escuchamos","author":"","date":"marzo 29, 2025","format":false,"excerpt":"Un potente y mortal terremoto sacudi\u00f3 el viernes el coraz\u00f3n de Myanmar, devastada por la guerra civil, lo que ha a\u00f1adido m\u00e1s miseria a una naci\u00f3n empobrecida que estaba aislada de gran parte del mundo incluso antes de que se produjera este desastre natural.El momento no pod\u00eda ser peor. El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460541,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/03\/28\/terremoto-myanmar-tailandia-victimas-danos-trax\/","url_meta":{"origin":1447758,"position":5},"title":"\u00bfQu\u00e9 ha pasado tras el fuerte terremoto en Myanmar y Tailandia y cu\u00e1ntas v\u00edctimas hay? Esto sabemos","author":"","date":"marzo 28, 2025","format":false,"excerpt":"Un fuerte terremoto de magnitud 7,7 sacudi\u00f3 el centro de Myanmar, provocando temblores y r\u00e9plicas a lo largo de cientos de kil\u00f3metros en el sudeste asi\u00e1tico.El terremoto se produjo cerca de Mandalay, la segunda ciudad m\u00e1s grande de Myanmar y hogar de m\u00e1s de un mill\u00f3n de personas, pero evaluar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1447758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1447758"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1447758\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1447758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1447758"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1447758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}