{"id":1447955,"date":"2024-04-11T12:03:43","date_gmt":"2024-04-11T19:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/"},"modified":"2024-04-11T12:03:43","modified_gmt":"2024-04-11T19:03:43","slug":"drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/","title":{"rendered":"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En el a\u00f1o en que Argentina cumple, por primera vez en su historia, 40 a\u00f1os ininterrumpidos de democracia, el pa\u00eds tiene un gobierno que confronta abiertamente las pol\u00edticas llamadas de \u201cMemoria, verdad y justicia\u201d, que juzgan los delitos cometidos por la \u00faltima dictadura militar (1976-1983), que incluye el secuestro, tortura, asesinato y desaparici\u00f3n de miles de personas y el robo de menores. Esa discrepancia termina reflej\u00e1ndose en el desfinanciamiento de las pol\u00edticas oficiales de derechos humanos y, sobre todo, las relacionadas con la reparaci\u00f3n por los delitos de la dictadura. Desde el gobierno sostienen que no hubo recortes, sino &#171;ahorro&#187; porque &#171;el despilfarro era absoluto y total&#187; y que &#171;todas las \u00e1reas est\u00e1n llevando adelante sus actividades de acuerdo con el nuevo paradigma&#187;.<\/p>\n<p>Seg\u00fan c\u00e1lculos del Centro de Estudios de Pol\u00edtica Econ\u00f3mica Argentina (CEPA), el gobierno ejecut\u00f3 17% menos de presupuesto en t\u00e9rminos reales en pol\u00edticas de derechos humanos si se compara el periodo enero-marzo de 2024 con el de 2023.<\/p>\n<p>El Banco Nacional de Datos Gen\u00e9ticos, un ente oficial creado en 1987 para recolectar y preservar muestras biol\u00f3gicas de familiares de personas desaparecidas para encontrar a ni\u00f1os robados y apropiados por la \u00faltima dictadura, tiene una subejecuci\u00f3n de 37,25% en t\u00e9rminos reales hasta ahora, seg\u00fan este an\u00e1lisis basado en datos oficiales.<\/p>\n<p>Mayor fue el recorte del Archivo Nacional de la Memoria, que preserva documentaci\u00f3n sobre la violaci\u00f3n de derechos humanos en Argentina, en su mayor\u00eda vinculados con la \u00faltima dictadura, y que sirve como prueba en los juicios por delitos de lesa humanidad: sufri\u00f3 una poda de 56%.<\/p>\n<p>El informe tambi\u00e9n da cuenta de que otras actividades no han tenido ejecuci\u00f3n alguna: cayeron 100%. Eso sucede, por ejemplo, con el programa de fortalecimiento de procesos judiciales contra delitos de lesa humanidad, que busca ayudar, entre otras cuestiones, a agilizar las etapas de instrucci\u00f3n de las causas (producci\u00f3n de pruebas) y juicios para evitar la llamada \u201cimpunidad biol\u00f3gica\u201d, por el fallecimiento de los imputados antes de lograr ser condenados, as\u00ed como de testigos y familiares de v\u00edctimas.<\/p>\n<p>La misma suerte corre la muestra permanente del Museo Sitio de Memoria ESMA, donde funcion\u00f3 el centro de detenci\u00f3n y tortura m\u00e1s emblem\u00e1tico de la dictadura en Argentina y que desde 2023 forma parte de la Lista del Patrimonio Mundial de la Unesco. Su prepuesto no ha sido ejecutado en lo que va del a\u00f1o.<\/p>\n<p>\u201cEn t\u00e9rminos reales, descontada la inflaci\u00f3n, la ejecuci\u00f3n de todas \u2013\u2013menos una\u2013\u2013 de las partidas en materia de derechos humanos cay\u00f3 muy fuerte. Hay algunos sectores en los que, directamente, no se han ejecutado ni un solo peso. Hablamos de una paralizaci\u00f3n total, han sido abandonados\u201d, explica el investigador del CEPA Juan Pablo Costa, que realiz\u00f3 este an\u00e1lisis. \u201cLa \u00fanica actividad que tuvo un crecimiento fue la categor\u00eda de promoci\u00f3n y defensa de los derechos humanos, con una suba del 6% real\u201d, agrega.<\/p>\n<p>Adem\u00e1s, estos sectores no escapan a los recortes generales de todos los organismos del Estado, que est\u00e1n trabajando con el presupuesto prorrogado de 2023, atrasado en t\u00e9rminos reales por la inflaci\u00f3n, que ese a\u00f1o fue de 211,4% \u2013la m\u00e1s alta del mundo\u2013, y que en el primer bimestre de 2024 acumula 36,6%.<\/p>\n<p>\u201cEn el resto de las \u00e1reas del Estado tambi\u00e9n hubo un fuerte ajuste, pero no con niveles de ca\u00edda tan fuertes y con tantas actividades con pr\u00e1cticamente sin ejecuci\u00f3n como en derechos humanos. Hablamos de una paralizaci\u00f3n casi total que est\u00e1 vinculada, obviamente, a que este es un gobierno que a la lucha por los derechos humanos no la tiene en agenda\u201d, a\u00f1ade Costa.<\/p>\n<p>Desde la Secretar\u00eda de Derechos Humanos sostienen que &#171;no hay subejecuci\u00f3n presupuestaria. Hay ahorro.<\/p>\n<p>La justicia argentina ordena la inhibici\u00f3n de bienes del expresidente Alberto Fern\u00e1ndez por la causa de los seguros<\/p>\n<p>Sus voceros agregaron que ning\u00fan Espacio de Memoria dej\u00f3 de funcionar. &#171;El Museo Sitio de Memoria ex ESMA funciona normalmente, el Archivo Nacional de la Memoria tambi\u00e9n. Todas las \u00e1reas est\u00e1n llevando adelante sus actividades de acuerdo al nuevo paradigma. Adem\u00e1s se mejor\u00f3 la imagen internacional de nuestro pa\u00eds contestando los requerimientos de los organismos Interamericanos y del Sistema Universal de Protecci\u00f3n de Derechos Humanos&#187;, sostuvieron.<\/p>\n<p>Al igual que en otras \u00e1reas del Estado, ya ha habido despidos y muchos temen quedarse sin empleo en las pr\u00f3ximas semanas, a medida que el gobierno decide no renovar los contratos de trabajo temporales, como acaba de hacer con muchos que vencieron el 31 de marzo. Por eso, la Asociaci\u00f3n de Trabajadores del Estado (ATE) realiz\u00f3 varias protestas frente a la sede de la Secretar\u00eda de Derechos Humanos reclamando la reincorporaci\u00f3n de los despedidos y la renovaci\u00f3n a los trabajadores contratados.<\/p>\n<p>La directora ejecutiva de Amnist\u00eda Internacional Argentina, Mariela Belski, rechaza que se desmantelen estas pol\u00edticas p\u00fablicas, de las que Argentina es punta de lanza.<\/p>\n<p>\u201cArgentina es un ejemplo a nivel regional e internacional respecto a c\u00f3mo se lleva adelante todo lo que tiene que ver con la dictadura militar y sobre todo la implementaci\u00f3n de pol\u00edticas de reparaci\u00f3n. Ahora viene el Gobierno y cierra y desmantela todos estos programas que costaron mucho llevar adelante y que tienen que ver con la memoria colectiva\u201d, sostiene.<\/p>\n<p>\u201cTiene que ver con la construcci\u00f3n del proceso democr\u00e1tico argentino, con la creencia de un Estado de derecho. Todas cuestiones en las que este gobierno realmente no cree\u201d, agrega.<\/p>\n<p>La versi\u00f3n del gobierno de Milei sobre lo sucedido en los 70<\/p>\n<p>Ning\u00fan otro gobierno, ni siquiera el de Carlos Menem, que indult\u00f3 en 1989 y 1990 a los m\u00e1ximos responsables de esos cr\u00edmenes atroces (indultos que luego fueron declarados inconstitucionales), se anim\u00f3 a tanto con un tema tan sensible para los argentinos.<\/p>\n<p>Para el presidente Javier Milei \u201cen los 70 hubo una guerra\u201d en la que \u201clas fuerzas del Estado cometieron excesos\u201d, tal como sostuvo en el primer debate presidencial, donde dijo estar \u201cen contra de una visi\u00f3n tuerta de la historia\u201d al recordar que \u201cterroristas de Montoneros, del ERP (Ej\u00e9rcito Revolucionario del Pueblo) mataron gente, asesinaron, torturaron, pusieron bombas\u201d, sin diferenciar las magnitudes de los delitos de un lado y del otro. En el primer caso, fue el Estado el que mont\u00f3 esa inmensa maquinaria represiva sistem\u00e1tica e ilegal, comprobada y condenada por numerosos tribunales de Justicia argentinos e internacionales, que tambi\u00e9n condenaron y encarcelaron a varios miembros de esas organizaciones subversivas aludidas.<\/p>\n<p>La vicepresidenta, Victoria Villarruel, cuestiona la cifra de desaparecidos, que oscila entre alrededor de 9.000 que document\u00f3 Conadep hasta los 30.000 que sostienen algunos organismos de DD.HH., y trata de instalar un manto de sospecha de corrupci\u00f3n en el cobro de las indemnizaciones a las v\u00edctimas del terrorismo de Estado.<\/p>\n<p>El Gobierno de Argentina quiere reformar Ley de Educaci\u00f3n para \u201cpenalizar el adoctrinamiento\u201d en las escuelas<\/p>\n<p>Belski recuerda que el nuevo Gobierno tiene varios puntos de contraste con las pol\u00edticas anteriores.<\/p>\n<p>\u201cEl gobierno tiene una estrategia muy peculiar en t\u00e9rminos de marcar una diferencia con el gobierno kirchnerista. Construyeron muy bien esta idea de \u2018casta\u2019 en el sentido de que detr\u00e1s de todas esas personas hay procesos, contrataciones o negocios turbios, oscuros y que entonces todo lo que es \u2018casta\u2019 est\u00e1 vinculado a la corrupci\u00f3n, al robo y b\u00e1sicamente a los problemas que tenemos hoy los argentinos desde el punto de vista econ\u00f3mico\u201d, sostiene.<\/p>\n<p>\u201cCon esta idea de que la casta es lo malo y a donde no hay que volver, lamentablemente se monta esta idea que todo lo que fue el proceso de Verdad, memoria y justicia hay que cuestionarlo, hay que volver a discutirlo y replantearlo\u201d, a\u00f1ade.<\/p>\n<p>Villarruel se refer\u00eda en esos t\u00e9rminos en 2022: \u201cTodo lo que han escuchado en los \u00faltimos 40 a\u00f1os de la Rep\u00fablica argentina en lo referido a su pasado es falso. Todo lo que han escuchado respecto de Argentina ha sido construido por la izquierda, por las Madres de Plaza de Mayo, por las Abuelas (de Plaza de Mayo) y por todos aquellos que integraron Montoneros y el Ej\u00e9rcito Revolucionario del Pueblo. Ni Argentina est\u00e1 en la vanguardia de los derechos humanos ni las Madres y las Abuelas son blancas palomas\u201d, sosten\u00eda la actual vicepresidenta en una conferencia en Espa\u00f1a organizada por el partido de ultraderecha Vox.<\/p>\n<p>Villarruel proviene de una familia de militares activos en la d\u00e9cada del 70, fund\u00f3 una asociaci\u00f3n civil autodenominada Centro de Estudios Legales sobre el Terrorismo y sus V\u00edctimas (Celtyv) y ha reconocido que sostuvo encuentros en la c\u00e1rcel con el dictador Jorge Rafael Videla, m\u00e1ximo responsable de la mayor\u00eda de las desapariciones denunciadas por haber gobernado entre 1976 y 1981.<\/p>\n<p>Ya en el poder, Milei y Villarruel insisten en sus teor\u00edas: \u201cEn los 70 se combati\u00f3 al terrorismo. \u00bfD\u00f3nde est\u00e1n los que lo combatieron? Presos\u201d, afirm\u00f3 la vicepresidenta el 21 de marzo, en su primera entrevista televisiva desde que asumi\u00f3 el cargo, pocos d\u00edas antes de un nuevo D\u00eda Nacional de la Memoria por la Verdad y la Justicia, que se conmemora cada 24 de marzo para recordar el inicio de la \u00faltima dictadura y que el kirchnerismo convirti\u00f3 en feriado.<\/p>\n<p>Ese domingo, mientras varios organismos de derechos humanos, partidos de izquierda, el peronismo, gremios y muchos ciudadanos sin banderas pol\u00edticas marchaban hacia Plaza de Mayo como cada 24 de marzo, el gobierno difundi\u00f3 en redes sociales \u201csu versi\u00f3n\u201d sobre los \u030170 y la dictadura: un video de casi 13 minutos titulado &#171;Memoria, verdad y justicia completa&#187; en el que sostiene que \u201cla historia no se cont\u00f3 de manera completa\u201d y que \u201cse hizo por plata\u201d.<\/p>\n<p>\u201cHubo un reconocimiento a quienes hab\u00edan destrozado la Argentina, o iban a destrozar la Argentina, y se quedaron con mucho dinero. Cifras enormes, de aquel entonces y de hoy, US$ 200.000 para cada uno\u201d, expres\u00f3 all\u00ed Juan Bautista \u201cTata\u201d Yofre, periodista y exjefe de los servicios de inteligencia durante la presidencia de Menem.<\/p>\n<p>Argentina concede asilo a l\u00edderes opositores venezolanos hospedados en su embajada en Caracas<\/p>\n<p>En el video tambi\u00e9n aparece Luis Labra\u00f1a, exintegrante de la organizaci\u00f3n Montoneros, que sostiene que la cifra de v\u00edctimas de la dictadura se &#171;invent\u00f3&#187; y \u00e9l fue quien pronunci\u00f3 por primera vez el n\u00famero de 30.000 desaparecidos, luego convertido en s\u00edmbolo. Tambi\u00e9n habla una de las principales defensoras de la denominada &#171;memoria completa&#187;: Mar\u00eda Fernanda, hija del capit\u00e1n Humberto Viola, muerto el 1\u00b0 de diciembre de 1974 en un operativo del ERP.<\/p>\n<p>Adem\u00e1s de retuitear el video del gobierno, la vicepresidenta public\u00f3 en su cuenta de X otro video, realizado por su asociaci\u00f3n civil, donde escribi\u00f3: \u201cLos DDHH son para Todos. La Memoria tambi\u00e9n. Verdad, Justicia y Reparaci\u00f3n para las v\u00edctimas del terrorismo. Los responsables de estos cr\u00edmenes no pueden quedar impunes. #NoFueron30000\u201d. Esa etiqueta fue usada por muchos de sus seguidores para contrarrestar a quienes marchaban proclamando lo contrario.<\/p>\n<p>Belski vincula las t\u00e1cticas de polarizaci\u00f3n con intenciones ajenas al asunto.<\/p>\n<p>\u201cNosotros creemos que la confrontaci\u00f3n funciona como un veh\u00edculo para desviar la atenci\u00f3n de problemas reales, como la pobreza, la indigencia, el hambre, la falta de acceso a medicamentos y todo ese tipo de problemas que estamos teniendo en Argentina. Con todo esto se tapa\u201d, afirma la directora ejecutiva de Amnist\u00eda Internacional Argentina.<\/p>\n<p>Pero esta t\u00e1ctica no solo se utiliza en el campo de los derechos humanos. Por eso, desde la organizaci\u00f3n advierten sobre los riesgos de un aumento de violencia con este tipo de discursos desde el gobierno. \u201cSi el propio presidente est\u00e1 todo el d\u00eda agrediendo, insultando y generando odio y violencia, eso es lo que transmite a la sociedad, que cree que est\u00e1 habilitada para eso. Entonces, es probable que se genere una sociedad mucho m\u00e1s violenta, mucho m\u00e1s agresiva\u201d, finaliza.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; En el a\u00f1o en que Argentina cumple, por primera vez en su historia, 40 a\u00f1os ininterrumpidos de democracia, el pa\u00eds tiene un gobierno que confronta abiertamente las pol\u00edticas llamadas de \u201cMemoria, verdad y justicia\u201d, que juzgan los delitos cometidos por la \u00faltima dictadura militar (1976-1983), que incluye el secuestro, tortura, asesinato y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1447955","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; En el a\u00f1o en que Argentina cumple, por primera vez en su historia, 40 a\u00f1os ininterrumpidos de democracia, el pa\u00eds tiene un gobierno que confronta abiertamente las pol\u00edticas llamadas de \u201cMemoria, verdad y justicia\u201d, que juzgan los delitos cometidos por la \u00faltima dictadura militar (1976-1983), que incluye el secuestro, tortura, asesinato y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-11T19:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos\",\"datePublished\":\"2024-04-11T19:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/\"},\"wordCount\":2064,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/\",\"name\":\"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-04-11T19:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; En el a\u00f1o en que Argentina cumple, por primera vez en su historia, 40 a\u00f1os ininterrumpidos de democracia, el pa\u00eds tiene un gobierno que confronta abiertamente las pol\u00edticas llamadas de \u201cMemoria, verdad y justicia\u201d, que juzgan los delitos cometidos por la \u00faltima dictadura militar (1976-1983), que incluye el secuestro, tortura, asesinato y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/","og_site_name":"Noticias","article_published_time":"2024-04-11T19:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/"},"author":{"name":"","@id":""},"headline":"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos","datePublished":"2024-04-11T19:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/"},"wordCount":2064,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/","url":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/","name":"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-04-11T19:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El dr\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos","url":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/11\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-04-11T19:03:43Z","datePublished":"2024-04-11T19:03:43Z","dateModified":"2024-04-11T19:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El dr\\u00e1stico giro de Argentina en DD.HH.: nuevo discurso y menos recursos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/04\\\/11\\\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/04\\\/11\\\/drastico-giro-argentina-dd-hh-nuevo-discurso-menos-recursos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-04-11T19:03:43Z\",\"datePublished\":\"2024-04-11T19:03:43Z\",\"dateModified\":\"2024-04-11T19:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452107,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/08\/23\/milei-cierra-organismo-ninos-apropiados-dictadura-argentina-orix\/","url_meta":{"origin":1447955,"position":0},"title":"Milei cierra un organismo oficial que buscaba a los ni\u00f1os apropiados ilegalmente durante la \u00faltima dictadura en Argentina","author":"","date":"agosto 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Las Abuelas de Plaza de Mayo han encontrado a casi 140 nietos. Eran ni\u00f1os \u2014hoy adultos de alrededor de 45 a\u00f1os\u2014 que fueron sustra\u00eddos ilegalmente a sus padres, quienes fueron detenidos durante la \u00faltima dictadura de Argentina (1976-1983) y que en muchos casos permanecen desaparecidos. Pero a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447321,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/03\/25\/javier-milei-difunde-polemico-video-dia-de-la-memoria-orix\/","url_meta":{"origin":1447955,"position":1},"title":"El Gobierno de Javier Milei difunde un pol\u00e9mico video en el D\u00eda de la Memoria","author":"","date":"marzo 25, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 La Casa Rosada public\u00f3 en su cuenta oficial de X un video de casi 13 minutos titulado \u201cD\u00eda de la Memoria por la Verdad y la Justicia. Completa\u201d, que se enfoca en los a\u00f1os previos al golpe castrense de 1976 sin mencionar a los desaparecidos de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451981,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/08\/19\/investigacion-visita-diputados-represores-dictadura-argentina-orix\/","url_meta":{"origin":1447955,"position":2},"title":"Comienza la investigaci\u00f3n por la visita de diputados oficialistas a represores de la dictadura militar en Argentina","author":"","date":"agosto 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La pol\u00e9mica que desencaden\u00f3 la visita en una c\u00e1rcel por seis diputados oficialistas a militares condenados por cr\u00edmenes perpetrados durante la dictadura de los 70 en Argentina tendr\u00e1 este martes un nuevo cap\u00edtulo en la C\u00e1mara de Diputados. La Comisi\u00f3n de Peticiones, Poderes y Reglamento de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447295,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/03\/24\/que-se-conmemora-24-de-marzo-argentina-orix\/","url_meta":{"origin":1447955,"position":3},"title":"\u00bfQu\u00e9 se conmemora el 24 de marzo en Argentina?","author":"","date":"marzo 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Los argentinos gozan de su periodo de democracia ininterrumpida m\u00e1s prolongado, pero 48 a\u00f1os atr\u00e1s la historia era muy diferente. \u00bfPor qu\u00e9 el 24 de marzo es una fecha tan significativa?Este domingo, Argentina conmemora el D\u00eda de la Memoria por la Verdad y la Justicia, un feriado inamovible\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460342,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/03\/24\/juan-cabandie-el-nunca-mas-no-tiene-partido-politico-es-un-consenso\/","url_meta":{"origin":1447955,"position":4},"title":"Juan Cabandi\u00e9: &#171;El Nunca M\u00e1s no tiene partido pol\u00edtico: es un consenso&#187;","author":"","date":"marzo 24, 2025","format":false,"excerpt":"Juan Cabandi\u00e9, exministro de Ambiente y nieto n\u00famero 77, convers\u00f3 con Nacho Gir\u00f3n en La Ma\u00f1ana de CNN sobre el video del Gobierno de Javier Milei por el D\u00eda de la Memoria.Sobre el video del Gobierno por el D\u00eda de la Memoria, Cabandi\u00e9 expres\u00f3: \u201cMemoria completa implica analizar la \u00faltima\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455751,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/11\/11\/milei-venta-centro-clandestino-inmueble-argentina-orix\/","url_meta":{"origin":1447955,"position":5},"title":"Milei pone en venta un inmueble donde funcion\u00f3 un centro clandestino de detenci\u00f3n","author":"","date":"noviembre 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Gobierno de Argentina puso en venta, a trav\u00e9s de un decreto, un inmueble que fue utilizado como centro clandestino de detenci\u00f3n durante la \u00faltima dictadura c\u00edvico-militar (1976-1983) en la provincia de C\u00f3rdoba. Incluy\u00f3 tambi\u00e9n en la lista de futuras subastas un predio que fue identificado como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1447955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1447955"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1447955\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1447955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1447955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1447955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}