{"id":1451347,"date":"2024-07-22T18:03:38","date_gmt":"2024-07-23T01:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/"},"modified":"2024-07-22T18:03:38","modified_gmt":"2024-07-23T01:03:38","slug":"descubrimiento-oxigeno-oscuro-fondo-marino-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/","title":{"rendered":"Cient\u00edficos descubren que se produce ox\u00edgeno &#171;oscuro&#187; a 4.000 metros de profundidad en el oc\u00e9ano"},"content":{"rendered":"<p>(CNN) &#8212; Un fen\u00f3meno misterioso observado por primera vez en 2013 a bordo de un barco en una parte remota del oc\u00e9ano Pac\u00edfico parec\u00eda tan absurdo que convenci\u00f3 al cient\u00edfico oce\u00e1nico Andrew Sweetman de que su equipo de monitoreo estaba defectuoso.<\/p>\n<p>Las lecturas de los sensores parec\u00edan mostrar que se estaba produciendo ox\u00edgeno en el lecho marino a 4.000 metros debajo de la superficie, donde la luz no puede penetrar. Lo mismo ocurri\u00f3 en tres viajes posteriores a una regi\u00f3n conocida como Zona Clarion-Clipperton.<\/p>\n<p>\u201cB\u00e1sicamente les dije a mis alumnos que simplemente volvieran a colocar los sensores en la caja. Los enviaremos de regreso al fabricante y los haremos analizar porque simplemente nos est\u00e1n diciendo tonter\u00edas\u201d, dijo Sweetman, profesor de la Asociaci\u00f3n Escocesa de Ciencias Marinas y l\u00edder del grupo de biogeoqu\u00edmica y ecolog\u00eda del fondo marino de la instituci\u00f3n. \u201cY cada vez el fabricante respond\u00eda: funcionan&#8217;. Est\u00e1n calibrados&#8217;\u201d.<\/p>\n<p>Los organismos fotosint\u00e9ticos como las plantas, el plancton y las algas utilizan la luz solar para producir ox\u00edgeno que circula hacia las profundidades del oc\u00e9ano, pero estudios previos realizados en las profundidades del mar han demostrado que el ox\u00edgeno s\u00f3lo lo consumen, no lo producen, los organismos que viven all\u00ed, dijo Sweetman.<\/p>\n<p>Ahora, la investigaci\u00f3n de su equipo desaf\u00eda esta suposici\u00f3n de larga data, al encontrar ox\u00edgeno producido sin fotos\u00edntesis.<\/p>\n<p>\u201cHay que ser cauteloso cuando se observa algo que va en contra de lo que deber\u00eda estar sucediendo\u201d, afirm\u00f3.<\/p>\n<p>El estudio, publicado el lunes en la revista Nature Geoscience, demuestra cu\u00e1nto se desconoce a\u00fan sobre las profundidades del oc\u00e9ano y subraya lo que est\u00e1 en juego en el impulso para explotar el fondo del oc\u00e9ano en busca de metales y minerales raros. Su hallazgo de que existe otra fuente de ox\u00edgeno en el planeta adem\u00e1s de la fotos\u00edntesis tambi\u00e9n tiene implicaciones de gran alcance que podr\u00edan ayudar a desentra\u00f1ar los or\u00edgenes de la vida.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-1451347-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/07\/microbubbles-horizontal-20240719171244359.mp4?_=1\" \/><a href=\"https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/07\/microbubbles-horizontal-20240719171244359.mp4\">https:\/\/cnnespanol.cnn.com\/wp-content\/uploads\/2024\/07\/microbubbles-horizontal-20240719171244359.mp4<\/a><\/video><\/div>\n<p>Muestreo del fondo marino<\/p>\n<p>Sweetman hizo por primera vez la inesperada observaci\u00f3n de que se produc\u00eda ox\u00edgeno &#171;oscuro&#187; en el fondo marino mientras evaluaba la biodiversidad en un \u00e1rea destinada a la extracci\u00f3n de n\u00f3dulos polimet\u00e1licos del tama\u00f1o de una patata. Los n\u00f3dulos se forman a lo largo de millones de a\u00f1os mediante procesos qu\u00edmicos que hacen que los metales se precipiten fuera del agua alrededor de fragmentos de conchas, picos de calamar y dientes de tibur\u00f3n y cubren un \u00e1rea sorprendentemente grande del fondo marino.<\/p>\n<p>Los metales como el cobalto, el n\u00edquel, el cobre, el litio y el manganeso contenidos en los n\u00f3dulos tienen una gran demanda para su uso en paneles solares, bater\u00edas de autom\u00f3viles el\u00e9ctricos y otras tecnolog\u00edas ecol\u00f3gicas. Sin embargo, los cr\u00edticos dicen que la miner\u00eda en aguas profundas podr\u00eda da\u00f1ar irrevocablemente el pr\u00edstino entorno submarino, ya que el ruido y las columnas de sedimentos levantadas por los equipos mineros deterioran los ecosistemas de aguas medias, as\u00ed como los organismos en el fondo marino que a menudo viven en los n\u00f3dulos.<\/p>\n<p>Tambi\u00e9n es posible, advierten estos cient\u00edficos, que la miner\u00eda en aguas profundas pueda alterar la forma en que se almacena el carbono en el oc\u00e9ano, contribuyendo a la crisis clim\u00e1tica.<\/p>\n<p>Para ese experimento de 2013, Sweetman y sus colegas utilizaron un m\u00f3dulo de aterrizaje en las profundidades del oc\u00e9ano que se hunde hasta el fondo marino para introducir una c\u00e1mara, m\u00e1s peque\u00f1a que una caja de zapatos, en el sedimento para encerrar una peque\u00f1a \u00e1rea de fondo marino y un volumen de agua sobre ella.<\/p>\n<p>Lo que esperaba que detectara el sensor era que los niveles de ox\u00edgeno cayeran lentamente con el tiempo a medida que los animales microsc\u00f3picos lo inhalaran. A partir de esos datos, plane\u00f3 calcular algo llamado &#171;consumo de ox\u00edgeno de la comunidad de sedimentos&#187;, que proporciona informaci\u00f3n importante sobre la actividad de la fauna y los microorganismos del fondo marino.<\/p>\n<p>Cada d\u00eda se vierte al oc\u00e9ano el equivalente a 2.000 camiones cargados pl\u00e1stico. Este es el destino de la mayor parte<\/p>\n<p>No fue hasta 2021, cuando Sweetman utiliz\u00f3 otro m\u00e9todo de respaldo para detectar ox\u00edgeno y produjo el mismo resultado, que acept\u00f3 que se produc\u00eda ox\u00edgeno en el fondo marino y necesitaba controlar lo que estaba sucediendo.<\/p>\n<p>&#171;Pens\u00e9: &#8216;Dios m\u00edo, durante los \u00faltimos ocho o nueve a\u00f1os, he estado ignorando algo profundo y enorme'&#187;, coment\u00f3.<\/p>\n<p>Sweetman observ\u00f3 el fen\u00f3meno una y otra vez durante casi una d\u00e9cada y en varios lugares de la zona Clarion-Clipperton, una gran \u00e1rea que se extiende m\u00e1s de 6.400 kil\u00f3metros y est\u00e1 m\u00e1s all\u00e1 de la jurisdicci\u00f3n de cualquier pa\u00eds.<\/p>\n<p>El equipo tom\u00f3 algunas de las muestras de sedimentos, agua de mar y n\u00f3dulos polimet\u00e1licos para estudiarlas en el laboratorio e intentar comprender exactamente c\u00f3mo se produc\u00eda el ox\u00edgeno.<\/p>\n<p>Entendiendo el ox\u00edgeno oscuro<\/p>\n<p>A trav\u00e9s de una serie de experimentos, los investigadores descartaron procesos biol\u00f3gicos como los microbios y se\u00f1alaron los propios n\u00f3dulos como el origen del fen\u00f3meno. Quiz\u00e1s, razonaron, se trataba de ox\u00edgeno liberado del \u00f3xido de manganeso en el n\u00f3dulo. Pero tal liberaci\u00f3n no es la causa, dijo Sweetman.<\/p>\n<p>Un documental sobre la miner\u00eda en aguas profundas que Sweetman vio en el bar de un hotel en S\u00e3o Paulo, Brasil, desat\u00f3 un gran avance. &#171;Hab\u00eda alguien all\u00ed que dec\u00eda: &#8216;Eso es una bater\u00eda en una roca'&#187;, record\u00f3. \u201cAl ver esto, de repente pens\u00e9: \u00bfpodr\u00eda ser electroqu\u00edmico? Estas cosas que quieren extraer para fabricar bater\u00edas, \u00bfpodr\u00edan ser realmente bater\u00edas?\u201d<\/p>\n<p>La corriente el\u00e9ctrica, incluso de una bater\u00eda AA, cuando se pone en agua salada, puede dividir el agua en ox\u00edgeno e hidr\u00f3geno, un proceso conocido como electr\u00f3lisis del agua de mar, explic\u00f3 Sweetman. Quiz\u00e1s el n\u00f3dulo hac\u00eda algo similar, razon\u00f3.<\/p>\n<p>Sweetman se acerc\u00f3 a Franz Geiger, electroqu\u00edmico de la Universidad Northwestern en Evanston, Illinois, y juntos investigaron m\u00e1s. Utilizando un dispositivo llamado mult\u00edmetro para medir peque\u00f1os voltajes y variaciones de voltaje, registraron lecturas de 0,95 voltios desde la superficie de los n\u00f3dulos.<\/p>\n<p>Estas lecturas fueron inferiores al voltaje de 1,5 requerido para la electr\u00f3lisis del agua de mar, pero sugirieron que podr\u00edan producirse voltajes significativos cuando los n\u00f3dulos se agrupan.<\/p>\n<p>&#171;Parece que descubrimos una &#8216;geobater\u00eda&#8217; natural&#187;, dijo Geiger, profesor de qu\u00edmica Charles E. y Emma H. \u200b\u200bMorrison en la Facultad de Artes y Ciencias Weinberg de Northwestern, en un comunicado de prensa. &#171;Estas geobater\u00edas son la base para una posible explicaci\u00f3n de la producci\u00f3n de ox\u00edgeno oscuro en el oc\u00e9ano&#187;.<\/p>\n<p>Desafiando el paradigma<\/p>\n<p>El descubrimiento de que los n\u00f3dulos abisales o de aguas profundas producen ox\u00edgeno es &#171;un hallazgo sorprendente e inesperado&#187;, dijo Daniel Jones, profesor y jefe de biogeociencias oce\u00e1nicas en el Centro Nacional de Oceanograf\u00eda en Southampton, Inglaterra, que ha trabajado con Sweetman pero no particip\u00f3 directamente en la investigaci\u00f3n. &#171;Hallazgos como este demuestran el valor de las expediciones mar\u00edtimas a estas \u00e1reas remotas pero importantes de los oc\u00e9anos del mundo&#187;, dijo por correo electr\u00f3nico.<\/p>\n<p>El estudio definitivamente desaf\u00eda \u201cel paradigma tradicional del ciclo del ox\u00edgeno en las profundidades del mar\u201d, seg\u00fan Beth Orcutt, cient\u00edfica investigadora principal del Laboratorio Bigelow de Ciencias Oce\u00e1nicas en Maine. Pero el equipo proporcion\u00f3 &#171;suficientes datos de apoyo para justificar la observaci\u00f3n como una se\u00f1al verdadera&#187;, dijo Orcutt, que no particip\u00f3 en la investigaci\u00f3n.<\/p>\n<p>Craig Smith, profesor em\u00e9rito de oceanograf\u00eda de la Universidad de Hawaii en M\u0101noa, calific\u00f3 la hip\u00f3tesis de las geobater\u00edas como una explicaci\u00f3n razonable para la producci\u00f3n de ox\u00edgeno oscuro.<\/p>\n<p>&#171;Sin embargo, al igual que con cualquier nuevo descubrimiento, puede haber explicaciones alternativas&#187;, dijo por correo electr\u00f3nico.<\/p>\n<p>&#171;La importancia regional de tal (producci\u00f3n de ox\u00edgeno oscuro) realmente no puede evaluarse debido a la naturaleza limitada de este estudio, pero s\u00ed sugiere una posible funci\u00f3n ecosist\u00e9mica no apreciada de los n\u00f3dulos de manganeso en el fondo del mar profundo&#187;, afirm\u00f3 Smith, quien tampoco particip\u00f3 en el estudio.<\/p>\n<p>Los n\u00f3dulos polimet\u00e1licos encontrados en el fondo marino de la zona Clarion-Clipperton, como el que se ve aqu\u00ed, son ricos en manganeso, cobre, cobalto y n\u00edquel. Camille Bridgewater\/Universidad del Noroeste<\/p>\n<p>Desentra\u00f1ando los or\u00edgenes de la vida<\/p>\n<p>El Servicio Geol\u00f3gico de Estados Unidos estima que en la zona Clarion-Clipperton existen 21.100 millones de toneladas secas de n\u00f3dulos polimet\u00e1licos, que contienen m\u00e1s metales clave que todas las reservas terrestres del mundo juntas.<\/p>\n<p>La Autoridad Internacional de los Fondos Marinos, en virtud de la Convenci\u00f3n de las Naciones Unidas sobre el Derecho del Mar, regula la miner\u00eda en la regi\u00f3n y ha emitido contratos de exploraci\u00f3n. El grupo se reunir\u00e1 en Jamaica este mes para considerar nuevas reglas que permitan a las empresas extraer metales del fondo del oc\u00e9ano.<\/p>\n<p>Sin embargo, varios pa\u00edses, incluidos el Reino Unido y Francia, han expresado cautela y han apoyado una moratoria o prohibici\u00f3n de la miner\u00eda en aguas profundas para salvaguardar los ecosistemas marinos y conservar la biodiversidad. A principios de este mes, Hawaii prohibi\u00f3 la miner\u00eda en aguas profundas en sus aguas estatales.<\/p>\n<p>Sweetman y Geiger dijeron que la industria minera deber\u00eda considerar las implicaciones de este nuevo descubrimiento antes de explotar potencialmente los n\u00f3dulos de las profundidades marinas.<\/p>\n<p>Smith, de la Universidad de Hawaii, dijo que estaba a favor de una pausa en la extracci\u00f3n de n\u00f3dulos, considerando el impacto que tendr\u00eda en un ambiente vulnerable, biodiverso y pr\u00edstino.<\/p>\n<p>Los primeros intentos de explotaci\u00f3n minera en la zona en la d\u00e9cada de 1980 proporcionaron una advertencia, indic\u00f3 Geiger.<\/p>\n<p>\u201cEn 2016 y 2017, los bi\u00f3logos marinos visitaron sitios que fueron minados en la d\u00e9cada de 1980 y descubrieron que ni siquiera se hab\u00edan recuperado bacterias en las \u00e1reas minadas\u201d, dijo Geiger.<\/p>\n<p>El pepino de mar Amperima sp. se ve en el fondo en la zona este de Clarion-Clipperton. Cortes\u00eda de Craig Smith y Diva Amon, Proyecto ABYSSLINE<\/p>\n<p>\u201cSin embargo, en las regiones no minadas la vida marina floreci\u00f3. A\u00fan se desconoce por qu\u00e9 estas \u201czonas muertas\u201d persisten durante d\u00e9cadas\u201d, a\u00f1adi\u00f3. &#171;Sin embargo, esto pone un asterisco importante en las estrategias para la miner\u00eda del fondo marino, ya que la diversidad de fauna del fondo del oc\u00e9ano en \u00e1reas ricas en n\u00f3dulos es mayor que en las selvas tropicales m\u00e1s diversas&#187;.<\/p>\n<p>Sweetman, cuya investigaci\u00f3n cient\u00edfica ha sido financiada y apoyada por dos empresas interesadas en explotar la zona Clarion-Clipperton, dijo que era crucial contar con supervisi\u00f3n cient\u00edfica sobre la miner\u00eda en aguas profundas.<\/p>\n<p>Quedan muchas preguntas sin respuesta sobre c\u00f3mo se produce el ox\u00edgeno oscuro y qu\u00e9 papel desempe\u00f1a en el ecosistema de las profundidades marinas.<\/p>\n<p>Comprender c\u00f3mo el fondo del oc\u00e9ano produce ox\u00edgeno tambi\u00e9n puede arrojar luz sobre los or\u00edgenes de la vida, a\u00f1adi\u00f3 Sweetman. Una teor\u00eda de larga data es que la vida evolucion\u00f3 en respiraderos hidrotermales de aguas profundas, y el descubrimiento de que la electr\u00f3lisis del agua de mar podr\u00eda formar ox\u00edgeno en las profundidades podr\u00eda inspirar nuevas formas de pensar sobre c\u00f3mo comenz\u00f3 la vida en la Tierra.<\/p>\n<p>&#171;Creo que es necesario hacer m\u00e1s ciencia, especialmente en torno a este proceso y su importancia&#187;, dijo Sweetman. &#171;Espero que sea el comienzo de algo incre\u00edble&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Un fen\u00f3meno misterioso observado por primera vez en 2013 a bordo de un barco en una parte remota del oc\u00e9ano Pac\u00edfico parec\u00eda tan absurdo que convenci\u00f3 al cient\u00edfico oce\u00e1nico Andrew Sweetman de que su equipo de monitoreo estaba defectuoso. Las lecturas de los sensores parec\u00edan mostrar que se estaba produciendo ox\u00edgeno en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451347","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cient\u00edficos descubren que se produce ox\u00edgeno &quot;oscuro&quot; a 4.000 metros de profundidad en el oc\u00e9ano - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cient\u00edficos descubren que se produce ox\u00edgeno &quot;oscuro&quot; a 4.000 metros de profundidad en el oc\u00e9ano - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Un fen\u00f3meno misterioso observado por primera vez en 2013 a bordo de un barco en una parte remota del oc\u00e9ano Pac\u00edfico parec\u00eda tan absurdo que convenci\u00f3 al cient\u00edfico oce\u00e1nico Andrew Sweetman de que su equipo de monitoreo estaba defectuoso. Las lecturas de los sensores parec\u00edan mostrar que se estaba produciendo ox\u00edgeno en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-23T01:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cient\u00edficos descubren que se produce ox\u00edgeno &#171;oscuro&#187; a 4.000 metros de profundidad en el oc\u00e9ano\",\"datePublished\":\"2024-07-23T01:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/\"},\"wordCount\":2057,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/\",\"name\":\"Cient\u00edficos descubren que se produce ox\u00edgeno \\\"oscuro\\\" a 4.000 metros de profundidad en el oc\u00e9ano - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-23T01:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cient\u00edficos descubren que se produce ox\u00edgeno &#171;oscuro&#187; a 4.000 metros de profundidad en el oc\u00e9ano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cient\u00edficos descubren que se produce ox\u00edgeno \"oscuro\" a 4.000 metros de profundidad en el oc\u00e9ano - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cient\u00edficos descubren que se produce ox\u00edgeno \"oscuro\" a 4.000 metros de profundidad en el oc\u00e9ano - Noticias","og_description":"(CNN) &#8212; Un fen\u00f3meno misterioso observado por primera vez en 2013 a bordo de un barco en una parte remota del oc\u00e9ano Pac\u00edfico parec\u00eda tan absurdo que convenci\u00f3 al cient\u00edfico oce\u00e1nico Andrew Sweetman de que su equipo de monitoreo estaba defectuoso. Las lecturas de los sensores parec\u00edan mostrar que se estaba produciendo ox\u00edgeno en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-23T01:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/"},"author":{"name":"","@id":""},"headline":"Cient\u00edficos descubren que se produce ox\u00edgeno &#171;oscuro&#187; a 4.000 metros de profundidad en el oc\u00e9ano","datePublished":"2024-07-23T01:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/"},"wordCount":2057,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/","name":"Cient\u00edficos descubren que se produce ox\u00edgeno \"oscuro\" a 4.000 metros de profundidad en el oc\u00e9ano - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-23T01:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cient\u00edficos descubren que se produce ox\u00edgeno &#171;oscuro&#187; a 4.000 metros de profundidad en el oc\u00e9ano"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cient\u00edficos descubren que se produce ox\u00edgeno &#171;oscuro&#187; a 4.000 metros de profundidad en el oc\u00e9ano","url":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/22\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-23T01:03:38Z","datePublished":"2024-07-23T01:03:38Z","dateModified":"2024-07-23T01:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cient\\u00edficos descubren que se produce ox\\u00edgeno &#171;oscuro&#187; a 4.000 metros de profundidad en el oc\\u00e9ano\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/07\\\/22\\\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/07\\\/22\\\/descubrimiento-oxigeno-oscuro-fondo-marino-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-23T01:03:38Z\",\"datePublished\":\"2024-07-23T01:03:38Z\",\"dateModified\":\"2024-07-23T01:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463012,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/05\/30\/parapentista-chino-nubes-oxigeno-trax\/","url_meta":{"origin":1451347,"position":0},"title":"Un parapentista chino sobrevive tras elevarse m\u00e1s de 8.000 metros sin ox\u00edgeno, informan medios estatales","author":"","date":"mayo 30, 2025","format":false,"excerpt":"El parapentista chino Peng Yujiang tuvo suerte de volver a tierra tras sobrevivir a una potente corriente ascendente que lo elev\u00f3 repentinamente a la atm\u00f3sfera superior sobre las monta\u00f1as Qilian, en la provincia china de Gansu, el s\u00e1bado, seg\u00fan informaron los medios estatales.Seg\u00fan informes de la Televisi\u00f3n Central de China\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442419,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2023\/12\/21\/tierra-de-los-perdidos-se-encuentra-una-red-de-lagunas-ocultas-con-fosiles-vivientes-similares-a-los-de-hace-mas-de-3-000-millones-de-anos\/","url_meta":{"origin":1451347,"position":1},"title":"Tierra de los perdidos: se encuentra una red de lagunas ocultas con f\u00f3siles vivientes similares a los de hace m\u00e1s de 3.000 millones de a\u00f1os","author":"","date":"diciembre 21, 2023","format":false,"excerpt":"(CNN) --\u00a0 Los cient\u00edficos descubrieron un ecosistema previamente oculto con un extenso sistema de lagunas en las llanuras saladas de la Puna de Atacama, una meseta \u00e1rida en Argentina, con estromatolitos gigantes que podr\u00edan permitir vislumbrar la vida m\u00e1s temprana en La Tierra y posiblemente incluso Marte, seg\u00fan una nueva\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459256,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/02\/26\/antiguo-glaciar-evolucion-tierra-vida-trax\/","url_meta":{"origin":1451347,"position":2},"title":"El hallazgo de un antiguo glaciar revela pistas sobre c\u00f3mo evolucion\u00f3 la vida compleja en la Tierra, seg\u00fan los cient\u00edficos","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Hace m\u00e1s de 500 millones de a\u00f1os, en una Tierra g\u00e9lida y cubierta de hielo, los glaciares agitaron los ingredientes de la vida compleja al arrasar los minerales terrestres y depositarlos despu\u00e9s en el oc\u00e9ano, seg\u00fan un nuevo estudio.Cent\u00edmetro a cent\u00edmetro, a medida que los enormes glaciares se arrastraban sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457884,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/01\/25\/monticulos-marte-resolver-mayores-misterios-trax\/","url_meta":{"origin":1451347,"position":3},"title":"Inusuales mont\u00edculos en Marte podr\u00edan ayudar a resolver uno de los mayores misterios del planeta rojo","author":"","date":"enero 25, 2025","format":false,"excerpt":"Miles de misteriosos mont\u00edculos en Marte preservan capas de evidencia que apuntan a la existencia de agua antigua en el planeta rojo, que probablemente esculpi\u00f3 estas imponentes formaciones.M\u00e1s de 15.000 mont\u00edculos se elevan hacia el cielo desde las tierras bajas de Chryse Planitia en Marte, ubicados cerca de una l\u00ednea\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464459,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/07\/12\/zapatos-gigantes-muro-adriano-soldados-roma-trax\/","url_meta":{"origin":1451347,"position":4},"title":"Zapatos gigantes hallados cerca del Muro de Adriano plantean preguntas sobre los soldados de la antigua Roma","author":"","date":"julio 12, 2025","format":false,"excerpt":"Un antiguo misterio romano ha quedado planteado en las onduladas colinas del norte de Gran Breta\u00f1a.Arque\u00f3logos desenterraron un alijo de zapatos inusualmente grandes en las ruinas de un fuerte militar del siglo I a lo largo del Muro de Adriano, una barrera de piedra de 73 millas (117 kil\u00f3metros) que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469942,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/01\/09\/casa-barata-latronico-italia-salud-hijo-trax\/","url_meta":{"origin":1451347,"position":5},"title":"Compr\u00f3 una casa barata en Italia por el estilo de vida y la salud de su hijo mejor\u00f3 de forma dr\u00e1stica","author":"","date":"enero 9, 2026","format":false,"excerpt":"Cuando Lynnette Elser, de Crossville, Tennessee, lleg\u00f3 por primera vez al pueblo italiano de Latronico con su hijo adoptivo Kenny, de 5 a\u00f1os, que es autista, no ten\u00eda la intenci\u00f3n de convertirlo en su nuevo hogar.Pero esa primera noche, Kenny, que tiene graves problemas respiratorios, pareci\u00f3 poder respirar sin dificultad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1451347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1451347"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1451347\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1451347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1451347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1451347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}