{"id":1451351,"date":"2024-07-23T00:03:46","date_gmt":"2024-07-23T07:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/"},"modified":"2024-07-23T00:03:46","modified_gmt":"2024-07-23T07:03:46","slug":"harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/","title":{"rendered":"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado"},"content":{"rendered":"<p>(CNN) &#8212; La vicepresidenta Kamala Harris se neg\u00f3 a presidir el discurso del primer ministro de Israel, Benjamin Netanyahu, ante el Congreso ese mi\u00e9rcoles, dijo a CNN una fuente familiarizada con el asunto.<\/p>\n<p>La decisi\u00f3n de no asistir a la reuni\u00f3n conjunta pone de relieve la tensa relaci\u00f3n entre la administraci\u00f3n Biden y Netanyahu en un momento en que la guerra en Gaza ha provocado una creciente reacci\u00f3n de la izquierda.<\/p>\n<p>Un asistente de la vicepresidenta dijo que los dos l\u00edderes mundiales se reunir\u00e1n por separado a finales de esta semana. El asistente de Harris cit\u00f3 un evento previamente programado como la raz\u00f3n por la que no pudo asistir al discurso de este mi\u00e9rcoles.<\/p>\n<p>No se ha anunciado una fecha para la reuni\u00f3n Netanyahu y Harris, pero ser\u00e1 independiente de la reuni\u00f3n planeada del presidente Joe Biden con el primer ministro de Israel.<\/p>\n<p>El encuentro bilateral, seguido de cerca, marcar\u00e1 el primer encuentro de Harris con un l\u00edder mundial desde que Biden se hizo a un lado de su campa\u00f1a de reelecci\u00f3n y respald\u00f3 la candidatura de Harris.<\/p>\n<p>Se espera que Harris &#171;contin\u00fae su intenso compromiso con el conflicto en Gaza&#187;, dijo el asistente, se\u00f1alando que se espera que subraye su compromiso de garantizar que Israel pueda defenderse, condene el ataque de Hamas del 7 de octubre y reitere las preocupaciones sobre la situaci\u00f3n humanitaria en Gaza.<\/p>\n<p>\u201cEsperamos que la vicepresidenta transmita su opini\u00f3n de que es hora de que la guerra termine de una manera en que Israel est\u00e9 seguro, todos los rehenes sean liberados, el sufrimiento de los civiles palestinos en Gaza termine y el pueblo palestino pueda disfrutar de su derecho a la dignidad, la libertad y la autodeterminaci\u00f3n\u201d, seg\u00fan el asistente. \u201cY discutir\u00e1n los esfuerzos para llegar a un acuerdo sobre el alto el fuego\u201d.<\/p>\n<p>Este mi\u00e9rcoles, Harris tiene previsto dirigirse al Grand Boule de la hermandad Zeta Phi Beta en Indian\u00e1polis para una conversaci\u00f3n moderada, en un esfuerzo por involucrar a las mujeres votantes negras.<\/p>\n<p>\u201cSu viaje a Indian\u00e1polis el 24 de julio no debe interpretarse como un cambio en su posici\u00f3n con respecto a Israel\u201d, dijo el asistente.<\/p>\n<p>Harris no fue la \u00fanica dem\u00f3crata de alto rango que se neg\u00f3 a presidir el discurso de Netanyahu. La presidenta protempore del Senado, Patty Murray, dem\u00f3crata del estado de Washington, tambi\u00e9n se neg\u00f3 a presidir, seg\u00fan un portavoz.<\/p>\n<p>En su lugar, el presidente de Relaciones Exteriores del Senado, Ben Cardin, un dem\u00f3crata de Maryland, presidir\u00e1 el discurso de Netanyahu en el Capitolio, dijo a CNN una fuente familiarizada con el asunto.<\/p>\n<p>Netanyahu aterriz\u00f3 en el \u00e1rea de Washington, DC, el lunes por la tarde, seg\u00fan una publicaci\u00f3n de un funcionario de la Embajada de Israel en X. Se espera que se re\u00fana con las familias de los rehenes tomados por Hamas en Gaza, incluidos estadounidenses, el lunes por la noche.<\/p>\n<p>Netanyahu tambi\u00e9n tiene previsto reunirse el mi\u00e9rcoles con los l\u00edderes del Congreso, incluido el presidente de la C\u00e1mara de Representantes, Mike Johnson, el l\u00edder de la minor\u00eda de la C\u00e1mara de Representantes, Hakeem Jeffries, el l\u00edder de la mayor\u00eda del Senado, Chuck Schumer, y el l\u00edder de la minor\u00eda del Senado, Mitch McConnell.<\/p>\n<p>Se espera que Biden se re\u00fana con Netanyahu este jueves, dijo un funcionario estadounidense, aunque la fecha de la reuni\u00f3n ha sido incierta a medida que el presidente estadounidense se recupera de Covid-19. Durante el fin de semana, Biden anunci\u00f3 que pondr\u00eda fin a su intento de reelecci\u00f3n y respald\u00f3 a Harris para ser la candidata dem\u00f3crata a la presidencia.<\/p>\n<p>MJ Lee de CNN contribuy\u00f3 a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La vicepresidenta Kamala Harris se neg\u00f3 a presidir el discurso del primer ministro de Israel, Benjamin Netanyahu, ante el Congreso ese mi\u00e9rcoles, dijo a CNN una fuente familiarizada con el asunto. La decisi\u00f3n de no asistir a la reuni\u00f3n conjunta pone de relieve la tensa relaci\u00f3n entre la administraci\u00f3n Biden y Netanyahu en [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451351","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La vicepresidenta Kamala Harris se neg\u00f3 a presidir el discurso del primer ministro de Israel, Benjamin Netanyahu, ante el Congreso ese mi\u00e9rcoles, dijo a CNN una fuente familiarizada con el asunto. La decisi\u00f3n de no asistir a la reuni\u00f3n conjunta pone de relieve la tensa relaci\u00f3n entre la administraci\u00f3n Biden y Netanyahu en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-23T07:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado\",\"datePublished\":\"2024-07-23T07:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/\"},\"wordCount\":675,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/\",\"name\":\"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-23T07:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado - Noticias","og_description":"(CNN) &#8212; La vicepresidenta Kamala Harris se neg\u00f3 a presidir el discurso del primer ministro de Israel, Benjamin Netanyahu, ante el Congreso ese mi\u00e9rcoles, dijo a CNN una fuente familiarizada con el asunto. La decisi\u00f3n de no asistir a la reuni\u00f3n conjunta pone de relieve la tensa relaci\u00f3n entre la administraci\u00f3n Biden y Netanyahu en [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-23T07:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/"},"author":{"name":"","@id":""},"headline":"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado","datePublished":"2024-07-23T07:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/"},"wordCount":675,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/","name":"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-23T07:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Harris no asistir\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado","url":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/23\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-23T07:03:46Z","datePublished":"2024-07-23T07:03:46Z","dateModified":"2024-07-23T07:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Harris no asistir\\u00e1 al discurso de Netanyahu ante el Congreso pero planea reunirse por separado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/07\\\/23\\\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/07\\\/23\\\/harris-no-asistira-discurso-netanyahu-congreso-pero-planea-reunirse-por-separado-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-23T07:03:46Z\",\"datePublished\":\"2024-07-23T07:03:46Z\",\"dateModified\":\"2024-07-23T07:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451378,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/24\/netanyahu-congreso-estados-unidos-atencion-estadounidense-medio-oriente-trax\/","url_meta":{"origin":1451351,"position":0},"title":"Netanyahu hablar\u00e1 ante el Congreso de Estados Unidos y tratar\u00e1 de redirigir la atenci\u00f3n estadounidense a Medio Oriente","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN) -- El primer ministro de Israel, Benjam\u00edn Netanyahu, se dirigir\u00e1 al Congreso de Estados Unidos este mi\u00e9rcoles, tratando de apuntalar el apoyo estadounidense a su guerra en Gaza y redirigir la atenci\u00f3n de una naci\u00f3n que ha estado preocupada durante semanas por una corriente de cuestiones pol\u00edticas internas.El discurso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451431,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/26\/kamala-harris-silencio-gaza-netanyahu-trax\/","url_meta":{"origin":1451351,"position":1},"title":"Harris dice que &#171;no se quedar\u00e1 en silencio&#187; ante el sufrimiento de Gaza y le pide a Netanyahu que concrete un acuerdo de alto el fuego","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN) -- La vicepresidenta Kamala Harris prometi\u00f3 \"no callarse\" ante el sufrimiento en Gaza en medio de la guerra entre Israel y Hamas, y afirm\u00f3 que expres\u00f3 su \"seria preocupaci\u00f3n\" al primer ministro israel\u00ed, Benjamin Netanyahu, este jueves, al tiempo que le dijo que es hora de cerrar un acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451394,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/25\/kamala-harris-biden-netanyahu-postura-israel-trax\/","url_meta":{"origin":1451351,"position":2},"title":"Kamala Harris navega entre Biden y Netanyahu mientras considera su postura sobre Israel","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN) -- Al cuarto d\u00eda de la semana m\u00e1s importante de la vida pol\u00edtica de Kamala Harris, la vicepresidenta tiene que enfrentarse a la cuesti\u00f3n de pol\u00edtica exterior m\u00e1s tensa a la que se enfrenta el pa\u00eds mirando directamente a los ojos de un primer ministro de Israel que decidi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451692,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/08\/08\/harris-navega-conflicto-gaza-campana-trax\/","url_meta":{"origin":1451351,"position":3},"title":"Harris navega por el conflicto de Gaza en campa\u00f1a","author":"","date":"agosto 8, 2024","format":false,"excerpt":"(CNN) --\u00a0La vicepresidenta Kamala Harris abord\u00f3 la angustia dentro de su propio partido sobre el conflicto en Gaza de frente en un mitin de campa\u00f1a en Detroit este mi\u00e9rcoles por la noche, y se movi\u00f3 r\u00e1pidamente para frenar las protestas que interrumpieron su evento.\"Porque creemos en la democracia, la voz\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451382,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/24\/netanyahu-discurso-congreso-estados-unidos-acusaciones-genocidio-trax\/","url_meta":{"origin":1451351,"position":4},"title":"Netanyahu rechaza acusaciones de genocidio en discurso ante el Congreso de EE.UU. y califica de &#171;antiisrael\u00edes&#187; a quienes se manifiestan contra la guerra en Gaza","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN) -- El primer ministro de Israel, Benjamin Netanyahu, adopt\u00f3 un tono desafiante en su discurso del mi\u00e9rcoles ante el Congreso de Estados Unidos: atac\u00f3 a sus cr\u00edticos y rechaz\u00f3 las acusaciones de que est\u00e9 perpetuando un genocidio en Gaza.Durante su discurso de casi 52 minutos ante el Congreso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451423,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/25\/exclusiva-nikki-haley-habla-sobre-trump-harris-trax\/","url_meta":{"origin":1451351,"position":5},"title":"Exclusiva: Haley no se disculpa por lo que dijo sobre Trump durante las primarias y defiende su decisi\u00f3n de apoyarlo en lugar de Harris","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN) -- La exgobernadora de Carolina del Sur, Nikki Haley, no se disculp\u00f3 el jueves por las \"cosas duras\" que dijo sobre Donald Trump durante su enfrentamiento en las primarias republicanas, pero le dijo a Jake Tapper de CNN que no duda de su decisi\u00f3n de apoyar al expresidente en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1451351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1451351"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1451351\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1451351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1451351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1451351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}