{"id":1451388,"date":"2024-07-24T19:03:49","date_gmt":"2024-07-25T02:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/"},"modified":"2024-07-24T19:03:49","modified_gmt":"2024-07-25T02:03:49","slug":"covid-juegos-olimpicos-paris-2024-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/","title":{"rendered":"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19"},"content":{"rendered":"<p>(CNN) &#8212; Despu\u00e9s de que varias jugadoras australianas de waterpolo dieran positivo por covid-19 esta semana, surgieron preguntas sobre c\u00f3mo se mitigar\u00e1 la propagaci\u00f3n de la enfermedad en los Juegos Ol\u00edmpicos de Verano en Par\u00eds.<\/p>\n<p>Hasta este mi\u00e9rcoles, cinco jugadoras del equipo femenino de waterpolo de Australia hab\u00edan dado positivo por covid-19.<\/p>\n<p>Existen \u201cprotocolos establecidos\u201d para estos casos, que recomiendan el uso de mascarillas para las personas que den positivo, dijo un portavoz de Par\u00eds 2024 este mi\u00e9rcoles en un comunicado.<\/p>\n<p>\u201cRecordamos peri\u00f3dicamente a los atletas y a todas las dem\u00e1s partes presentes en los Juegos las buenas pr\u00e1cticas que deben adoptar si experimentan cualquier s\u00edntoma respiratorio: usar una mascarilla en presencia de otras personas, limitar los contactos y lavarse las manos regularmente con agua y jab\u00f3n o usar desinfectante para manos\u201d, dice el comunicado.<\/p>\n<p>D\u00f3nde competir\u00e1 cada uno de los deportes de los Juegos Ol\u00edmpicos de Par\u00eds<\/p>\n<p>\u201cEn todas las zonas residenciales y en el restaurante de la Villa Ol\u00edmpica se pueden encontrar estaciones de desinfecci\u00f3n de manos\u201d, seg\u00fan el comunicado. \u201cSeguimos de cerca la situaci\u00f3n de la salud p\u00fablica en Francia, en colaboraci\u00f3n con el ministerio competente\u201d.<\/p>\n<p>Muchos de los equipos nacionales tambi\u00e9n pueden tener sus propios protocolos de seguridad para proteger a sus atletas, dijo Lucia Mullen, investigadora asociada del Centro de Seguridad Sanitaria Johns Hopkins y miembro del grupo de expertos en reuniones masivas de la Organizaci\u00f3n Mundial de la Salud, que trabaja regularmente sobre estos temas.<\/p>\n<p>\u201cFrente a los casos de covid-19, al igual que con otras enfermedades respiratorias y tambi\u00e9n otras enfermedades gastrointestinales, se promover\u00e1 la higiene de manos y otras medidas de higiene b\u00e1sica, como mantener la distancia, acudir a las cl\u00ednicas para hacerse la prueba si no se siente bien y, por supuesto, si presenta s\u00edntomas\u201d, dijo Mullen. \u201cLuego, por supuesto, aislarse si da positivo\u201d.<\/p>\n<p>El equipo australiano de waterpolo est\u00e1 tratando el covid-19 de la misma manera que cualquier otra enfermedad respiratoria, afirm\u00f3 Anna Meares, jefa de misi\u00f3n del equipo ol\u00edmpico australiano.<\/p>\n<p>&#171;Este es un entorno de alto rendimiento, por lo que estamos siendo diligentes&#187;, dijo Meares en una conferencia de prensa este martes cuando se anunci\u00f3 el primer caso de covid-19 del equipo.<\/p>\n<p>\u201cTambi\u00e9n estamos haciendo que los compa\u00f1eros de equipo usen mascarillas y se adhieran a las medidas de distanciamiento social, reunirse al aire libre, ese tipo de cosas\u201d, dijo.<\/p>\n<p>Un atleta prueba en un divertido video la famosa cama &#171;antisexo&#187; de los Juegos Ol\u00edmpicos Par\u00eds 2024<\/p>\n<p>Agreg\u00f3 que, cuando se presentan enfermedades respiratorias, la persona se a\u00edsla hasta que sus s\u00edntomas disminuyan y las pruebas salgan bien.<\/p>\n<p>&#171;Pero debo enfatizar que estamos tratando al covid-19 de la misma manera que a otros virus como la gripe. Esto no es Tokio&#187;, dijo Meares, en referencia a los Juegos de Verano de Tokio 2020, que se retrasaron un a\u00f1o debido a la pandemia y se celebraron sin espectadores presenciales.<\/p>\n<p>Aunque el mundo ya no se encuentra en una situaci\u00f3n de emergencia de salud p\u00fablica debido a la pandemia de covid-19, los Juegos Ol\u00edmpicos se celebran en un momento en que una ola de infecciones por covid-19 afectan a Estados Unidos. Incluso el presidente de Estados Unidos Joe Biden dio positivo recientemente a la enfermedad.<\/p>\n<p>Los Centros para el Control y la Prevenci\u00f3n de Enfermedades de Estados Unidos recomiendan que, si das positivo en la prueba de covid-19, te quedes en casa hasta que no tengas fiebre sin la ayuda de medicamentos antifebriles durante al menos 24 horas y tus s\u00edntomas hayan tenido mejoras durante 24 horas. Adem\u00e1s, recomiendan usar una mascarilla cerca de otras personas durante los cinco d\u00edas siguientes.<\/p>\n<p>\u201cEstamos en un per\u00edodo en el que el covid-19 todav\u00eda est\u00e1 circulando. Estamos viendo nuevamente un aumento de casos\u201d, dijo Mullen.<\/p>\n<p>\u201cY probablemente estemos informando niveles inferiores a los reales. Muchos pa\u00edses est\u00e1n reduciendo sus medidas de vigilancia\u201d, a\u00f1adi\u00f3. \u201cSeguramente haya algunas personas que viajen a los Juegos, ya sean espectadores o simplemente para visitar Par\u00eds, que tal vez no sepan que tienen covid-19 y que est\u00e9n enfermas y, por supuesto, contagien a otras personas\u201d.<\/p>\n<p>Se espera que la capital francesa reciba a unos 15 millones de turistas durante su celebraci\u00f3n de los Juegos Ol\u00edmpicos.<\/p>\n<p>La semana pasada, la OMS, el Ministerio de Salud y Prevenci\u00f3n de Francia y el Centro Europeo para la Prevenci\u00f3n y el Control de Enfermedades publicaron una gu\u00eda de salud p\u00fablica particular para los viajeros que asistan a los Juegos Ol\u00edmpicos y Paral\u00edmpicos de verano de 2024.<\/p>\n<p>La gu\u00eda recomienda verificar su estado de vacunaci\u00f3n contra enfermedades infecciosas comunes, como el sarampi\u00f3n, la tos ferina, la polio y el covid-19.<\/p>\n<p>\u201cLos casos de sarampi\u00f3n est\u00e1n aumentando en todo el mundo, incluso en Europa y en Francia\u201d, se\u00f1ala la gu\u00eda. \u201cAsistir a un evento multitudinario aumenta las probabilidades de estar expuesto a enfermedades respiratorias, incluidas la tos ferina y el covid-19. Si tienes s\u00edntomas, como tos, fiebre o dolor de garganta, qu\u00e9date en tu casa o en tu hotel si es posible y considera usar una mascarilla cuando salgas del hotel o de tu casa\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Despu\u00e9s de que varias jugadoras australianas de waterpolo dieran positivo por covid-19 esta semana, surgieron preguntas sobre c\u00f3mo se mitigar\u00e1 la propagaci\u00f3n de la enfermedad en los Juegos Ol\u00edmpicos de Verano en Par\u00eds. Hasta este mi\u00e9rcoles, cinco jugadoras del equipo femenino de waterpolo de Australia hab\u00edan dado positivo por covid-19. Existen \u201cprotocolos establecidos\u201d [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451388","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Despu\u00e9s de que varias jugadoras australianas de waterpolo dieran positivo por covid-19 esta semana, surgieron preguntas sobre c\u00f3mo se mitigar\u00e1 la propagaci\u00f3n de la enfermedad en los Juegos Ol\u00edmpicos de Verano en Par\u00eds. Hasta este mi\u00e9rcoles, cinco jugadoras del equipo femenino de waterpolo de Australia hab\u00edan dado positivo por covid-19. Existen \u201cprotocolos establecidos\u201d [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-25T02:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19\",\"datePublished\":\"2024-07-25T02:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/\"},\"wordCount\":933,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/\",\"name\":\"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-25T02:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19 - Noticias","og_description":"(CNN) &#8212; Despu\u00e9s de que varias jugadoras australianas de waterpolo dieran positivo por covid-19 esta semana, surgieron preguntas sobre c\u00f3mo se mitigar\u00e1 la propagaci\u00f3n de la enfermedad en los Juegos Ol\u00edmpicos de Verano en Par\u00eds. Hasta este mi\u00e9rcoles, cinco jugadoras del equipo femenino de waterpolo de Australia hab\u00edan dado positivo por covid-19. Existen \u201cprotocolos establecidos\u201d [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-25T02:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/"},"author":{"name":"","@id":""},"headline":"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19","datePublished":"2024-07-25T02:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/"},"wordCount":933,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/","name":"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-25T02:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un invitado no deseado se sum\u00f3 a los Juegos Ol\u00edmpicos de Par\u00eds: el covid-19","url":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/24\/covid-juegos-olimpicos-paris-2024-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-25T02:03:49Z","datePublished":"2024-07-25T02:03:49Z","dateModified":"2024-07-25T02:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un invitado no deseado se sum\\u00f3 a los Juegos Ol\\u00edmpicos de Par\\u00eds: el covid-19\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/07\\\/24\\\/covid-juegos-olimpicos-paris-2024-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2024\\\/07\\\/24\\\/covid-juegos-olimpicos-paris-2024-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-25T02:03:49Z\",\"datePublished\":\"2024-07-25T02:03:49Z\",\"dateModified\":\"2024-07-25T02:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451432,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/26\/canada-suspende-entrenadora-futbol-femenino-drones-juegos-olimpicos-trax\/","url_meta":{"origin":1451388,"position":0},"title":"Canad\u00e1 suspende a su entrenadora de f\u00fatbol femenino por espiar a equipos rivales con drones durante los Juegos Ol\u00edmpicos","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN) --\u00a0El Comit\u00e9 Ol\u00edmpico Canadiense (COC) ha suspendido a la entrenadora de la selecci\u00f3n nacional femenina de f\u00fatbol, \u200b\u200bBev Priestman, por el resto de los Juegos Ol\u00edmpicos de Par\u00eds 2024, citando \"nuevas revelaciones\" en medio de un esc\u00e1ndalo de drones. Canad\u00e1 es el \u00faltimo campe\u00f3n ol\u00edmpico en f\u00fatbol femenino.\"En las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451711,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/08\/10\/espana-medalla-de-oro-waterpolo-femenino-orix\/","url_meta":{"origin":1451388,"position":1},"title":"Espa\u00f1a se queda con la medalla de oro en waterpolo femenino","author":"","date":"agosto 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El equipo femenino de waterpolo de Espa\u00f1a venci\u00f3 este s\u00e1bado a Australia en la final qued\u00e1ndose con la medalla de oro.Espa\u00f1a gan\u00f3 el partido contra Australia por \u00a011 a 9.\u00bfCu\u00e1ntas medallas lleva Espa\u00f1a en los Juegos Ol\u00edmpicos de Par\u00eds 2024?El equipo espa\u00f1ol obtuvo su revancha tras participar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451272,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/19\/espana-cuantas-medallas-juegos-olimpicos-mejor-participacion-orix\/","url_meta":{"origin":1451388,"position":2},"title":"Cu\u00e1ntas medallas ha ganado Espa\u00f1a en su historia en los Juegos Ol\u00edmpicos y cu\u00e1l fue su mejor participaci\u00f3n","author":"","date":"julio 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Espa\u00f1a ha participado en un 24 ediciones de los Juegos Ol\u00edmpicos. El pa\u00eds hizo su debut en 1900, pero no volvi\u00f3 a competir hasta 1920. Este a\u00f1o Espa\u00f1a vuelve con las pilas cargadas para demostrar que tiene atletas de gran calibre. Casi 400 espa\u00f1oles ser\u00e1n los encargados de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451686,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/08\/08\/tebogo-medalla-oro-noah-lyles-bronce-covid-juegos-olimpicos-2024-orix\/","url_meta":{"origin":1451388,"position":3},"title":"Letsile Tebogo gana oro hist\u00f3rico en los 200 m y deja a Noah Lyles con el bronce, quien habr\u00eda competido con covid, segun NBC","author":"","date":"agosto 8, 2024","format":false,"excerpt":"(CNN) -- Lleg\u00f3 el momento de los 200 metros masculinos y el estadounidense Noah Lyles esperaba a\u00f1adir otro oro a su colecci\u00f3n en Par\u00eds. Era su carrera estrella, y confiaba plenamente en sus posibilidades tras ganar los 100 metros el domingo. Sin embargo, Letsile Tebogo, de Botswana, complet\u00f3 la sorpresa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450618,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/06\/22\/shacarri-richardson-gana-final-100-metros-y-se-clasifica-para-los-juegos-olimpicos-de-paris-2024-trax\/","url_meta":{"origin":1451388,"position":4},"title":"Sha&#8217;Carri Richardson gana la final de los 100 metros y se clasifica para los Juegos Ol\u00edmpicos de Par\u00eds 2024","author":"","date":"junio 22, 2024","format":false,"excerpt":"(CNN) -- Sha'Carri Richardson se clasific\u00f3 para sus primeros Juegos Ol\u00edmpicos tras ganar la final de los 100 metros lisos este s\u00e1bado en las pruebas ol\u00edmpicas en el Hayward Field de Eugene, Oreg\u00f3n.Richardson termin\u00f3 en primer lugar con un tiempo de 10.71 -el tiempo m\u00e1s r\u00e1pido en los 100 metros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451714,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/08\/10\/estados-unidos-vence-brasil-medalla-oro-futbol-femenino-trax\/","url_meta":{"origin":1451388,"position":5},"title":"Estados Unidos vence a Brasil por 1-0 y se lleva la medalla de oro en f\u00fatbol femenino","author":"","date":"agosto 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El gol de Mallory Swanson en el segundo tiempo fue todo lo que Estados Unidos necesit\u00f3 para ganar la medalla de oro contra Brasil, que en esta oportunidad deber\u00e1 conformarse con llevarse la plata.Decenas de miles de fan\u00e1ticos estadounidenses que se encontraban en el Parque de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1451388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1451388"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1451388\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1451388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1451388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1451388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}