{"id":1466771,"date":"2025-09-24T06:03:47","date_gmt":"2025-09-24T13:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/"},"modified":"2025-09-24T06:03:47","modified_gmt":"2025-09-24T13:03:47","slug":"tiroteo-ice-dallas-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/24\/tiroteo-ice-dallas-trax\/","title":{"rendered":"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino"},"content":{"rendered":"<p>Al menos tres personas resultaron heridas en un tiroteo ocurrido en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas en la ma\u00f1ana de este mi\u00e9rcoles, seg\u00fan el director interino del ICE, Todd Lyons.<\/p>\n<p>\u201cLa informaci\u00f3n preliminar indica que se trata de un posible francotirador\u201d, declar\u00f3 Lyons. \u201cTenemos tres personas heridas en este momento. Desconocemos su estado de salud. Han sido trasladadas al hospital\u201d.<\/p>\n<p>El sospechoso falleci\u00f3 por una herida de bala autoinfligida, inform\u00f3 la secretaria de Seguridad Nacional, Kristi Noem.<\/p>\n<p>Hasta el momento, no se dispon\u00eda de detalles sobre qui\u00e9nes fueron baleados en la oficina local del ICE, ni siquiera si eran empleados del ICE.<\/p>\n<p><em>Esta noticia est\u00e1 en desarrollo y ser\u00e1 actualizada.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos tres personas resultaron heridas en un tiroteo ocurrido en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas en la ma\u00f1ana de este mi\u00e9rcoles, seg\u00fan el director interino del ICE, Todd Lyons. \u201cLa informaci\u00f3n preliminar indica que se trata de un posible francotirador\u201d, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1466771","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al menos tres personas resultaron heridas en un tiroteo ocurrido en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas en la ma\u00f1ana de este mi\u00e9rcoles, seg\u00fan el director interino del ICE, Todd Lyons. \u201cLa informaci\u00f3n preliminar indica que se trata de un posible francotirador\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T13:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino\",\"datePublished\":\"2025-09-24T13:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/\"},\"wordCount\":164,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/\",\"name\":\"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-09-24T13:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino - Noticias","og_description":"Al menos tres personas resultaron heridas en un tiroteo ocurrido en una oficina local del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas en la ma\u00f1ana de este mi\u00e9rcoles, seg\u00fan el director interino del ICE, Todd Lyons. \u201cLa informaci\u00f3n preliminar indica que se trata de un posible francotirador\u201d, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/","og_site_name":"Noticias","article_published_time":"2025-09-24T13:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/"},"author":{"name":"","@id":""},"headline":"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino","datePublished":"2025-09-24T13:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/"},"wordCount":164,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/","url":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/","name":"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-09-24T13:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/09\/24\/tiroteo-ice-dallas-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/24\/tiroteo-ice-dallas-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\u00fan su director interino","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/24\/tiroteo-ice-dallas-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/24\/tiroteo-ice-dallas-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-09-24T13:03:47Z","datePublished":"2025-09-24T13:03:47Z","dateModified":"2025-09-24T13:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos 3 heridos en tiroteo en oficina del ICE en Dallas, seg\\u00fan su director interino\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/09\\\/24\\\/tiroteo-ice-dallas-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/09\\\/24\\\/tiroteo-ice-dallas-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-09-24T13:03:47Z\",\"datePublished\":\"2025-09-24T13:03:47Z\",\"dateModified\":\"2025-09-24T13:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1466797,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/25\/ataque-instalacion-ice-texas-que-sabemos-trax\/","url_meta":{"origin":1466771,"position":0},"title":"Un detenido muri\u00f3 despu\u00e9s de un tiroteo en una instalaci\u00f3n de ICE en Texas: las claves del caso","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"Las personas detenidas por el Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos son procesadas cada d\u00eda en la oficina de campo de la agencia en Dallas, un edificio rectangular de ladrillo escondido entre una autopista muy transitada, varias oficinas de abogados y un complejo de apartamentos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466788,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/24\/joshua-jahn-presunto-atacante-tiroteo-ice-dallas-trax\/","url_meta":{"origin":1466771,"position":1},"title":"\u00bfQui\u00e9n era Joshua Jahn, el presunto atacante contra una instalaci\u00f3n del ICE en Dallas?","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"El atacante se\u00f1alado como responsable de matar a un detenido y herir a otros dos en una instalaci\u00f3n del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas, Texas, es Joshua Jahn, seg\u00fan tres fuentes con conocimiento del caso.Ten\u00eda 29 a\u00f1os, asegur\u00f3 a CNN\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464874,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/07\/26\/fuegos-artificiales-linternas-francotiradores-ataques-instalaciones-migratorias-alerta-trax\/","url_meta":{"origin":1466771,"position":2},"title":"Fuegos artificiales, linternas y francotiradores: ataques a instalaciones migratorias ponen en alerta a las fuerzas del orden","author":"","date":"julio 26, 2025","format":false,"excerpt":"En la noche del 4 de julio, un grupo de asaltantes mont\u00f3 un ataque coordinado en un centro de detenci\u00f3n de inmigrantes cerca de Fort Worth, Texas, utilizando actos de vandalismo y fuegos artificiales para atraer a los agentes hacia el exterior y ponerlos en la mira de dos tiradores\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466976,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/30\/muere-segundo-detenido-tiroteo-oficina-ice-dallas-trax\/","url_meta":{"origin":1466771,"position":3},"title":"Muere el inmigrante mexicano detenido que fue herido en tiroteo en oficina de ICE en Dallas","author":"","date":"septiembre 30, 2025","format":false,"excerpt":"Un segundo detenido que recibi\u00f3 un disparo en un centro de ICE en Dallas la semana pasada falleci\u00f3 este martes, seg\u00fan un funcionario de Seguridad Nacional y portavoz nacional de LULAC, David Cruz.Miguel \u00c1ngel Garc\u00eda Hern\u00e1ndez, un inmigrante mexicano de 32 a\u00f1os, uno de los tres detenidos de ICE que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460987,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/04\/09\/muertos-heridos-tiroteo-spotsylvania-virginia-trax\/","url_meta":{"origin":1466771,"position":4},"title":"Tres muertos y tres heridos en un tiroteo en Virginia","author":"","date":"abril 9, 2025","format":false,"excerpt":"Tres personas murieron y otras tres resultaron heridas en un tiroteo en el condado de Spotsylvania, al noreste de Virginia, el martes por la tarde, informaron las autoridades.El tiroteo ocurri\u00f3 alrededor de las 5:30 p.m. en la zona de Olde Greenwich Circle y, al llegar, los agentes encontraron a varias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469602,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/12\/27\/tres-heridos-tiroteo-idaho-trax\/","url_meta":{"origin":1466771,"position":5},"title":"Tiroteo contra la Oficina del Sheriff en Idaho deja tres heridos; un hombre fue abatido, dicen autoridades","author":"","date":"diciembre 27, 2025","format":false,"excerpt":"Un atacante armado con varias armas abri\u00f3 fuego en el vest\u00edbulo de la Oficina del Sheriff de Idaho y en la calle el viernes, hiriendo a tres personas antes de ser abatido en un enfrentamiento con la polic\u00eda, dijo el sheriff local.El presunto atacante dispar\u00f3 contra una camioneta afuera de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1466771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1466771"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1466771\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1466771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1466771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1466771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}