{"id":1467303,"date":"2025-10-11T19:03:41","date_gmt":"2025-10-12T02:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/"},"modified":"2025-10-11T19:03:41","modified_gmt":"2025-10-12T02:03:41","slug":"mundo-espectaculo-muerte-diane-keaton-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/","title":{"rendered":"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton"},"content":{"rendered":"<p>La muerte de la aclamada actriz Diane Keaton, quien protagoniz\u00f3 \u201cAnnie Hall\u201d y \u201cEl Padrino\u201d, ha sido recibida con gran dolor y sorpresa.<\/p>\n<p>La <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/11\/entretenimiento\/muere-diane-keaton-actriz-79-anios-trax\">muerte de Keaton<\/a> fue confirmada a CNN por Dori Rath, una productora que trabaj\u00f3 en varias de sus pel\u00edculas m\u00e1s recientes. No se revel\u00f3 la causa de la muerte, y CNN contact\u00f3 a sus representantes para obtener comentarios.<\/p>\n<p>Las actrices Goldie Hawn y Bette Midler, quienes coprotagonizaron junto a Keaton la comedia de 1996 \u201cThe First Wives Club\u201d, donde interpretaron a divorciadas que buscan venganza contra sus exmaridos, estuvieron entre las muchas personas que le rindieron homenaje.<\/p>\n<p>La actriz Bette Midler escribi\u00f3 en una <a href=\"https:\/\/www.instagram.com\/p\/DPrlJwskXoW\/\">publicaci\u00f3n de Instagram<\/a> que la muerte de Keaton la entristeci\u00f3 profundamente. \u201cEra divertid\u00edsima, completamente original y sin ninguna malicia ni la competitividad que uno esperar\u00eda de una estrella as\u00ed\u201d, dijo sobre Keaton.<\/p>\n<p>Por su parte, Hawn expres\u00f3 en una publicaci\u00f3n en <a href=\"https:\/\/www.instagram.com\/p\/DPr-aZuEmRo\/\">Instagram<\/a> un sentimiento probablemente compartido por seguidores y quienes la conocieron: \u201cDiane, no estamos listos para perderte\u201d.<\/p>\n<p>\u201cQuedamos en envejecer juntas, y alg\u00fan d\u00eda, tal vez vivir juntas con todas nuestras amigas\u201d, agreg\u00f3. \u201cBueno, nunca llegamos a vivir juntas, pero s\u00ed envejecimos juntas. Qui\u00e9n sabe\u2026 tal vez en la pr\u00f3xima vida\u201d.<\/p>\n<p>El ganador del Oscar, Leonardo DiCaprio, record\u00f3 a Keaton, con quien protagoniz\u00f3 \u201cMarvin\u2019s Room\u201d cuando \u00e9l ten\u00eda solo 18 a\u00f1os, como \u201cuna leyenda, un \u00edcono y una persona verdaderamente amable\u201d.<\/p>\n<p>Kimberly Williams Paisley, quien coprotagoniz\u00f3 junto a Keaton la pel\u00edcula de 1991 \u201cFather of the Bride\u201d, escribi\u00f3: \u201cDiane, trabajar contigo siempre ser\u00e1 uno de los momentos m\u00e1s destacados de mi vida\u201d, en una publicaci\u00f3n en <a href=\"https:\/\/www.instagram.com\/p\/DPrmRhLie79\/\">Instagram.<\/a><\/p>\n<p>El actor Ben Stiller calific\u00f3 a Keaton como \u201cuna de las mejores actrices de cine de todos los tiempos\u201d y \u201cun \u00edcono del estilo, humor y comedia\u201d en una <a href=\"https:\/\/x.com\/BenStiller\/status\/1977095630804881676\">publicaci\u00f3n en X<\/a>.<\/p>\n<p>Y el dramaturgo ganador del Tony, Jeremy O. Harris, escribi\u00f3 que Keaton \u201cmantuvo un sentido de identidad a lo largo de sus numerosos papeles que me record\u00f3, como joven int\u00e9rprete, que la persona m\u00e1s interesante que puedes descubrir son los m\u00faltiples aspectos de uno mismo\u201d.<\/p>\n<p>La Academia de Artes y Ciencias Cinematogr\u00e1ficas, que otorg\u00f3 a Keaton un Oscar por su papel estelar junto a Woody Allen en \u201cAnnie Hall\u201d de 1977, escribi\u00f3 que ella \u201cencarn\u00f3 las contradicciones de ser humano: divertida y fr\u00e1gil, brillante y herida, siempre dolorosamente honesta\u201d en una <a href=\"https:\/\/x.com\/TheAcademy\/status\/1977131780000870699\">publicaci\u00f3n en X<\/a>.<\/p>\n<p>\u201cSu esp\u00edritu vivir\u00e1 para siempre en la pantalla y en los corazones de todos los que se vieron reflejados en ella\u201d, contin\u00faa la publicaci\u00f3n. Keaton fue nominada al Oscar a mejor actriz en cuatro ocasiones en total, incluyendo por \u201cAnnie Hall\u201d.<\/p>\n<p>Charles Miers, editor de Rizzoli, que public\u00f3 el libro de Keaton en 2024, \u201cFashion First\u201d, sobre su vida y estilo \u00fanico, escribi\u00f3 en un comunicado: \u201cFue ella misma en todo momento y de todas las maneras: extremadamente atenta, muy divertida, generosa hasta el extremo, siempre trabajadora con energ\u00eda y simplemente fiel a las personas de la mejor manera posible\u201d.<\/p>\n<p>\u201cEstamos muy honrados de haber trabajado con ella, orgullosos de los libros que a\u00fan tenemos, pero muy tristes de no estar trabajando en otro con ella y su entusiasmo contagioso\u201d, escribi\u00f3.<\/p>\n<p>El American Film Institute, que homenaje\u00f3 a la actriz con un Premio a la Trayectoria en 2017, escribi\u00f3 que Keaton \u201cllen\u00f3 nuestros corazones de risas y l\u00e1grimas y de la humanidad m\u00e1s profunda durante d\u00e9cadas\u201d.<\/p>\n<p>En un <a href=\"https:\/\/www.facebook.com\/ParamountMovies\/posts\/pfbid0sWmf5NsA5hDPAxC8jS4WPHbw53kV2S2Vb1MFbB5NyYUEWQdYJdAqzcjTKFYbHUTnl\">comunicado<\/a>, Paramount dijo que Keaton se convirti\u00f3 en \u201cun \u00edcono cinematogr\u00e1fico haciendo lo m\u00e1s atrevido de todo: ser completamente ella misma\u201d. La compa\u00f1\u00eda agreg\u00f3: \u201cSu legado seguir\u00e1 brillando tan intensamente como ella lo hizo en la pantalla para las generaciones venideras\u201d.<\/p>\n<p>SAG-AFTRA, el sindicato que representa a actores y otros trabajadores de los medios, <a href=\"https:\/\/www.facebook.com\/SAGAFTRA\/posts\/pfbid0QPbjDBYkkwGG4Jm5KaxSFMt8eLv7fhaWXnFbu4gYqDEBYFhXtvBExgukY54LZ8cDl\">escribi\u00f3<\/a>: \u201cHemos perdido a una leyenda\u201d.<\/p>\n<p>\u201cDel teatro a la televisi\u00f3n y al cine, cautiv\u00f3 a las audiencias y conquist\u00f3 corazones con su esp\u00edritu y dedicaci\u00f3n\u201d, se lee en el comunicado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La muerte de la aclamada actriz Diane Keaton, quien protagoniz\u00f3 \u201cAnnie Hall\u201d y \u201cEl Padrino\u201d, ha sido recibida con gran dolor y sorpresa. La muerte de Keaton fue confirmada a CNN por Dori Rath, una productora que trabaj\u00f3 en varias de sus pel\u00edculas m\u00e1s recientes. No se revel\u00f3 la causa de la muerte, y CNN [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467303","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton - Noticias\" \/>\n<meta property=\"og:description\" content=\"La muerte de la aclamada actriz Diane Keaton, quien protagoniz\u00f3 \u201cAnnie Hall\u201d y \u201cEl Padrino\u201d, ha sido recibida con gran dolor y sorpresa. La muerte de Keaton fue confirmada a CNN por Dori Rath, una productora que trabaj\u00f3 en varias de sus pel\u00edculas m\u00e1s recientes. No se revel\u00f3 la causa de la muerte, y CNN [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-12T02:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton\",\"datePublished\":\"2025-10-12T02:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/\"},\"wordCount\":703,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/\",\"name\":\"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-12T02:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton - Noticias","og_description":"La muerte de la aclamada actriz Diane Keaton, quien protagoniz\u00f3 \u201cAnnie Hall\u201d y \u201cEl Padrino\u201d, ha sido recibida con gran dolor y sorpresa. La muerte de Keaton fue confirmada a CNN por Dori Rath, una productora que trabaj\u00f3 en varias de sus pel\u00edculas m\u00e1s recientes. No se revel\u00f3 la causa de la muerte, y CNN [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-12T02:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/"},"author":{"name":"","@id":""},"headline":"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton","datePublished":"2025-10-12T02:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/"},"wordCount":703,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/","name":"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-12T02:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El mundo del espect\u00e1culo lamenta la muerte de Diane Keaton","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/11\/mundo-espectaculo-muerte-diane-keaton-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-12T02:03:41Z","datePublished":"2025-10-12T02:03:41Z","dateModified":"2025-10-12T02:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El mundo del espect\\u00e1culo lamenta la muerte de Diane Keaton\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/11\\\/mundo-espectaculo-muerte-diane-keaton-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/11\\\/mundo-espectaculo-muerte-diane-keaton-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-12T02:03:41Z\",\"datePublished\":\"2025-10-12T02:03:41Z\",\"dateModified\":\"2025-10-12T02:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467304,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/11\/peliculas-conocer-diane-keaton-segun-critico-cine-orix\/","url_meta":{"origin":1467303,"position":0},"title":"5 pel\u00edculas para conocer a Diane Keaton, seg\u00fan un cr\u00edtico de cine","author":"","date":"octubre 11, 2025","format":false,"excerpt":"La actriz estadounidense Diane Keaton, quien muri\u00f3 este s\u00e1bado a los 79 a\u00f1os, tuvo una amplia carrera en el cine que incluye alrededor de 100 cr\u00e9ditos tanto por su labor frente a las c\u00e1maras como detr\u00e1s de ellas como productora o directora, de acuerdo con los registros de Internet Movie\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467300,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/11\/muere-diane-keaton-actriz-79-anios-trax\/","url_meta":{"origin":1467303,"position":1},"title":"Muere Diane Keaton, actriz y estrella de Hollywood, a los 79 a\u00f1os","author":"","date":"octubre 11, 2025","format":false,"excerpt":"Diane Keaton, reconocida actriz ganadora del Oscar y referente del cine estadounidense, muri\u00f3 a los 79 a\u00f1os, inform\u00f3 la productora Dori Rath a CNN este s\u00e1bado.La noticia de su fallecimiento fue reportada inicialmente por la revista People. CNN ha intentado confirmar la informaci\u00f3n con sus representantes y con el Departamento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467298,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/11\/muere-diane-keaton-actriz-y-estrella-de-hollywood-a-los-79-anos\/","url_meta":{"origin":1467303,"position":2},"title":"Muere Diane Keaton, actriz y estrella de Hollywood, a los 79 a\u00f1os","author":"","date":"octubre 11, 2025","format":false,"excerpt":"Diane Keaton, reconocida actriz ganadora del Oscar y referente del cine estadounidense, muri\u00f3 a los 79 a\u00f1os, inform\u00f3 la productora Dori Rath a CNN este s\u00e1bado.La noticia de su fallecimiento fue reportada inicialmente por la revista People. CNN ha intentado confirmar la informaci\u00f3n con sus representantes y con el Departamento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467460,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/17\/5-cosas-17-octubre-orix\/","url_meta":{"origin":1467303,"position":3},"title":"Las 5 cosas que debes saber este 17 de octubre: detenciones de ICE, ataques en el Caribe y muerte de Ace Frehley","author":"","date":"octubre 17, 2025","format":false,"excerpt":"EE.UU. ejecuta otro ataque militar en el Caribe y crecen las tensiones. Trump dice que se reunir\u00e1 con Putin para discutir sobre la guerra en Ucrania. Las personas que quieran tramitar o renovar su \u2018parole\u2019 en EE.UU. deber\u00e1n pagar US$ 1.000. Esto es lo que debes saber para comenzar el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469617,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/12\/27\/famosos-muertos-2025-trax\/","url_meta":{"origin":1467303,"position":4},"title":"Los famosos que murieron en 2025","author":"","date":"diciembre 27, 2025","format":false,"excerpt":"El papa Francisco, Paquita la del Barrio, Pepe Mujica, Diogo Jota, Diane Keaton\u2026 Estas son algunas personas notables que murieron en 2025.The-CNN-Wire\u2122 & \u00a9 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469016,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/12\/05\/mas-buscado-google-2025-ia-charlie-kirk-orix\/","url_meta":{"origin":1467303,"position":5},"title":"Lo m\u00e1s buscado en Google en 2025: IA, Charlie Kirk y la Copa Mundial dominaron las tendencias","author":"","date":"diciembre 5, 2025","format":false,"excerpt":"Google dio a conocer este viernes la clasificaci\u00f3n de tendencias anuales de su motor de b\u00fasqueda durante 2025 a nivel global, entre las que figuran avances tecnol\u00f3gicos, acontecimientos sociales en todo el mundo, grandes eventos deportivos y personalidades.Su tradicional informe \u201cEl a\u00f1o en b\u00fasquedas\u201d es una muestra del pulso informativo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467303"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467303\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}