{"id":1467350,"date":"2025-10-14T02:03:46","date_gmt":"2025-10-14T09:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/"},"modified":"2025-10-14T02:03:46","modified_gmt":"2025-10-14T09:03:46","slug":"atacante-ice-dallas-tiro-registros-ap","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/","title":{"rendered":"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros"},"content":{"rendered":"<p>Los padres del atacante de 29 a\u00f1os que abri\u00f3 fuego en una instalaci\u00f3n de inmigraci\u00f3n de Dallas en septiembre dijeron a la polic\u00eda que su hijo era \u201ccompletamente normal\u201d antes de mudarse al estado de Washington y regresar a casa hace varios a\u00f1os creyendo que ten\u00eda enfermedad por radiaci\u00f3n, seg\u00fan registros recientemente publicados.<\/p>\n<p>Joshua Jahn hab\u00eda comenzado a usar guantes de algod\u00f3n para evitar el contacto con el pl\u00e1stico y practicaba tiro al blanco con un rifle reci\u00e9n comprado en Oklahoma un mes antes del mortal ataque en la azotea de un edificio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos, seg\u00fan un informe escrito por un oficial del Departamento de Polic\u00eda de Fairview.<\/p>\n<p>Jahn <a href=\"https:\/\/www.cnn.com\/2025\/09\/30\/us\/dallas-ice-facility-shooting-detainee-dies\">mat\u00f3 a dos detenidos<\/a> e hiri\u00f3 a otro antes de quitarse la vida en el tiroteo del 24 de septiembre.<\/p>\n<p>Los escritos del atacante de ICE eran \u201cdefinitivamente anti-ICE\u201d e inclu\u00edan \u201codio hacia el Gobierno federal\u201d, afirma el fiscal.<\/p>\n<p>Los registros, obtenidos por The Associated Press mediante una solicitud de acceso a los registros, no revelan ninguna pista sobre el posible motivo del ataque.<\/p>\n<p>Las autoridades federales afirmaron previamente que Jahn <a href=\"https:\/\/www.cnn.com\/2025\/09\/25\/us\/wwk-dallas-ice-facility-shooting\" rel=\"noopener noreferrer\" target=\"_blank\">escribi\u00f3 \u201cANTI-ICE\u201d en una bala<\/a> y dej\u00f3 notas manuscritas indicando que pretend\u00eda emboscar y aterrorizar a los agentes de ICE.<\/p>\n<p>Los nuevos registros muestran que el d\u00eda del tiroteo, los padres de Jahn declararon al FBI que \u00e9l \u201cocasionalmente hablaba de actualidad\u201d con su madre, pero que rara vez conversaban con \u00e9l. Agregaron que era un \u201csolitario\u201d obsesionado con la tecnolog\u00eda de inteligencia artificial.<\/p>\n<p>Ambos padres, Andrew y Sharon Jahn, no respondieron de inmediato el lunes a los mensajes de texto y tel\u00e9fono de AP.<\/p>\n<p>Los documentos describen a Jahn como un joven desempleado y sin amigos que se hab\u00eda encerrado en la casa de sus padres, en un suburbio de Dallas, para jugar videojuegos en su habitaci\u00f3n. Jahn no fue diagnosticado ni tratado por ning\u00fan trastorno mental o f\u00edsico, seg\u00fan sus padres.<\/p>\n<p>Ni la polic\u00eda ni el FBI respondieron de inmediato a una solicitud de comentarios. El FBI se limit\u00f3 a decir que, debido al cierre del Gobierno, se centraba en la seguridad nacional, las violaciones de la ley federal y las funciones esenciales de seguridad p\u00fablica.<\/p>\n<p>Jahn hab\u00eda llevado una vida \u201ccompletamente normal\u201d hasta que regres\u00f3 del estado de Washington hace cinco a\u00f1os, seg\u00fan informaron sus padres.<\/p>\n<p>Anteriormente, hab\u00eda asistido a clases en un colegio comunitario de Texas de forma intermitente durante a\u00f1os, antes de cruzar el pa\u00eds en coche para responder a un anuncio en l\u00ednea de un trabajo temporal cosechando marihuana en una granja legal de cannabis en Washington.<\/p>\n<p>Jahn parec\u00eda no tener rumbo y durmi\u00f3 en su coche durante meses, seg\u00fan declar\u00f3 previamente a AP el due\u00f1o de la granja, Ryan Sanderson.<\/p>\n<p>Tras regresar de Washington por no poder conservar su trabajo, los padres de Jahn declararon al FBI que cre\u00eda que era al\u00e9rgico al pl\u00e1stico y que procuraba evitar el contacto directo con la piel.<\/p>\n<p>El condado donde trabajaba en el estado de Washington era uno de los sitios del Proyecto Manhattan, un programa secreto para desarrollar bombas at\u00f3micas. Y dijeron que su hijo se convenci\u00f3 de que, durante su estancia en Washington, hab\u00eda estado expuesto a la radiaci\u00f3n de una instalaci\u00f3n cercana y sufr\u00eda de enfermedad por radiaci\u00f3n.<\/p>\n<p>Las fotograf\u00edas del lugar del tiroteo muestran un autom\u00f3vil que lleva pegado un mapa que representa la lluvia radiactiva en Estados Unidos.<\/p>\n<p>Los registros indican que su vida familiar distaba mucho de ser armoniosa. El padre de Jahn presion\u00f3 a su hermano mayor para que buscara trabajo o se alistara en el ej\u00e9rcito despu\u00e9s de terminar la secundaria, y su madre llam\u00f3 a la polic\u00eda cuando su hermano no se present\u00f3 a una reuni\u00f3n con un reclutador del Ej\u00e9rcito para firmar los documentos de alistamiento en 2014, seg\u00fan consta en los registros policiales.<\/p>\n<p>La madre de Jahn llam\u00f3 a la polic\u00eda una ma\u00f1ana porque su hermana se qued\u00f3 dormida en lugar de ir a la escuela secundaria, se mud\u00f3 de la casa durante semanas cuando era adolescente y una vez pint\u00f3 con aerosol un insulto en la entrada de la casa familiar.<\/p>\n<p>Pero los Jahn apoyaron econ\u00f3micamente a Joshua, su hijo menor, mientras \u00e9l se quedaba en su habitaci\u00f3n del segundo piso y jugaba juegos de computadora.<\/p>\n<p>Aproximadamente un mes antes de que Jahn atacara las instalaciones del ICE, el sospechoso fue con su padre a practicar tiro en su propiedad en Durant, Oklahoma, donde est\u00e1n construyendo una nueva casa.<\/p>\n<p>Aunque el padre de Jahn ten\u00eda varias armas, se sorprendi\u00f3 al ver a su hijo sacar un \u201cviejo rifle\u201d en su auto. Afirm\u00f3 que hab\u00eda comprado el arma \u201crecientemente\u201d por internet, seg\u00fan consta en los registros policiales.<\/p>\n<p>Su madre le dijo al FBI que \u201cno ten\u00eda idea\u201d de que su hijo pose\u00eda un arma.<\/p>\n<p>El FBI afirm\u00f3 previamente que Jahn obtuvo legalmente el rifle de cerrojo utilizado en el tiroteo. Sin embargo, los registros policiales no indican si esa fue la pistola que Jahn utiliz\u00f3 durante el tiro al blanco.<\/p>\n<p>Analistas del Instituto para el Di\u00e1logo Estrat\u00e9gico, especializado en odio y extremismo, que trabaja en un programa organizado por el Centro para la Seguridad en Internet, afirmaron haber descubierto que Jahn jugaba en l\u00ednea bajo el nombre de usuario \u201cFrank Hoenniker\u201d.<\/p>\n<p> Al parecer, el nombre de usuario es una referencia mal escrita a un personaje fr\u00edo y calculador de la novela sat\u00edrica de Kurt Vonnegut de 1963, \u201cLa Cuna del Gato\u201d, sobre pol\u00edtica, religi\u00f3n y proliferaci\u00f3n nuclear.<\/p>\n<p>Steam, una plataforma de distribuci\u00f3n de juegos, muestra que Jahn registr\u00f3 m\u00e1s de 11.000 horas en juegos de disparos en primera persona y de supervivencia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los padres del atacante de 29 a\u00f1os que abri\u00f3 fuego en una instalaci\u00f3n de inmigraci\u00f3n de Dallas en septiembre dijeron a la polic\u00eda que su hijo era \u201ccompletamente normal\u201d antes de mudarse al estado de Washington y regresar a casa hace varios a\u00f1os creyendo que ten\u00eda enfermedad por radiaci\u00f3n, seg\u00fan registros recientemente publicados. Joshua Jahn [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467350","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los padres del atacante de 29 a\u00f1os que abri\u00f3 fuego en una instalaci\u00f3n de inmigraci\u00f3n de Dallas en septiembre dijeron a la polic\u00eda que su hijo era \u201ccompletamente normal\u201d antes de mudarse al estado de Washington y regresar a casa hace varios a\u00f1os creyendo que ten\u00eda enfermedad por radiaci\u00f3n, seg\u00fan registros recientemente publicados. Joshua Jahn [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-14T09:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros\",\"datePublished\":\"2025-10-14T09:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/\"},\"wordCount\":1044,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/\",\"name\":\"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-14T09:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/","og_locale":"es_ES","og_type":"article","og_title":"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros - Noticias","og_description":"Los padres del atacante de 29 a\u00f1os que abri\u00f3 fuego en una instalaci\u00f3n de inmigraci\u00f3n de Dallas en septiembre dijeron a la polic\u00eda que su hijo era \u201ccompletamente normal\u201d antes de mudarse al estado de Washington y regresar a casa hace varios a\u00f1os creyendo que ten\u00eda enfermedad por radiaci\u00f3n, seg\u00fan registros recientemente publicados. Joshua Jahn [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/","og_site_name":"Noticias","article_published_time":"2025-10-14T09:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/"},"author":{"name":"","@id":""},"headline":"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros","datePublished":"2025-10-14T09:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/"},"wordCount":1044,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/","url":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/","name":"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-14T09:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El atacante de instalaciones de ICE de Dallas tem\u00eda la exposici\u00f3n a la radiaci\u00f3n y practic\u00f3 el tiro, seg\u00fan muestran registros","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/atacante-ice-dallas-tiro-registros-ap\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-14T09:03:46Z","datePublished":"2025-10-14T09:03:46Z","dateModified":"2025-10-14T09:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El atacante de instalaciones de ICE de Dallas tem\\u00eda la exposici\\u00f3n a la radiaci\\u00f3n y practic\\u00f3 el tiro, seg\\u00fan muestran registros\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/14\\\/atacante-ice-dallas-tiro-registros-ap\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/14\\\/atacante-ice-dallas-tiro-registros-ap\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-14T09:03:46Z\",\"datePublished\":\"2025-10-14T09:03:46Z\",\"dateModified\":\"2025-10-14T09:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466788,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/24\/joshua-jahn-presunto-atacante-tiroteo-ice-dallas-trax\/","url_meta":{"origin":1467350,"position":0},"title":"\u00bfQui\u00e9n era Joshua Jahn, el presunto atacante contra una instalaci\u00f3n del ICE en Dallas?","author":"","date":"septiembre 24, 2025","format":false,"excerpt":"El atacante se\u00f1alado como responsable de matar a un detenido y herir a otros dos en una instalaci\u00f3n del Servicio de Inmigraci\u00f3n y Control de Aduanas (ICE, por sus siglas en ingl\u00e9s) en Dallas, Texas, es Joshua Jahn, seg\u00fan tres fuentes con conocimiento del caso.Ten\u00eda 29 a\u00f1os, asegur\u00f3 a CNN\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451157,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/07\/16\/thomas-crooks-disparo-mitin-trump-investigacion-trax\/","url_meta":{"origin":1467350,"position":1},"title":"Un campo de tiro, una armer\u00eda y la compra de una escalera: siguiendo los movimientos del atacante del mitin de Trump previos a su ataque","author":"","date":"julio 16, 2024","format":false,"excerpt":"(CNN) -- En las 48 horas previas a abrir fuego contra el expresidente Donald Trump, Thomas Matthew Crooks, de 20 a\u00f1os, hizo una serie de paradas en su ciudad natal de los suburbios de Pittsburgh y sus alrededores.Este viernes, fue a un campo de tiro del que era miembro, y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466797,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/25\/ataque-instalacion-ice-texas-que-sabemos-trax\/","url_meta":{"origin":1467350,"position":2},"title":"Un detenido muri\u00f3 despu\u00e9s de un tiroteo en una instalaci\u00f3n de ICE en Texas: las claves del caso","author":"","date":"septiembre 25, 2025","format":false,"excerpt":"Las personas detenidas por el Servicio de Inmigraci\u00f3n y Control de Aduanas de Estados Unidos son procesadas cada d\u00eda en la oficina de campo de la agencia en Dallas, un edificio rectangular de ladrillo escondido entre una autopista muy transitada, varias oficinas de abogados y un complejo de apartamentos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445342,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/02\/13\/la-atacante-del-tiroteo-en-iglesia-de-houston-tenia-un-largo-historial-criminal-segun-la-policia-quien-era-genesse-ivonne-moreno\/","url_meta":{"origin":1467350,"position":3},"title":"La atacante del tiroteo en iglesia de Houston ten\u00eda un largo historial criminal, seg\u00fan la Polic\u00eda: \u00bfqui\u00e9n era Genesse Ivonne Moreno?","author":"","date":"febrero 13, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 La mujer que abri\u00f3 fuego en una gran iglesia de Houston, Texas, la tarde de este domingo, luego de entrar con su hijo de 7 a\u00f1os, fue identificada como Genesse Ivonne Moreno, de 36 a\u00f1os, en una orden de registro.Poco despu\u00e9s de que Moreno comenzara a disparar en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445348,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/02\/13\/la-atacante-del-tiroteo-en-iglesia-de-houston-tenia-un-largo-historial-criminal-segun-la-policia-quien-era-genesse-ivonne-moreno-2\/","url_meta":{"origin":1467350,"position":4},"title":"La atacante del tiroteo en iglesia de Houston ten\u00eda un largo historial criminal, seg\u00fan la Polic\u00eda: \u00bfqui\u00e9n era Genesse Ivonne Moreno?","author":"","date":"febrero 13, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 La mujer que abri\u00f3 fuego en una gran iglesia de Houston, Texas, la tarde de este domingo, luego de entrar con su hijo de 7 a\u00f1os, fue identificada como Genesse Ivonne Moreno, de 36 a\u00f1os, en una orden de registro.Poco despu\u00e9s de que Moreno comenzara a disparar en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445288,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/02\/11\/reportan-tiroteo-en-una-iglesia-de-houston-y-la-sospechosa-fue-abatida-segun-las-autoridades\/","url_meta":{"origin":1467350,"position":5},"title":"Reportan tiroteo en una iglesia de Houston y la sospechosa fue abatida, seg\u00fan las autoridades","author":"","date":"febrero 11, 2024","format":false,"excerpt":"(CNN) -- La atacante en la Iglesia Lakewood era una mujer de entre 30 y 35 a\u00f1os que estaba armada con un rifle largo y acompa\u00f1ada por un ni\u00f1o, dijo el jefe de la Polic\u00eda de Houston, Troy Finner, a los periodistas en una conferencia de prensa el domingo.\"Ella muri\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467350"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467350\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}