{"id":1467371,"date":"2025-10-14T17:03:39","date_gmt":"2025-10-15T00:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/"},"modified":"2025-10-14T17:03:39","modified_gmt":"2025-10-15T00:03:39","slug":"impacto-despidos-empleados-cierre-gobierno-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/","title":{"rendered":"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.?"},"content":{"rendered":"<p>Douglas Jackson, un veterano discapacitado en servicio que fue despedido durante los recortes federales del viernes, no pod\u00eda creerlo cuando escuch\u00f3 al vicepresidente decir que el Gobierno de Trump se ve\u00eda obligado a elegir entre los estadounidenses y los \u201cbur\u00f3cratas federales\u201d.<\/p>\n<p>\u201cSoy un veterano de Orlando. No soy un bur\u00f3crata de Washington\u201d, dijo a CNN, solo d\u00edas despu\u00e9s de que la Casa Blanca enviara avisos de reducci\u00f3n de personal \u2014o RIF\u2014 a m\u00e1s de 3.500 trabajadores federales. \u201cO no saben a qui\u00e9n est\u00e1n despidiendo, o simplemente no les importa\u201d.<\/p>\n<p>Jackson, quien sirvi\u00f3 en los Marines durante cuatro a\u00f1os y estuvo expuesto a fosas de quema en Iraq, describi\u00f3 una sensaci\u00f3n de disgusto y traici\u00f3n cuando escuch\u00f3 al presidente Donald Trump decir que la mayor\u00eda de los despedidos \u201cresulta que son dem\u00f3cratas\u201d.<\/p>\n<p>\u201cNo hay manera de que \u00e9l pueda saber nuestra afiliaci\u00f3n pol\u00edtica\u201d, dijo Jackson, se\u00f1alando que no est\u00e1 registrado en ning\u00fan partido y que ha votado tanto por dem\u00f3cratas como por republicanos.<\/p>\n<p>El hombre de 40 a\u00f1os hab\u00eda sido reincorporado a principios de este a\u00f1o a su puesto de relaciones p\u00fablicas en la Divisi\u00f3n de Grandes Empresas e Internacional del IRS, despu\u00e9s de haber sido despedido como parte de la reducci\u00f3n de personal del Departamento de Eficiencia Gubernamental. Pero el despido m\u00e1s reciente lo ha hecho sentir que la administraci\u00f3n incumpli\u00f3 su promesa de proteger a los veteranos, trat\u00e1ndolo a \u00e9l y a otros como piezas en la lucha pol\u00edtica sobre la mejor manera de financiar al Gobierno.<\/p>\n<p>El Gobierno de Trump ejecut\u00f3 recortes en siete agencias federales el viernes, despidiendo a empleados que manejan una amplia gama de temas \u2014desde asuntos del Servicio de Impuestos Internos de Estados Unidos (IRS)\u2014 como los que maneja Jackson hasta subvenciones para vivienda, programas de educaci\u00f3n especial y la defensa del pa\u00eds contra ciberataques.<\/p>\n<p>Los despidos ocurrieron despu\u00e9s de que la Casa Blanca advirtiera durante varias semanas que usar\u00eda el cierre del Gobierno como una oportunidad para seguir reduciendo la fuerza laboral federal. Otra ola de RIF podr\u00eda estar en camino, dijo el Gobierno en un documento judicial.<\/p>\n<p>La Oficina de Administraci\u00f3n y Presupuesto de la Casa Blanca (OMB, por sus siglas en ingl\u00e9s) <a href=\"https:\/\/www.cnn.com\/2025\/09\/24\/politics\/white-house-mass-firings-government-shut-down\"> aconsej\u00f3 a las agencias<\/a> a finales de septiembre que el cierre ser\u00eda una oportunidad para recortar programas considerados \u201cincompatibles\u201d con las prioridades de Trump. Y aunque la idea no fue bien recibida por muchos republicanos en el Congreso, la administraci\u00f3n decidi\u00f3 seguir adelante.<\/p>\n<p>Trump redobl\u00f3 su postura el viernes por la tarde, diciendo que planea despedir a \u201cmuchos\u201d empleados federales en represalia por el cierre del Gobierno, y prometi\u00f3 enfocarse en aquellos considerados<a href=\"https:\/\/www.cnn.com\/politics\/live-news\/government-shutdown-news-10-10-25?post-id=cmglf1iyb00003b6npyjnr3u3\"> alineados con el Partido Dem\u00f3crata. <\/a>No detall\u00f3 a qu\u00e9 se refer\u00eda.<\/p>\n<p>El vicepresidente J. D. Vance dijo el domingo que los despidos durante el cierre del Gobierno son necesarios para continuar con <a href=\"https:\/\/www.cnn.com\/politics\/live-news\/trump-government-shutdown-news-10-12-25?post-id=cmgns2wg000053b6n8hjvez1b\">programas federales cr\u00edticos de asistencia<\/a>, incluido el programa de asistencia nutricional Programa Especial de Nutrici\u00f3n Suplementaria para Mujeres (WIC, por sus siglas en ingl\u00e9s), y para pagar a las fuerzas armadas.<\/p>\n<p>\u201cTenemos que despedir a algunos empleados federales en medio de este cierre para preservar los beneficios esenciales que el Gobierno s\u00ed proporciona al pueblo estadounidense\u201d, dijo en \u201cMeet the Press\u201d de NBC, culpando a los dem\u00f3cratas por las reducciones.<\/p>\n<p>Sin embargo, expertos en presupuesto se\u00f1alaron varias razones por las que la declaraci\u00f3n de Vance no era cierta. Entre ellas, muchos empleados federales no est\u00e1n recibiendo salario durante el cierre, por lo que despedirlos no liberar\u00eda fondos; adem\u00e1s, si estuvieran siendo pagados, el dinero no estar\u00eda disponible hasta dentro de 60 d\u00edas, cuando la mayor\u00eda debe dejar realmente sus puestos, explic\u00f3 Bobby Kogan, director s\u00e9nior de pol\u00edtica presupuestaria federal en el Centro para el Progreso Estadounidense, de tendencia progresista, y exfuncionario de la OMB durante el Gobierno de Biden. Adem\u00e1s, la semana pasada, el Gobierno de Trump dijo que extender\u00e1 la financiaci\u00f3n de WIC usando ingresos por aranceles.<\/p>\n<p>Adem\u00e1s, cualquier fondo ahorrado al despedir a varios miles de empleados federales ser\u00eda solo una fracci\u00f3n m\u00ednima de lo necesario para financiar el WIC y las fuerzas armadas, se\u00f1al\u00f3 Michael Linden, ex alto funcionario de la OMB durante el Gobierno de Biden y ahora investigador s\u00e9nior de pol\u00edticas en el Centro de Washington para el Crecimiento Equitativo, de tendencia progresista.<\/p>\n<p>Mientras tanto, la AFGE, junto con otro sindicato que rerepresenta a empleados federales, present\u00f3 una demanda en un tribunal federal de California para intentar frenar los despidos masivos del Gobierno de Trump, calific\u00e1ndolos de ilegales.<\/p>\n<p>Los sindicatos pidieron el viernes a la jueza de distrito Susan Illston que detuviera de inmediato los RIF, ahora que el Gobierno ha comenzado a implementarlos. La presentaci\u00f3n del Gobierno del viernes, que revela el n\u00famero de personas afectadas, sigui\u00f3 a la solicitud de los sindicatos la semana pasada de una orden de<a href=\"https:\/\/www.cnn.com\/politics\/live-news\/government-shutdown-news-10-05-25#cmge76xnk00003b6oqp1jsw1p\"> restricci\u00f3n temporal <\/a>para impedir que el Gobierno cumpliera su amenaza. La jueza a\u00fan no se ha pronunciado sobre la solicitud.<\/p>\n<p>Jackson tambi\u00e9n cuestion\u00f3 la legalidad de los despidos.<\/p>\n<p>\u201cEs retaliaci\u00f3n, es represalia\u201d, dijo. \u201cGenera incertidumbre para todos los afectados, y no s\u00e9 c\u00f3mo se sostendr\u00e1 esto en los tribunales\u201d.<\/p>\n<p>Esto es lo que sabemos sobre los despidos:<\/p>\n<p>Al menos 1.300 empleados del IRS recibieron avisos de RIF la semana pasada, seg\u00fan una fuente familiarizada con el asunto. Los despidos afectaron a personal como Jackson en la Divisi\u00f3n de Grandes Empresas e Internacional (LB&#038;I) de la agencia, que se encarga de la administraci\u00f3n tributaria para corporaciones nacionales y extranjeras, as\u00ed como en la Divisi\u00f3n de Tecnolog\u00eda de la Informaci\u00f3n y la Oficina de Privacidad, Enlace Gubernamental y Divulgaci\u00f3n (PGLD, por sus siglas en ingl\u00e9s), una oficina clave que hab\u00eda planteado preocupaciones legales internas sobre ciertas iniciativas de intercambio de datos de contribuyentes entre el IRS y el Servicio de Inmigraci\u00f3n y Control de Aduanas de EE.UU. (ICE).<\/p>\n<p>El personal de la Oficina de Impacto Econ\u00f3mico de las Minor\u00edas del departamento fue informado el viernes sobre planes para una gran reorganizaci\u00f3n. La divisi\u00f3n \u201ccontiene programas, proyectos o actividades que son incompatibles con las prioridades de la administraci\u00f3n\u201d, seg\u00fan un memorando obtenido por CNN.<\/p>\n<p>La carta a\u00f1ad\u00eda que, como resultado, la oficina \u201csufrir\u00e1 una gran reorganizaci\u00f3n, y su puesto puede ser reasignado a otra organizaci\u00f3n, transferido a otra funci\u00f3n o eliminado\u201d. La oficina es responsable de evaluar c\u00f3mo los programas, pol\u00edticas y regulaciones energ\u00e9ticas del departamento afectan a las comunidades minoritarias.<\/p>\n<p>La agencia dijo que los recortes siguieron a \u201cdeterminaciones tomadas al identificar programas que no est\u00e1n alineados con la agenda de gesti\u00f3n del Presidente o las prioridades de la Administraci\u00f3n\u201d, seg\u00fan un memorando del subsecretario adjunto del Departamento de Vivienda y Desarrollo Urbano (HUD, por sus siglas en ingl\u00e9s), Andrew Hughes, dirigido a funcionarios sindicales y obtenido por CNN.<\/p>\n<p>La Oficina de Planificaci\u00f3n y Desarrollo Comunitario de HUD, que supervisa subvenciones para apoyar a comunidades de bajos ingresos, programas de vivienda y de personas sin hogar, tambi\u00e9n enfrenta reducciones de personal.<\/p>\n<p>La Agencia de Seguridad de Infraestructura y Ciberseguridad (CISA) del DHS, responsable de defender contra ciberataques y proteger la infraestructura cr\u00edtica del pa\u00eds, es una de las oficinas afectadas por los despidos. La misi\u00f3n de CISA incluye mejorar las comunicaciones de emergencia, evaluar riesgos en sistemas vitales y fortalecer alianzas p\u00fablico-privadas para aumentar la resiliencia nacional.<\/p>\n<p>\u201cDurante la \u00faltima administraci\u00f3n, CISA se centr\u00f3 en la censura, la imagen y la propaganda electoral. Esto es parte de devolver a CISA a su misi\u00f3n\u201d, dijo una portavoz de la agencia a CNN.<\/p>\n<p>Empleados de la Oficina de Gesti\u00f3n de Tierras y Emergencias de la EPA recibieron el viernes avisos de intenci\u00f3n de RIF. La divisi\u00f3n se enfoca en la limpieza de desechos peligrosos y la respuesta a sitios contaminados, incluyendo la supervisi\u00f3n del programa Brownfields, que ayuda a los estados a limpiar y reutilizar sitios previamente contaminados.<\/p>\n<p>\u201cEs indignante que la administraci\u00f3n de Trump est\u00e9 usando el cierre del Gobierno como excusa para despedir a empleados federales, incluidos trabajadores dedicados de la EPA que brindan servicios cr\u00edticos a comunidades en todo el pa\u00eds\u201d, dijo Justin Chen, presidente del Consejo 238 de Federaci\u00f3n Estadounidense de Empleados del Gobierno, en un comunicado el viernes.<\/p>\n<p>Chen se\u00f1al\u00f3 que entre los trabajadores despedidos hab\u00eda empleados que supervisaban el reciclaje y la seguridad de bater\u00edas, la reducci\u00f3n de pl\u00e1sticos, la recopilaci\u00f3n de datos nacionales sobre residuos s\u00f3lidos y subvenciones para reciclaje.<\/p>\n<p>Consultado el viernes, un portavoz de la EPA dijo: \u201cEs lamentable que los dem\u00f3cratas hayan optado por cerrar el Gobierno y hayan provocado este resultado. Si quieren reabrir el Gobierno, pueden elegir hacerlo en cualquier momento\u201d.<\/p>\n<p>El Departamento de Educaci\u00f3n ha recortado casi todo su personal encargado de la educaci\u00f3n especial, seg\u00fan m\u00faltiples fuentes dentro de la agencia dijeron a CNN.<\/p>\n<p>Los despidos afectaron principalmente a la Oficina de Servicios de Educaci\u00f3n Especial y Rehabilitaci\u00f3n, con la excepci\u00f3n de un peque\u00f1o grupo compuesto principalmente por altos funcionarios, dijeron las fuentes a CNN.<\/p>\n<p>La oficina respalda programas que atienden a millones de ni\u00f1os, j\u00f3venes y adultos con discapacidades en todo el pa\u00eds.<\/p>\n<p>\u201cA pesar de los amplios esfuerzos para minimizar el impacto en los empleados y los programas durante el actual cierre del Gobierno, la continua falta de financiaci\u00f3n ha hecho necesario implementar la RIF (reducci\u00f3n de personal)\u201d, dec\u00eda la carta enviada a algunos empleados despedidos.<\/p>\n<p>No est\u00e1 claro cu\u00e1ntas de las 466 personas despedidas en la agencia pertenecen a la oficina de OSERS.<\/p>\n<p>Un portavoz del Departamento de Educaci\u00f3n dijo a CNN que \u201calgunos\u201d empleados de la oficina se ver\u00e1n afectados, pero no respondi\u00f3 con detalles sobre cu\u00e1ntos ser\u00edan afectados en total.<\/p>\n<p>Alrededor de 1.300 trabajadores de los Centros para el Control y la Prevenci\u00f3n de Enfermedades (CDC) recibieron avisos de despido el viernes por la noche, pero aproximadamente 700 fueron reincorporados el s\u00e1bado, seg\u00fan la Federaci\u00f3n Estadounidense de Empleados del Gobierno. Eso deja a unos 600 que siguen despedidos.<\/p>\n<p>El personal de la oficina de Washington de los CDC, en los programas de Prevenci\u00f3n de la Violencia y en la Oficina del Director del Centro de Lesiones, sigue separado de la agencia.<\/p>\n<p>Entre los empleados reincorporados se encuentran quienes publican la revista principal de la agencia, el Informe Semanal de Morbilidad y Mortalidad; el Centro Nacional de Inmunizaci\u00f3n y Enfermedades Respiratorias; el Centro de Salud Global; y el Centro de Infraestructura de Salud P\u00fablica, que gestiona m\u00e1s de US$ 3.000 millones en subvenciones para 107 gobiernos estatales y locales para ayudar a fortalecer la fuerza laboral de salud p\u00fablica local. Adem\u00e1s, el personal y los oficiales del Servicio de Inteligencia Epidemiol\u00f3gica de los CDC que pudieron revisar sus correos electr\u00f3nicos recibieron avisos de que sus despidos fueron un error.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Douglas Jackson, un veterano discapacitado en servicio que fue despedido durante los recortes federales del viernes, no pod\u00eda creerlo cuando escuch\u00f3 al vicepresidente decir que el Gobierno de Trump se ve\u00eda obligado a elegir entre los estadounidenses y los \u201cbur\u00f3cratas federales\u201d. \u201cSoy un veterano de Orlando. No soy un bur\u00f3crata de Washington\u201d, dijo a CNN, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467371","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.? - Noticias\" \/>\n<meta property=\"og:description\" content=\"Douglas Jackson, un veterano discapacitado en servicio que fue despedido durante los recortes federales del viernes, no pod\u00eda creerlo cuando escuch\u00f3 al vicepresidente decir que el Gobierno de Trump se ve\u00eda obligado a elegir entre los estadounidenses y los \u201cbur\u00f3cratas federales\u201d. \u201cSoy un veterano de Orlando. No soy un bur\u00f3crata de Washington\u201d, dijo a CNN, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T00:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.?\",\"datePublished\":\"2025-10-15T00:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/\"},\"wordCount\":1936,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/\",\"name\":\"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-15T00:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.? - Noticias","og_description":"Douglas Jackson, un veterano discapacitado en servicio que fue despedido durante los recortes federales del viernes, no pod\u00eda creerlo cuando escuch\u00f3 al vicepresidente decir que el Gobierno de Trump se ve\u00eda obligado a elegir entre los estadounidenses y los \u201cbur\u00f3cratas federales\u201d. \u201cSoy un veterano de Orlando. No soy un bur\u00f3crata de Washington\u201d, dijo a CNN, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-15T00:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.?","datePublished":"2025-10-15T00:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/"},"wordCount":1936,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/","name":"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-15T00:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfCu\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.?","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/impacto-despidos-empleados-cierre-gobierno-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-15T00:03:39Z","datePublished":"2025-10-15T00:03:39Z","dateModified":"2025-10-15T00:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfCu\\u00e1ntos empleados federales han sido impactados por despidos tras el cierre del Gobierno de EE.UU.?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/14\\\/impacto-despidos-empleados-cierre-gobierno-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/14\\\/impacto-despidos-empleados-cierre-gobierno-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-15T00:03:39Z\",\"datePublished\":\"2025-10-15T00:03:39Z\",\"dateModified\":\"2025-10-15T00:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459658,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/03\/08\/despedidos-trabajadores-federales-votantes-trump-trax\/","url_meta":{"origin":1467371,"position":0},"title":"Votaron a Trump en 2024. Meses despu\u00e9s, su administraci\u00f3n los despidi\u00f3","author":"","date":"marzo 8, 2025","format":false,"excerpt":"Michael Graugnard dijo que vot\u00f3 por el presidente Donald Trump en las elecciones de 2024 porque pensaba que Trump era el mejor candidato para mejorar la econom\u00eda.Pero a los tres meses de asumir su nuevo cargo como abogado asesor del Departamento de Agricultura de Estados Unidos, Graugnard fue despedido junto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460885,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/04\/06\/sindicatos-critican-acciones-trump-trabajadores-protesta-washington-trax\/","url_meta":{"origin":1467371,"position":1},"title":"Presidentes de sindicatos de empleados critican acciones de Trump contra trabajadores en protesta en la ciudad de Washington","author":"","date":"abril 6, 2025","format":false,"excerpt":"Representantes de dos sindicatos de empleados federales se manifestaron este s\u00e1bado contra el presidente Donald Trump y las pol\u00edticas que afectan a los trabajadores del gobierno, en el marco de una protesta de \u201cHands Off\u201d en la ciudad de Washington.\u201cEl gobierno de Trump est\u00e1 destruyendo por completo los servicios p\u00fablicos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459243,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/02\/26\/funcionarios-despedido-trump-federal-trax\/","url_meta":{"origin":1467371,"position":2},"title":"\u00bfA cu\u00e1ntos funcionarios ha despedido Trump? As\u00ed ha sido la reforma a la fuerza laboral federal en EE.UU.","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Miles de empleados federales han sido puestos en licencia administrativa, despedidos o han recibido notificaciones de despido inmediato como parte del plan del presidente Donald Trump y Elon Musk para recortar el gasto y reducir el tama\u00f1o del gobierno federal.CNN est\u00e1 siguiendo paso a paso la situaci\u00f3n ca\u00f3tica y de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467382,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/analisis-acciones-trump-cierre-gobierno-ee-uu-trax\/","url_meta":{"origin":1467371,"position":3},"title":"Las acciones de Trump durante el cierre del Gobierno de EE.UU. muestran que el presidente cree que controla la bolsa federal","author":"","date":"octubre 15, 2025","format":false,"excerpt":"La Casa Blanca de Trump est\u00e1 tratando las leyes de gasto como meras sugerencias mientras intenta silenciar los efectos del cierre del Gobierno y atacar programas que considera prioridades dem\u00f3cratas mientras se prepara para un cierre prolongado.Transferencia de dinero. El dinero destinado por el Congreso a la investigaci\u00f3n en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467314,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/12\/restituyen-personal-despedido-cdc-trax\/","url_meta":{"origin":1467371,"position":4},"title":"M\u00e1s de la mitad del personal de los CDC recientemente despedido por la administraci\u00f3n Trump ha sido reintegrado","author":"","date":"octubre 12, 2025","format":false,"excerpt":"Cientos de empleados de los Centros para el Control y la Prevenci\u00f3n de Enfermedades de EE.UU. (CDC, por sus siglas en ingl\u00e9s) despedidos el viernes por la noche fueron reincorporados, seg\u00fan la Federaci\u00f3n Estadounidense de Empleados Gubernamentales (AFGE, pro sus siglas en ingl\u00e9s).Tras una nueva ronda de notificaciones de despido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471240,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/02\/14\/cambio-vida-exfuncionarios-perdida-empleo-doge-trax\/","url_meta":{"origin":1467371,"position":5},"title":"Mudanzas, pr\u00e9stamos y problemas m\u00e9dicos: as\u00ed cambi\u00f3 la vida de exfuncionarios que perdieron su empleo tras la llegada de DOGE","author":"","date":"febrero 14, 2026","format":false,"excerpt":"Para Ashley Garley, el \u00faltimo a\u00f1o ha sido \u201cdesordenado, desafiante y desgarrador\u201d.Garley, excontratista y experta en malaria de la Agencia de Estados Unidos para el Desarrollo Internacional (USAID, por sus siglas en ingl\u00e9s) fue una de las primeras personas afectadas por la enorme reducci\u00f3n de la fuerza laboral federal del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467371"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467371\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}