{"id":1467374,"date":"2025-10-14T18:03:41","date_gmt":"2025-10-15T01:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/"},"modified":"2025-10-14T18:03:41","modified_gmt":"2025-10-15T01:03:41","slug":"desconfianza-agentes-juicio-anti-ice-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/","title":{"rendered":"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington"},"content":{"rendered":"<p>Los residentes de la capital del Estados Unidos expresaron su creciente oposici\u00f3n y desconfianza hacia los agentes federales \u2014especialmente en torno a los esfuerzos de deportaci\u00f3n del Gobierno\u2014 durante la selecci\u00f3n del jurado el martes en el juicio de una manifestante anti-ICE acusada de agredir a un agente.<\/p>\n<p>Durante unas tres horas, los abogados interrogaron a los posibles miembros del jurado sobre su capacidad para ser imparciales en el juicio de Sydney Reid, quien fue arrestada en julio mientras filmaba la detenci\u00f3n de una persona no ciudadana. Casi una decena de personas en el grupo del jurado federal dijo que no pod\u00eda ser imparciales en el caso debido a sus sentimientos.<\/p>\n<p>\u201cTengo una opini\u00f3n muy negativa de ellos\u201d, se\u00f1al\u00f3 una mujer a la jueza que preside el caso sobre los agentes de inmigraci\u00f3n.<\/p>\n<p>\u201cJusto el mes pasado\u201d, dijo entre l\u00e1grimas repentinas, disculp\u00e1ndose por la interrupci\u00f3n, \u201cme quitaron a mi prima y a mi t\u00eda\u201d.<\/p>\n<p>La mujer dijo que no podr\u00eda ser una jurado imparcial en el juicio de Reid, y agreg\u00f3 que su familia ha enfrentado crecientes dificultades econ\u00f3micas porque su pap\u00e1 y su mam\u00e1 \u201chan dejado de trabajar, por miedo\u201d a las autoridades federales.<\/p>\n<p>\u201cLamento mucho lo que ha sucedido\u201d, dijo la jueza a cargo, Sparkle Sooknanan, antes de dispensar a la mujer.<\/p>\n<p>Los fiscales, tras fracasar tres veces en conseguir una acusaci\u00f3n formal a trav\u00e9s de un jurado investigador, acusaron a Reid de agresi\u00f3n simple. Dicen que levant\u00f3 la rodilla de manera amenazante hacia un agente federal que la estaba sujetando mientras filmaba.<\/p>\n<p>Los abogados de Reid argumentan que el movimiento de la rodilla fue una reacci\u00f3n y que de ninguna manera constituy\u00f3 una agresi\u00f3n al agente, quien no result\u00f3 herido.<\/p>\n<p>Durante la selecci\u00f3n del jurado, se pregunt\u00f3 a los residentes de Washington si ten\u00edan alg\u00fan sentimiento hacia ICE y las fuerzas del orden que les impidiera servir como jurado.<\/p>\n<p>\u201cDesde enero, la ciudad ha cambiado y estoy muy angustiada\u201d, dijo una mujer a la jueza cuando le preguntaron sobre su opini\u00f3n de ICE. \u201cMe gustar\u00eda que se fueran\u201d.<\/p>\n<p>\u201cMoralmente siento que me costar\u00eda trabajo\u201d, dijo otra posible jurado, antes de agregar que no podr\u00eda emitir un veredicto imparcial en el caso.<\/p>\n<p>Varios otros posibles jurados lucharon con la idea de si podr\u00edan ser justos.<\/p>\n<p>\u201cHonestamente, y no puedo creer que est\u00e9 diciendo esto en una sala de audiencias, ya no conf\u00edo en el Gobierno como antes\u201d, dijo una persona \u2014que no fue descartada pero finalmente no fue seleccionada para el jurado\u2014 a la jueza.<\/p>\n<p>Cuando se le pregunt\u00f3 si podr\u00eda considerar de manera justa el testimonio de los agentes de ICE que podr\u00edan declarar en el caso, un posible jurado dijo que \u201cle costar\u00eda mucho creer en su integridad\u201d.<\/p>\n<p>A pesar del escepticismo y la oposici\u00f3n expresados por muchos de los residentes interrogados, el jurado fue conformado el martes por la tarde, y la mayor\u00eda de los posibles jurados dijeron a la jueza que podr\u00edan dejar de lado cualquier sesgo personal durante el juicio.<\/p>\n<p>Durante los alegatos iniciales, el fiscal Travis Wolf intent\u00f3 encontrar un equilibrio entre reconocer el derecho de Reid a filmar y protestar contra los agentes federales mientras deten\u00edan a personas no ciudadanas y explicar por qu\u00e9 los agentes sintieron la necesidad de sujetar a Reid, sugiriendo que \u201cno ten\u00edan otra opci\u00f3n\u201d.<\/p>\n<p>A pesar de la falta de contacto o da\u00f1o f\u00edsico, Wolf argument\u00f3 que \u201ctodo lo que se requiere es una amenaza\u201d de da\u00f1ar a un agente para cumplir con el cargo de agresi\u00f3n simple. Wolf afirm\u00f3 que la amenaza fue que Reid levantara la rodilla, lo que calific\u00f3 como \u201ccontacto ofensivo\u201d.<\/p>\n<p>Uno de los agentes del FBI involucrados en el incidente luego envi\u00f3 un mensaje de texto a un colega, llamando a Reid \u201clibtard\u201d, cont\u00f3 el abogado defensor de Reid, Eugene Ohm, al jurado durante su declaraci\u00f3n inicial. Agreg\u00f3 que los agentes le dijeron a Reid al arrestarla que \u201cdebi\u00f3 haberse metido en sus asuntos\u201d y luego minimizaron la supuesta agresi\u00f3n, diciendo que eran \u201craspones\u201d.<\/p>\n<p>Ohm dijo que el movimiento de la rodilla fue una reacci\u00f3n ante la agresi\u00f3n de los agentes, quienes sujetaron a Reid a pesar de que ella solo estaba filmando y protestando por el arresto.<\/p>\n<p>\u201cLa Sra. Reid fue arrestada porque asom\u00f3 la cabeza\u201d, dijo Ohm. \u201cY ellos quer\u00edan volver a meterla dentro\u201d.<\/p>\n<p>Se espera que el juicio concluya a finales de esta semana.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los residentes de la capital del Estados Unidos expresaron su creciente oposici\u00f3n y desconfianza hacia los agentes federales \u2014especialmente en torno a los esfuerzos de deportaci\u00f3n del Gobierno\u2014 durante la selecci\u00f3n del jurado el martes en el juicio de una manifestante anti-ICE acusada de agredir a un agente. Durante unas tres horas, los abogados interrogaron [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467374","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los residentes de la capital del Estados Unidos expresaron su creciente oposici\u00f3n y desconfianza hacia los agentes federales \u2014especialmente en torno a los esfuerzos de deportaci\u00f3n del Gobierno\u2014 durante la selecci\u00f3n del jurado el martes en el juicio de una manifestante anti-ICE acusada de agredir a un agente. Durante unas tres horas, los abogados interrogaron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T01:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington\",\"datePublished\":\"2025-10-15T01:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/\"},\"wordCount\":804,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/\",\"name\":\"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-15T01:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington - Noticias","og_description":"Los residentes de la capital del Estados Unidos expresaron su creciente oposici\u00f3n y desconfianza hacia los agentes federales \u2014especialmente en torno a los esfuerzos de deportaci\u00f3n del Gobierno\u2014 durante la selecci\u00f3n del jurado el martes en el juicio de una manifestante anti-ICE acusada de agredir a un agente. Durante unas tres horas, los abogados interrogaron [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-15T01:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/"},"author":{"name":"","@id":""},"headline":"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington","datePublished":"2025-10-15T01:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/"},"wordCount":804,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/","name":"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-15T01:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/desconfianza-agentes-juicio-anti-ice-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-15T01:03:41Z","datePublished":"2025-10-15T01:03:41Z","dateModified":"2025-10-15T01:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Desconfianza hacia los agentes federales cobra protagonismo en el juicio de una manifestante anti-ICE en Washington\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/14\\\/desconfianza-agentes-juicio-anti-ice-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/14\\\/desconfianza-agentes-juicio-anti-ice-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-15T01:03:41Z\",\"datePublished\":\"2025-10-15T01:03:41Z\",\"dateModified\":\"2025-10-15T01:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1448156,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/16\/conclusiones-primer-dia-juicio-trump-dinero-silencio-trax\/","url_meta":{"origin":1467374,"position":0},"title":"Conclusiones del primer d\u00eda del juicio a Trump por el pago de dinero por silencio","author":"","date":"abril 16, 2024","format":false,"excerpt":"(CNN) -- Lleg\u00f3 el primer juicio penal al expresidente Donald Trump.La jornada inaugural del primer juicio penal contra un expresidente de Estados Unidos comenz\u00f3 este lunes, dando un golpe de realidad al hecho de que el presunto candidato republicano a la presidencia se sentar\u00e1 en una sala de Manhattan como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448175,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/16\/conclusiones-segundo-juicio-trump-dinero-secreto-trax\/","url_meta":{"origin":1467374,"position":1},"title":"Conclusiones del segundo d\u00eda de selecci\u00f3n del jurado en el juicio a Trump por el pago de dinero por silencio","author":"","date":"abril 16, 2024","format":false,"excerpt":"(CNN) -- Siete miembros del jurado fueron nombrados este martes en el panel que decidir\u00e1 la culpabilidad o inocencia del expresidente Donald Trump en el caso de dinero por silencio en Nueva York, un proceso que expuso lo dif\u00edcil \u2014y a menudo pol\u00e9mico\u2014 que ser\u00e1 elegir un jurado entero.Los abogados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461978,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/05\/05\/seleccion-jurado-juicio-sean-diddy-combs-trax\/","url_meta":{"origin":1467374,"position":2},"title":"Por qu\u00e9 la selecci\u00f3n del jurado en el juicio de Sean &#8216;Diddy&#8217; Combs ser\u00e1 m\u00e1s dif\u00edcil que en un caso promedio","author":"","date":"mayo 5, 2025","format":false,"excerpt":"Sean Combs, un magnate de la m\u00fasica que una vez encabez\u00f3 las listas de \u00e9xitos antes de experimentar una ca\u00edda que ha acaparado los titulares, estar\u00e1 presente en un tribunal de Nueva York este lunes durante la selecci\u00f3n de un jurado de sus pares que decidir\u00e1 su destino en medio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449843,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/05\/29\/conclusiones-deliberaciones-juicio-penal-donald-trump-trax\/","url_meta":{"origin":1467374,"position":3},"title":"Conclusiones del primer d\u00eda de deliberacionesn del jurado en el juicio penal contra Donald Trump","author":"","date":"mayo 29, 2024","format":false,"excerpt":"(CNN) -- El jurado en el juicio de Donald Trump por el pago de dinero por silencio en Nueva York termin\u00f3 su primer d\u00eda de deliberaciones el mi\u00e9rcoles sin llegar a un veredicto despu\u00e9s de m\u00e1s de cuatro horas y media de sesi\u00f3n.Los miembros del jurado volver\u00e1n el jueves a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448104,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/15\/que-esperar-seleccion-jurado-para-el-juicio-penal-de-donald-trump-nueva-york-trax\/","url_meta":{"origin":1467374,"position":4},"title":"Qu\u00e9 esperar en la selecci\u00f3n del jurado para el juicio penal de Donald Trump en Nueva York","author":"","date":"abril 15, 2024","format":false,"excerpt":"(CNN) -- La selecci\u00f3n del jurado comenzar\u00e1 este lunes para formar un grupo de 12 neoyorquinos que en \u00faltima instancia decidir\u00e1n si condenan al expresidente Donald Trump en su primer juicio penal.Los funcionarios del tribunal esperan que alrededor de 500 nuevos jurados se presenten cada d\u00eda a partir del 15\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464865,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/07\/25\/que-son-archivos-epstein-que-contienen-trax\/","url_meta":{"origin":1467374,"position":5},"title":"\u00bfQu\u00e9 son los archivos de Epstein y qu\u00e9 contienen? Esto sabemos","author":"","date":"julio 25, 2025","format":false,"excerpt":"Fiscales federales reunieron millones de registros durante la investigaci\u00f3n y el proceso judicial por tr\u00e1fico sexual contra Jeffrey Epstein y su c\u00f3mplice y expareja, Ghislaine Maxwell.La pregunta sobre qu\u00e9 contienen realmente esos documentos \u2014y si el p\u00fablico podr\u00e1 verlos alguna vez\u2014 se ha vuelto central en una creciente crisis de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467374"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467374\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}