{"id":1467376,"date":"2025-10-14T20:03:47","date_gmt":"2025-10-15T03:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/"},"modified":"2025-10-14T20:03:47","modified_gmt":"2025-10-15T03:03:47","slug":"estadio-azteca-banorte-polemica-palcos-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/","title":{"rendered":"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos?"},"content":{"rendered":"<p>El Estadio Azteca esconde un sinf\u00edn de historias y recuerdos. Este coloso ubicado en la Ciudad de M\u00e9xico fue sede de momentos imborrables en la historia del f\u00fatbol.<\/p>\n<p>All\u00ed se consagr\u00f3 Pel\u00e9. Sobre su c\u00e9sped, italianos y alemanes protagonizaron el llamado \u201cpartido del siglo\u201d, un 4-3 en el Mundial de 1970 que endulz\u00f3 los ojos de todos los amantes de este deporte. Sus tribunas todav\u00eda abrigan la escapada de Maradona entre piernas inglesas, y all\u00ed a\u00fan se escucha el eco de \u201cla mano de Dios\u201d.<\/p>\n<p>Sin embargo, hoy, a casi 60 a\u00f1os de su inauguraci\u00f3n, tambi\u00e9n alberga una pol\u00e9mica gigante.<\/p>\n<p>La Copa del Mundo del pr\u00f3ximo a\u00f1o marcar\u00e1 un hecho in\u00e9dito: el Azteca se convertir\u00e1 en el \u00fanico estadio en recibir tres veces el Mundial de la FIFA. Pero lo que para muchos result\u00f3 un motivo de orgullo y alegr\u00eda, para otros fue el inicio de meses de incertidumbre y disputa.<\/p>\n<p>\u201cNos enteramos de que los propietarios del estadio hab\u00edan firmado un convenio y hab\u00edan entregado todo el estadio\u201d, relata Javier Coello Trejo, representante legal de la propietaria de un palco en el Estadio Banorte, como se lo conoce ahora por motivos de patrocinio. \u201cEsto dejaba a los due\u00f1os de los palcos en el aire\u201d, agrega sobre el inicio de las disputas, all\u00e1 por 2024.<\/p>\n<p>Los palcos y plateas en cuesti\u00f3n se pusieron a la venta al p\u00fablico tras la construcci\u00f3n del estadio en 1964, con el objetivo de recaudar el dinero que hac\u00eda falta para completar las obras. Se estima que en ese momento se pagaron US$ 9.000 por cada uno. Hoy, se ofrecen hasta por US$ 1 mill\u00f3n, seg\u00fan publicaciones de <a href=\"https:\/\/inmueble.mercadolibre.com.mx\/MLM-3653590832-palco-en-estadio-azteca-_JM?has_official_store=false&#038;highlight=false&#038;headerTopBrand=false#polycard_client=search-nordic&#038;search_layout=grid&#038;position=5&#038;type=item&#038;tracking_id=5b8f3c0b-3d86-41e5-b10b-53c774e26105)\">Mercado Libre<\/a>.<\/p>\n<p>\u201cA nosotros como palcohabitantes no nos dec\u00edan qu\u00e9 era lo que iba a pasar\u201d, dijo a CNN Mary Claudia Gonz\u00e1lez Cano, propietaria de un palco, resaltando que la primera dificultad que afront\u00f3 fue la falta de claridad sobre un espacio que su padre compr\u00f3, obteniendo, como varios otros, acceso ilimitado por 99 a\u00f1os: \u201cSer palcohabitante te permite entrar a todos los eventos dentro del Estadio Azteca, incluyendo eventos deportivos como el f\u00fatbol, la NFL, conciertos, lo que sea\u201d.<\/p>\n<p>Esta situaci\u00f3n no es universal. En Argentina, por ejemplo, los palcos no se obtienen para cualquier evento, pero s\u00ed es el caso particular del Azteca.<\/p>\n<p>Molestos por la situaci\u00f3n, los due\u00f1os de palcos se organizaron y presentaron una denuncia ante la Fiscal\u00eda de la Ciudad de M\u00e9xico, alegando que los administradores del estadio no los consultaron antes de firmar el convenio con la FIFA para el uso de todas las instalaciones del Azteca durante la pr\u00f3xima Copa del Mundo.<\/p>\n<p>La presentaci\u00f3n judicial tuvo, al menos al principio, un final feliz. Los administradores del estadio anunciaron un acuerdo con la FIFA, asegurando que se respetar\u00eda el derecho de uso de los due\u00f1os durante los cinco partidos que se espera albergue el Azteca en la gran cita de 2026.<\/p>\n<p>\u201cEl estadio se comprometi\u00f3 a pagarle a la FIFA el equivalente a los lugares de palcos y plateas\u201d, dice a CNN Roberto Ruano, due\u00f1o de uno de esos palcos y miembro de la Asociaci\u00f3n Mexicana de Titulares de Palcos y Plateas, una entidad que nuclea a 134 propietarios.<\/p>\n<p>\u201cNo hubo problemas en 1970. Para el Mundial de 1986 nos quer\u00edan fuera. Nos reunimos con funcionarios de la FIFA y nos permitieron usar nuestro lugar sin pago extra, as\u00ed que hay un precedente para ello\u201d, manifest\u00f3 Ruano a <a href=\"https:\/\/apnews.com\/article\/azteca-stadium-world-cup-box-fifa-9175d2a22234233b4e48ca6c4058d216\">Associated Press<\/a> en mayo.<\/p>\n<p>Tras el acuerdo, cuando parec\u00eda que hab\u00eda final feliz para esta historia, surgi\u00f3 otro foco de disputa. Los administradores habilitaron un preregistro obligatorio para todos los due\u00f1os de los palcos, con el objetivo, dijeron, de verificar que los t\u00edtulos estuvieran en regla.<\/p>\n<p>Sin embargo, en las \u00faltimas semanas los due\u00f1os han denunciado que all\u00ed se los obligaba a firmar nuevas reglas de uso, centrando la nueva pol\u00e9mica en la venta de paquetes de alimentos, algo nuevo para los palcohabitantes, acostumbrados a poder llevar la comida que quieran al espacio que les pertenece.<\/p>\n<p>La gerencia del Banorte dice que ahora no se autorizar\u00e1 la introducci\u00f3n de alimentos y bebidas, llevando a los due\u00f1os a tener que comprar paquetes que van desde los US$ 6.000 hasta los US$ 15.000. Una imposici\u00f3n que los propietarios rechazan vehementemente. \u201cEs una trampa, porque un apoderado dice \u2018o firmas o no tienes derecho al palco\u2019\u201d, seg\u00fan Trejo.<\/p>\n<p>\u201cEstamos espantados\u201d, agrega Gonz\u00e1lez Cano. \u201cEn un principio decidimos ceder a esto (comida y estacionamiento) durante el Mundial \u00fanicamente, pero, recientemente, informaron que los precios son desproporcionados\u201d, afirm\u00f3 Ruano. La gerencia dice que la compra de estos paquetes no es obligatoria, pero la Asociaci\u00f3n Mexicana de Titulares de Palcos y Plateas sigue analizando qu\u00e9 medidas tomar\u00e1.<\/p>\n<p>CNN ha buscado una respuesta de los administradores del Estadio Banorte a las acusaciones, pero hasta el momento no se ha recibido respuesta. La FIFA, por su parte, termina siendo un tercer actor involuntario, ya que negoci\u00f3 directamente con la gerencia del estadio la disponibilidad del lugar para el Mundial.<\/p>\n<p>El enojo no ha sido hegem\u00f3nico entre los due\u00f1os de palcos. Seg\u00fan declaraciones que recogi\u00f3 <a href=\"https:\/\/apnews.com\/article\/azteca-stadium-world-cup-box-fifa-9175d2a22234233b4e48ca6c4058d216\">Associated Press<\/a> hace meses, Ruano reconoci\u00f3 que algunos propietarios fuera de su asociaci\u00f3n \u201cacordaron liberar sus asientos para el torneo a cambio de mejoras de sus palcos y otros beneficios\u201d.<\/p>\n<p>Sin embargo, la pol\u00e9mica se mantiene y, mientras tanto, los due\u00f1os de los palcos que demandaron a la gerencia del Banorte esperan poder ponerle un cierre pronto, cuando faltan unos 270 d\u00edas para el inicio del Mundial. \u201cQue nos dejen seguir disfrutando\u201d, dice Gonz\u00e1lez Cano. \u201cSon muchos a\u00f1os de grandes momentos. Es lo m\u00ednimo que merecemos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Estadio Azteca esconde un sinf\u00edn de historias y recuerdos. Este coloso ubicado en la Ciudad de M\u00e9xico fue sede de momentos imborrables en la historia del f\u00fatbol. All\u00ed se consagr\u00f3 Pel\u00e9. Sobre su c\u00e9sped, italianos y alemanes protagonizaron el llamado \u201cpartido del siglo\u201d, un 4-3 en el Mundial de 1970 que endulz\u00f3 los ojos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467376","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Estadio Azteca esconde un sinf\u00edn de historias y recuerdos. Este coloso ubicado en la Ciudad de M\u00e9xico fue sede de momentos imborrables en la historia del f\u00fatbol. All\u00ed se consagr\u00f3 Pel\u00e9. Sobre su c\u00e9sped, italianos y alemanes protagonizaron el llamado \u201cpartido del siglo\u201d, un 4-3 en el Mundial de 1970 que endulz\u00f3 los ojos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T03:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos?\",\"datePublished\":\"2025-10-15T03:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/\"},\"wordCount\":1015,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/\",\"name\":\"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-15T03:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos? - Noticias","og_description":"El Estadio Azteca esconde un sinf\u00edn de historias y recuerdos. Este coloso ubicado en la Ciudad de M\u00e9xico fue sede de momentos imborrables en la historia del f\u00fatbol. All\u00ed se consagr\u00f3 Pel\u00e9. Sobre su c\u00e9sped, italianos y alemanes protagonizaron el llamado \u201cpartido del siglo\u201d, un 4-3 en el Mundial de 1970 que endulz\u00f3 los ojos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-15T03:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/"},"author":{"name":"","@id":""},"headline":"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos?","datePublished":"2025-10-15T03:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/"},"wordCount":1015,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/","name":"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-15T03:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Pol\u00e9mica sin fin en el Estadio Azteca a 270 d\u00edas del Mundial de 2026: \u00bfqu\u00e9 pasar\u00e1 con los due\u00f1os de los palcos?","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/estadio-azteca-banorte-polemica-palcos-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-15T03:03:47Z","datePublished":"2025-10-15T03:03:47Z","dateModified":"2025-10-15T03:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Pol\\u00e9mica sin fin en el Estadio Azteca a 270 d\\u00edas del Mundial de 2026: \\u00bfqu\\u00e9 pasar\\u00e1 con los due\\u00f1os de los palcos?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/14\\\/estadio-azteca-banorte-polemica-palcos-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/14\\\/estadio-azteca-banorte-polemica-palcos-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-15T03:03:47Z\",\"datePublished\":\"2025-10-15T03:03:47Z\",\"dateModified\":\"2025-10-15T03:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472651,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/03\/28\/aficionado-muere-caida-reinaguracion-estadio-azteca-orix\/","url_meta":{"origin":1467376,"position":0},"title":"Un aficionado muere tras una ca\u00edda durante la reinauguraci\u00f3n del Estadio Azteca de la Ciudad de M\u00e9xico de cara al Mundial","author":"","date":"marzo 28, 2026","format":false,"excerpt":"Un aficionado muri\u00f3 este s\u00e1bado tras caer de la zona de palcos del Estadio Azteca de la Ciudad de M\u00e9xico, que este d\u00eda fue reinaugurado de cara al Mundial de F\u00fatbol del que M\u00e9xico ser\u00e1 anfitri\u00f3n junto con Estados Unidos y Canad\u00e1, inform\u00f3 la Secretar\u00eda de Seguridad Ciudadana de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472399,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/03\/20\/cristiano-ronaldo-estadio-azteca-no-entra-convocatoria-portugal-orix\/","url_meta":{"origin":1467376,"position":1},"title":"Cristiano Ronaldo se pierde la reinauguraci\u00f3n del Estadio Azteca: no entra en la convocatoria de Portugal","author":"","date":"marzo 20, 2026","format":false,"excerpt":"Se viene una nueva fecha FIFA de partidos amistosos internacionales y, como no, el repechaje mundialista que entrega los \u00faltimos seis cupos a la cita de Canad\u00e1, Estados Unidos y M\u00e9xico. Pero tambi\u00e9n tendremos la reinauguraci\u00f3n del Estadio Azteca, que extra\u00f1ar\u00e1 a quien aparec\u00eda como invitado de lujo.Se trata de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471633,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/02\/25\/fifa-confianza-seguridad-mexico-mundial-futbol-efe\/","url_meta":{"origin":1467376,"position":2},"title":"La FIFA afirma que tiene confianza total en M\u00e9xico para el Mundial, pese a violencia","author":"","date":"febrero 25, 2026","format":false,"excerpt":"El presidente de la FIFA, Gianni Infantino, afirm\u00f3 este martes en la ciudad colombiana de Barranquilla que tiene \u201cconfianza total en M\u00e9xico\u201d para la realizaci\u00f3n del Mundial de este a\u00f1o, que tiene partidos programados en Ciudad de M\u00e9xico, Guadalajara y Monterrey, pese a la violencia desatada en el pa\u00eds.\u201cEstamos analizando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473565,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/04\/28\/mundial-futbol-mexico-quejas-precios-entradas-orix\/","url_meta":{"origin":1467376,"position":3},"title":"&#171;Este Mundial no es de M\u00e9xico&#187;: los precios de las entradas generan malestar entre los aficionados mexicanos","author":"","date":"abril 28, 2026","format":false,"excerpt":"M\u00e9xico har\u00e1 historia como el primer pa\u00eds en albergar tres Copas del Mundo este verano, pero la euforia por este r\u00e9cord no se refleja en los aficionados mexicanos.Francisco Javier Ferreira, de 70 a\u00f1os, recuerda las dos Copas del Mundo a las que asisti\u00f3 en su pa\u00eds natal, M\u00e9xico 1970 y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468553,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/11\/20\/inter-miami-messi-inauguracion-freedom-park-orix\/","url_meta":{"origin":1467376,"position":4},"title":"Lionel Messi y el Inter Miami ya tienen fecha y hora para inaugurar su nuevo estadio","author":"","date":"noviembre 20, 2025","format":false,"excerpt":"Debido al Mundial de f\u00fatbol de 2026, la Major League Soccer (MLS, por sus siglas en ingl\u00e9s) ha decidido ajustar su calendario, que en el verano del hemisferio norte normalmente sigue en curso con su temporada, a diferencia del resto de las ligas de f\u00fatbol alrededor del mundo.El anuncio de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469096,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/12\/08\/mundial-2026-camino-seleccion-mexico-orix\/","url_meta":{"origin":1467376,"position":5},"title":"Mundial 2026: el camino de M\u00e9xico, con un grupo accesible pero Inglaterra en el horizonte","author":"","date":"diciembre 8, 2025","format":false,"excerpt":"Respira M\u00e9xico. Los millones de ciudadanos que sintonizaron el sorteo del Mundial 2026 estar\u00e1n aliviados, sabiendo que ning\u00fan gigante ni firme candidato duerme en el mismo Grupo A que el Tri.Ser organizador ayud\u00f3, claro. La selecci\u00f3n azteca ocupa el 15\u00b0 lugar del ranking FIFA, por lo que, t\u00e9cnicamente, habr\u00eda sido\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467376"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467376\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}