{"id":1467381,"date":"2025-10-15T03:03:40","date_gmt":"2025-10-15T10:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/"},"modified":"2025-10-15T03:03:40","modified_gmt":"2025-10-15T10:03:40","slug":"fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/","title":{"rendered":"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025"},"content":{"rendered":"<p>Una imagen de una rara hiena de pie frente a un edificio abandonado en una antigua ciudad minera de diamantes en Namibia gan\u00f3 el premio Wildlife Photographer of the Year 2025.<\/p>\n<p>Fotografiada por el sudafricano Wim van den Heever en la ciudad de Kolmanskop, \u201cGhost Town Visitor\u201d es el resultado de 10 a\u00f1os de trabajo utilizando tecnolog\u00eda de c\u00e1maras trampa, seg\u00fan un comunicado de los organizadores difundido este martes.<\/p>\n<p>La fotograf\u00eda, que fue una de las 60.636 participaciones, muestra a una hiena parda, miembro de la especie de hiena m\u00e1s rara del mundo.<\/p>\n<p>Nocturnas y en gran parte solitarias, las hienas pardas rara vez se ven, por lo que Van den Heever empez\u00f3 a utilizar una c\u00e1mara trampa despu\u00e9s de notar sus huellas en la zona.<\/p>\n<p>Kathy Moran, presidenta del jurado de Wildlife Photographer of the Year, dijo que la imagen mostraba c\u00f3mo la fauna hab\u00eda repoblado una ciudad abandonada por los humanos.<\/p>\n<p>\u201cQu\u00e9 apropiado que esta fotograf\u00eda se haya hecho en una ciudad fantasma\u201d, dijo en el comunicado.<\/p>\n<p>\u201cSe siente un escalofr\u00edo solo con mirar esta imagen y sabes que est\u00e1s en el reino de esta hiena\u201d.<\/p>\n<p>El miembro del jurado Akanksha Sood Singh a\u00f1adi\u00f3 que la \u201cimagen es una escalofriante yuxtaposici\u00f3n de la naturaleza recuperando la civilizaci\u00f3n humana\u201d.<\/p>\n<p>\u201cLa imagen es inquietante, pero hipnotizante porque la hiena solitaria ocupa el centro del escenario como s\u00edmbolo de resiliencia en medio de la decadencia\u201d, dijo.<\/p>\n<p>El fot\u00f3grafo italiano Andrea Dominizi gan\u00f3 el premio Young Wildlife Photographer of the Year 2025, para concursantes de 17 a\u00f1os o menos, con su imagen de un escarabajo de cuernos largos que parece estar observando maquinaria de tala abandonada.<\/p>\n<p>Titulado \u201cAfter the Destruction\u201d, Dominizi tom\u00f3 la fotograf\u00eda en las monta\u00f1as Lepini, en el centro de Italia, que alguna vez fueron fuente de antiguos hayedos.<\/p>\n<p>\u201cUna fotograf\u00eda impactante, pero desgarradora, es una que anima al espectador a contemplar la naturaleza de esta complicada relaci\u00f3n\u201d, dijo el miembro del jurado Andy Parkinson sobre la imagen de Dominizi.<\/p>\n<p>Los organizadores del premio tambi\u00e9n destacaron el Impact Award, que fue otorgado al fot\u00f3grafo brasile\u00f1o Fernando Faciole por su imagen de una cr\u00eda hu\u00e9rfana de oso hormiguero gigante siguiendo a un cuidador humano.<\/p>\n<p>Adem\u00e1s, el jurado seleccion\u00f3 a 19 ganadores de categor\u00eda. Estas im\u00e1genes se exhibir\u00e1n en una muestra que se inaugurar\u00e1 en el Museo de Historia Natural de Londres el viernes.<\/p>\n<p>\u201cAhora, en su sexag\u00e9simo primer a\u00f1o, estamos encantados de continuar con el Wildlife Photographer of the Year como una poderosa plataforma para la narraci\u00f3n visual, mostrando la diversidad, belleza y complejidad del mundo natural y la relaci\u00f3n de la humanidad con \u00e9l\u201d, dijo el director del museo, Doug Gurr, en el comunicado.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una imagen de una rara hiena de pie frente a un edificio abandonado en una antigua ciudad minera de diamantes en Namibia gan\u00f3 el premio Wildlife Photographer of the Year 2025. Fotografiada por el sudafricano Wim van den Heever en la ciudad de Kolmanskop, \u201cGhost Town Visitor\u201d es el resultado de 10 a\u00f1os de trabajo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467381","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025 - Noticias\" \/>\n<meta property=\"og:description\" content=\"Una imagen de una rara hiena de pie frente a un edificio abandonado en una antigua ciudad minera de diamantes en Namibia gan\u00f3 el premio Wildlife Photographer of the Year 2025. Fotografiada por el sudafricano Wim van den Heever en la ciudad de Kolmanskop, \u201cGhost Town Visitor\u201d es el resultado de 10 a\u00f1os de trabajo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T10:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025\",\"datePublished\":\"2025-10-15T10:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/\"},\"wordCount\":507,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/\",\"name\":\"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-15T10:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/","og_locale":"es_ES","og_type":"article","og_title":"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025 - Noticias","og_description":"Una imagen de una rara hiena de pie frente a un edificio abandonado en una antigua ciudad minera de diamantes en Namibia gan\u00f3 el premio Wildlife Photographer of the Year 2025. Fotografiada por el sudafricano Wim van den Heever en la ciudad de Kolmanskop, \u201cGhost Town Visitor\u201d es el resultado de 10 a\u00f1os de trabajo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/","og_site_name":"Noticias","article_published_time":"2025-10-15T10:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/"},"author":{"name":"","@id":""},"headline":"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025","datePublished":"2025-10-15T10:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/"},"wordCount":507,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/","url":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/","name":"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-15T10:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una fotograf\u00eda de una hiena con apariencia fantasmal gan\u00f3 el premio Wildlife Photographer of the Year 2025","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-15T10:03:40Z","datePublished":"2025-10-15T10:03:40Z","dateModified":"2025-10-15T10:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una fotograf\\u00eda de una hiena con apariencia fantasmal gan\\u00f3 el premio Wildlife Photographer of the Year 2025\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/15\\\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/15\\\/fotografia-hiena-wildlife-photographer-of-the-year-2025-cte-llamado-tierra\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-15T10:03:40Z\",\"datePublished\":\"2025-10-15T10:03:40Z\",\"dateModified\":\"2025-10-15T10:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452294,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/08\/30\/fotografias-concurso-wildlife-photographer-of-the-year-llamado-tierra-cte\/","url_meta":{"origin":1467381,"position":0},"title":"Las impresionantes im\u00e1genes que compiten en el concurso Wildlife Photographer of the Year","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) -- Focas adormiladas, un armi\u00f1o \"bailar\u00edn\" y el encuentro fatal de un caim\u00e1n con un jaguar son algunas de las im\u00e1genes m\u00e1s elogiadas en el concurso Wildlife Photographer of the Year de este a\u00f1o.Ahora puedes seguirnos en\u00a0WhatsApp ChannelLa 60 edici\u00f3n del concurso recibi\u00f3 la cifra r\u00e9cord de 59.228 obras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456489,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/12\/11\/ardilla-premio-fotografia-vida-salvaje-trax\/","url_meta":{"origin":1467381,"position":1},"title":"Una ardilla atrapada gana el premio de fotograf\u00eda de vida salvaje y comedia de 2024","author":"","date":"diciembre 11, 2024","format":false,"excerpt":"Una imagen de una ardilla atrapada en un \u00e1rbol fue nombrada ganadora general de los Nikon Comedy Wildlife Photography Awards de este a\u00f1o, con una rana en una burbuja y un besugo persiguiendo a un \u00e1guila calva entre los ganadores de la categor\u00eda.\u201cStuck Squirrel\u201d de Milko Marchetti fue elegida ganadora\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452622,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/09\/12\/mejores-imagenes-concurso-fotografo-astronomico-trax\/","url_meta":{"origin":1467381,"position":2},"title":"Las mejores im\u00e1genes del concurso Fot\u00f3grafo Astron\u00f3mico del A\u00f1o","author":"","date":"septiembre 12, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Las fases de Venus, la Aurora Austral y la Estaci\u00f3n Espacial Internacional en tr\u00e1nsito alrededor del Sol aparecen como ganadores de categor\u00edas en el concurso Fot\u00f3grafo Astron\u00f3mico del A\u00f1o.Ryan Imperio fue nombrado total ganador por su fotograf\u00eda que captura la progresi\u00f3n de las cuentas de Baily durante el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470923,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/02\/05\/ganadores-close-up-photographer-trax-cte-llamado-tierra\/","url_meta":{"origin":1467381,"position":3},"title":"Coral psicod\u00e9lico, ef\u00edmeras desconcertadas y una ara\u00f1a hambrienta, entre los ganadores de Close-up Photographer of the Year","author":"","date":"febrero 5, 2026","format":false,"excerpt":"Una imagen psicod\u00e9lica de un coral, un enjambre de ef\u00edmeras y una ara\u00f1a muy hambrienta figuran entre las fotograf\u00edas ganadoras del premio Close-up Photographer of the Year.El premio, en su s\u00e9ptima edici\u00f3n, recibi\u00f3 m\u00e1s de 12.000 im\u00e1genes procedentes de 63 pa\u00edses, evaluadas por fot\u00f3grafos, naturalistas y editores, de acuerdo con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469879,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/01\/07\/fosiles-desenterrados-marruecos-evolucion-humana-trax\/","url_meta":{"origin":1467381,"position":4},"title":"F\u00f3siles desenterrados en Marruecos son los primeros de un per\u00edodo poco comprendido de la evoluci\u00f3n humana","author":"","date":"enero 7, 2026","format":false,"excerpt":"F\u00f3siles desenterrados en Marruecos de un per\u00edodo poco comprendido de la evoluci\u00f3n humana podr\u00edan ayudar a los cient\u00edficos a resolver un misterio de larga data: \u00bfqui\u00e9nes vinieron antes que nosotros?Tres mand\u00edbulas, incluida una de un ni\u00f1o, dientes, v\u00e9rtebras y un f\u00e9mur fueron desenterrados de una cueva conocida como Grotte \u00e0\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444176,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/01\/20\/estas-impactantes-fotografias-en-primer-plano-revelan-las-maravillas-ocultas-de-la-naturaleza\/","url_meta":{"origin":1467381,"position":5},"title":"Estas impactantes fotograf\u00edas en primer plano revelan las maravillas ocultas de la naturaleza","author":"","date":"enero 20, 2024","format":false,"excerpt":"Nota del editor:\u00a0Llamado a la Tierra es una serie editorial de CNN comprometida con reportar los desaf\u00edos ambientales que enfrenta nuestro planeta, adem\u00e1s de mostrar las soluciones a esos retos. La iniciativa Perpetual Planet de Rolex se ha asociado con CNN para crear conciencia y educaci\u00f3n sobre los asuntos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467381"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467381\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}