{"id":1467398,"date":"2025-10-15T10:03:42","date_gmt":"2025-10-15T17:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/"},"modified":"2025-10-15T10:03:42","modified_gmt":"2025-10-15T17:03:42","slug":"ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/","title":{"rendered":"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos"},"content":{"rendered":"<p>Al menos un ataque militar estadounidense en el Caribe en los \u00faltimos dos meses tuvo como objetivo a ciudadanos colombianos en un barco que hab\u00eda partido desde Colombia, seg\u00fan dos personas informadas por el Pent\u00e1gono sobre los ataques.<\/p>\n<p>El Ej\u00e9rcito de EE.UU. ha llevado a cabo <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/14\/venezuela\/ataques-eeuu-supuestos-barcos-narcotraficantes-caribe-orix\">al menos cinco ataques hasta la fecha<\/a> contra cinco barcos diferentes en el Caribe. El tercer ataque reconocido p\u00fablicamente, el 19 de septiembre, tuvo como objetivo un barco que sal\u00eda de Colombia, dijeron las fuentes.<\/p>\n<p>Se sospechaba que el barco transportaba colombianos afiliados a organizaciones terroristas colombianas, dijeron las fuentes, pero el Pent\u00e1gono no pudo determinar la identidad individual de cada persona en los barcos antes de atacarlos.<\/p>\n<p>La selecci\u00f3n deliberada de colombianos, que no se hab\u00eda reportado previamente, sugiere que la campa\u00f1a militar de EE.UU. contra presuntos grupos de narcotr\u00e1fico en el Caribe es m\u00e1s amplia de lo que se cre\u00eda. El Gobierno de Trump ha producido un dictamen legal clasificado que justifica ataques letales contra una lista secreta y amplia de c\u00e1rteles y presuntos narcotraficantes, inform\u00f3 CNN.<\/p>\n<p>El dictamen es significativo, dijeron previamente expertos legales a CNN, porque parece justificar que se otorgue al presidente el poder de designar a narcotraficantes como combatientes enemigos y permitir que sean asesinados sumariamente sin revisi\u00f3n legal. Hist\u00f3ricamente, quienes estaban involucrados en el narcotr\u00e1fico eran considerados criminales con derechos de debido proceso, con la Guardia Costera interceptando embarcaciones de narcotr\u00e1fico y arrestando a los contrabandistas.<\/p>\n<p>CNN se ha comunicado con el Ministerio de Relaciones Exteriores de Colombia para obtener comentarios.<\/p>\n<p>Refiri\u00e9ndose a la embarcaci\u00f3n atacada el 19 de septiembre, el presidente colombiano Gustavo Petro dijo en ese momento en X: \u201cSi el barco fue hundido en Rep\u00fablica Dominicana, entonces es posible que fueran colombianos. Esto significa que funcionarios de EE.UU. y la Rep\u00fablica Dominicana ser\u00edan culpables del asesinato de ciudadanos colombianos\u201d.<\/p>\n<p>Al ser consultada sobre el ataque, la portavoz de la Casa Blanca Anna Kelly dijo a CNN que cada ataque realizado por el Ej\u00e9rcito estadounidense ha \u201csido contra narcoterroristas designados que llevan veneno mortal a nuestras costas\u201d.<\/p>\n<p>\u201cDurante la campa\u00f1a presidencial, el presidente Trump prometi\u00f3 enfrentarse a los c\u00e1rteles, y ha tomado acciones sin precedentes para detener el flagelo del narcoterrorismo que ha resultado en la muerte innecesaria de estadounidenses inocentes\u201d, dijo Kelly. A\u00f1adi\u00f3 que \u201cel presidente continuar\u00e1 utilizando todos los elementos del poder estadounidense para evitar que las drogas inunden nuestro pa\u00eds y llevar a los responsables ante la justicia\u201d.<\/p>\n<p>Petro tambi\u00e9n dijo en X a principios de este mes que \u201chay indicios\u201d de que el cuarto ataque militar estadounidense tambi\u00e9n tuvo como objetivo a colombianos. \u201cLa agresi\u00f3n es contra toda Am\u00e9rica Latina y el Caribe\u201d, dijo. EE.UU. hab\u00eda anunciado d\u00edas antes que hab\u00eda golpeado un cuarto barco en el Caribe.<\/p>\n<p>La Casa Blanca <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/09\/colombia\/eeuu-rechaza-version-petro-ataque-lancha-trax\">neg\u00f3 las afirmaciones de Petro en un comunicado<\/a>, diciendo que \u201cEstados Unidos espera que el presidente Petro se retracte p\u00fablicamente de su declaraci\u00f3n infundada y reprobable\u201d.<\/p>\n<p>Pero fuentes dijeron a CNN que, si bien el cuarto ataque militar estadounidense puede no haber tenido como objetivo a colombianos, al menos el ataque anterior del 19 de septiembre s\u00ed lo hizo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos un ataque militar estadounidense en el Caribe en los \u00faltimos dos meses tuvo como objetivo a ciudadanos colombianos en un barco que hab\u00eda partido desde Colombia, seg\u00fan dos personas informadas por el Pent\u00e1gono sobre los ataques. El Ej\u00e9rcito de EE.UU. ha llevado a cabo al menos cinco ataques hasta la fecha contra cinco [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467398","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos - Noticias\" \/>\n<meta property=\"og:description\" content=\"Al menos un ataque militar estadounidense en el Caribe en los \u00faltimos dos meses tuvo como objetivo a ciudadanos colombianos en un barco que hab\u00eda partido desde Colombia, seg\u00fan dos personas informadas por el Pent\u00e1gono sobre los ataques. El Ej\u00e9rcito de EE.UU. ha llevado a cabo al menos cinco ataques hasta la fecha contra cinco [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T17:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos\",\"datePublished\":\"2025-10-15T17:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/\"},\"wordCount\":594,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/\",\"name\":\"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-15T17:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos - Noticias","og_description":"Al menos un ataque militar estadounidense en el Caribe en los \u00faltimos dos meses tuvo como objetivo a ciudadanos colombianos en un barco que hab\u00eda partido desde Colombia, seg\u00fan dos personas informadas por el Pent\u00e1gono sobre los ataques. El Ej\u00e9rcito de EE.UU. ha llevado a cabo al menos cinco ataques hasta la fecha contra cinco [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-15T17:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/"},"author":{"name":"","@id":""},"headline":"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos","datePublished":"2025-10-15T17:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/"},"wordCount":594,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/","name":"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-15T17:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-15T17:03:42Z","datePublished":"2025-10-15T17:03:42Z","dateModified":"2025-10-15T17:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos un ataque militar de EE.UU. contra un presunto barco narcotraficante en el Caribe tuvo como objetivo a colombianos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/15\\\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/15\\\/ataque-militar-presunto-barco-narcotraficante-caribe-colombianos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-15T17:03:42Z\",\"datePublished\":\"2025-10-15T17:03:42Z\",\"dateModified\":\"2025-10-15T17:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467363,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/14\/ataques-eeuu-supuestos-barcos-narcotraficantes-caribe-orix\/","url_meta":{"origin":1467398,"position":0},"title":"Qu\u00e9 se sabe de los ataques de EE.UU. contra al menos cinco supuestos barcos narcotraficantes en el Caribe","author":"","date":"octubre 14, 2025","format":false,"excerpt":"El Gobierno de Estados Unidos anunci\u00f3 este martes un nuevo ataque contra una embarcaci\u00f3n en aguas internacionales del Caribe que, seg\u00fan Washington, transportaba drogas, en lo que constituye al menos el quinto episodio confirmado por las autoridades con un saldo reportado de 27 muertos, sin que hasta ahora presenten pruebas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467214,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/08\/petro-ultimo-barco-bombardeado-podria-ser-colombiano-trax\/","url_meta":{"origin":1467398,"position":1},"title":"Petro dice que el \u00faltimo bote destruido por Estados Unidos en el Caribe podr\u00eda haber sido colombiano","author":"","date":"octubre 8, 2025","format":false,"excerpt":"El presidente de Colombia, Gustavo Petro, dijo este mi\u00e9rcoles que el \u00faltimo bote destruido por Estados Unidos en el Caribe la semana pasada podr\u00eda haber sido colombiano.\u201cIndicios muestran que la \u00faltima lancha bombardeada era colombiana con ciudadanos colombianos en su interior, espero que aparezcan sus familias y denuncien\u201d, escribi\u00f3 Petro\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467713,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/24\/ataques-botes-caribe-pacifico-cronologia-orix\/","url_meta":{"origin":1467398,"position":2},"title":"10 botes destruidos, 43 muertos y una crisis que crece en el Caribe y el Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"octubre 24, 2025","format":false,"excerpt":"El Gobierno de Estados Unidos anunci\u00f3 este viernes un nuevo ataque contra una embarcaci\u00f3n en aguas internacionales del Caribe, el d\u00e9cimo desde el 2 de septiembre, d\u00eda en que comenzaron las ofensivas. EE.UU. argument\u00f3 que estos barcos transportaban narc\u00f3ticos, sin proporcionar pruebas que respalden esas afirmaciones.Hasta el momento son 43\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467811,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/28\/cronologia-ataques-caribe-pacifico-muertos-orix\/","url_meta":{"origin":1467398,"position":3},"title":"14 botes destruidos, 57 muertos y una crisis que crece en el Caribe y el Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"octubre 28, 2025","format":false,"excerpt":"El Gobierno de Estados Unidos anunci\u00f3 este martes nuevos ataques contra embarcaciones en aguas internacionales del Pac\u00edfico, la und\u00e9cima ofensiva desde el 2 de septiembre. EE.UU. argument\u00f3 que estos barcos transportaban narc\u00f3ticos, sin proporcionar pruebas que respalden esas afirmaciones.Hasta el momento son 57 las personas que murieron en estos ataques\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467230,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/09\/eeuu-rechaza-version-petro-ataque-lancha-trax\/","url_meta":{"origin":1467398,"position":4},"title":"La Casa Blanca rechaza la versi\u00f3n de Petro de que la lancha atacada frente a la costa de Venezuela llevaba colombianos","author":"","date":"octubre 9, 2025","format":false,"excerpt":"La Casa Blanca desestim\u00f3 el jueves la afirmaci\u00f3n del presidente de Colombia, Gustavo Petro, quien se\u00f1al\u00f3 que el ataque militar m\u00e1s reciente de Estados Unidos en el Caribe pudo haber tenido como objetivo una embarcaci\u00f3n colombiana, y dijo a CNN que la acusaci\u00f3n era \u201cinfundada y reprochable\u201d.\u201cEstados Unidos espera que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468049,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/11\/05\/ataques-caribe-pacifico-cronologia-orix\/","url_meta":{"origin":1467398,"position":5},"title":"17 botes destruidos, 67 muertos y una crisis que crece en el Caribe y el Pac\u00edfico: cronolog\u00eda de los ataques de EE.UU.","author":"","date":"noviembre 5, 2025","format":false,"excerpt":"El Gobierno de Estados Unidos anunci\u00f3 este martes un nuevo ataque contra una embarcaci\u00f3n en aguas internacionales del Pac\u00edfico, la decimotercera ofensiva desde el 2 de septiembre. Washington argument\u00f3 que estos barcos transportaban narc\u00f3ticos, sin proporcionar pruebas que respalden esas afirmaciones.Hasta el momento son 67 las personas que murieron en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467398"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467398\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}