{"id":1467400,"date":"2025-10-15T12:03:43","date_gmt":"2025-10-15T19:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/"},"modified":"2025-10-15T12:03:43","modified_gmt":"2025-10-15T19:03:43","slug":"migrantes-construccion-trump-desplomo-recupere-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/","title":{"rendered":"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil"},"content":{"rendered":"<p>Tal vez muchos conozcan el nombre de <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/22\/eeuu\/video\/caso-abrego-garcia-resumen-el-salvador-orix\">Kilmar \u00c1brego Garc\u00eda<\/a>, un caso ic\u00f3nico de la dura pol\u00edtica migratoria en el segundo mandato de Donald Trump como presidente de Estados Unidos. Pero hay un da\u00f1o colateral poco comentado sobre todo el proceso que ha atravesado este salvadore\u00f1o desde que fue deportado por \u201c<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/22\/eeuu\/historia-kilmar-abrego-deportacion-liberacion-trax\">error<\/a>\u201d: el hueco que deja en un sector laboral golpeado por varios factores, entre ellos las redadas de inmigraci\u00f3n.<\/p>\n<p>\u00c1brego Garc\u00eda fue inicialmente detenido luego de completar un turno en una obra de construcci\u00f3n.<\/p>\n<p>Desde entonces, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/11\/eeuu\/abrego-garcia-tres-paises-africa-no-aceptan-trax\">su caso se suma al de tantos migrantes<\/a> que van dejando un vac\u00edo laboral en la construcci\u00f3n, una industria que carece de mano de obra todos los meses desde hace a\u00f1os en EE.UU. Se estima que este sector lleva una d\u00e9cada con escasez de trabajadores y que mensualmente hay un faltante de cercano a los 300.000 empleados, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/04\/27\/eeuu\/aranceles-deportaciones-precios-construccion-vivienda-orix#:~:text=El%20sector%20reclama%20trabajadores\">seg\u00fan<\/a> Robert Dietz, economista jefe de la Asociaci\u00f3n Nacional de Constructores de Viviendas (NAHB, por sus siglas en ingl\u00e9s).<\/p>\n<p>Como \u00c1brego, tambi\u00e9n est\u00e1 el vac\u00edo laboral que dej\u00f3 el migrante mexicano Leonel Ch\u00e1vez, quien fue detenido a mediados de agosto junto a su hermano Ricardo Ch\u00e1vez en Norwalk, Connecticut, y luego <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/26\/eeuu\/deportan-mexico-leonel-chavez-connecticut-orix\">deportado a Tamaulipas<\/a>, en M\u00e9xico.<\/p>\n<p>Su <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/08\/27\/eeuu\/pesadilla-inmigrante-connecticut-mexico-entrevista-orix\">detenci\u00f3n<\/a>, en la que seg\u00fan el Gobierno mexicano hubo exceso \u201cen el uso de la fuerza\u201d, se realiz\u00f3 mientras los dos hermanos iban rumbo a su trabajo. Leonel Ch\u00e1vez, que viv\u00eda en Estados Unidos hace d\u00e9cadas, llevaba adelante un peque\u00f1o negocio de construcci\u00f3n desde hace unos cinco a\u00f1os. Su hija mayor, Leonela, se har\u00e1 cargo del negocio ahora, pero Leonel ya no est\u00e1 ah\u00ed para dirigirlo.<\/p>\n<p>Boris Bolagay es otro caso relacionado a la industria de la construcci\u00f3n. Es migrante ecuatoriano y vivi\u00f3 los \u00faltimos cuatro a\u00f1os en EE.UU. Pese a que estaba en proceso para regularizar su estatus migratorio, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/10\/11\/eeuu\/sueno-pesadilla-americana-historias-migrantes-vuelven-tiempos-trump-orix\">decidi\u00f3 regresar<\/a> de manera voluntaria a su pa\u00eds de origen recientemente.<\/p>\n<p>Bolagay regres\u00f3 a Ecuador junto a su familia. Dice que tomar esa decisi\u00f3n fue m\u00e1s f\u00e1cil al considerar la situaci\u00f3n migratoria en tiempos de Trump, as\u00ed como la precarizaci\u00f3n del trabajo para los inmigrantes.<\/p>\n<p>\u201cCuando tomamos la decisi\u00f3n de regresar tampoco fue algo que lo pens\u00e1ramos mucho, porque creo que la situaci\u00f3n migratoria con el presidente Trump estaba supercomplicada (\u2026) Por ejemplo, t\u00fa ibas por la autopista y ya te encontrabas patrulleros de la Patrulla Fronteriza, hac\u00edan requisas a las camionetas que pasaban porque como inmigrantes nosotros nos tocaba trabajar en lo que hay y lo que m\u00e1s hab\u00eda era construcci\u00f3n, entonces era mala paga\u201d, se\u00f1ala en entrevista.<\/p>\n<p>Trabajadores como Bolagay comenzaron a tener miedo de salir a trabajar en empleos de la construcci\u00f3n, sobre todo cuando una de las estrategias del Gobierno estadounidense para detener inmigrantes indocumentados se ha centrado en acudir a negocios como <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/18\/eeuu\/home-depot-jornaleros-ice-trax\">Home Depot<\/a>.<\/p>\n<p>Los jornaleros llevan mucho tiempo reuni\u00e9ndose afuera de los estacionamientos de tiendas <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/13\/eeuu\/ice-redadas-deportaciones-migrantes-trabajo-trax\">Home Depot o comercios similares<\/a> para buscar trabajo. Home Depot, en particular, es un lugar conveniente para que contratistas y propietarios se acerquen y contraten trabajadores para pintar paredes, poner techos y realizar otros trabajos manuales. A esta fuerza laboral a menudo se les paga en efectivo, y muchos regresan a estos lugares todos los d\u00edas con la esperanza de conseguir m\u00e1s trabajo.<\/p>\n<p>\u201cLas recientes redadas de inmigraci\u00f3n en empresas en todo el pa\u00eds est\u00e1n creando serios desaf\u00edos para las econom\u00edas locales, comunidades e industrias que dependen de la mano de obra inmigrante para operar y prosperar\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/13\/eeuu\/ice-redadas-deportaciones-migrantes-trabajo-trax\">dijo<\/a> Rebecca Shi, directora ejecutiva de la American Business Immigration Coalition, un grupo que representa a empleadores con inmigrantes.<\/p>\n<p>\u201cEn este momento estoy atrasado con mi renta porque tengo miedo de que me detengan en la esquina de Home Depot o de tener un encuentro con ICE\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/18\/eeuu\/home-depot-jornaleros-ice-trax\">dijo<\/a> un jornalero indocumentado que lleva una d\u00e9cada en Estados Unidos.<\/p>\n<p>Este trabajador, quien habl\u00f3 este verano bajo condici\u00f3n de anonimato por temor a la deportaci\u00f3n, ha dejado de buscar empleo fuera de un Home Depot en East Windsor, Nueva Jersey. \u201cEsta es la temporada m\u00e1s importante para que trabajemos, y el miedo nos est\u00e1 impidiendo salir\u201d, agreg\u00f3.<\/p>\n<p>A pesar del miedo, esta poblaci\u00f3n debe salir a trabajar para poder pagar las cuentas, seg\u00fan Antonieta C\u00e1diz, directora ejecutiva de Climate Power en Acci\u00f3n, un proyecto de comunicaciones para la comunidad latina centrado en clima y justicia medioambiental.<\/p>\n<p>\u201cNuestra comunidad est\u00e1 viviendo tiempos muy dif\u00edciles en Estados Unidos y tienen que salir a trabajar porque no hay opci\u00f3n, si no c\u00f3mo mantienen a su familia, c\u00f3mo pagan sus cuentas, c\u00f3mo lidian con los costos. Se ponen en riesgo todos los d\u00edas, todos los d\u00edas salen de su casa con miedo. Esa es la realidad que estamos viviendo en Estados Unidos hoy en d\u00eda, y es aterradora\u201d, <a href=\"https:\/\/www.youtube.com\/watch?v=bcNtv8w5Ums\">declar\u00f3<\/a> C\u00e1diz en una conferencia virtual a inicios de agosto.<\/p>\n<p>La <a href=\"https:\/\/www.cnn.com\/2025\/10\/03\/economy\/no-jobs-report-data-snapshot-september\">construcci\u00f3n<\/a>, que se observa de cerca como un indicador de la actividad econ\u00f3mica, se ha visto afectada por una combinaci\u00f3n de altas tasas de inter\u00e9s, una persistente crisis de asequibilidad de la vivienda, deportaciones de trabajadores e incertidumbre relacionada con aranceles.<\/p>\n<p>La ofensiva migratoria de Trump \u2014que ha apuntado a inmigrantes indocumentados con y sin antecedentes penales\u2014 ha tenido un impacto notorio en la construcci\u00f3n, ya que una parte importante de esta poblaci\u00f3n sostiene a esa industria.<\/p>\n<p>Los inmigrantes indocumentados representan entre el 4 % y el 5 % de la fuerza laboral total de Estados Unidos, pero su participaci\u00f3n se eleva a un rango entre el 15 % y el 20 % en industrias como la producci\u00f3n de cultivos, el procesamiento de alimentos y la construcci\u00f3n, seg\u00fan Goldman Sachs, que advirti\u00f3 en <a href=\"https:\/\/www.goldmansachs.com\/insights\/articles\/how-will-declining-immigration-impact-the-us-economy\">un informe<\/a> en febrero que perder una \u201cparte significativa\u201d de esos trabajadores podr\u00eda resultar en cuellos de botella temporales, escasez y aumento de precios.<\/p>\n<p>La estimaci\u00f3n de Goldman Sachs coincide con la del Foro Nacional de Inmigraci\u00f3n, una organizaci\u00f3n que aboga por una reforma en el sector, que <a href=\"https:\/\/www.cnn.com\/2024\/11\/19\/economy\/new-home-undocumented-immigrants-trump\/index.html#:~:text=the%20National%20Immigration%20Forum%2C%20an%20organization%20that%20advocates%20for%20immigration%20reform%2C%20estimated%20that%20undocumented%20workers%20make%20up%20nearly%20a%20quarter%20of%20the%20construction%20workforce%20in%20America\">calcula<\/a> que los inmigrantes indocumentados representan casi una cuarta parte de la mano de obra de la construcci\u00f3n en EE.UU.<\/p>\n<p>En m\u00e1s de la mitad de Estados Unidos, la industria de la construcci\u00f3n recae fuertemente en los inmigrantes indocumentados. En 2023, la construcci\u00f3n fue la industria con la mayor proporci\u00f3n de inmigrantes indocumentados en 28 estados y la ciudad de Washington, seg\u00fan Pew Research.<\/p>\n<p>Varios representantes de la industria <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/03\/eeuu\/trump-preocupaciones-deportaciones-trabajadores-inmigrantes-trax\">han expresado<\/a> su preocupaci\u00f3n por las redadas indiscriminadas contra inmigrantes indocumentados sin antecedentes penales que han sido detenidos para su deportaci\u00f3n, incluso en sectores que son cr\u00edticos para la agenda m\u00e1s amplia del presidente.<\/p>\n<p>\u201cEsto har\u00e1 que sea pr\u00e1cticamente imposible apoyar el esfuerzo del Gobierno para fortalecer la manufactura\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/07\/03\/eeuu\/trump-preocupaciones-deportaciones-trabajadores-inmigrantes-trax\">dijo<\/a> Kip Eideberg, vicepresidente s\u00e9nior de relaciones gubernamentales e industriales de la Asociaci\u00f3n de Fabricantes de Equipos, a pesar del apoyo abrumador dentro de la industria a ese esfuerzo.<\/p>\n<p>\u201cEstamos entre la espada y la pared\u201d, coment\u00f3 Eideberg, y agreg\u00f3 que las deportaciones masivas reducir\u00e1n la fuerza laboral.<\/p>\n<p>Para organizaciones como Americans for Tax Fairness (ATF), el impacto de las pol\u00edticas de Trump ha sido muy fuerte en industrias donde los latinos tienen tasas de empleo elevadas, como la construcci\u00f3n.<\/p>\n<p>En un <a href=\"https:\/\/americansfortaxfairness.org\/trabajadores-latinos-bajo-trump\/\">an\u00e1lisis<\/a> publicado a inicios de octubre, ATF se\u00f1al\u00f3 que, entre enero y agosto de 2025 (los primeros ocho meses del actual Gobierno de Trump), se crearon 9.000 empleos en la industria de la construcci\u00f3n; en tanto, en ese mismo lapso del a\u00f1o pasado (todav\u00eda en el Gobierno de Joe Biden), se crearon 124.000 trabajos en ese sector, es decir, casi 14 veces m\u00e1s empleos.<\/p>\n<p>ATF destac\u00f3 la ca\u00edda en esta industria porque, seg\u00fan sus estimaciones, la construcci\u00f3n no solo recae en los inmigrantes, sino en personas de origen latino.<\/p>\n<p>\u201cLa construcci\u00f3n es la industria con m\u00e1s trabajadores latinos (en Estados Unidos) y una de las dos en la que los latinos (documentados e indocumentados) representan m\u00e1s del 40 % de la fuerza laboral total\u201d, dijo David Kass, director ejecutivo de ATF, en una <a href=\"https:\/\/www.youtube.com\/watch?v=bcNtv8w5Ums\">conferencia virtual<\/a> previa a la publicaci\u00f3n del an\u00e1lisis.<\/p>\n<p>Dichas estimaciones se aproximan a las cifras oficiales: m\u00e1s de un tercio de los trabajadores de la construcci\u00f3n en el pa\u00eds nacieron fuera de EE.UU, <a href=\"https:\/\/www.cnn.com\/2024\/11\/19\/economy\/new-home-undocumented-immigrants-trump\/index.html#:~:text=More%20than%20one%2Dthird%20of%20construction%20workers%20in%20the%20labor%20force%20are%20foreign%2Dborn%2C%20according%20to%20the%20US%20Census%20Bureau%E2%80%99s%202023%20American%20Community%20Survey.\">seg\u00fan<\/a> datos de 2023 de la Oficina del Censo, que no incluye preguntas sobre el estatus migratorio.<\/p>\n<p>\u201cEn oficios de alta demanda como el de enlucido, instalaci\u00f3n de paneles de yeso y pintura, los inmigrantes (documentados e indocumentados) a menudo constituyen m\u00e1s del 40 % de la fuerza laboral, lo que demuestra su papel indispensable para satisfacer la demanda de mano de obra calificada en la industria\u201d, <a href=\"https:\/\/nhca.pro\/press-releases\/national-hispanic-construction-alliance-2025-policy-report\/\">se\u00f1ala<\/a> el reporte \u2018State of Hispanics in Construction 2025\u2019 de National Hispanic Construction Alliance (NHCA), publicado en marzo de este a\u00f1o.<\/p>\n<p>Luego del <a href=\"https:\/\/www.cnn.com\/2025\/10\/03\/economy\/no-jobs-report-data-snapshot-september\">informe oficial<\/a> de empleo de septiembre \u2014en el que, entre otras cosas, se menciona que la industria de la construcci\u00f3n perdi\u00f3 7.000 empleos de julio a agosto\u2014, Mark Zandi, economista jefe de la consultora Moody\u2019s Analytics, dijo que Estados Unidos estaba en una \u201crecesi\u00f3n de trabajos\u201d. (El nuevo informe de empleo debi\u00f3 publicarse en los primeros d\u00edas de octubre, pero est\u00e1 retrasado debido al cierre del Gobierno, as\u00ed que el informe de septiembre es el m\u00e1s reciente hasta el momento).<\/p>\n<p>\u201cEl sector de bienes de la econom\u00eda, incluyendo la manufactura, la miner\u00eda y la construcci\u00f3n, est\u00e1 perdiendo una cantidad significativa de empleos, al igual que el gobierno federal. Solo la atenci\u00f3n m\u00e9dica y la hosteler\u00eda est\u00e1n aumentando las n\u00f3minas. No es una recesi\u00f3n total, ya que el PIB, los ingresos y las ganancias a\u00fan est\u00e1n creciendo lentamente. Pero \u00bfpor cu\u00e1nto tiempo m\u00e1s, si la econom\u00eda sigue perdiendo empleos?\u201d, <a href=\"https:\/\/x.com\/Markzandi\/status\/1963989362728743008\">explic\u00f3<\/a> Zandi en un mensaje en X.<\/p>\n<p>La recesi\u00f3n, <a href=\"https:\/\/x.com\/Markzandi\/status\/1957090986863038850\">afirm\u00f3<\/a> Zandi en X, no solo es en empleos, sino en industrias de la econom\u00eda, entre ellas la construcci\u00f3n.<\/p>\n<p>\u201cLas industrias con mayores dificultades son las m\u00e1s afectadas por el aumento de los aranceles, la pol\u00edtica de inmigraci\u00f3n altamente restrictiva y los recortes del DOGE (Departamento de Eficiencia Gubernamental, por sus siglas en ingl\u00e9s)\u201d, indic\u00f3 el economista jefe de Moody\u2019s Analytics.<\/p>\n<p>La construcci\u00f3n en EE.UU. es impactada por factores como la escasez de mano de obra calificada, el envejecimiento de la fuerza laboral y la desigualdad en los salarios, seg\u00fan el reporte de NHCA. Sin embargo, otro factor que afecta a la industria es la pol\u00edtica migratoria del gobierno, menciona el reporte \u2018Americas Construction Crisis\u2019, <a href=\"https:\/\/hispanicconstructioncouncil.com\/wp-content\/uploads\/2025\/09\/Americas-Construction-Crisis.pdf\">publicado<\/a> a finales de septiembre por Hispanic Construction Council (NHC).<\/p>\n<p>En el caso de California, estado que ha sido afectado por redadas migratorias y despliegues de la Guardia Nacional en los \u00faltimos meses, la ofensiva de inmigraci\u00f3n de Trump tiene el potencial de generar afectaciones a largo plazo, seg\u00fan el reporte de NHC.<\/p>\n<p>\u201cLas deportaciones masivas tambi\u00e9n amplifican los desaf\u00edos a largo plazo relacionados con la fuerza laboral y la equidad. Los trabajadores hispanos son el segmento m\u00e1s joven de la industria (de la construcci\u00f3n) y representan la fuente m\u00e1s s\u00f3lida para reemplazar jubilaciones y avanzar hacia oficios con licencia. Su expulsi\u00f3n vaciar\u00eda el futuro grupo de l\u00edderes justo cuando el estado (de California) incrementa programas plurianuales vinculados a los mandatos de vivienda y a los fondos federales de infraestructura\u201d, indica el reporte.<\/p>\n<p>George Carrillo, cofundador y CEO de NHC, dijo a CNN que el riesgo en la construcci\u00f3n tambi\u00e9n es a corto plazo, pues \u201ctenemos un retraso de 22 % en proyectos de infraestructura cr\u00edticos y adem\u00e1s tenemos un d\u00e9ficit de viviendas de aproximadamente 4 millones\u201d.<\/p>\n<p>\u201cPor lo tanto, estimamos que para 2030 necesitamos alrededor de 3,2 millones de trabajadores de la construcci\u00f3n adicionales y 120.000 empresas para apoyar a esa fuerza laboral\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Aunque los trabajadores latinos son imprescindibles en esta industria, eso no parece estar deteniendo al Gobierno de Trump, que sigue con su ofensiva migratoria. Seg\u00fan cifras oficiales, alrededor de <a href=\"https:\/\/www.dhs.gov\/news\/2025\/09\/23\/new-milestone-over-2-million-illegal-aliens-out-united-states-less-250-days\">2 millones de inmigrantes indocumentados<\/a> se han ido de EE.UU. en los primeros 250 d\u00edas de la nueva presidencia, ya sea por deportaci\u00f3n (m\u00e1s de 400.000 personas) o por salida voluntaria (un estimado de 1,6 millones).<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tal vez muchos conozcan el nombre de Kilmar \u00c1brego Garc\u00eda, un caso ic\u00f3nico de la dura pol\u00edtica migratoria en el segundo mandato de Donald Trump como presidente de Estados Unidos. Pero hay un da\u00f1o colateral poco comentado sobre todo el proceso que ha atravesado este salvadore\u00f1o desde que fue deportado por \u201cerror\u201d: el hueco que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467400","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil - Noticias\" \/>\n<meta property=\"og:description\" content=\"Tal vez muchos conozcan el nombre de Kilmar \u00c1brego Garc\u00eda, un caso ic\u00f3nico de la dura pol\u00edtica migratoria en el segundo mandato de Donald Trump como presidente de Estados Unidos. Pero hay un da\u00f1o colateral poco comentado sobre todo el proceso que ha atravesado este salvadore\u00f1o desde que fue deportado por \u201cerror\u201d: el hueco que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T19:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil\",\"datePublished\":\"2025-10-15T19:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/\"},\"wordCount\":2156,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/\",\"name\":\"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-15T19:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil - Noticias","og_description":"Tal vez muchos conozcan el nombre de Kilmar \u00c1brego Garc\u00eda, un caso ic\u00f3nico de la dura pol\u00edtica migratoria en el segundo mandato de Donald Trump como presidente de Estados Unidos. Pero hay un da\u00f1o colateral poco comentado sobre todo el proceso que ha atravesado este salvadore\u00f1o desde que fue deportado por \u201cerror\u201d: el hueco que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/","og_site_name":"Noticias","article_published_time":"2025-10-15T19:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/"},"author":{"name":"","@id":""},"headline":"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil","datePublished":"2025-10-15T19:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/"},"wordCount":2156,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/","url":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/","name":"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-15T19:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Miles de inmigrantes sosten\u00edan la construcci\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\u00e1 dif\u00edcil","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/migrantes-construccion-trump-desplomo-recupere-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-15T19:03:43Z","datePublished":"2025-10-15T19:03:43Z","dateModified":"2025-10-15T19:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Miles de inmigrantes sosten\\u00edan la construcci\\u00f3n en EE.UU. Con Trump, esa fuerza se desvanece y recuperarla ser\\u00e1 dif\\u00edcil\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/15\\\/migrantes-construccion-trump-desplomo-recupere-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/15\\\/migrantes-construccion-trump-desplomo-recupere-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-15T19:03:43Z\",\"datePublished\":\"2025-10-15T19:03:43Z\",\"dateModified\":\"2025-10-15T19:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461693,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/04\/27\/aranceles-deportaciones-precios-construccion-vivienda-orix\/","url_meta":{"origin":1467400,"position":0},"title":"Deportaciones y aranceles, el combo que amenaza con encarecer las viviendas en EE.UU.","author":"","date":"abril 27, 2025","format":false,"excerpt":"El sector de bienes ra\u00edces en Estados Unidos se ve afectado por dos ejes clave del Gobierno del presidente Donald Trump que impactan especialmente los costos de construcci\u00f3n: la imposici\u00f3n de aranceles y la campa\u00f1a de deportaciones masivas, que en conjunto podr\u00eda exacerbar a\u00fan m\u00e1s la crisis de asequibilidad de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465772,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/08\/22\/historia-kilmar-abrego-deportacion-liberacion-trax\/","url_meta":{"origin":1467400,"position":1},"title":"El caso de Kilmar \u00c1brego Garc\u00eda: desde su deportaci\u00f3n por error a El Salvador hasta su liberaci\u00f3n de custodia criminal","author":"","date":"agosto 22, 2025","format":false,"excerpt":"La pesadilla de Kilmar \u00c1brego Garc\u00eda comenz\u00f3 en marzo pasado, cuando fue deportado por un \u201cerror administrativo\u201d a El Salvador y encarcelado en una prisi\u00f3n de m\u00e1xima seguridad del pa\u00eds. Su caso fue motivo de una prolongada batalla pol\u00edtica y legal del Gobierno de Donald Trump contra los jueces que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464194,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/07\/03\/malas-ocultas-informe-empleo-junio-trax\/","url_meta":{"origin":1467400,"position":2},"title":"Estas son las malas noticias ocultas en el informe de empleo de junio","author":"","date":"julio 3, 2025","format":false,"excerpt":"A simple vista, el informe de empleo de junio presenta un panorama s\u00f3lido de la econom\u00eda estadounidense, con una tasa de desempleo hist\u00f3ricamente baja, una cantidad saludable de empleos creados y un crecimiento salarial que supera la inflaci\u00f3n. Sin embargo, un an\u00e1lisis m\u00e1s detallado de los datos revela aspectos negativos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472732,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/03\/31\/mercado-laboral-febrero-trax\/","url_meta":{"origin":1467400,"position":3},"title":"El ritmo de contrataci\u00f3n en EE.UU. acaba de caer al nivel m\u00e1s bajo desde 2011, sin contar la pandemia","author":"","date":"marzo 31, 2026","format":false,"excerpt":"Las empresas estadounidenses est\u00e1n incorporando trabajadores al ritmo m\u00e1s d\u00e9bil en 15 a\u00f1os, excluyendo el inicio de la pandemia, seg\u00fan nuevos datos el martes, una se\u00f1al de que un enfriamiento a\u00fan m\u00e1s profundo ya estaba atravesando el mercado laboral antes de que el conflicto en el Medio Oriente amenazara con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470860,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/02\/04\/empleo-sector-privado-desplome-enero-trax\/","url_meta":{"origin":1467400,"position":4},"title":"La contrataci\u00f3n del sector privado se desplom\u00f3 en enero: se crearon solo 22.000 empleos","author":"","date":"febrero 4, 2026","format":false,"excerpt":"El breve cierre del Gobierno de EE.UU. ha retrasado el informe oficial de empleo de enero (los datos se publicar\u00e1n el 11 de febrero en lugar del pr\u00f3ximo viernes). Sin embargo, un primer an\u00e1lisis de la actividad de contrataci\u00f3n en el sector privado mostr\u00f3 que el crecimiento del empleo se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460942,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/04\/08\/cronologia-deportacion-kilmar-abrego-el-salvador-trax\/","url_meta":{"origin":1467400,"position":5},"title":"Cronolog\u00eda de la batalla legal por la deportaci\u00f3n err\u00f3nea de Kilmar \u00c1brego a El Salvador","author":"","date":"abril 8, 2025","format":false,"excerpt":"El lunes, la Corte Suprema suspendi\u00f3 temporalmente el plazo impuesto por un tribunal inferior para devolver a Estados Unidos a un hombre de Maryland deportado por error a El Salvador, lo que le otorga al gobierno de Trump tiempo adicional para revisar el caso.Kilmar Armando \u00c1brego Garc\u00eda, trabajador metal\u00fargico y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467400"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467400\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}