{"id":1467416,"date":"2025-10-15T20:03:41","date_gmt":"2025-10-16T03:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/"},"modified":"2025-10-15T20:03:41","modified_gmt":"2025-10-16T03:03:41","slug":"hegseth-condicion-fisica-estandares-ejercito-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/","title":{"rendered":"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares"},"content":{"rendered":"<p>El secretario de Defensa, Pete Hegseth, orden\u00f3 a los altos mandos militares de Estados Unidos que verifiquen que todos los miembros del departamento hayan visto el<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/09\/30\/eeuu\/video\/hegseth-tropas-militares-eeuu-generales-obsesos-trax\"> discurso que pronunci\u00f3<\/a> el mes pasado en una inusual reuni\u00f3n de altos mandos en Quantico, Virginia, y que revisen los cambios de pol\u00edtica que anunci\u00f3 tras ese evento, seg\u00fan un memorando revisado por CNN.<\/p>\n<p>\u201cLos l\u00edderes en todos los niveles deber\u00e1n asegurarse de que todo el personal vea la grabaci\u00f3n completa o lea la transcripci\u00f3n oficial del discurso, y revise los cambios de pol\u00edtica a m\u00e1s tardar el 31 de octubre de 2025\u201d, indica el memorando de Hegseth del 6 de octubre.<\/p>\n<p>El memorando de Hegseth llega despu\u00e9s de que ordenara a los altos mandos viajar a Quantico para lo que fue, en gran medida, un discurso pol\u00edtico en el que expuso su visi\u00f3n sobre c\u00f3mo ser\u00e1 el aspecto f\u00edsico y la actuaci\u00f3n de las Fuerzas Armadas.<\/p>\n<p>Tambi\u00e9n lanz\u00f3 un ultim\u00e1tum contundente durante su discurso: si no est\u00e1n de acuerdo, renuncien.<\/p>\n<p>Mientras Hegseth pronunci\u00f3 su discurso en persona ante cientos de altos mandos militares, el memorando posterior deja claro que quiere asegurarse de que el mensaje llegue al personal de defensa en todos los niveles.<\/p>\n<p>Los l\u00edderes \u201cdeben inculcar nuestro cambio cultural y asegurarse de que cada miembro del Departamento de Guerra comprenda mi orientaci\u00f3n\u201d, escribi\u00f3 Hegseth en el memorando, utilizando el nombre preferido por el Gobierno de Trump para el Departamento de Defensa.<\/p>\n<p>Consultado sobre el nuevo memorando, un portavoz del Pent\u00e1gono dijo que \u201cel discurso del secretario fue para toda la fuerza y este memorando solo refuerza esa orientaci\u00f3n\u201d.<\/p>\n<p>Las directrices que acompa\u00f1aron al discurso revierten en gran medida los esfuerzos realizados durante la \u00faltima d\u00e9cada para erradicar la cultura t\u00f3xica en las Fuerzas Armadas, tanto para reducir comportamientos nocivos como el acoso, como para satisfacer las necesidades pr\u00e1cticas de reclutar personal militar y retenerlo durante m\u00e1s tiempo.<\/p>\n<p>En su discurso, Hegseth tambi\u00e9n hizo especial hincapi\u00e9 en la forma f\u00edsica y la apariencia de los miembros del servicio. Hegseth dijo a los militares de alto rango presentes en la sala que no quer\u00eda ver a ning\u00fan general \u201cgordo\u201d paseando por los pasillos del Pent\u00e1gono.<\/p>\n<p>Tras el discurso de Hegseth en Quantico, el Departamento Militar de Texas retir\u00f3 a siete soldados de la Guardia Nacional que hab\u00edan sido desplegados en Chicago porque \u201cno cumpl\u00edan los requisitos de la misi\u00f3n\u201d, seg\u00fan inform\u00f3 a CNN un portavoz de la Guardia Nacional de Texas.<\/p>\n<p>\u201cEstos miembros del servicio fueron devueltos a su base de origen. La Guardia Nacional de Texas se hace eco del mensaje del secretario Hegseth a las fuerzas: \u2018Nuestros est\u00e1ndares ser\u00e1n altos, inflexibles y claros\u2019, dijo el portavoz.<\/p>\n<p>Los militares, enviados a Chicago como parte de la misi\u00f3n nacional del presidente Donald Trump centrada en la delincuencia, fueron sustituidos en medio de las cr\u00edticas en las redes sociales por unas fotos en las que se ve\u00eda a algunos miembros de la Guardia con sobrepeso.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Defensa, Pete Hegseth, orden\u00f3 a los altos mandos militares de Estados Unidos que verifiquen que todos los miembros del departamento hayan visto el discurso que pronunci\u00f3 el mes pasado en una inusual reuni\u00f3n de altos mandos en Quantico, Virginia, y que revisen los cambios de pol\u00edtica que anunci\u00f3 tras ese evento, seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1467416","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares - Noticias\" \/>\n<meta property=\"og:description\" content=\"El secretario de Defensa, Pete Hegseth, orden\u00f3 a los altos mandos militares de Estados Unidos que verifiquen que todos los miembros del departamento hayan visto el discurso que pronunci\u00f3 el mes pasado en una inusual reuni\u00f3n de altos mandos en Quantico, Virginia, y que revisen los cambios de pol\u00edtica que anunci\u00f3 tras ese evento, seg\u00fan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-16T03:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares\",\"datePublished\":\"2025-10-16T03:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/\",\"name\":\"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-10-16T03:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares - Noticias","og_description":"El secretario de Defensa, Pete Hegseth, orden\u00f3 a los altos mandos militares de Estados Unidos que verifiquen que todos los miembros del departamento hayan visto el discurso que pronunci\u00f3 el mes pasado en una inusual reuni\u00f3n de altos mandos en Quantico, Virginia, y que revisen los cambios de pol\u00edtica que anunci\u00f3 tras ese evento, seg\u00fan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/","og_site_name":"Noticias","article_published_time":"2025-10-16T03:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/"},"author":{"name":"","@id":""},"headline":"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares","datePublished":"2025-10-16T03:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/","url":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/","name":"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-10-16T03:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\u00f3n f\u00edsica y est\u00e1ndares","url":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/15\/hegseth-condicion-fisica-estandares-ejercito-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-10-16T03:03:41Z","datePublished":"2025-10-16T03:03:41Z","dateModified":"2025-10-16T03:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Hegseth ordena que todo el personal conozca el discurso que dio a altos mandos militares sobre condici\\u00f3n f\\u00edsica y est\\u00e1ndares\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/15\\\/hegseth-condicion-fisica-estandares-ejercito-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2025\\\/10\\\/15\\\/hegseth-condicion-fisica-estandares-ejercito-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-10-16T03:03:41Z\",\"datePublished\":\"2025-10-16T03:03:41Z\",\"dateModified\":\"2025-10-16T03:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1466874,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/26\/reunion-altos-mandos-militares-hegseth-departamento-guerra-trax\/","url_meta":{"origin":1467416,"position":0},"title":"Hegseth se reunir\u00e1 con altos mandos militares para describir c\u00f3mo ser\u00e1 el nuevo &#171;Departamento de Guerra&#187;, dicen fuentes","author":"","date":"septiembre 26, 2025","format":false,"excerpt":"La sorpresiva reuni\u00f3n del secretario de Defensa, Pete Hegseth, con cientos de generales y almirantes en Virginia la pr\u00f3xima semana ha sido convocada para que pueda describir la reinvenci\u00f3n del Gobierno del Departamento de Defensa como el \u201cDepartamento de Guerra\u201d y detallar nuevos est\u00e1ndares para el personal militar, seg\u00fan media\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467829,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/28\/analisis-creciente-politizacion-fuerzas-armadas-trump-contraproducente-trax\/","url_meta":{"origin":1467416,"position":1},"title":"Por qu\u00e9 la creciente politizaci\u00f3n de las fuerzas armadas por parte de Trump podr\u00eda resultar contraproducente","author":"","date":"octubre 28, 2025","format":false,"excerpt":"\u00bfCu\u00e1l es la diferencia entre la cubierta de vuelo de un poderoso portaviones estadounidense y un mitin MAGA? No mucha en la mente del presidente Donald Trump.El comandante en jefe utiliz\u00f3 este martes un discurso a bordo del USS George Washington, atracado en Jap\u00f3n, para revivir las falsedades de las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462026,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/05\/06\/hegseth-pentagono-generales-alto-rango-20-trax\/","url_meta":{"origin":1467416,"position":2},"title":"Hegseth ordena al Pent\u00e1gono reducir el n\u00famero de generales de alto rango en 20 %","author":"","date":"mayo 6, 2025","format":false,"excerpt":"El secretario de Defensa de Estados Unidos, Pete Hegseth, orden\u00f3 a los altos mandos del Pent\u00e1gono reducir el n\u00famero de generales y almirantes de cuatro estrellas en al menos un 20 % en todas las fuerzas armadas, seg\u00fan un memorando firmado por Hegseth fechado el lunes y obtenido por CNN.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467867,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/10\/30\/destituyen-general-tres-estrellas-tensiones-pete-hegseth-trax\/","url_meta":{"origin":1467416,"position":3},"title":"Exclusiva: Destituyen a un general de tres estrellas en medio de tensiones con Pete Hegseth","author":"","date":"octubre 30, 2025","format":false,"excerpt":"Un general de tres estrellas que formaba parte del Estado Mayor Conjunto del Pent\u00e1gono fue destituido de su cargo tras meses de tensiones con el secretario de Defensa, Pete Hegseth, seg\u00fan fuentes familiarizadas con el asunto. Su ascenso bloqueado tambi\u00e9n contribuy\u00f3 a su retiro anticipado, a\u00f1adieron las fuentes.El teniente general\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461428,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/04\/20\/hegseth-segundo-chat-signal-planes-militares-trax\/","url_meta":{"origin":1467416,"position":4},"title":"Hegseth comparti\u00f3 planes militares detallados en un segundo chat de Signal en el que estaban su esposa y su hermano","author":"","date":"abril 20, 2025","format":false,"excerpt":"El secretario de Defensa Pete Hegseth comparti\u00f3 planes detallados sobre una operaci\u00f3n militar contra los hut\u00edes en Yemen en un segundo chat grupal de Signal, en el que estaban su esposa, su abogado y su hermano, seg\u00fan informaron a CNN tres personas familiarizadas con el chat.La revelaci\u00f3n se produce cuando\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459901,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/03\/13\/pentagono-opciones-militares-acceso-canal-de-panama-trax\/","url_meta":{"origin":1467416,"position":5},"title":"Trump pide al Pent\u00e1gono &#171;opciones militares&#187; para garantizar el acceso de EE.UU. al canal de Panam\u00e1, seg\u00fan un memorando","author":"","date":"marzo 13, 2025","format":false,"excerpt":"El Gobierno de Trump solicit\u00f3 formalmente a los funcionarios del Pent\u00e1gono \u201copciones militares cre\u00edbles\u201d para garantizar el acceso sin restricciones de Estados Unidos al canal de Panam\u00e1, una de varias nuevas directivas delineadas en lo que equivale a una revisi\u00f3n importante de las prioridades estrat\u00e9gicas de EE.UU., seg\u00fan un nuevo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1467416"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1467416\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1467416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1467416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1467416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}