{"id":1473816,"date":"2026-05-05T12:03:44","date_gmt":"2026-05-05T19:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/"},"modified":"2026-05-05T12:03:44","modified_gmt":"2026-05-05T19:03:44","slug":"ciudad-mexico-hundimiento-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/","title":{"rendered":"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio"},"content":{"rendered":"<p>Ciudad de M\u00e9xico se est\u00e1 hundiendo a un ritmo tan alarmante que puede observarse desde el espacio. Im\u00e1genes de un potente sistema de radar de la NASA revelan tasas de subsidencia superiores a 1,3 cent\u00edmetros al mes, lo que la convierte en una de las capitales que m\u00e1s r\u00e1pido se hunden en el planeta.<\/p>\n<p>La extensa metr\u00f3poli, tambi\u00e9n una de las ciudades m\u00e1s grandes del mundo, se extiende sobre un lago de gran altitud y se asienta sobre un antiguo acu\u00edfero, que proporciona alrededor del 60 % del agua potable para sus 22 millones de habitantes.<\/p>\n<p>Con el paso de los a\u00f1os, este acu\u00edfero ha sido sobreexplotado hasta tal punto que ha provocado el hundimiento del terreno que se encuentra encima. La sobreextracci\u00f3n tambi\u00e9n ha contribuido a una crisis h\u00eddrica cr\u00f3nica que ha dejado a la Ciudad de M\u00e9xico <a href=\"https:\/\/cnnespanol.cnn.com\/2024\/02\/25\/ciudad-mexico-agua-trax\/\">frente a un posible \u201cd\u00eda cero\u201d<\/a>, cuando los grifos podr\u00edan quedarse sin agua.<\/p>\n<p>El r\u00e1pido hundimiento de la ciudad se ha visto agravado por el desarrollo urbano constante, con nuevas infraestructuras que a\u00f1aden peso adicional sobre el suelo rico en arcilla.<\/p>\n<p>La subsidencia de la Ciudad de M\u00e9xico fue documentada por primera vez en la d\u00e9cada de 1920, y desde entonces los residentes han experimentado sus efectos, con carreteras agrietadas, edificios inclinados y da\u00f1os en el sistema ferroviario.<\/p>\n<p>Nuevas im\u00e1genes del sat\u00e9lite NISAR, un proyecto conjunto entre la NASA y la Indian Space Research Organisation, revelan la magnitud del problema con un nivel de detalle sorprendente.<\/p>\n<p>NISAR fue dise\u00f1ado para mapear algunos de los procesos m\u00e1s complejos del planeta y es capaz de rastrear movimientos sutiles como el hundimiento del terreno. Es uno de los sistemas de radar m\u00e1s potentes jam\u00e1s lanzados al espacio, <a href=\"https:\/\/www.nasa.gov\/missions\/nisar\/us-indian-space-mission-maps-extreme-subsidence-in-mexico-city\/\">seg\u00fan la NASA.<\/a><\/p>\n<p>Entre octubre de 2025 y enero de 2026, durante la temporada seca de la Ciudad de M\u00e9xico, NISAR cartografi\u00f3 el movimiento del suelo bajo la ciudad. Sus hallazgos revelan que algunas zonas se hunden a un ritmo de aproximadamente 2 cent\u00edmetros al mes, lo que equivale a m\u00e1s de 24 cent\u00edmetros al a\u00f1o.<\/p>\n<p>Las \u00e1reas m\u00e1s afectadas incluyen el Aeropuerto Internacional Benito Ju\u00e1rez, el principal aeropuerto de la ciudad.<\/p>\n<p>Uno de los monumentos m\u00e1s emblem\u00e1ticos refleja los efectos del hundimiento. El \u00c1ngel de la Independencia, de 35 metros de altura y construido en 1910 para conmemorar el centenario de la independencia de M\u00e9xico, ha tenido que <a href=\"https:\/\/mexicocity.cdmx.gob.mx\/venues\/el-angel-independencia\/?lang=en\">a\u00f1adir 14 escalones<\/a> en su base a medida que el terreno bajo \u00e9l se hunde.<\/p>\n<p>\u201cLa Ciudad de M\u00e9xico es un punto cr\u00edtico bien conocido cuando se trata de subsidencia, e im\u00e1genes como esta son solo el comienzo para NISAR\u201d, dijo David Bekaert, gerente de proyecto en el Instituto Flamenco de Investigaci\u00f3n Tecnol\u00f3gica y miembro del equipo cient\u00edfico de NISAR. \u201cVamos a ver una avalancha de nuevos descubrimientos en todo el mundo\u201d.<\/p>\n<p>El sat\u00e9lite tambi\u00e9n puede rastrear otros procesos planetarios, como el deslizamiento de glaciares o el crecimiento de cultivos, as\u00ed como desastres naturales como erupciones volc\u00e1nicas.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad de M\u00e9xico se est\u00e1 hundiendo a un ritmo tan alarmante que puede observarse desde el espacio. Im\u00e1genes de un potente sistema de radar de la NASA revelan tasas de subsidencia superiores a 1,3 cent\u00edmetros al mes, lo que la convierte en una de las capitales que m\u00e1s r\u00e1pido se hunden en el planeta. La [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1473816","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio - Noticias\" \/>\n<meta property=\"og:description\" content=\"Ciudad de M\u00e9xico se est\u00e1 hundiendo a un ritmo tan alarmante que puede observarse desde el espacio. Im\u00e1genes de un potente sistema de radar de la NASA revelan tasas de subsidencia superiores a 1,3 cent\u00edmetros al mes, lo que la convierte en una de las capitales que m\u00e1s r\u00e1pido se hunden en el planeta. La [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T19:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio\",\"datePublished\":\"2026-05-05T19:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/\"},\"wordCount\":560,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/\",\"name\":\"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-05-05T19:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio - Noticias","og_description":"Ciudad de M\u00e9xico se est\u00e1 hundiendo a un ritmo tan alarmante que puede observarse desde el espacio. Im\u00e1genes de un potente sistema de radar de la NASA revelan tasas de subsidencia superiores a 1,3 cent\u00edmetros al mes, lo que la convierte en una de las capitales que m\u00e1s r\u00e1pido se hunden en el planeta. La [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/","og_site_name":"Noticias","article_published_time":"2026-05-05T19:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/"},"author":{"name":"","@id":""},"headline":"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio","datePublished":"2026-05-05T19:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/"},"wordCount":560,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/","url":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/","name":"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-05-05T19:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Ciudad de M\u00e9xico se hunde tan r\u00e1pido que ya es visible desde el espacio","url":"http:\/\/noticiasya.com\/stockton-modesto\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/stockton-modesto\/2026\/05\/05\/ciudad-mexico-hundimiento-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-05-05T19:03:44Z","datePublished":"2026-05-05T19:03:44Z","dateModified":"2026-05-05T19:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Ciudad de M\\u00e9xico se hunde tan r\\u00e1pido que ya es visible desde el espacio\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2026\\\/05\\\/05\\\/ciudad-mexico-hundimiento-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/stockton-modesto\\\/2026\\\/05\\\/05\\\/ciudad-mexico-hundimiento-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-05-05T19:03:44Z\",\"datePublished\":\"2026-05-05T19:03:44Z\",\"dateModified\":\"2026-05-05T19:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447230,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/03\/22\/analisis-acabar-crisis-agua-ciudad-de-mexico-orix\/","url_meta":{"origin":1473816,"position":0},"title":"AN\u00c1LISIS | \u00bfEs posible acabar con la crisis del agua en la Ciudad de M\u00e9xico?","author":"","date":"marzo 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Ciudad de M\u00e9xico, como muchas de las grandes urbes en el mundo, vive una crisis de escasez de agua. La alta y creciente densidad poblacional, el ca\u00f3tico y poco controlado desarrollo urbano y los meses de sequ\u00eda se suman al cambio clim\u00e1tico y la geograf\u00eda como\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448259,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2024\/04\/19\/sistema-aguas-ciudad-de-mexico-denuncia-fiscalia-sabotaje-trax\/","url_meta":{"origin":1473816,"position":1},"title":"Sistema de Aguas de la Ciudad de M\u00e9xico denunci\u00f3 ante la fiscal\u00eda sabotaje de aguas","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Sistema de Aguas de la Ciudad de M\u00e9xico present\u00f3 el mi\u00e9rcoles ante la Fiscal\u00eda General de Justicia de la capital una denuncia por el presunto delito de sabotaje, tras encontrarse un compuesto de aceites degradados en el pozo Alfonso XIII, que abastece de agua a parte\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473437,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/04\/23\/ciudad-mexico-obras-publicas-mundial-tiempo-orix\/","url_meta":{"origin":1473816,"position":2},"title":"Contra el reloj, la Ciudad de M\u00e9xico avanza en obras p\u00fablicas para recibir el Mundial","author":"","date":"abril 23, 2026","format":false,"excerpt":"El ruido de herramientas cortando metal, de veh\u00edculos pesados transportando materiales y de trabajadores hablando entre s\u00ed se mezcla con los sonidos habituales de una de las zonas m\u00e1s transitadas del centro de la Ciudad de M\u00e9xico: autom\u00f3viles, vendedores, peatones en su camino de regreso a casa.Aunque ya anocheci\u00f3, las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470441,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2026\/01\/23\/amplia-politica-ciudad-de-mexico-aborto-dei-trax\/","url_meta":{"origin":1473816,"position":3},"title":"El Gobierno de Trump ampl\u00eda la Pol\u00edtica de la &#171;Ciudad de M\u00e9xico&#187; sobre el aborto para prohibir fondos a ONG que promueven DEI","author":"","date":"enero 23, 2026","format":false,"excerpt":"El vicepresidente J. D. Vance dijo este viernes que el Gobierno de Trump est\u00e1 ampliando la llamada Pol\u00edtica de la Ciudad de M\u00e9xico, para no solo prohibir el financiamiento del Gobierno de Estados Unidos a organizaciones que realizan y promueven abortos, sino tambi\u00e9n a aquellas que, seg\u00fan el Gobierno, promueven\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459636,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/03\/07\/aumento-de-personas-en-situacion-de-calle-mas-del-70-provienen-de-la-provincia-de-buenos-aires\/","url_meta":{"origin":1473816,"position":4},"title":"Personas en situaci\u00f3n de calle: seg\u00fan el ministro Mraida de CABA, &#171;m\u00e1s del 70% provienen de la provincia de Buenos Aires&#187;","author":"","date":"marzo 7, 2025","format":false,"excerpt":"(CNN Radio Argentina) \u2013 Gabriel Mraida, ministro de Desarrollo Humano y H\u00e1bitat de la Ciudad de Buenos Aires, habl\u00f3 este viernes con CNN Radio sobre el aumento de personas en situaci\u00f3n de calle y la asistencia que brinda la Ciudad ante esta problem\u00e1tica.En di\u00e1logo con Regreso CNN con Mariana Arias\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466148,"url":"https:\/\/noticiasya.com\/stockton-modesto\/2025\/09\/04\/ciudad-de-mexico-lejos-dia-cero-lluvias-orix\/","url_meta":{"origin":1473816,"position":5},"title":"Lluvias hist\u00f3ricas alejan a Ciudad de M\u00e9xico del temido \u2018d\u00eda cero\u2019. Expertos advierten que crisis del agua no ha terminado","author":"","date":"septiembre 4, 2025","format":false,"excerpt":"Ester Flores recuerda que hace un a\u00f1o deb\u00eda ahorrar toda el agua que pod\u00eda y pedir a sus vecinos que le \u201cprestaran una o dos cubetas para lavar los trastes\u201d. Ahora, la situaci\u00f3n es completamente diferente: cada semana recibe agua corriente que le permite a ella y a su familia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/stockton-modesto\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1473816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/comments?post=1473816"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/posts\/1473816\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/media?parent=1473816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/categories?post=1473816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/stockton-modesto\/wp-json\/wp\/v2\/tags?post=1473816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}