{"id":1451275,"date":"2024-07-19T18:03:53","date_gmt":"2024-07-20T01:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/"},"modified":"2024-07-19T18:03:53","modified_gmt":"2024-07-20T01:03:53","slug":"primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/","title":{"rendered":"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados"},"content":{"rendered":"<p>Nueva York (CNN) &#8212; El pardo y anta\u00f1o contaminado r\u00edo Sena de Par\u00eds no es el m\u00e1s brillante ni el m\u00e1s glamuroso, especialmente en una ciudad llena de lugares emblem\u00e1ticos. Pero Chase espera que este curso de agua se convierta en todo un espect\u00e1culo.<\/p>\n<p>En los Juegos Ol\u00edmpicos de Verano de 2024, que comienzan oficialmente el pr\u00f3ximo viernes en la capital francesa, el banco, junto con la compa\u00f1\u00eda de tarjetas de cr\u00e9dito Visa, estrena una sala flotante exclusiva para los titulares de su costosa tarjeta Chase Sapphire Reserve. Es s\u00f3lo una peque\u00f1a muestra de lo que est\u00e1n haciendo las empresas en su incursi\u00f3n durante las dos semanas de espect\u00e1culo deportivo.<\/p>\n<p>Mira el\u00a0r\u00edo\u00a0Sena tras una limpieza de\u00a0US$\u00a01.500 millones para los Juegos Ol\u00edmpicos<\/p>\n<p>Se espera que los organizadores de Par\u00eds 2024 ingresen unos US$ 1.300 millones en concepto de patrocinios, procedentes de una mezcla de socios nacionales que suman 60 empresas, como Accor y LVMH, y socios internacionales, desde Coca-Cola hasta relojes Omega. Por primera vez, Anheuser-Bush InBev patrocina los Juegos Ol\u00edmpicos con una cerveza sin alcohol.<\/p>\n<p>En el sal\u00f3n del Sapphire, a orillas del Sena, los invitados disfrutar\u00e1n de buena comida francesa, actuaciones en vivo de DJs y grupos musicales y una vista \u00fanica de Par\u00eds que despertar\u00e1 la envidia de sus seguidores de Instagram. Todo ello est\u00e1 pensado para promocionar la exclusividad que ofrece la tarjeta y quiz\u00e1 sea su intento m\u00e1s lujoso de ampliar su concepto de sala VIP de lujo, m\u00e1s habitual en los aeropuertos.<\/p>\n<p>Los juegos son &#171;obviamente, un gran momento cultural&#187; con un p\u00fablico cautivo, seg\u00fan Sam Palmer, director general de Chase Sapphire, una popular tarjeta de cr\u00e9dito Visa que atrae a consumidores de alto poder adquisitivo con lujosas ventajas, como la sala VIP, para compensar la cuota anual de US$ 550.<\/p>\n<p>Una ciclista pasea por el puente Alexandre III, donde se han colocado filas de asientos para la ceremonia de apertura de los Juegos. Cr\u00e9dito: Olympia De Maismont\/AFP\/Getty Images<\/p>\n<p>&#171;Est\u00e1 muy alineado con lo que les gusta a los miembros de la tarjeta Sapphire Reserve&#187;, dijo a CNN. &#171;Si piensas en los Juegos Ol\u00edmpicos &#8230; se trata de viajes, restaurantes, cultura, emoci\u00f3n, comunidad&#187;.<\/p>\n<p>Todas esas cosas se conjugan cada cuatro a\u00f1os en los Juegos Ol\u00edmpicos, que congregan a millones de aficionados y miles de atletas. Par\u00eds, una ciudad conocida por su opulencia, acoge este a\u00f1o los primeros juegos posteriores a los de la pandemia de covid-19 sin restricciones de p\u00fablico por primera vez en seis a\u00f1os. (Tanto los juegos de verano en Tokio 2021 como los de invierno en Beijing 2022 prohibieron o limitaron la entrada de espectadores o visitantes).<\/p>\n<p>Seg\u00fan los informes, LVMH, la marca de lujo francesa, ha gastado US$ 160 millones para ser el primer &#171;socio creativo&#187; de los Juegos, con un gran alcance en todo el evento para su diversidad de marcas. Louis Vuitton dise\u00f1\u00f3 las bandejas en las que se entregar\u00e1n las medallas, el fabricante de cuero Berluti confeccion\u00f3 los uniformes de los atletas franceses en las ceremonias de inauguraci\u00f3n y el champ\u00e1n Mo\u00ebt &#038; Chandon fluir\u00e1 en los actos y en un restaurante pop-up con el c\u00e9lebre chef Yannick Allen.<\/p>\n<p>Turismo tibio<\/p>\n<p>A pesar de la expectativa de las empresas, los aficionados est\u00e1n, de momento, m\u00e1s moderados. Aunque se espera que la ciudad atraiga a 11,3 millones de visitantes, s\u00f3lo el 10% de ellos proceder\u00e1 de fuera de Francia, seg\u00fan el departamento de turismo de la ciudad.<\/p>\n<p>Incluso los hoteles y las compa\u00f1\u00edas a\u00e9reas, que suelen sacar provecho financiero de los grandes acontecimientos (Taylor Swift, por ejemplo), no se han mostrado muy satisfechos con los Juegos, y temen que las aglomeraciones, la agitaci\u00f3n pol\u00edtica y los elevados precios desanimen a los visitantes.<\/p>\n<p>BlackTomato, una empresa de viajes de lujo, ha observado que su n\u00famero de reservas para Par\u00eds este verano ha &#171;disminuido ligeramente&#187;, un 15% en comparaci\u00f3n con 2023, lo que demuestra que el entusiasmo por visitar la ciudad ha deca\u00eddo durante los Juegos.<\/p>\n<p>Turistas y parisinos observan las gradas construidas para los Juegos Ol\u00edmpicos de Par\u00eds en el jard\u00edn de las Tuller\u00edas. Cr\u00e9dito: Vincent Koebel\/NurPhoto\/Getty Images<\/p>\n<p>&#171;Hemos recibido muchas reservas para los asistentes a los Juegos Ol\u00edmpicos, pero los que no participan en ellos han dudado en viajar en un momento en el que abundan las tarifas m\u00e1s altas y las estancias m\u00ednimas&#187;, explica a CNN Carolyn Addison, jefa de producto de BlackTomato. Se\u00f1ala que los viajeros est\u00e1n optando por otras zonas de Francia, como la Provenza y Niza, en lugar de Par\u00eds.<\/p>\n<p>Las tasas de ocupaci\u00f3n de los hoteles parisinos rondan el 80%, seg\u00fan CoStar, un proveedor mundial de datos sobre viajes, muy por debajo del casi 90% que tuvieron los Juegos de Londres 2012 y de la impactante cifra del 94% de ocupaci\u00f3n de los Juegos de 2016 en R\u00edo de Janeiro.<\/p>\n<p>Accor, propietaria de varias marcas, desde la econ\u00f3mica Ibis hasta la lujosa Raffles, est\u00e1 lejos de haber agotado las plazas en sus 200 hoteles de la ciudad. La empresa declar\u00f3 a CNN que tiene una tasa de ocupaci\u00f3n del 75% durante los Juegos, y que se espera que esa cifra aumente hasta entre el 80% y el 85% una vez que empiecen.<\/p>\n<p>Otro dato que muestra la indecisi\u00f3n de los viajeros son las reservas de vuelos. Seg\u00fan la empresa de viajes ForwardKeys, se espera que la cifra aumente s\u00f3lo un 10% durante los Juegos, que se celebrar\u00e1n del 26 de julio al 11 de agosto.<\/p>\n<p>Esta cifra es muy inferior a la de R\u00edo, donde se registr\u00f3 un aumento del 115% en las reservas de vuelos. Incluso los \u00faltimos Juegos de verano, celebrados en 2021 en Tokio y en los que se prohibi\u00f3 la entrada de espectadores, registraron un aumento del 20%.<br \/>\nSeg\u00fan un portavoz de ForwardKeys, los juegos celebrados en temporada baja, como los de R\u00edo, en invierno en el hemisferio sur, aumentaron m\u00e1s el n\u00famero de visitantes que los celebrados cuando el turismo ya est\u00e1 en pleno auge.<\/p>\n<p>Algunas de las mayores aerol\u00edneas del mundo advierten de enormes p\u00e9rdidas econ\u00f3micas. Delta Air Lines, patrocinador del Equipo de Estados Unidos, ha revelado que va a perder unos US$ 100 millones debido a la ausencia de viajeros en Par\u00eds. Air France, &#171;socio oficial&#187; de los Juegos, ha declarado en un comunicado reciente que el tr\u00e1fico a la ciudad est\u00e1 &#171;rezagado con respecto a otras grandes ciudades europeas&#187; y que est\u00e1 sufriendo una merma de unos US$ 200 millones durante el verano, debido a que la gente opta por visitar la ciudad o hacer escala en otro lugar.<\/p>\n<p>Una novedad para los Juegos<\/p>\n<p>A pesar de que los Juegos no son un atractivo para algunos, millones de personas acudir\u00e1n a vivir el encanto de Par\u00eds en uno de los acontecimientos m\u00e1s singulares del mundo. Este a\u00f1o, los organizadores ol\u00edmpicos esperan que la compra de entradas sea menos dolorosa que en el pasado, ya que esperan ingresar US$ 1.500 millones en ventas.<\/p>\n<p>Banderas de Par\u00eds 2024 cerca del Hotel de Ville en Par\u00eds. Cr\u00e9dito: Maja Hitij\/Getty Images<\/p>\n<p>Una mujer toma una fotograf\u00eda desde la Torre Eiffel. Cr\u00e9dito: Olympia De Maismont\/AFP\/Getty Images<\/p>\n<p>On Location, una empresa de gesti\u00f3n de eventos, se encarga ahora de vender entradas y suites de hospitalidad para los visitantes en un \u00fanico sitio web, lo que supone un cambio con respecto a los Juegos anteriores, cuando varios revendedores autorizados en distintos pa\u00edses vend\u00edan entradas y paquetes de viaje.<\/p>\n<p>Hay m\u00e1s de 300 pruebas en 32 deportes repartidos por varias ciudades de Francia, e incluso una prueba, la de surf, que se celebra a miles de kil\u00f3metros, en el territorio semiaut\u00f3nomo franc\u00e9s de Tahit\u00ed. Seg\u00fan Paul Caine, presidente de On Location, esto resulta confuso y complicado a la hora de planificar un viaje.<\/p>\n<p>Por qu\u00e9 Tahit\u00ed ser\u00e1 sede de parte de los Juegos Ol\u00edmpicos de Par\u00eds y la pol\u00e9mica que conlleva<\/p>\n<p>&#171;Con cualquier acontecimiento, suele ser muy sencillo, porque suelen ser eventos de un solo lugar o de un solo d\u00eda, por lo que est\u00e1 muy claro con un solo tipo de deporte. Pero cuando se llega a los Juegos Ol\u00edmpicos, la oferta es mucho m\u00e1s compleja&#187;, explica a CNN.<\/p>\n<p>&#171;Se trata de la oferta de hospitalidad m\u00e1s ambiciosa que ha organizado Par\u00eds, lo que significa que realmente quer\u00edan ampliar su oferta como ciudad anfitriona para que la gente pudiera disfrutar de todo lo que Par\u00eds puede ofrecer&#187;, explic\u00f3 Caine. &#171;Realmente no es como lo que se ha visto antes en los Juegos&#187;.<\/p>\n<p>El presidente de Francia, Emmanuel Macron, asiste a una demostraci\u00f3n del equipo franc\u00e9s de esgrima durante su reciente visita al Grand Palais. Cr\u00e9dito: Yoan Valat\/Pool\/Reuters<\/p>\n<p>Los precios oscilan entre unos US$ 175 para ver el golf, que incluye acceso a un sal\u00f3n que sirve comida fresca y alcohol, hasta un paquete de US$ 4.000 que incluye una vista privilegiada de las ceremonias de apertura en el r\u00edo Sena.<\/p>\n<p>Durante las dos semanas, On Location elaborar\u00e1 210 men\u00fas diferentes y 3.815 platillos elaborados por 80 chefs que suman 23 estrellas Michelin. La selecci\u00f3n de vinos, que consta de 10 opciones, es por supuesto toda francesa. Y habr\u00e1 montones de macarons -200.000 para ser exactos- y 3,5 toneladas de queso fresco, adem\u00e1s de 4,6 toneladas de fruta fresca.<\/p>\n<p>Para algunos eventos las entradas ya est\u00e1n agotadas, pero a\u00fan hay disponibilidad para muchos otros, como el tenis en Roland Garros y la esgrima en la reci\u00e9n remodelada sala de exposiciones Grand Palais.<\/p>\n<p>Caine afirma que existe una &#171;fuerte demanda&#187; y que los organizadores est\u00e1n viendo una &#171;amplia gama&#187; de visitantes de distintas edades procedentes de todo el mundo que compran los lujosos paquetes, incluidas familias, viajeros en solitario y empresas que buscan agasajar a sus mejores clientes.<\/p>\n<p>&#171;Eso es lo bueno de los Juegos Ol\u00edmpicos, que no hay un cliente definido. Hay un abanico muy amplio de clientes&#187;, afirma.<\/p>\n<p>Simone Biles habla de su regreso a los Juegos Ol\u00edmpicos tras priorizar su salud mental<\/p>\n<p>Un &#171;gran momento cultural&#187; para las marcas<\/p>\n<p>M\u00e1s all\u00e1 de los atletas, los Juegos Ol\u00edmpicos son un escaparate para las marcas que han firmado acuerdos multimillonarios con el Comit\u00e9 Ol\u00edmpico Internacional para convertirse en socios oficiales de los Juegos y de los miles de millones de televidentes que los siguen.<\/p>\n<p>La cervecera Anheuser-Busch InBev ha optado por promocionar Corona Cero, una marca sin alcohol que no se vende en Estados Unidos. (No se han revelado los t\u00e9rminos financieros).<\/p>\n<p>Corona Cero, una cerveza sin alcohol, estar\u00e1 presente en los Juegos. Cr\u00e9dito: Kenzo Tribouillard\/AFP\/Getty Images<\/p>\n<p>Se eligi\u00f3 Corona Cero porque &#171;es la marca m\u00e1s global que tenemos en la empresa, y \u00e9sta es una asociaci\u00f3n global&#187;, declar\u00f3 anteriormente Marcel Marcondes, director de Marketing de Anheuser-Busch InBev. &#171;S\u00f3lo tiene sentido para nosotros ir con la marca que tenemos el mayor alcance a nivel mundial&#187;.<\/p>\n<p>En Estados Unidos, los espectadores ver\u00e1n anuncios de Michelob Ultra, que es la &#171;cerveza patrocinadora exclusiva&#187; de los atletas del Team USA hasta 2028 y ser\u00e1 la cerveza oficial de los Juegos de Verano de Los \u00c1ngeles 2028.<\/p>\n<p>Eventos ostentosos como \u00e9stos son la forma en que Sapphire &#171;aporta m\u00e1s valor y eleva el estilo de vida y las cosas que importan a los miembros de nuestra tarjeta&#187;, dijo Palmer, de Chase, que no quiso revelar el precio de todos sus eventos. &#171;Y, por supuesto, tambi\u00e9n ayuda a dar a conocer nuestro nombre y atraer a nuevos miembros de la tarjeta, \u00bfno?&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nueva York (CNN) &#8212; El pardo y anta\u00f1o contaminado r\u00edo Sena de Par\u00eds no es el m\u00e1s brillante ni el m\u00e1s glamuroso, especialmente en una ciudad llena de lugares emblem\u00e1ticos. Pero Chase espera que este curso de agua se convierta en todo un espect\u00e1culo. En los Juegos Ol\u00edmpicos de Verano de 2024, que comienzan oficialmente [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1451275","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados - Noticias\" \/>\n<meta property=\"og:description\" content=\"Nueva York (CNN) &#8212; El pardo y anta\u00f1o contaminado r\u00edo Sena de Par\u00eds no es el m\u00e1s brillante ni el m\u00e1s glamuroso, especialmente en una ciudad llena de lugares emblem\u00e1ticos. Pero Chase espera que este curso de agua se convierta en todo un espect\u00e1culo. En los Juegos Ol\u00edmpicos de Verano de 2024, que comienzan oficialmente [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-20T01:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados\",\"datePublished\":\"2024-07-20T01:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/\"},\"wordCount\":2024,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/\",\"name\":\"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-07-20T01:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados - Noticias","og_description":"Nueva York (CNN) &#8212; El pardo y anta\u00f1o contaminado r\u00edo Sena de Par\u00eds no es el m\u00e1s brillante ni el m\u00e1s glamuroso, especialmente en una ciudad llena de lugares emblem\u00e1ticos. Pero Chase espera que este curso de agua se convierta en todo un espect\u00e1culo. En los Juegos Ol\u00edmpicos de Verano de 2024, que comienzan oficialmente [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/","og_site_name":"Noticias","article_published_time":"2024-07-20T01:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/"},"author":{"name":"","@id":""},"headline":"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados","datePublished":"2024-07-20T01:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/"},"wordCount":2024,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/","url":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/","name":"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-07-20T01:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Los primeros Juegos Ol\u00edmpicos tras la pandemia emocionan m\u00e1s a los patrocinadores que a los aficionados","url":"http:\/\/noticiasya.com\/tampa\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2024\/07\/19\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-07-20T01:03:53Z","datePublished":"2024-07-20T01:03:53Z","dateModified":"2024-07-20T01:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Los primeros Juegos Ol\\u00edmpicos tras la pandemia emocionan m\\u00e1s a los patrocinadores que a los aficionados\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/07\\\/19\\\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/07\\\/19\\\/primeros-juegos-olimpicos-pandemia-patrocinadores-aficionados-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-07-20T01:03:53Z\",\"datePublished\":\"2024-07-20T01:03:53Z\",\"dateModified\":\"2024-07-20T01:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451370,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/24\/ministerio-interior-francia-rechazo-solicitudes-acreditacion-juegos-olimpicos-trax\/","url_meta":{"origin":1451275,"position":0},"title":"El Ministerio del Interior franc\u00e9s rechaz\u00f3 unas 5.000 solicitudes de acreditaci\u00f3n de seguridad para voluntarios y trabajadores de los Juegos Ol\u00edmpicos, de las cuales unas 1.000 fueron bloqueadas por sospechas de intromisi\u00f3n o espionaje","author":"","date":"julio 24, 2024","format":false,"excerpt":"(CNN) -- El Ministerio del Interior de Francia rechaz\u00f3 alrededor de 5.000 solicitudes de acreditaci\u00f3n de seguridad para voluntarios y trabajadores de los Juegos Ol\u00edmpicos, y aproximadamente 1.000 de esos casos fueron bloqueados debido a sospechas de intromisi\u00f3n o espionaje.El Ministerio del Interior indic\u00f3 en un comunicado este martes que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451492,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/30\/olimpicos-aplazan-pruebas-triatlon-masculino-contaminacion-rio-senat-trax\/","url_meta":{"origin":1451275,"position":1},"title":"Autoridades ol\u00edmpicas aplazan pruebas de triatl\u00f3n masculino por contaminaci\u00f3n del r\u00edo Sena","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN) -- La prueba de triatl\u00f3n individual masculino de los Juegos Ol\u00edmpicos de Par\u00eds 2024 fue aplazada debido a la mala calidad del agua del r\u00edo Sena, anunci\u00f3 este lunes el organismo rector de este deporte, el Triatl\u00f3n Mundial.Inicialmente prevista para el martes, el Triatl\u00f3n Mundial, su equipo m\u00e9dico, el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451782,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/12\/recordaremos-juegos-olimpicos-paris-2024-trax\/","url_meta":{"origin":1451275,"position":2},"title":"Lo que siempre recordaremos de los Juegos Ol\u00edmpicos de Par\u00eds 2024","author":"","date":"agosto 12, 2024","format":false,"excerpt":"Par\u00eds (CNN) -- Los Juegos Ol\u00edmpicos de Par\u00eds 2024 fueron realmente incre\u00edbles.Es dif\u00edcil condensar un periodo de dos semanas tan repleto de momentos memorables como estos incre\u00edbles Juegos Ol\u00edmpicos de Par\u00eds, pero \u00e9ste es nuestro mejor intento.Estas son las 12 cosas que siempre recordaremos de los Juegos Ol\u00edmpicos de Verano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451575,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/03\/historias-importantes-primera-semana-juegos-olimpicos-2024-trax\/","url_meta":{"origin":1451275,"position":3},"title":"Las diez noticias m\u00e1s importantes de la primera semana de los Juegos Ol\u00edmpicos de 2024","author":"","date":"agosto 3, 2024","format":false,"excerpt":"(CNN) -- La primera semana pas\u00f3 volando, \u00bfverdad?Los Juegos Ol\u00edmpicos de Verano de 2024 est\u00e1n entrando en su segundo fin de semana, y realmente es para los libros de historia. Desde la incre\u00edble reaparici\u00f3n de Simone Biles hasta la semana de L\u00e9on Marchand en la piscina, pasando por el chico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451520,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/31\/pruebas-triatlon-olimpico-rio-sena-calidad-agua-trax\/","url_meta":{"origin":1451275,"position":4},"title":"Dan luz verde al triatl\u00f3n ol\u00edmpico en el r\u00edo Sena. La calidad del agua mejor\u00f3, seg\u00fan los organizadores","author":"","date":"julio 31, 2024","format":false,"excerpt":"(CNN) -- Las competiciones de triatl\u00f3n se han puesto en marcha este mi\u00e9rcoles en Par\u00eds, despu\u00e9s de que la preocupaci\u00f3n por la calidad del agua del r\u00edo Sena obligara a aplazar la prueba masculina un d\u00eda antes.Durante la noche llovi\u00f3 m\u00e1s en Par\u00eds, pero el Triatl\u00f3n Mundial y Par\u00eds 2024\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448159,"url":"https:\/\/noticiasya.com\/tampa\/2024\/04\/16\/encienden-llama-olimpica-paris-2024-grecia-trax\/","url_meta":{"origin":1451275,"position":5},"title":"Encienden la llama de Par\u00eds 2024 en un evento coreografiado en la cuna de los antiguos Juegos Ol\u00edmpicos","author":"","date":"abril 16, 2024","format":false,"excerpt":"(CNN) -- La llama de los Juegos Ol\u00edmpicos de Par\u00eds 2024 se encendi\u00f3 en Olimpia, la cuna de los antiguos Juegos Ol\u00edmpicos. La llama comenzar\u00e1 ahora su recorrido en un relevo para encender el pebetero que marcar\u00e1 la apertura de los Juegos en julio.Dignatarios y miembros del p\u00fablico se reunieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1451275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1451275"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1451275\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1451275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1451275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1451275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}