{"id":1452187,"date":"2024-08-26T20:03:52","date_gmt":"2024-08-27T03:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/"},"modified":"2024-08-26T20:03:52","modified_gmt":"2024-08-27T03:03:52","slug":"cne-venezuela-denuncia-ataque-pagina-web-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/","title":{"rendered":"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 El Consejo Nacional Electoral de Venezuela (CNE) denunci\u00f3 este lunes, sin presentar pruebas, que su p\u00e1gina web fue objeto de un ataque cibern\u00e9tico, lo que volvi\u00f3 a afectar el acceso de los usuarios, apenas unas horas despu\u00e9s de que volviera en l\u00ednea, tras un mes de permanecer ca\u00edda.<\/p>\n<p>Este nuevo ataque, seg\u00fan el CNE, se dio &#171;contra los centros de divulgaci\u00f3n, donde se encuentra alojada la p\u00e1gina web oficial&#187;, inform\u00f3 la cadena estatal VTV.<\/p>\n<p>Juan Delpino, rector del CNE, reconoce falta de transparencia y veracidad en las elecciones de Venezuela<\/p>\n<p>&#171;Este incidente ha sido identificado t\u00e9cnicamente como un ataque de denegaci\u00f3n de servicio, cuyo objetivo es saturar los enlaces de telecomunicaciones, para afectar el acceso a la p\u00e1gina web&#187;, agreg\u00f3 VTV.<\/p>\n<p>Seg\u00fan la cadena estatal, el ataque proviene de &#171;direcciones IP ubicadas en el exterior, lo que indica que se trata de un ataque dirigido desde fuera del pa\u00eds&#187;.<\/p>\n<p>La televisora agreg\u00f3 que personal t\u00e9cnico ya trabaja para restablecer el acceso a la p\u00e1gina.<\/p>\n<p>CNN intenta obtener m\u00e1s detalles del incidente de parte del CNE.<\/p>\n<p>La denuncia surge luego de que la p\u00e1gina volviera en l\u00ednea casi un mes despu\u00e9s de las elecciones presidenciales del 28 de julio y sin contener los resultados de esa contienda.<\/p>\n<p>La p\u00e1gina se hab\u00eda mantenido ca\u00edda luego de las elecciones. Aunque las autoridades electorales no hab\u00edan hablado sobre el sitio directamente, s\u00ed hab\u00edan dicho que el CNE fue objeto de ciberataques, aunque no se present\u00f3 pruebas de forma p\u00fablica.<\/p>\n<p>Este lunes, la autoridad electoral dijo en un comunicado que publicar\u00eda los resultados electorales en cumplimiento a una sentencia de la Sala Electoral del Tribunal Supremo de Justicia (TSJ), que dio por v\u00e1lidos los resultados anunciados que dieron la victoria al presidente Nicol\u00e1s Maduro y que han sido cuestionados por la oposici\u00f3n y la mayor parte de la comunidad internacional. Tanto el CNE como el Tribunal est\u00e1n encabezados por funcionarios afines al chavismo.<\/p>\n<p>\u2013\u2013 Osmary Hern\u00e1ndez colabor\u00f3 con este reporte<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 El Consejo Nacional Electoral de Venezuela (CNE) denunci\u00f3 este lunes, sin presentar pruebas, que su p\u00e1gina web fue objeto de un ataque cibern\u00e9tico, lo que volvi\u00f3 a afectar el acceso de los usuarios, apenas unas horas despu\u00e9s de que volviera en l\u00ednea, tras un mes de permanecer ca\u00edda. Este nuevo ataque, seg\u00fan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452187","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013\u2013 El Consejo Nacional Electoral de Venezuela (CNE) denunci\u00f3 este lunes, sin presentar pruebas, que su p\u00e1gina web fue objeto de un ataque cibern\u00e9tico, lo que volvi\u00f3 a afectar el acceso de los usuarios, apenas unas horas despu\u00e9s de que volviera en l\u00ednea, tras un mes de permanecer ca\u00edda. Este nuevo ataque, seg\u00fan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-27T03:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web\",\"datePublished\":\"2024-08-27T03:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/\"},\"wordCount\":390,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/\",\"name\":\"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-27T03:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/","og_locale":"es_ES","og_type":"article","og_title":"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013\u2013 El Consejo Nacional Electoral de Venezuela (CNE) denunci\u00f3 este lunes, sin presentar pruebas, que su p\u00e1gina web fue objeto de un ataque cibern\u00e9tico, lo que volvi\u00f3 a afectar el acceso de los usuarios, apenas unas horas despu\u00e9s de que volviera en l\u00ednea, tras un mes de permanecer ca\u00edda. Este nuevo ataque, seg\u00fan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/","og_site_name":"Noticias","article_published_time":"2024-08-27T03:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/"},"author":{"name":"","@id":""},"headline":"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web","datePublished":"2024-08-27T03:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/"},"wordCount":390,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/","url":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/","name":"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-27T03:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\u00e1gina web","url":"http:\/\/noticiasya.com\/tampa\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2024\/08\/26\/cne-venezuela-denuncia-ataque-pagina-web-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-27T03:03:52Z","datePublished":"2024-08-27T03:03:52Z","dateModified":"2024-08-27T03:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Consejo Nacional Electoral de Venezuela denuncia, sin presentar pruebas, otro ataque contra su p\\u00e1gina web\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/26\\\/cne-venezuela-denuncia-ataque-pagina-web-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/26\\\/cne-venezuela-denuncia-ataque-pagina-web-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-27T03:03:52Z\",\"datePublished\":\"2024-08-27T03:03:52Z\",\"dateModified\":\"2024-08-27T03:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1452219,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/27\/protestas-elecciones-venezuela-un-mes-oposicion-oficialismo-orix\/","url_meta":{"origin":1452187,"position":0},"title":"Oposici\u00f3n y oficialismo vuelven a las calles de Venezuela un mes despu\u00e9s de las elecciones: as\u00ed llegan las protestas","author":"","date":"agosto 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Este mi\u00e9rcoles se cumple un mes de las elecciones presidenciales en Venezuela, en las que el Consejo Nacional Electoral (CNE) dio por ganador al presidente Nicol\u00e1s Maduro, sin que hasta la fecha se conozcan los resultados detallados de los comicios por centros y mesas de votaci\u00f3n. Han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451513,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/30\/actas-elecciones-presidenciales-venezuela-direcciones-web-orix\/","url_meta":{"origin":1452187,"position":1},"title":"\u00bfD\u00f3nde est\u00e1n las actas de las\u00a0elecciones presidenciales de Venezuela? Algunas de ellas podr\u00edan estar en\u00a0dos\u00a0direcciones web","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Consejo Nacional Electoral (CNE) no ha publicado los resultados detallados por colegio electoral y mesa de votaci\u00f3n que respaldan el anuncio de la victoria del presidente Nicol\u00e1s Maduro en las elecciones presidenciales del domingo, pero las actas que contienen esos resultados ya circulan en internet, seg\u00fan pudo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452182,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/26\/maria-corina-machado-convoca-nueva-jornada-de-protestas-venezuela-orix\/","url_meta":{"origin":1452187,"position":2},"title":"Mar\u00eda Corina Machado convoca a nueva jornada de protestas en Venezuela y el mundo a un mes de las elecciones presidenciales del 28 de julio","author":"","date":"agosto 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La l\u00edder opositora venezolana Mar\u00eda Corina Machado convoc\u00f3 este lunes a una nueva jornada de protestas en el pa\u00eds y el mundo para este mi\u00e9rcoles, cuando se cumple un mes de las elecciones presidenciales del 28 de julio, en las que la oposici\u00f3n asegura que triunf\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461317,"url":"https:\/\/noticiasya.com\/tampa\/2025\/04\/17\/luisa-gonzalez-denuncia-irregularidades-ecuador-orix\/","url_meta":{"origin":1452187,"position":3},"title":"Luisa Gonz\u00e1lez denuncia nuevamente supuestas &#171;irregularidades&#187; en elecciones en Ecuador","author":"","date":"abril 17, 2025","format":false,"excerpt":"La excandidata del Movimiento Revoluci\u00f3n Ciudadana, Luisa Gonz\u00e1lez, denunci\u00f3 nuevamente este mi\u00e9rcoles, a trav\u00e9s de un video publicado en su cuenta de X, supuestas irregularidades en las elecciones presidenciales y exigi\u00f3 al Consejo Nacional Electoral (CNE) de Ecuador que publique \u201ctodas las actas firmadas\u201d.El domingo, Gonz\u00e1lez denunci\u00f3 sin presentar pruebas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455042,"url":"https:\/\/noticiasya.com\/tampa\/2024\/10\/11\/venezuela-maduro-tsj-ratifica-sentencia-cne-elecciones-orix\/","url_meta":{"origin":1452187,"position":4},"title":"El TSJ de Venezuela ratifica la sentencia que valid\u00f3 la proclamaci\u00f3n de Maduro como ganador de las elecciones","author":"","date":"octubre 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Sala Constitucional del Tribunal Supremo de Justicia (TSJ) de Venezuela ratific\u00f3 este viernes la controvertida sentencia de la Sala Electoral que en agosto valid\u00f3 la decisi\u00f3n del Consejo Nacional Electoral (CNE) de proclamar al presidente Nicol\u00e1s Maduro ganador de las elecciones del 28 de julio.El fallo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452203,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/27\/edmundo-gonzalez-no-asiste-segunda-citacion-ministerio-publico-orix\/","url_meta":{"origin":1452187,"position":5},"title":"Edmundo Gonz\u00e1lez no asiste a segunda citaci\u00f3n ante el Ministerio P\u00fablico venezolano","author":"","date":"agosto 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El candidato presidencial opositor, Edmundo Gonz\u00e1lez Urrutia, no asisti\u00f3 este martes a la segunda citaci\u00f3n del Ministerio P\u00fablico de Venezuela (MP). Minutos antes del horario de la comparecencia, la Plataforma Unitaria Democr\u00e1tica denunci\u00f3 el \"acoso judicial\u201d al cual est\u00e1 sometido Gonz\u00e1lez Urrutia en una publicaci\u00f3n en X.\"La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1452187"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452187\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1452187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1452187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1452187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}