{"id":1452250,"date":"2024-08-28T16:03:40","date_gmt":"2024-08-28T23:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/"},"modified":"2024-08-28T16:03:40","modified_gmt":"2024-08-28T23:03:40","slug":"cidh-informe-crisis-drechos-humanos-venezuela-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/","title":{"rendered":"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 La Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) se\u00f1al\u00f3 en un informe que en Venezuela se registra una \u201cgrave crisis\u201d que incluye uso arbitrario de la fuerza, detenciones arbitrarias, persecuci\u00f3n judicial, restricci\u00f3n a la libertad de expresi\u00f3n y obst\u00e1culos a la labor de organizaciones para la defensa de los derechos humanos.<\/p>\n<p>La presidenta del organismo, Roberta Clarke, present\u00f3 este mi\u00e9rcoles el reporte ante el Consejo Permanente de la Organizaci\u00f3n de los Estados Americanos (OEA), donde resalt\u00f3 que al menos 23 personas han muerto en el marco del conflicto poselectoral.<\/p>\n<p>\u201cMuertes atribuibles a fuerzas del Estado, fuerzas militares, polic\u00edas y colectivos que act\u00faan con el consentimiento del Estado\u201d, dijo.<\/p>\n<p>La comisionada tambi\u00e9n denunci\u00f3 la detenci\u00f3n arbitraria de opositores y el hostigamiento de personas que simplemente no reconocen los resultados anunciados por las autoridades electorales \u2015encabezadas por funcionarios afines al chavismo y que hasta ahora no han publicado las actas desglosadas por centros de votaci\u00f3n, como han pedido varios gobiernos.<\/p>\n<p>&#171;No tenemos miedo\u201d: as\u00ed se manifiesta la oposici\u00f3n de Venezuela en calles de Caracas<\/p>\n<p>\u201cEstamos exhortando al Estado a que ponga fin de inmediato a la penalizaci\u00f3n, el hostigamiento y la persecuci\u00f3n de los defensores de los derechos humanos. La democracia, el orden y el Estado de derecho se deben reestablecer\u201d, dijo Clarke.<\/p>\n<p>CNN intenta comunicarse con el Ministerio de Comunicaci\u00f3n de Venezuela para obtener una reacci\u00f3n a este informe.<\/p>\n<p>Desde 2017, el Gobierno de Venezuela anunci\u00f3 que empezar\u00eda el proceso formal para retirarse de la OEA y que dejar\u00eda de participar en sus reuniones. Por su parte, el secretario general, Luis Almagro, ha se\u00f1alado que la posici\u00f3n de la OEA es que Venezuela sigue siendo Estado miembro.<\/p>\n<p>Embajadores debaten sobre la crisis<\/p>\n<p>El embajador de Uruguay en la OEA, Washington Abdala, hizo un llamado a la comunidad internacional a luchar al lado de quienes buscan la democracia en Venezuela.<\/p>\n<p>\u201cLos venezolanos que est\u00e1n dentro del pa\u00eds o los que est\u00e1n afuera sienten que est\u00e1n devaluando su gesta, su sacrificio. O nos ponemos del lado del coraje o nos ubicamos del lado de la debilidad. Punto (\u2026) O con la democracia o con los asesinos de la democracia\u201d, dijo.<\/p>\n<p>\u201cHay 30 millones de venezolanos que suplican por paz, respeto y democracia. \u00bfAlguien los puede o\u00edr o est\u00e1n sentenciados a vivir en el infierno?\u201d, plante\u00f3 el representante de Uruguay, uno de los 12 convocantes a la sesi\u00f3n de este mi\u00e9rcoles.<\/p>\n<p>El embajador de Paraguay, Ra\u00fal Florent\u00edn, dijo que \u201cno hay otro camino que la publicaci\u00f3n cuanto antes de las actas electorales y que se proceda a la verificaci\u00f3n imparcial e independiente de las elecciones&#187; en Venezuela.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 La Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) se\u00f1al\u00f3 en un informe que en Venezuela se registra una \u201cgrave crisis\u201d que incluye uso arbitrario de la fuerza, detenciones arbitrarias, persecuci\u00f3n judicial, restricci\u00f3n a la libertad de expresi\u00f3n y obst\u00e1culos a la labor de organizaciones para la defensa de los derechos humanos. La presidenta [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452250","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013\u2013 La Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) se\u00f1al\u00f3 en un informe que en Venezuela se registra una \u201cgrave crisis\u201d que incluye uso arbitrario de la fuerza, detenciones arbitrarias, persecuci\u00f3n judicial, restricci\u00f3n a la libertad de expresi\u00f3n y obst\u00e1culos a la labor de organizaciones para la defensa de los derechos humanos. La presidenta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-28T23:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela\",\"datePublished\":\"2024-08-28T23:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/\"},\"wordCount\":492,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/\",\"name\":\"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-28T23:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013\u2013 La Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) se\u00f1al\u00f3 en un informe que en Venezuela se registra una \u201cgrave crisis\u201d que incluye uso arbitrario de la fuerza, detenciones arbitrarias, persecuci\u00f3n judicial, restricci\u00f3n a la libertad de expresi\u00f3n y obst\u00e1culos a la labor de organizaciones para la defensa de los derechos humanos. La presidenta [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-28T23:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/"},"author":{"name":"","@id":""},"headline":"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela","datePublished":"2024-08-28T23:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/"},"wordCount":492,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/","name":"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-28T23:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La CIDH presenta informe de \u201cgrave crisis\u201d de DD.HH. en Venezuela","url":"http:\/\/noticiasya.com\/tampa\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2024\/08\/28\/cidh-informe-crisis-drechos-humanos-venezuela-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-28T23:03:40Z","datePublished":"2024-08-28T23:03:40Z","dateModified":"2024-08-28T23:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La CIDH presenta informe de \\u201cgrave crisis\\u201d de DD.HH. en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/28\\\/cidh-informe-crisis-drechos-humanos-venezuela-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/28\\\/cidh-informe-crisis-drechos-humanos-venezuela-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-28T23:03:40Z\",\"datePublished\":\"2024-08-28T23:03:40Z\",\"dateModified\":\"2024-08-28T23:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472940,"url":"https:\/\/noticiasya.com\/tampa\/2026\/04\/07\/cidh-medicos-cubanos-informe-orix\/","url_meta":{"origin":1452250,"position":0},"title":"Un informe de la CIDH pone la lupa en las misiones m\u00e9dicas de Cuba: estos son los hallazgos","author":"","date":"abril 7, 2026","format":false,"excerpt":"Las misiones m\u00e9dicas internacionales de Cuba, piedra angular de d\u00e9cadas en la pol\u00edtica exterior de su gobierno socialista, est\u00e1n bajo la lupa en medio de la fuerte crisis que enfrenta la isla por sus problemas econ\u00f3micos estructurales y la creciente presi\u00f3n de Estados Unidos. Un nuevo informe de la Comisi\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457186,"url":"https:\/\/noticiasya.com\/tampa\/2025\/01\/03\/cidh-medidas-cautelares-gendarme-argentino-venezuela-nahuel-orix\/","url_meta":{"origin":1452250,"position":1},"title":"La CIDH otorga medidas cautelares a favor del gendarme argentino detenido en Venezuela","author":"","date":"enero 3, 2025","format":false,"excerpt":"La Comisi\u00f3n Interamericana de Derechos Humanos (CIDH) anunci\u00f3 este viernes medidas cautelares en beneficio del gendarme argentino Nahuel Agust\u00edn Gallo, detenido en Venezuela desde el pasado 8 de diciembre.Seg\u00fan la CIDH, Gallo \u201cse encuentra en una situaci\u00f3n de gravedad y urgencia toda vez que sus derechos a la vida e\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445429,"url":"https:\/\/noticiasya.com\/tampa\/2024\/02\/14\/quien-es-rocio-san-miguel-la-activista-actualmente-detenida-en-venezuela\/","url_meta":{"origin":1452250,"position":2},"title":"Qui\u00e9n es Roc\u00edo San Miguel, la activista actualmente detenida en Venezuela","author":"","date":"febrero 14, 2024","format":false,"excerpt":"(CNN) -- Roc\u00edo del Carmen San Miguel Sosa es una ciudadana venezolano-espa\u00f1ola, de 57 a\u00f1os, de profesi\u00f3n abogada con especializaci\u00f3n en Derecho y pol\u00edtica Internacional. Tambi\u00e9n es mag\u00edster en el Instituto de Altos Estudios de la Defensa Nacional (Iaeden).Se desempe\u00f1a como presidenta de la asociaci\u00f3n civil Control Ciudadano, organismo especializado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469913,"url":"https:\/\/noticiasya.com\/tampa\/2026\/01\/08\/centro-comercial-prision-torturas-denuncias-el-helicoide-orix\/","url_meta":{"origin":1452250,"position":3},"title":"De centro comercial a centro de tortura, seg\u00fan denuncias: esto sabemos sobre El Helicoide, la c\u00e1rcel m\u00e1s temida de Venezuela","author":"","date":"enero 8, 2026","format":false,"excerpt":"Un enorme edificio con forma de espiral que iba a ser el s\u00edmbolo del progreso de Venezuela es, desde hace a\u00f1os, una imagen que infunde temor a muchos venezolanos. La sede del Servicio Bolivariano de Inteligencia Nacional (Sebin), conocida como El Helicoide, es la prisi\u00f3n en la que decenas de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452414,"url":"https:\/\/noticiasya.com\/tampa\/2024\/09\/04\/represion-disidencia-politica-mas-mortifera-ultimos-anos-trax\/","url_meta":{"origin":1452250,"position":4},"title":"La represi\u00f3n de la disidencia pol\u00edtica en Venezuela es la m\u00e1s mort\u00edfera de los \u00faltimos a\u00f1os, seg\u00fan Human Rights Watch","author":"","date":"septiembre 4, 2024","format":false,"excerpt":"(CNN) -- La represi\u00f3n de la disidencia pol\u00edtica en Venezuela con motivo de las controvertidas elecciones presidenciales es la m\u00e1s mort\u00edfera de los \u00faltimos a\u00f1os, seg\u00fan un nuevo an\u00e1lisis de Human Rights Watch.El grupo de derechos humanos dice que ha documentado 11 asesinatos que, seg\u00fan afirma, tuvieron lugar en el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456808,"url":"https:\/\/noticiasya.com\/tampa\/2024\/12\/20\/sentencia-cidh-el-salvador-violo-derechos-beatriz-aborto-orix\/","url_meta":{"origin":1452250,"position":5},"title":"El Salvador viol\u00f3 los derechos de &#171;Beatriz&#187;, dictamina la Corte IDH en caso clave sobre el aborto en el pa\u00eds","author":"","date":"diciembre 20, 2024","format":false,"excerpt":"La Corte Interamericana de Derechos Humanos declar\u00f3 responsable a la Rep\u00fablica de El Salvador de violar los derechos a la integridad personal, la vida privada y la salud en el denominado caso \u201cBeatriz\u201d y deber\u00e1 adoptar \u201ctodas las medidas normativas necesarias\u201d para que no se repita una situaci\u00f3n similar, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1452250"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452250\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1452250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1452250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1452250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}