{"id":1452310,"date":"2024-08-30T20:03:56","date_gmt":"2024-08-31T03:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/"},"modified":"2024-08-30T20:03:56","modified_gmt":"2024-08-31T03:03:56","slug":"fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/","title":{"rendered":"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense"},"content":{"rendered":"<p>(CNN) &#8212; Fuerzas de EE.UU. y de seguridad iraqu\u00edes mataron a m\u00e1s de una decena de agentes de ISIS en una redada en la madrugada del jueves en el oeste de Iraq, inform\u00f3 el ej\u00e9rcito estadounidense.<\/p>\n<p>Los 15 agentes de ISIS que murieron estaban \u201carmados con numerosas armas, granadas y cinturones explosivos suicidas\u201d, dijo el Comando Central de EE.UU. (CENTCOM, por sus siglas en ingl\u00e9s) en un comunicado este viernes.<\/p>\n<p>No hubo indicios de v\u00edctimas civiles, dijo el CENTCOM.<\/p>\n<p>\u201cEsta operaci\u00f3n estaba dirigida a los l\u00edderes de ISIS para interrumpir y degradar la capacidad de ISIS de planear, organizar y llevar a cabo ataques contra civiles iraqu\u00edes, as\u00ed como ciudadanos estadounidenses, aliados y socios en toda la regi\u00f3n y m\u00e1s all\u00e1\u201d, de acuerdo con el comunicado.<\/p>\n<p>Iraq aplaza los planes de finalizar la presencia militar estadounidense en medio de las tensiones regionales<\/p>\n<p>El ej\u00e9rcito estadounidense dijo que las fuerzas de seguridad iraqu\u00edes est\u00e1n trabajando \u201cpara explotar a\u00fan m\u00e1s los lugares atacados\u201d, ya que ISIS sigue siendo una \u201camenaza para la regi\u00f3n, nuestros aliados, as\u00ed como nuestra patria\u201d.<\/p>\n<p>El CENTCOM dijo que EE.UU. seguir\u00e1 persiguiendo agresivamente los operativos de ISIS con la coalici\u00f3n y socios iraqu\u00edes.<\/p>\n<p>CNN inform\u00f3 a principios de este mes que Iraq pospuso el anuncio de una fecha final para la operaci\u00f3n Inherent Resolve, la operaci\u00f3n militar estadounidense para combatir a ISIS, por \u201cacontecimientos recientes\u201d, lo que plantea interrogantes sobre el futuro de la presencia militar estadounidense en el estado del Golfo en medio de una mayor tensi\u00f3n en la regi\u00f3n.<\/p>\n<p>EE.UU. tiene actualmente en Iraq unos 2.500 soldados que operan all\u00ed con capacidad de \u201casesoramiento y asistencia\u201d desde diciembre de 2021, cuando el ej\u00e9rcito estadounidense anunci\u00f3 el fin de su papel de combate en el pa\u00eds.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Fuerzas de EE.UU. y de seguridad iraqu\u00edes mataron a m\u00e1s de una decena de agentes de ISIS en una redada en la madrugada del jueves en el oeste de Iraq, inform\u00f3 el ej\u00e9rcito estadounidense. Los 15 agentes de ISIS que murieron estaban \u201carmados con numerosas armas, granadas y cinturones explosivos suicidas\u201d, dijo el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452310","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Fuerzas de EE.UU. y de seguridad iraqu\u00edes mataron a m\u00e1s de una decena de agentes de ISIS en una redada en la madrugada del jueves en el oeste de Iraq, inform\u00f3 el ej\u00e9rcito estadounidense. Los 15 agentes de ISIS que murieron estaban \u201carmados con numerosas armas, granadas y cinturones explosivos suicidas\u201d, dijo el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-31T03:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense\",\"datePublished\":\"2024-08-31T03:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/\",\"name\":\"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-31T03:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense - Noticias","og_description":"(CNN) &#8212; Fuerzas de EE.UU. y de seguridad iraqu\u00edes mataron a m\u00e1s de una decena de agentes de ISIS en una redada en la madrugada del jueves en el oeste de Iraq, inform\u00f3 el ej\u00e9rcito estadounidense. Los 15 agentes de ISIS que murieron estaban \u201carmados con numerosas armas, granadas y cinturones explosivos suicidas\u201d, dijo el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-31T03:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/"},"author":{"name":"","@id":""},"headline":"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense","datePublished":"2024-08-31T03:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/","name":"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-31T03:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense","url":"http:\/\/noticiasya.com\/tampa\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-31T03:03:56Z","datePublished":"2024-08-31T03:03:56Z","dateModified":"2024-08-31T03:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Fuerzas de EE.UU. y de seguridad iraqu\\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\\u00fan el ej\\u00e9rcito estadounidense\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/30\\\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/30\\\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-31T03:03:56Z\",\"datePublished\":\"2024-08-31T03:03:56Z\",\"dateModified\":\"2024-08-31T03:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1455457,"url":"https:\/\/noticiasya.com\/tampa\/2024\/10\/30\/hasta-35-operativos-isis-murieron-siria-ejercito-eeuu-trax\/","url_meta":{"origin":1452310,"position":0},"title":"Hasta 35 agentes de ISIS murieron en ataques estadounidenses en Siria, seg\u00fan el ej\u00e9rcito de EE.UU.","author":"","date":"octubre 30, 2024","format":false,"excerpt":"(CNN) -- Hasta 35 agentes de ISIS murieron en ataques estadounidenses contra m\u00faltiples campamentos de ISIS en Siria el lunes por la noche, anunci\u00f3 el mi\u00e9rcoles el ej\u00e9rcito de Estados Unidos.\"Las fuerzas del Comando Central de EE.UU. llevaron a cabo una serie de ataques contra varios campamentos conocidos de ISIS\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452318,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/31\/siete-militares-estadounidenses-heridos-isis-iraq-trax\/","url_meta":{"origin":1452310,"position":1},"title":"Siete militares estadounidenses resultaron heridos durante una redada en la que murieron 15 operativos de ISIS en Iraq","author":"","date":"agosto 31, 2024","format":false,"excerpt":"(CNN) --\u00a0Siete militares estadounidenses resultaron heridos en una incursi\u00f3n en Irak el jueves por la noche en la que murieron 15 miembros del ISIS, seg\u00fan informaron tres funcionarios de defensa.Cinco de los miembros del personal resultaron heridos durante la operaci\u00f3n, y uno de ellos fue evacuado para recibir tratamiento adicional.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452363,"url":"https:\/\/noticiasya.com\/tampa\/2024\/09\/02\/estados-unidos-captura-lider-isis-ejercito-trax\/","url_meta":{"origin":1452310,"position":2},"title":"Estados Unidos captura a un l\u00edder de ISIS que ayud\u00f3 a escapar a miembros del grupo terrorista, seg\u00fan el Ej\u00e9rcito","author":"","date":"septiembre 2, 2024","format":false,"excerpt":"(CNN) --\u00a0 Estados Unidos captur\u00f3 a un l\u00edder de ISIS que ayud\u00f3 a fugitivos del grupo terrorista despu\u00e9s de que huyeran de un centro de detenci\u00f3n en Siria, seg\u00fan el Comando Central de Estados Unidos.En colaboraci\u00f3n con las Fuerzas Democr\u00e1ticas Sirias, EE.UU. captur\u00f3 a Khaled Ahmed al-Dandal la madrugada del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464861,"url":"https:\/\/noticiasya.com\/tampa\/2025\/07\/25\/ejercito-mata-lider-isis-siria-trax\/","url_meta":{"origin":1452310,"position":3},"title":"El Ej\u00e9rcito de Estados Unidos mata a l\u00edder de ISIS en Siria","author":"","date":"julio 25, 2025","format":false,"excerpt":"El Ej\u00e9rcito de Estados Unidos mat\u00f3 a un alto l\u00edder de ISIS en una operaci\u00f3n en Siria este viernes, as\u00ed como a dos de sus hijos, tambi\u00e9n vinculados al grupo, seg\u00fan un comunicado del Comando Central de Estados Unidos (CENTCOM, por sus siglas en ingl\u00e9s).El l\u00edder, Dhiya\u2019 Zawba Muslih al-Hardani,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469676,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/30\/agentes-isis-muerto-capturados-ataques-trax\/","url_meta":{"origin":1452310,"position":4},"title":"Cerca de dos docenas de agentes de ISIS han muerto o han sido capturados desde los ataques de represalia de EE.UU. este mes","author":"","date":"diciembre 30, 2025","format":false,"excerpt":"Aproximadamente dos docenas de agentes de ISIS han muerto o han sido capturados en Siria por fuerzas de EE.UU. y aliadas desde los ataques a\u00e9reos estadounidenses de principios de este mes, realizados en respuesta a la muerte de dos militares de Estados Unidos.Casi 25 agentes murieron o fueron capturados entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471179,"url":"https:\/\/noticiasya.com\/tampa\/2026\/02\/12\/ee-uu-retira-fuerzas-base-militar-siria-trax\/","url_meta":{"origin":1452310,"position":5},"title":"EE.UU. retira sus \u00faltimas fuerzas armadas de una instalaci\u00f3n militar clave en Siria","author":"","date":"febrero 12, 2026","format":false,"excerpt":"Las fuerzas militares de Estados Unidos abandonaron una instalaci\u00f3n militar estrat\u00e9gica en Siria despu\u00e9s de m\u00e1s de una d\u00e9cada \u201ccomo parte de una transici\u00f3n deliberada y basada en condiciones\u201d hacia una presencia estadounidense menor en el pa\u00eds, inform\u00f3 el Comando Central de Estados Unidos (CENTCOM) este jueves.Las fuerzas estadounidenses en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1452310"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452310\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1452310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1452310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1452310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}