{"id":1452311,"date":"2024-08-30T20:03:56","date_gmt":"2024-08-31T03:03:56","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/"},"modified":"2024-08-30T20:03:56","modified_gmt":"2024-08-31T03:03:56","slug":"falcon-9-space-x-tiene-autorizacion-volver-volar-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/","title":{"rendered":"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante"},"content":{"rendered":"<p>(CNN) &#8212; El cohete m\u00e1s prol\u00edfico del mundo, el SpaceX Falcon 9, recibi\u00f3 autorizaci\u00f3n para volar nuevamente, anunciaron los reguladores federales este viernes por la noche, poniendo al veh\u00edculo de nuevo en camino para dos misiones espaciales de alto perfil.<\/p>\n<p>La Administraci\u00f3n Federal de Aviaci\u00f3n de Estados Unidos (FAA, por sus siglas en ingl\u00e9s), que otorga licencias para el lanzamiento de cohetes comerciales, dej\u00f3 en tierra el cohete de SpaceX el 28 de agosto, despu\u00e9s de que explot\u00f3 parte de un propulsor Falcon 9 mientras intentaba aterrizar. Solo dos d\u00edas despu\u00e9s, la agencia dijo que hab\u00eda autorizado al cohete a volver a volar.<\/p>\n<p>SpaceX retrasa el lanzamiento de la misi\u00f3n Polaris Dawn a los cinturones de radiaci\u00f3n de la Tierra<\/p>\n<p>\u201cEl veh\u00edculo Falcon 9 de SpaceX puede volver a las operaciones de vuelo mientras la investigaci\u00f3n general de la anomal\u00eda durante la misi\u00f3n (del mi\u00e9rcoles) sigue abierta, siempre que se cumplan todos los dem\u00e1s requisitos de la licencia\u201d, dijo la agencia en un comunicado enviado por correo electr\u00f3nico. \u201cSpaceX present\u00f3 la solicitud de regreso al vuelo el 29 de agosto y la FAA dio la aprobaci\u00f3n el 30 de agosto\u201d.<\/p>\n<p>La autorizaci\u00f3n del Falcon 9 llega en un momento en que SpaceX tiene dos misiones fundamentales en su manifiesto. La compa\u00f1\u00eda tiene previsto lanzar una misi\u00f3n llamada Polaris Dawn que llevar\u00e1 a una tripulaci\u00f3n de viajeros espaciales civiles en un ambicioso viaje para intentar la primera caminata espacial comercial. El lanzamiento se retras\u00f3 por un problema con los sistemas terrestres y las previsiones de mal tiempo.<\/p>\n<p>Conoce a la tripulaci\u00f3n de 4 personas que lidera la atrevida misi\u00f3n Polaris Dawn deSpaceX<\/p>\n<p>A finales de septiembre, SpaceX tiene previsto enviar a dos astronautas de la NASA a la Estaci\u00f3n Espacial Internacional en Crew-9, una misi\u00f3n que, tras una rotaci\u00f3n de meses, tiene como objetivo traer a casa a la tripulaci\u00f3n de vuelo de prueba de Boeing Starliner en 2025.<\/p>\n<p>Los astronautas de la NASA Suni Williams y Butch Wilmore han estado en el limbo en el laboratorio en \u00f3rbita desde su vuelo en Starliner a principios de junio.<\/p>\n<p>Los raros fracasos del Falcon 9<\/p>\n<p>Los intentos fallidos de aterrizaje del cohete Falcon 9, como el que ocurri\u00f3 el mi\u00e9rcoles, no afectan el \u00e9xito general de una misi\u00f3n de SpaceX. La compa\u00f1\u00eda intenta la maniobra \u00fanicamente para poder renovar y reutilizar los cohetes propulsores, una pr\u00e1ctica que reduce el costo de cada vuelo, de acuerdo con SpaceX.<\/p>\n<p>Hace aproximadamente una d\u00e9cada, SpaceX intentaba aterrizar sus cohetes propulsores despu\u00e9s del vuelo sin \u00e9xito. La compa\u00f1\u00eda incluso comparti\u00f3 un video de las explosiones en 2017.<\/p>\n<p>Sin embargo, en los \u00faltimos a\u00f1os los cohetes Falcon 9 han encontrado su equilibrio de forma rutinaria al regresar a la Tierra.<\/p>\n<p>El cohete Falcon 9 que explot\u00f3 el 28 de agosto fue reacondicionado y vol\u00f3 22 veces antes de estrellarse. No obstante, la misi\u00f3n que lanz\u00f3 el d\u00eda del accidente fue finalmente exitosa, y puso en \u00f3rbita un lote de sat\u00e9lites Starlink que transmiten Internet.<\/p>\n<p>Esa explosi\u00f3n marc\u00f3 la segunda vez en dos meses que una anomal\u00eda impuls\u00f3 a la FAA a abrir una investigaci\u00f3n sobre el Falcon 9, que tambi\u00e9n tiene un historial de cientos de vuelos que se han realizado sin ning\u00fan problema.<\/p>\n<p>Sin embargo, en julio, cuando un Falcon 9 estaba poniendo en \u00f3rbita otro conjunto de sat\u00e9lites Starlink, la etapa superior del cohete, que es distinta del cohete impulsor m\u00e1s bajo, fall\u00f3 abruptamente en pleno vuelo.<\/p>\n<p>Una c\u00e1psula Crew Dragon de SpaceX traer\u00e1 de regreso a la Tierra a la tripulaci\u00f3n del Boeing Starliner<\/p>\n<p>Los sat\u00e9lites no entraron en la \u00f3rbita prevista y la misi\u00f3n en general fue un fracaso.<\/p>\n<p>SpaceX revel\u00f3 m\u00e1s tarde que se produjo una fuga de ox\u00edgeno mientras la segunda etapa del cohete estaba en vuelo. (El ox\u00edgeno l\u00edquido, o LOX, se usa com\u00fanmente como oxidante o propulsor para cohetes). La fuga provoc\u00f3 lo que el CEO de SpaceX, Elon Musk, describi\u00f3 en un momento como un \u201cRUD\u201d (desmontaje r\u00e1pido no programado, por sus siglas en ingl\u00e9s), una frase que la empresa suele utilizar para referirse a una explosi\u00f3n.<\/p>\n<p>Aproximadamente dos semanas despu\u00e9s de esa explosi\u00f3n, la FAA determin\u00f3 que no hab\u00eda \u201cproblemas de seguridad p\u00fablica\u201d involucrados y permiti\u00f3 que el Falcon 9 de SpaceX volviera a volar. Sin embargo, la investigaci\u00f3n de la FAA sobre el percance a\u00fan est\u00e1 en curso, dijo la agencia a CNN este viernes. Esa revisi\u00f3n no est\u00e1 relacionada con la investigaci\u00f3n sobre el aterrizaje fallido del cohete propulsor del 28 de agosto, lo que significa que se est\u00e1n llevando a cabo dos investigaciones sobre incidentes separados del Falcon 9.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El cohete m\u00e1s prol\u00edfico del mundo, el SpaceX Falcon 9, recibi\u00f3 autorizaci\u00f3n para volar nuevamente, anunciaron los reguladores federales este viernes por la noche, poniendo al veh\u00edculo de nuevo en camino para dos misiones espaciales de alto perfil. La Administraci\u00f3n Federal de Aviaci\u00f3n de Estados Unidos (FAA, por sus siglas en ingl\u00e9s), que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452311","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El cohete m\u00e1s prol\u00edfico del mundo, el SpaceX Falcon 9, recibi\u00f3 autorizaci\u00f3n para volar nuevamente, anunciaron los reguladores federales este viernes por la noche, poniendo al veh\u00edculo de nuevo en camino para dos misiones espaciales de alto perfil. La Administraci\u00f3n Federal de Aviaci\u00f3n de Estados Unidos (FAA, por sus siglas en ingl\u00e9s), que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-31T03:03:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante\",\"datePublished\":\"2024-08-31T03:03:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/\"},\"wordCount\":849,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/\",\"name\":\"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-31T03:03:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante - Noticias","og_description":"(CNN) &#8212; El cohete m\u00e1s prol\u00edfico del mundo, el SpaceX Falcon 9, recibi\u00f3 autorizaci\u00f3n para volar nuevamente, anunciaron los reguladores federales este viernes por la noche, poniendo al veh\u00edculo de nuevo en camino para dos misiones espaciales de alto perfil. La Administraci\u00f3n Federal de Aviaci\u00f3n de Estados Unidos (FAA, por sus siglas en ingl\u00e9s), que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-31T03:03:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/"},"author":{"name":"","@id":""},"headline":"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante","datePublished":"2024-08-31T03:03:56+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/"},"wordCount":849,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/","name":"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-31T03:03:56+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El cohete Falcon 9 de SpaceX tiene autorizaci\u00f3n para volar nuevamente con dos misiones de alto perfil por delante","url":"http:\/\/noticiasya.com\/tampa\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2024\/08\/30\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-31T03:03:56Z","datePublished":"2024-08-31T03:03:56Z","dateModified":"2024-08-31T03:03:56Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El cohete Falcon 9 de SpaceX tiene autorizaci\\u00f3n para volar nuevamente con dos misiones de alto perfil por delante\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/30\\\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/30\\\/falcon-9-space-x-tiene-autorizacion-volver-volar-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-31T03:03:56Z\",\"datePublished\":\"2024-08-31T03:03:56Z\",\"dateModified\":\"2024-08-31T03:03:56Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1457243,"url":"https:\/\/noticiasya.com\/tampa\/2025\/01\/05\/cohete-desafiar-dominio-spacex-despegar-trax\/","url_meta":{"origin":1452311,"position":0},"title":"El cohete que podr\u00eda desafiar el dominio de SpaceX est\u00e1 listo para despegar","author":"","date":"enero 5, 2025","format":false,"excerpt":"En una plataforma de lanzamiento de Florida, que ha estado inactiva durante casi dos d\u00e9cadas, un nuevo cohete de aproximadamente 98 metros desarrollado por Blue Origin, la empresa de Jeff Bezos, est\u00e1 listo para su vuelo inaugural.El veh\u00edculo de lanzamiento sin tripulaci\u00f3n, llamado New Glenn, marcar\u00e1 el primer intento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452569,"url":"https:\/\/noticiasya.com\/tampa\/2024\/09\/09\/spacex-lanzamiento-polaris-dawn-trax\/","url_meta":{"origin":1452311,"position":1},"title":"SpaceX prepara el lanzamiento de la tripulaci\u00f3n de Polaris Dawn en una arriesgada excursi\u00f3n a los cinturones de radiaci\u00f3n de la Tierra","author":"","date":"septiembre 9, 2024","format":false,"excerpt":"(CNN) -- La cuenta regresiva ya est\u00e1 en marcha para la \u00faltima misi\u00f3n de SpaceX: un arriesgado y audaz viaje a los cinturones de radiaci\u00f3n Van Allen de la Tierra con una tripulaci\u00f3n de cuatro civiles que pretenden realizar el primer paseo espacial comercial.La misi\u00f3n, bautizada como Polaris Dawn, est\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455061,"url":"https:\/\/noticiasya.com\/tampa\/2024\/10\/12\/spacex-vuelo-prueba-ambicioso-momento-starship-esto-es-lo-que-debes-saber-trax\/","url_meta":{"origin":1452311,"position":2},"title":"SpaceX est\u00e1 a punto de intentar su vuelo de prueba m\u00e1s ambicioso hasta el momento con Starship. Esto es lo que debes saber","author":"","date":"octubre 12, 2024","format":false,"excerpt":"(CNN) -- SpaceX se prepara para lanzar el \u00faltimo vuelo de prueba de Starship, el sistema de cohetes m\u00e1s poderoso jam\u00e1s construido, que alg\u00fan d\u00eda podr\u00eda usarse para transportar humanos a la Luna y Marte.Se espera que el despegue del cohete propulsor Super Heavy, coronado por la nave espacial Starship\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442806,"url":"https:\/\/noticiasya.com\/tampa\/2023\/12\/28\/el-falcon-heavy-de-spacex-lanzara-el-avion-x-37b-uno-de-los-secretos-mas-fascinantes-del-ejercito-de-ee-uu\/","url_meta":{"origin":1452311,"position":3},"title":"El Falcon Heavy de SpaceX lanzar\u00e1 el avi\u00f3n X-37B, uno de los secretos m\u00e1s fascinantes del Ej\u00e9rcito de EE.UU.","author":"","date":"diciembre 28, 2023","format":false,"excerpt":"(CNN) -- El enorme cohete Falcon Heavy de SpaceX volver\u00e1 a surcar los cielos el jueves por la noche, y esta vez lanzar\u00e1 una misteriosa nave espacial para el ej\u00e9rcito estadounidense que llevar\u00e1 a cabo investigaciones de vanguardia.Est\u00e1 previsto que el cohete despegue del Centro Espacial Kennedy de la NASA\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442842,"url":"https:\/\/noticiasya.com\/tampa\/2023\/12\/29\/el-falcon-heavy-de-spacex-lanza-el-avion-x-37b-uno-de-los-secretos-mas-fascinantes-del-ejercito-de-ee-uu\/","url_meta":{"origin":1452311,"position":4},"title":"El Falcon Heavy de SpaceX lanza el avi\u00f3n X-37B, uno de los secretos m\u00e1s fascinantes del Ej\u00e9rcito de EE.UU.","author":"","date":"diciembre 29, 2023","format":false,"excerpt":"(CNN) -- El enorme cohete Falcon Heavy de SpaceX regres\u00f3 a los cielos la noche de este jueves, y esta vez lanz\u00f3 una misteriosa nave espacial para el ej\u00e9rcito estadounidense que llevar\u00e1 a cabo investigaciones de vanguardia.El cohete despeg\u00f3 del Centro Espacial Kennedy de la NASA en Florida a las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468920,"url":"https:\/\/noticiasya.com\/tampa\/2025\/12\/03\/cohete-chino-reutilizable-explota-durante-primera-prueba-orbital-trax\/","url_meta":{"origin":1452311,"position":5},"title":"Cohete chino reutilizable explota durante su primera prueba orbital, en un intento fallido de alcanzar a SpaceX","author":"","date":"diciembre 3, 2025","format":false,"excerpt":"Una empresa espacial privada china envi\u00f3 con \u00e9xito su cohete Zhuque-3 a \u00f3rbita, pero fracas\u00f3 en su intento hist\u00f3rico de volver a aterrizar el veh\u00edculo propulsor el mi\u00e9rcoles.Este fue el primer intento de este tipo realizado por una empresa china mientras el creciente sector espacial comercial del pa\u00eds se apresura\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1452311"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452311\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1452311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1452311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1452311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}