{"id":1452324,"date":"2024-08-31T11:03:52","date_gmt":"2024-08-31T18:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/"},"modified":"2024-08-31T11:03:52","modified_gmt":"2024-08-31T18:03:52","slug":"bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/","title":{"rendered":"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos"},"content":{"rendered":"<p>(CNN) &#8211;Las autoridades declarararon este s\u00e1bado un d\u00eda de luto en la ciudad ucraniana de J\u00e1rkiv, mientras los equipos de rescate y emergencia concluyen sus operaciones tras un ataque con bomba ruso que mat\u00f3 al menos a seis civiles, incluido un ni\u00f1o en un parque infantil.<\/p>\n<p>Al menos 97 personas resultaron heridas, incluidos 24 ni\u00f1os, cuando Mosc\u00fa atac\u00f3 la ciudad con cinco bombas a\u00e9reas guiadas, seg\u00fan las autoridades ucranianas, en uno de los ataques rusos con m\u00e1s impacto en la regi\u00f3n durante el verano.\u00a0Entre los muertos se encontraba Sof\u00eda, de 14 a\u00f1os, que estaba en un parque infantil cuando fue asesinada el viernes, dijo el presidente de Ucrania, Volodymyr Zelensky.<\/p>\n<p>El s\u00e1bado, otras dos personas murieron y al menos 10 resultaron heridas, incluidos dos ni\u00f1os, cuando las fuerzas rusas atacaron la aldea de Cherkaska Lozova, tambi\u00e9n en J\u00e1rkiv.<\/p>\n<p>&#171;Estos horribles y cobardes ataques rusos apuntaron a hogares comunes y a un parque de la ciudad. Rusia tendr\u00e1 que hacerse responsable de todas sus malas acciones&#187;, dijo Zelensky, presionando nuevamente a los aliados occidentales para que aumenten su apoyo militar.<\/p>\n<p>&#171;Necesitamos decisiones, decisiones que puedan tomar nuestros socios, decisiones de aquellos pa\u00edses que tienen el poder para garantizar que tengamos la capacidad de destruir los aviones militares rusos en sus bases, donde la eliminaci\u00f3n de estos terroristas y sus aviones ser\u00e1 m\u00e1s efectiva&#187;, dijo el viernes.<\/p>\n<p>Desaparecieron durante semanas. Ahora Rusia dice que detuvo a dos hombres colombianos sospechosos de luchar por Ucrania<\/p>\n<p>Las fuerzas rusas llevaron a cabo el &#171;bombardeo masivo&#187; de la ciudad utilizando aviones de combate Su-34 que fueron desplegados desde la regi\u00f3n fronteriza de Belgorod, seg\u00fan el jefe de la oficina del fiscal regional de J\u00e1rkiv, Oleksandr Filchakov.<\/p>\n<p>Las bombas a\u00e9reas guiadas de 500 kilogramos fueron lanzadas desde territorio ruso y son muy dif\u00edciles de interceptar, seg\u00fan los funcionarios ucranianos.<\/p>\n<p>&#171;Se trata de una bomba con un m\u00f3dulo de control, lo que significa que el enemigo estaba apuntando espec\u00edficamente a la infraestructura residencial&#187;, dijo este s\u00e1bado el jefe de la administraci\u00f3n militar regional de J\u00e1rkiv, Oleh Syniehubov.<\/p>\n<p>En el ataque de este s\u00e1bado, el ej\u00e9rcito ruso utiliz\u00f3 una bomba guiada FAB-500, que da\u00f1\u00f3 unas 20 casas, seg\u00fan inform\u00f3 la fiscal\u00eda regional. &#171;Una mujer que se encontraba en el epicentro inmediato de la explosi\u00f3n muri\u00f3, as\u00ed como su vecina&#187;, indic\u00f3.<\/p>\n<p>Zelensky ha sostenido que atacar a los aviones que transportan esas bombas es la forma m\u00e1s eficaz de prevenir tales ataques, mientras sigue instando a Estados Unidos y a sus socios occidentales a que levanten las restricciones al uso de armas de largo alcance para atacar objetivos militares en territorio ruso.<\/p>\n<p>Las bombas a\u00e9reas guiadas alcanzaron la infraestructura civil en cuatro distritos de la ciudad en el ataque del viernes por la tarde, dijo Filchakov, y agreg\u00f3 que resultaron da\u00f1ados 82 edificios de apartamentos, 11 casas particulares, tres edificios administrativos, dos establecimientos educativos, 47 centros comerciales, 57 autom\u00f3viles, dos almacenes, 10 garajes y una instalaci\u00f3n empresarial.<\/p>\n<p>Mientras tanto, las evacuaciones de civiles contin\u00faan en la regi\u00f3n de Donetsk, donde las fuerzas rusas pretenden tomar el control de la ciudad estrat\u00e9gica de Pokrovsk. La ciudad sirve como un centro clave para el ej\u00e9rcito ucraniano debido a su f\u00e1cil acceso a Kostiantynivka, otro centro militar. Ucrania utiliza la carretera que conecta los dos para reabastecer las l\u00edneas del frente y evacuar a las v\u00edctimas.<\/p>\n<p>En los \u00faltimos tres d\u00edas, 86 ni\u00f1os han sido evacuados de Kostiantynivka y \u00e1reas cercanas junto con sus padres a medida que se intensifica el bombardeo ruso, dijeron el s\u00e1bado funcionarios regionales. Hab\u00eda casi 2.130 ni\u00f1os viviendo en la comunidad antes de la evacuaci\u00f3n obligatoria.<\/p>\n<p>Los ni\u00f1os y sus padres est\u00e1n siendo sacados en veh\u00edculos blindados de los asentamientos ubicados a menos de 10 kil\u00f3metros (aproximadamente 6,2 millas) de la l\u00ednea del frente, seg\u00fan la Polic\u00eda Nacional de Ucrania.<\/p>\n<p>&#171;Ni siquiera pensamos en irnos. No quer\u00edamos dejar lo que tenemos. Nos vamos por los ni\u00f1os, para mantenerlos a salvo&#187;, dijo una de las madres evacuadas.<\/p>\n<p>Al menos una persona muri\u00f3 en Kostiantynivka y al menos 11 resultaron heridas durante la \u00faltima semana, seg\u00fan la polic\u00eda.<\/p>\n<p>Las autoridades ucranianas afirman que Rusia atac\u00f3 espec\u00edficamente la infraestructura civil en J\u00e1rkiv. (Ivan Samoilov\/AFP\/Getty Images)<\/p>\n<p>Ucrania ataca la regi\u00f3n rusa de Belgorod<\/p>\n<p>Mientras tanto, los ataques ucranianos al otro lado de la frontera con Rusia continuaron este s\u00e1bado.<\/p>\n<p>Al menos cinco personas murieron y m\u00e1s de 50 resultaron heridas en la regi\u00f3n rusa de Belgorod en las \u00faltimas 24 horas, dijo el gobernador regional.<\/p>\n<p>La mayor\u00eda de las v\u00edctimas se produjeron en la ciudad de Belgorod, donde tres personas murieron y 31 civiles, incluidos tres ni\u00f1os, resultaron heridos. M\u00e1s de 20 personas permanec\u00edan hospitalizadas el s\u00e1bado, dijo el gobernador Vyacheslav Gladkov.<\/p>\n<p>La infraestructura civil en toda la regi\u00f3n result\u00f3 da\u00f1ada, dijo.<\/p>\n<p>Los ataques ucranianos en la regi\u00f3n rusa de Kursk tambi\u00e9n continuaron, dijo Mosc\u00fa el s\u00e1bado. Las fuerzas de Kiev han logrado nuevos avances en su incursi\u00f3n en la regi\u00f3n fronteriza, dijo el jefe del ej\u00e9rcito de Ucrania el viernes.<\/p>\n<p>Las tropas de Kyiv han avanzado hasta 2 kil\u00f3metros m\u00e1s en algunas \u00e1reas durante las \u00faltimas 24 horas, tomando el control de otros 5 kil\u00f3metros cuadrados del territorio, dijo el viernes el comandante superior de Ucrania, Oleksandr Syrskyi.<\/p>\n<p>Adem\u00e1s de las v\u00edctimas en J\u00e1rkiv, los ataques rusos en territorio ucraniano han matado al menos a tres personas y herido a 16 en las \u00faltimas 24 horas, seg\u00fan las autoridades.<\/p>\n<p>La Fuerza A\u00e9rea de Ucrania dijo el s\u00e1bado que las fuerzas rusas hab\u00edan atacado Ucrania durante la noche con un misil bal\u00edstico Iskander-M lanzado desde la regi\u00f3n de Voronezh, cuatro misiles antia\u00e9reos guiados S-300 lanzados desde partes ocupadas de la regi\u00f3n de Donetsk y 52 drones Shahed lanzados desde la regi\u00f3n de Kursk.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8211;Las autoridades declarararon este s\u00e1bado un d\u00eda de luto en la ciudad ucraniana de J\u00e1rkiv, mientras los equipos de rescate y emergencia concluyen sus operaciones tras un ataque con bomba ruso que mat\u00f3 al menos a seis civiles, incluido un ni\u00f1o en un parque infantil. Al menos 97 personas resultaron heridas, incluidos 24 ni\u00f1os, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452324","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8211;Las autoridades declarararon este s\u00e1bado un d\u00eda de luto en la ciudad ucraniana de J\u00e1rkiv, mientras los equipos de rescate y emergencia concluyen sus operaciones tras un ataque con bomba ruso que mat\u00f3 al menos a seis civiles, incluido un ni\u00f1o en un parque infantil. Al menos 97 personas resultaron heridas, incluidos 24 ni\u00f1os, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-31T18:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos\",\"datePublished\":\"2024-08-31T18:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/\"},\"wordCount\":1063,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/\",\"name\":\"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-08-31T18:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos - Noticias","og_description":"(CNN) &#8211;Las autoridades declarararon este s\u00e1bado un d\u00eda de luto en la ciudad ucraniana de J\u00e1rkiv, mientras los equipos de rescate y emergencia concluyen sus operaciones tras un ataque con bomba ruso que mat\u00f3 al menos a seis civiles, incluido un ni\u00f1o en un parque infantil. Al menos 97 personas resultaron heridas, incluidos 24 ni\u00f1os, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/","og_site_name":"Noticias","article_published_time":"2024-08-31T18:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/"},"author":{"name":"","@id":""},"headline":"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos","datePublished":"2024-08-31T18:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/"},"wordCount":1063,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/","url":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/","name":"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-08-31T18:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un bombardeo ruso en la ciudad ucraniana de J\u00e1rkiv deja al menos ocho muertos y m\u00e1s de 100 heridos","url":"http:\/\/noticiasya.com\/tampa\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2024\/08\/31\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-08-31T18:03:52Z","datePublished":"2024-08-31T18:03:52Z","dateModified":"2024-08-31T18:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un bombardeo ruso en la ciudad ucraniana de J\\u00e1rkiv deja al menos ocho muertos y m\\u00e1s de 100 heridos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/31\\\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/08\\\/31\\\/bombardeo-ruso-jarkiv-seis-muertos-100-heridos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-08-31T18:03:52Z\",\"datePublished\":\"2024-08-31T18:03:52Z\",\"dateModified\":\"2024-08-31T18:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1449723,"url":"https:\/\/noticiasya.com\/tampa\/2024\/05\/23\/rusia-ataca-ciudad-ucrania-jarkiv-siete-muertos-trax\/","url_meta":{"origin":1452324,"position":0},"title":"Rusia ataca la ciudad ucraniana clave de J\u00e1rkiv y deja al menos siete muertos, a medida avanzan sus tropas terrestres","author":"","date":"mayo 23, 2024","format":false,"excerpt":"(CNN) -- Una ola de ataques con misiles rusos azot\u00f3 este jueves varios lugares en J\u00e1rkiv, incluida una imprenta en la capital regional, y mat\u00f3 a siete personas, a medida que avanzan las fuerzas del Kremlin.Las tropas rusas aprovecharon una l\u00ednea de frente debilitada en Ucrania y durante las \u00faltimas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1442967,"url":"https:\/\/noticiasya.com\/tampa\/2023\/12\/31\/rusia-toma-represalias-contra-ucrania-despues-de-un-ataque-que-dejo-24-muertos-en-una-ciudad-fronteriza\/","url_meta":{"origin":1452324,"position":1},"title":"Rusia toma represalias contra Ucrania despu\u00e9s de un ataque que dej\u00f3 24 muertos en una ciudad fronteriza","author":"","date":"diciembre 31, 2023","format":false,"excerpt":"(CNN) --\u00a0Rusia dijo que lanz\u00f3 ataques contra sitios militares y \"mercenarios extranjeros\" en J\u00e1rkiv en represalia al bombardeo ucraniano contra la ciudad fronteriza rusa de Belgorod en el que murieron al menos a 24 personas.Al menos tres personas murieron y otras 28 resultaron heridas despu\u00e9s de que J\u00e1rkiv fuera atacada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456946,"url":"https:\/\/noticiasya.com\/tampa\/2024\/12\/25\/ataque-aereo-rusia-ucrania-navidad-trax\/","url_meta":{"origin":1452324,"position":2},"title":"Rusia lanza un ataque a\u00e9reo &#171;masivo&#187; contra Ucrania en la ma\u00f1ana de Navidad","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"Rusia lanz\u00f3 ataques a\u00e9reos contra el sector energ\u00e9tico de Ucrania \u201ca escala masiva\u201d durante la madrugada de este mi\u00e9rcoles, seg\u00fan las autoridades locales, que informaron de explosiones en todo el pa\u00eds en medio de la intensificaci\u00f3n de los bombardeos que han dejado a Ucrania en una posici\u00f3n precaria mientras la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449762,"url":"https:\/\/noticiasya.com\/tampa\/2024\/05\/25\/dos-muertos-desaparecidos-rusia-atacara-jarkov-trax\/","url_meta":{"origin":1452324,"position":3},"title":"Al menos dos muertos y varios desaparecidos tras ataque de Rusia a una ferreter\u00eda en J\u00e1rkov","author":"","date":"mayo 25, 2024","format":false,"excerpt":"(CNN) -- Funcionarios informaron que al menos dos personas murieron y 33 resultaron heridas despu\u00e9s de un ataque ruso contra una gran ferreter\u00eda en J\u00e1rkiv, Ucrania, este s\u00e1bado.Seg\u00fan las autoridades, otras 11 personas siguen desaparecidas, todos ellos empleados del comercio.Las autoridades dijeron que hab\u00eda casi 200 personas dentro del edificio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452299,"url":"https:\/\/noticiasya.com\/tampa\/2024\/08\/30\/ataque-ruso-mata-menor-parque-infantil-jarkiv-trax\/","url_meta":{"origin":1452324,"position":4},"title":"Ataque ruso mata a un menor en un parque infantil de J\u00e1rkiv, seg\u00fan autoridades ucranianas","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) --\u00a0Un ataque mortal en la ciudad ucraniana de J\u00e1rkiv este viernes mat\u00f3 a una ni\u00f1a en un parque infantil y dej\u00f3 a otros muertos en un edificio residencial, dijeron las autoridades ucranianas. Al menos cinco personas murieron y 28 resultaron heridas en el ataque.El ataque del viernes \"no habr\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462458,"url":"https:\/\/noticiasya.com\/tampa\/2025\/05\/17\/autobus-ataque-ruso-sumy-ucrania-trax\/","url_meta":{"origin":1452324,"position":5},"title":"Ucrania afirma que un ataque ruso contra un autob\u00fas en Sumy deja nueve muertos, horas despu\u00e9s de las conversaciones de paz","author":"","date":"mayo 17, 2025","format":false,"excerpt":"Un ataque con un dron ruso contra un autob\u00fas en el noreste de Ucrania caus\u00f3 la muerte de al menos nueve personas y heridas a otras siete, informaron este s\u00e1bado las autoridades ucranianas, apenas horas despu\u00e9s de que ambos pa\u00edses se reunieran para las primeras conversaciones de paz directas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1452324"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452324\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1452324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1452324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1452324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}