{"id":1452376,"date":"2024-09-02T23:03:53","date_gmt":"2024-09-03T06:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/"},"modified":"2024-09-02T23:03:53","modified_gmt":"2024-09-03T06:03:53","slug":"biden-reaparece-principal-representante-campana-harris-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/tampa\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/","title":{"rendered":"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris"},"content":{"rendered":"<p>(CNN) &#8212; El presidente de Estados Unidos, Joe Biden, reaparece en la campa\u00f1a electoral esta semana, y entra en una nueva fase pol\u00edtica mientras cierra su etapa en la Casa Blanca y trabaja para garantizar que la vicepresidenta, Kamala Harris, le suceda.<\/p>\n<p>Biden y Harris iniciar\u00e1n juntos la carrera final hacia las elecciones el D\u00eda del Trabajo, aprovechando la festividad para atraer a los votantes de clase trabajadora con un acto en un local sindical de Pittsburgh, una demostraci\u00f3n de fuerza simb\u00f3lica en una ciudad a la que el propio Biden acudi\u00f3 a menudo en momentos clave de su carrera pol\u00edtica.<\/p>\n<p>Los viajes de campa\u00f1a de Biden se producen tambi\u00e9n en el contexto de los \u00faltimos acontecimientos en Medio Oriente, despu\u00e9s de que el Ej\u00e9rcito israel\u00ed recuperara los cad\u00e1veres de seis rehenes que, seg\u00fan afirma, fueron asesinados por Hamas en Gaza. Entre ellos se encuentra el israel\u00ed-estadounidense Hersh Goldberg-Polin, con cuyos padres hablaron Biden y Harris este domingo.<\/p>\n<p>Funcionarios de EE.UU. y China discuten las conversaciones entre Biden y Xi mientras las elecciones en Estados Unidos pesan sobre las relaciones bilaterales<\/p>\n<p>El regreso a la campa\u00f1a, cuidadosamente elaborado, se produce en un momento en el que el presidente est\u00e1 pasando de candidato a sustituto tras abandonar su propia candidatura a un segundo mandato. Biden dijo a los periodistas que est\u00e1 deseando volver a la campa\u00f1a tras dos semanas de vacaciones en California y Delaware. Seg\u00fan fuentes conocedoras de la situaci\u00f3n, sus asesores han pasado las \u00faltimas semanas esbozando sus planes de campa\u00f1a para el oto\u00f1o, con el fin de pulir su legado.<\/p>\n<p>El presidente se perfila con una hoja de ruta inicial que recorre Pensilvania, Wisconsin y Michigan durante los pr\u00f3ximos cinco d\u00edas, visitando los estados cr\u00edticos del &#171;muro azul&#187; en los que venci\u00f3 por estrecho margen al expresidente Donald Trump en 2020. Incluir\u00e1 una mezcla de actos de campa\u00f1a y oficiales para promover temas populares de su agenda, ofreciendo un esquema de c\u00f3mo se desplegar\u00e1 en los pr\u00f3ximos meses.<\/p>\n<p>Su reincorporaci\u00f3n tambi\u00e9n coincide con la reducci\u00f3n de las apariciones p\u00fablicas de Harris, que se centra en la preparaci\u00f3n del debate presidencial del 10 de septiembre. Biden la sustituir\u00e1 esta semana en los principales estados en disputa.<\/p>\n<p>Biden pide votar por Kamala Harris y recuperar la C\u00e1mara de Representantes 3:30<\/p>\n<p>Se espera que Biden, que ha experimentado un peque\u00f1o repunte en su \u00edndice de aprobaci\u00f3n en algunas encuestas desde que termin\u00f3 su campa\u00f1a de reelecci\u00f3n, pase una cantidad sustancial de tiempo en Pensilvania, el estado donde naci\u00f3 y donde sus aliados esperan que su capital pol\u00edtico pueda ayudar a Harris. Es un estado en el que Biden cree que la vicepresidenta &#171;tiene que ganar&#187;, y ha indicado que ha hablado con el gobernador de Pensilvania, Josh Shapiro, sobre la posibilidad de iniciar una gira por la comunidad.<\/p>\n<p>Los aliados dem\u00f3cratas tambi\u00e9n creen que Biden seguir\u00e1 teniendo influencia entre los votantes de cuello azul y los votantes de m\u00e1s edad, que constituyeron un bloque importante del apoyo del presidente en su candidatura de 2024, incluso cuando vio disminuir el apoyo de otros grupos clave.<\/p>\n<p>Existe una estrecha coordinaci\u00f3n entre el Ala Oeste, la oficina de la vicepresidenta y la campa\u00f1a sobre los planes para llevar a Biden de gira all\u00ed donde sea m\u00e1s \u00fatil, dijo una fuente familiarizada con el asunto. El lugar exacto y la frecuencia de su despliegue podr\u00edan evolucionar a medida que avance la contienda, dijeron las fuentes, ya que la campa\u00f1a de Harris se enfrenta a un per\u00edodo truncado para presentar sus argumentos a los votantes.<\/p>\n<p>Biden habl\u00f3 con Netanyahu este mi\u00e9rcoles en un momento cr\u00edtico en las conversaciones sobre Gaza<\/p>\n<p>Tambi\u00e9n se est\u00e1n manteniendo conversaciones para determinar c\u00f3mo se puede utilizar al presidente en el circuito de recaudaci\u00f3n de fondos en oto\u00f1o, dijeron las fuentes.<\/p>\n<p>Los equipos a\u00fan tienen que determinar la frecuencia con la que Biden y Harris har\u00e1n campa\u00f1a juntos, y un aliado dijo que podr\u00eda haber un enfoque de &#171;divide y vencer\u00e1s&#187; en el per\u00edodo previo al d\u00eda de las elecciones.<\/p>\n<p>El presidente ha indicado que est\u00e1 dispuesto a hacer lo que sea necesario en la campa\u00f1a, dijo una fuente familiarizada con la din\u00e1mica, porque en opini\u00f3n de la Casa Blanca, ha hecho &#171;una gran apuesta&#187; al hacerse a un lado, &#171;y tiene que funcionar&#187;.<\/p>\n<p>Biden celebrar\u00e1 esta semana actos en la Casa Blanca en una zona rural del suroeste de Wisconsin, donde se centrar\u00e1 en las inversiones en empleos de energ\u00edas limpias y los esfuerzos para combatir el cambio clim\u00e1tico, y en Michigan, donde destacar\u00e1 la creaci\u00f3n de empleo en una comunidad local.<\/p>\n<p>El presidente de EE.UU., Joe Biden, y la vicepresidenta y candidata presidencial dem\u00f3crata para 2024, Kamala Harris, en la Convenci\u00f3n Nacional Dem\u00f3crata en Chicago el 19 de agosto de 2024. (Cr\u00e9dito: Robyn Beck\/AFP v\u00eda Getty Images)<\/p>\n<p>&#171;Va a participar realmente en la campa\u00f1a y exponer lo que ha hecho el Gobierno. Esa es una de las cosas clave que hay que destacar&#187;, dijo el exsenador por Delaware Ted Kaufman, amigo \u00edntimo y asesor de Biden desde hace mucho tiempo. &#171;Hay que ponerse manos a la obra&#187;.<\/p>\n<p>Pero podr\u00eda resultar una l\u00ednea muy fina para los dem\u00f3cratas, ya que los republicanos est\u00e1n ansiosos por vincular a Harris con lo que consideran pol\u00edticas fallidas de Biden en temas como la inmigraci\u00f3n y la econom\u00eda, \u00e1reas en las que Trump ha obtenido mejores resultados en las encuestas durante toda la campa\u00f1a.<\/p>\n<p>Aunque ha defendido una &#171;nueva forma de avanzar&#187;, Harris a\u00fan no se ha distanciado del historial de Biden en pol\u00edtica interior o exterior. Pero ha recurrido a diferentes estrategias de comunicaci\u00f3n, incluido un discurso econ\u00f3mico centrado en la accesibilidad en torno a cuestiones como los precios de los alimentos y la vivienda.<\/p>\n<p>La campa\u00f1a de Harris lanza un canal de WhatsApp dirigido a los votantes latinos<\/p>\n<p>En una entrevista concedida a CNN la semana pasada, Harris defendi\u00f3 la trayectoria econ\u00f3mica del presidente y eludi\u00f3 las preguntas sobre por qu\u00e9 no ha actuado en los nuevos asuntos que propone en campa\u00f1a durante su mandato como vicepresidenta.<\/p>\n<p>&#171;Ten\u00edamos que recuperarnos como econom\u00eda, y lo hemos hecho&#187;, dijo, se\u00f1alando su trabajo con Biden para reducir la inflaci\u00f3n y bajar los costes de los medicamentos con receta.<\/p>\n<p>&#171;Queda m\u00e1s por hacer, pero es un buen trabajo&#187;, afirm\u00f3.<\/p>\n<p>Harris tambi\u00e9n elogi\u00f3 a su excompa\u00f1ero de f\u00f3rmula, diciendo a CNN que Biden &#171;tiene la inteligencia, el compromiso, el juicio y la disposici\u00f3n que creo que el pueblo estadounidense merece en su presidente&#187;.<\/p>\n<p>Hacer el trabajo<\/p>\n<p>Adem\u00e1s de tratar de impulsar la candidatura de Harris, el presidente tambi\u00e9n est\u00e1 aprovechando este periodo para centrarse en objetivos clave de pol\u00edtica interior y exterior que quiere abordar antes de dejar el cargo,<\/p>\n<p>Ben LaBolt, director de comunicaciones de la Casa Blanca, dijo que el presidente se &#171;inclinar\u00e1 fuertemente&#187; a hacer campa\u00f1a por Harris al tiempo que se centra en gobernar.<\/p>\n<p>&#171;La agenda ser\u00e1 intensa, y tiene previsto dejarlo todo sobre el terreno para conseguir el mayor progreso posible para los estadounidenses que trabajan duro, ya sea mediante la acci\u00f3n ejecutiva o legislativa&#187;, afirm\u00f3 LaBolt.<\/p>\n<p>Biden ha presionado a su equipo para que se centre en la aplicaci\u00f3n de la legislaci\u00f3n clave y los esfuerzos para reducir los costos, junto con el trabajo en temas de legado como la iniciativa &#171;Cancer Moonshot&#187;, el apoyo a los veteranos, la lucha contra la violencia armada y la administraci\u00f3n de la inteligencia artificial, entre otras prioridades.<\/p>\n<p>Biden dice a Estados Unidos: \u201cTe di lo mejor de m\u00ed\u201d<\/p>\n<p>Trabajar para poner fin al conflicto entre Israel y Hamas sigue siendo una prioridad clave para el presidente, que recientemente ha hecho sendas llamadas a los l\u00edderes de Israel, Egipto y Qatar para impulsar los esfuerzos por alcanzar un alto el fuego y un acuerdo sobre los rehenes.<\/p>\n<p>&#171;Es hora de que esta guerra termine&#187;, dijo Biden el s\u00e1bado. &#171;Creo que estamos a punto de llegar a un acuerdo. Es hora de ponerle fin. Es hora de terminarla&#187;.<\/p>\n<p>La guerra en Ucrania es tambi\u00e9n uno de los temas principales de la agenda de Biden en sus \u00faltimos meses en el cargo. Recientemente habl\u00f3 con el presidente de Ucrania, Volodymyr Zelensky, que envi\u00f3 altos funcionarios a Washington la semana pasada.<\/p>\n<p>Zelensky dice que la incursi\u00f3n en Rusia es parte del plan de victoria que pretende mostrar a Biden<\/p>\n<p>Tambi\u00e9n se espera que el presidente, que ya no se ve limitado por las exigencias de la campa\u00f1a electoral, viaje al extranjero, considerando viajes a Polonia, a la cumbre del Foro de Cooperaci\u00f3n Econ\u00f3mica Asia-Pac\u00edfico en Per\u00fa, a la cumbre del G20 en Brasil y a \u00c1frica, donde lleva tiempo prometiendo una visita. Tambi\u00e9n se espera que asista a la reuni\u00f3n anual de la Asamblea General de las Naciones Unidas en Nueva York el mes que viene.<\/p>\n<p>Para Harris puede ser beneficioso tener a Biden en la escena mundial reuni\u00e9ndose con sus pares y reafirmando el liderazgo de Estados Unidos.<\/p>\n<p>&#171;La est\u00e1 preparando para el \u00e9xito al refrescar esas relaciones, y nadie lo hace mejor que \u00e9l&#187;, declar\u00f3 un antiguo funcionario estadounidense.<\/p>\n<p>C\u00f3mo podr\u00eda ayudar Biden<\/p>\n<p>Con su decisi\u00f3n de hacerse a un lado, Biden ha hecho la transici\u00f3n de principal a sustituto, reconociendo la nueva din\u00e1mica en sus declaraciones en la Convenci\u00f3n Nacional Dem\u00f3crata el mes pasado.<\/p>\n<p>&#171;Prometo que ser\u00e9 el mejor voluntario que la campa\u00f1a de Harris-Walz haya visto jam\u00e1s&#187;, dijo.<\/p>\n<p>El servicio y el legado de Biden fueron ampliamente elogiados aquella noche en Chicago, pero los tres d\u00edas siguientes de programaci\u00f3n de la convenci\u00f3n giraron en torno al futuro del partido. A\u00fan as\u00ed, mantiene su popularidad entre algunos grupos demogr\u00e1ficos clave que ser\u00e1n decisivos en noviembre.<\/p>\n<p>AN\u00c1LISIS | La entrevista de Harris con CNN es el \u00faltimo y muy esperado giro en la desenfrenada carrera presidencial<\/p>\n<p>Aunque se vio obligado a retirarse de la carrera de 2024 por preocupaciones sobre su edad y su capacidad para hacer campa\u00f1a, algunas encuestas han mostrado que los \u00edndices de aprobaci\u00f3n de Biden han subido. El \u00edndice de aprobaci\u00f3n del presidente se sit\u00faa en el 41%, seg\u00fan la encuesta de CNN Polls, frente al 37% de julio.<\/p>\n<p>&#171;Va a ser un sustituto especialmente poderoso para la vicepresidenta porque es muy querido y ser\u00e1 muy recordado&#187;, dijo Mitch Landrieu, copresidente de la campa\u00f1a de Harris que trabaj\u00f3 con el presidente y la vicepresidenta en la Casa Blanca. &#171;Su acto desinteresado de dimitir le ha dado una credibilidad incre\u00edble&#187;.<\/p>\n<p>Biden, ha dicho la presidenta de AFL-CIO, Liz Shuler, en una entrevista con CNN, ser\u00e1 &#171;el defensor definitivo&#187; de Harris ante los trabajadores afiliados a sindicatos. Shuler ha se\u00f1alado que 1 de cada 5 votantes en los estados del muro azul Michigan, Wisconsin y Minnesota son votantes sindicados, y que el 22% de los votantes de Pensilvania son votantes sindicados, un grupo que favorece rotundamente a Harris.<\/p>\n<p>AN\u00c1LISIS | Harris y Trump compiten por el centro<\/p>\n<p>&#171;Biden ser\u00eda muy motivador para la gente, y ser\u00eda un recurso m\u00e1s que la campa\u00f1a tendr\u00eda en su caja de herramientas&#187;, dijo Shuler.<\/p>\n<p>Biden tambi\u00e9n ser\u00e1 un sustituto clave de Harris entre los votantes de m\u00e1s edad. Si bien perdi\u00f3 terreno con varios grupos demogr\u00e1ficos clave mientras estaba en la carrera de 2024, el presidente hizo avances significativos con los votantes de m\u00e1s edad, un grupo que t\u00edpicamente ha votado por los republicanos.<\/p>\n<p>En su primer evento juntos despu\u00e9s de que Biden se retirara de la carrera, el presidente y la vicepresidenta se centraron en la capacidad de Medicare para negociar el precio de los medicamentos recetados, un tema que podr\u00eda resonar entre los votantes mayores.<\/p>\n<p>Biden explica qu\u00e9 lo motiv\u00f3 a postularse en 2020 2:47<\/p>\n<p>El factor Pensilvania<\/p>\n<p>Biden no ha ocultado lo importante que ser\u00e1 Pensilvania en las elecciones de noviembre. \u00c9l movi\u00f3 el estado de nuevo a la columna azul en 2020, superando a Trump all\u00ed por menos de 2 puntos porcentuales.<\/p>\n<p>&#171;Tenemos que ganar Pensilvania, mi estado natal original. (Shapiro) y yo estamos organizando una gira de campa\u00f1a en Pensilvania&#187;, dijo Biden en una entrevista con \u201cSunday Morning\u201d de CBS el mes pasado. &#171;Tambi\u00e9n voy a hacer campa\u00f1a en otros estados. Y voy a hacer lo que Kamala crea que puedo hacer para ayudar m\u00e1s&#187;.<\/p>\n<p>La victoria de Biden en 2020 se deriv\u00f3 de recabar apoyos en la zona de Filadelfia y apelar a los votantes del oeste y el noreste del estado, incluida la zona donde se encuentra su querida Scranton.<\/p>\n<p>Votantes de Pensilvania reaccionan al respaldo de Biden a Harris<\/p>\n<p>&#171;Joe Biden, creo, demostr\u00f3 ser el \u00fanico capaz de recuperar a los carpinteros, camioneros, obreros que se hab\u00edan alejado hacia Trump en 2016&#187;, dijo Conor Lamb, excongresista por Pensilvania, sobre el trabajo de Biden en las regiones noreste y oeste del estado.<\/p>\n<p>El presidente y la vicepresidenta har\u00e1n campa\u00f1a juntos en el condado de Allegheny, donde la campa\u00f1a de Biden vio crecer su apoyo en 2020 en comparaci\u00f3n con la de la excandidata dem\u00f3crata Hillary Clinton contra Trump un ciclo antes.<\/p>\n<p>Tambi\u00e9n es un \u00e1rea que ha ayudado a dar forma a la carrera pol\u00edtica de Biden.<\/p>\n<p>As\u00ed va la actividad pol\u00edtica de Harris y Trump a 64 d\u00edas de las elecciones<\/p>\n<p>En 2015, corri\u00f3 por la ruta de un desfile del D\u00eda del Trabajo en el centro de Pittsburgh al grito de &#171;\u00a1Corre, Joe, corre!&#187; en un momento en que estaba sopesando una entrada tard\u00eda en las primarias dem\u00f3cratas. Al final decidi\u00f3 no lanzar una campa\u00f1a, ya que segu\u00eda lidiando con la muerte de su hijo Beau.<\/p>\n<p>Biden volvi\u00f3 a ese mismo desfile del D\u00eda del Trabajo cuando meditaba presentarse a las elecciones de 2020. Y en Pittsburgh es donde empez\u00f3 y termin\u00f3 esa carrera hacia la Casa Blanca: empez\u00f3 con un mitin con trabajadores sindicales en abril de 2019 y volvi\u00f3 en la v\u00edspera de las elecciones para un mitin automovil\u00edstico al aire libre con Lady Gaga.<\/p>\n<p>Ahora Biden volver\u00e1 a esa ciudad al entrar en un nuevo cap\u00edtulo de sus m\u00e1s de cinco d\u00e9cadas en pol\u00edtica, buscando impulsar a su sucesora elegida Harris, de quien ha dicho que ser\u00e1 &#171;una presidenta incre\u00edble&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El presidente de Estados Unidos, Joe Biden, reaparece en la campa\u00f1a electoral esta semana, y entra en una nueva fase pol\u00edtica mientras cierra su etapa en la Casa Blanca y trabaja para garantizar que la vicepresidenta, Kamala Harris, le suceda. Biden y Harris iniciar\u00e1n juntos la carrera final hacia las elecciones el D\u00eda [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1452376","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El presidente de Estados Unidos, Joe Biden, reaparece en la campa\u00f1a electoral esta semana, y entra en una nueva fase pol\u00edtica mientras cierra su etapa en la Casa Blanca y trabaja para garantizar que la vicepresidenta, Kamala Harris, le suceda. Biden y Harris iniciar\u00e1n juntos la carrera final hacia las elecciones el D\u00eda [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-03T06:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris\",\"datePublished\":\"2024-09-03T06:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/\"},\"wordCount\":2521,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/\",\"name\":\"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-09-03T06:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris - Noticias","og_description":"(CNN) &#8212; El presidente de Estados Unidos, Joe Biden, reaparece en la campa\u00f1a electoral esta semana, y entra en una nueva fase pol\u00edtica mientras cierra su etapa en la Casa Blanca y trabaja para garantizar que la vicepresidenta, Kamala Harris, le suceda. Biden y Harris iniciar\u00e1n juntos la carrera final hacia las elecciones el D\u00eda [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/","og_site_name":"Noticias","article_published_time":"2024-09-03T06:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/"},"author":{"name":"","@id":""},"headline":"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris","datePublished":"2024-09-03T06:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/"},"wordCount":2521,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/","url":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/","name":"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-09-03T06:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/tampa\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\u00f1a de Harris","url":"http:\/\/noticiasya.com\/tampa\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/tampa\/2024\/09\/02\/biden-reaparece-principal-representante-campana-harris-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-09-03T06:03:53Z","datePublished":"2024-09-03T06:03:53Z","dateModified":"2024-09-03T06:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Biden, que ya no es candidato, reaparece como principal sustituto de la campa\\u00f1a de Harris\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/09\\\/02\\\/biden-reaparece-principal-representante-campana-harris-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/tampa\\\/2024\\\/09\\\/02\\\/biden-reaparece-principal-representante-campana-harris-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-09-03T06:03:53Z\",\"datePublished\":\"2024-09-03T06:03:53Z\",\"dateModified\":\"2024-09-03T06:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451430,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/26\/lanzamiento-campana-kamala-harris-cambio-carrera-presidencial-2024-trax\/","url_meta":{"origin":1452376,"position":0},"title":"C\u00f3mo el lanzamiento de campa\u00f1a de Kamala Harris, a una velocidad extrema, ha cambiado la carrera presidencial de 2024","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN) -- Los cinco d\u00edas transcurridos desde el lanzamiento a toda velocidad de la campa\u00f1a de la vicepresidenta Kamala Harris han transformado la carrera para 2024 y han dado a los dem\u00f3cratas nuevas esperanzas de evitar una segunda presidencia de Donald Trump.En las redes sociales han surgido memes a favor\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451312,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/22\/kamala-harris-candidata-democrata-respuestas-preguntas-decision-biden-abandonar-carrera-electoral-trax\/","url_meta":{"origin":1452376,"position":1},"title":"\u00bfEs Kamala Harris ahora la candidata dem\u00f3crata? Respuestas a las preguntas clave sobre la decisi\u00f3n de Biden de abandonar la carrera electoral","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN) -- El presidente Joe Biden anunci\u00f3 este domingo que no buscar\u00e1 ser reelegido como presidente en 2024, y respald\u00f3 a la vicepresidenta Kamala Harris para convertirse en la candidata dem\u00f3crata.Pero la decisi\u00f3n del presidente de 81 a\u00f1os \u2014a poco m\u00e1s de 100 d\u00edas de las elecciones\u2014 dio lugar a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451338,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/22\/que-pasara-con-us-96-millones-efectivo-campana-biden-harris-trax\/","url_meta":{"origin":1452376,"position":2},"title":"\u00bfQu\u00e9 pasar\u00e1 con los casi US$ 96 millones en efectivo recolectados por la campa\u00f1a de Biden?","author":"","date":"julio 22, 2024","format":false,"excerpt":"(CNN) --\u00a0La campa\u00f1a Biden-Harris modific\u00f3 formalmente este domingo los documentos presentados ante la Comisi\u00f3n Federal Electoral para cambiar el nombre de su comit\u00e9 principal y declarar a Kamala Harris candidata dem\u00f3crata a la presidencia.Seg\u00fan el Centro Legal de Campa\u00f1as, en caso de que Harris se mantenga en la candidatura para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1454969,"url":"https:\/\/noticiasya.com\/tampa\/2024\/10\/06\/harris-biden-desacuerdos-trax\/","url_meta":{"origin":1452376,"position":3},"title":"Harris sopesa m\u00e1s rupturas con Biden mientras participa en la campa\u00f1a","author":"","date":"octubre 6, 2024","format":false,"excerpt":"(CNN) -- Los principales asesores de Kamala Harris se dirigen hacia \u00faltimo mes de la carrera presidencial de 2024 todav\u00eda luchando con cu\u00e1nta distancia puede reclamar de forma cre\u00edble de Joe Biden, mientras busca m\u00e1s formas de intercalar rupturas con \u00e9l en la campa\u00f1a.Pero ella se ve arrastrada a su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451311,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/21\/equipo-trump-arremete-kamala-harris-trax\/","url_meta":{"origin":1452376,"position":4},"title":"El equipo de Trump ya empez\u00f3 a arremeter contra Kamala Harris","author":"","date":"julio 21, 2024","format":false,"excerpt":"(CNN) -- El domingo despu\u00e9s del debate presidencial del 27 de junio, los principales asesores de Donald Trump se fueron a la cama esperando que las quejas de los dem\u00f3cratas por la actuaci\u00f3n del presidente Joe Biden se enfriaran y dieran paso a un nuevo ciclo de titulares al comienzo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451300,"url":"https:\/\/noticiasya.com\/tampa\/2024\/07\/21\/por-que-biden-se-retiro-como-candidato-orix\/","url_meta":{"origin":1452376,"position":5},"title":"\u00bfPor qu\u00e9 Biden se retir\u00f3 como candidato dem\u00f3crata? Los momentos que dinamitaron su candidatura","author":"","date":"julio 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El retiro de Joe Biden de la campa\u00f1a presidencial se produjo despu\u00e9s semanas de preocupaci\u00f3n sobre la resistencia f\u00edsica y las capacidades mentales del presidente de 81 a\u00f1os y de escepticismo sobre su habilidad para hacer campa\u00f1a eficazmente contra el expresidente Donald Trump, as\u00ed como las inquietudes\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/tampa\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/comments?post=1452376"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/posts\/1452376\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/media?parent=1452376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/categories?post=1452376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/tampa\/wp-json\/wp\/v2\/tags?post=1452376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}